{"id":69878,"date":"2008-05-07T00:00:00","date_gmt":"2008-05-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/07\/vexes-non-peut-etre-un-moment-desenchantes\/"},"modified":"2008-05-07T00:00:00","modified_gmt":"2008-05-07T00:00:00","slug":"vexes-non-peut-etre-un-moment-desenchantes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/07\/vexes-non-peut-etre-un-moment-desenchantes\/","title":{"rendered":"<strong><em>Vex\u00e9s? Non, peut-\u00eatre un moment d\u00e9senchant\u00e9s&#8230;<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Vex\u00e9s? Non, peut-\u00eatre un moment d\u00e9senchant\u00e9s&#8230;<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t7 mai 2008  Rappellons ce rappel \u00e0 l&rsquo;ordre d&rsquo;un lecteur, le 24 avril, qui servira d&rsquo;introduction bienvenue \u00e0 notre message. (Ce texte est pr\u00e9sent\u00e9 temporairement en rubrique <em>Faits &#038; Commentaires<\/em>, pour attirer l&rsquo;attention et susciter d&rsquo;autant plus, nous l&rsquo;esp\u00e9rons, l&rsquo;int\u00e9r\u00eat de nos lecteurs. Il sera reclass\u00e9 dans notre rubrique <em>Messagerie<\/em> dans quelques jours, lorsque commencera notre deuxi\u00e8me campagne 2008.)<\/p>\n<\/p>\n<p><p>\tNotre lecteur, <em>Jeff<\/em>, nous \u00e9crivait ce <a href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=4853\" class=\"gen\">24 avril<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bient\u00f4t, quoi, trois mois de silence ? Apr\u00e8s l&rsquo;\u00e9chec relatif de votre campagne de financement.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nous aurions appr\u00e9ci\u00e9 un commentaire, une r\u00e9flexion de votre part sur cet \u00e9pisode. Mais c&rsquo;est le silence, c&rsquo;est dommage. Z&rsquo;\u00eates vex\u00e9?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAdmonestation justifi\u00e9e&#8230; Toutefois, nous contestons le dernier mot employ\u00e9. Nous n&rsquo;avons certes pas \u00e9t\u00e9 vex\u00e9s mais plut\u00f4t, comme l&rsquo;indique notre titre, peut-\u00eatre un moment d\u00e9senchant\u00e9s; peut-\u00eatre, \u00e9galement, un moment de d\u00e9couragement, certainement pour ce qui concerne la formule des donations (pour l&rsquo;activit\u00e9 du site elle-m\u00eame, nos lecteurs sont t\u00e9moins que cet instant de d\u00e9couragement n&rsquo;a gu\u00e8re eu de cons\u00e9quence); enfin, certainement une r\u00e9elle incertitude \u00e0 propos de cette formule. Nous n&rsquo;avons pas voulu \u00e9crire un texte, aussit\u00f4t \u00e0 la suite de cette campagne de donation d\u00e9cevante, sous le coup de ces \u00e9motions. Bref, nous n&rsquo;avons rien \u00e9crit \u00e0 propos de cette campagne ni tir\u00e9 aucun bilan. Reste aujourd&rsquo;hui l&rsquo;incertitude.<\/p>\n<\/p>\n<p><p>\t(Quant \u00e0 l&rsquo;id\u00e9e d&rsquo;\u00e9chef relatif selon <em>Jeff<\/em>, c&rsquo;est l&rsquo;\u00e9vidence. Nous avions fix\u00e9 notre ambition \u00e0 13.000. Nous avons obtenu 6.750. Echec relatif ou \u00e9chec cuisant? Les chiffres sont cruels. Ils offraient un contraste \u00e9galement un peu d\u00e9courageant par rapport \u00e0 la campagne de donation de juillet-ao\u00fbt 2007 o\u00f9 nous avions atteint et d\u00e9pass\u00e9 le but de 10.000 que nous nous \u00e9tions fix\u00e9.)<\/p>\n<\/p>\n<p><p>\tNous ne devons pas nous en tenir \u00e0 cette premi\u00e8re exp\u00e9rience d\u00e9cevante de janvier-f\u00e9vrier, qui commen\u00e7ait un cycle annuel complet. Nous devons conduire \u00e0 son terme l&rsquo;exp\u00e9rience plus g\u00e9n\u00e9rale du cycle annuel pour disposer d&rsquo;une appr\u00e9ciation plus circonstanci\u00e9e qui nous permettra de d\u00e9terminer en meilleure connaissance de cause notre orientation. Nous allons donc lancer, dans quelques jours, une deuxi\u00e8me campagne de donation. Une troisi\u00e8me aura lieu \u00e0 l&rsquo;automne, comme nous l&rsquo;avions <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4804\" class=\"gen\">d\u00e9j\u00e0<\/a> annonc\u00e9 en ouverture de la premi\u00e8re campagne pour 2008. Voici une citation de ce texte du 5 janvier 2008 pour rappeller nos objectifs, dont nous sommes bien loin pour l&rsquo;instant:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>2008, grande ann\u00e9e pour de defensa.org. Ann\u00e9e de d\u00e9cision, surtout, au travers de vos r\u00e9actions. Apr\u00e8s quelques h\u00e9sitations, nous avons pr\u00e9f\u00e9r\u00e9 abandonner l&rsquo;id\u00e9e de lancer une derni\u00e8re campagne de donation fin 2007. Nous pr\u00e9f\u00e9rons que la rupture soit plus nette, que 2008 soit vraiment une ann\u00e9e compl\u00e8te d&rsquo;exp\u00e9rimentation du syst\u00e8me que nous vous proposons. Le 3 janvier 2008, nous lan\u00e7ons la premi\u00e8re campagne d&rsquo;appel \u00e0 donation. Notre but sera d&rsquo;atteindre 13.000, de fa\u00e7on \u00e0 r\u00e9unir les 40.000 (39.000) en trois campagnes pour 2008. Comme nous vous l&rsquo;avions dit, nous pr\u00e9f\u00e9rons ce chiffre aux 10.000 que nous recherchions jusqu&rsquo;ici par campagne pour r\u00e9duire le nombre de campagnes \u00e0 trois. En principe, les deux autres campagnes auront lieu du d\u00e9but mai \u00e0 la mi-juin et de la mi-septembre \u00e0 la fin-octobre.<\/em>\u00bb<\/p>\n<h3>Une \u00e9volution \u00e9vidente<\/h3>\n<\/p>\n<p><p>\tNous n&rsquo;avons pas grand&rsquo;chose \u00e0 ajouter dans l&rsquo;argumentation, pour ce qui concerne notre organisation, nos buts, nos ambitions. Il est \u00e9vident que si ces campagnes de donation ne donnaient pas le r\u00e9sultat attendu, ou dans tous les cas approchant, nous devrions explorer et appliquer une autre formule. De cela, nous vous avons \u00e9galement entretenu.<\/p>\n<\/p>\n<p><p>\tPour le reste, qui est d&rsquo;un autre point de vue l&rsquo;essentiel, il nous semble que les \u00e9v\u00e9nements et la fa\u00e7on dont <em>dedefensa.org<\/em> les suit renforcent notre argumentation g\u00e9n\u00e9rale de l&rsquo;utilit\u00e9 de ce site (et, par cons\u00e9quent, de la n\u00e9cessit\u00e9 de son soutien par vous, lecteurs). Il appara\u00eet que ce qui s&rsquo;est pass\u00e9 depuis le d\u00e9but 2008 confirme chaque jour que nous sommes entr\u00e9 dans une p\u00e9riode cruciale de notre temps historique, et de notre histoire tout court, dans une \u00e9poque o\u00f9 la communication et l&rsquo;information jouent incontestablement le <strong>premier r\u00f4le<\/strong> de la bataille gigantesque qui est en cours. La n\u00e9cessit\u00e9 de sources alternatives d&rsquo;information et de commentaire, en pr\u00e9sence d&rsquo;une information officielle et d&rsquo;une presse officielle en totale d\u00e9liquescence et engag\u00e9es dans une entreprise \u00e9trange et monstrueuse de d\u00e9ni de la r\u00e9alit\u00e9,  cette n\u00e9cessit\u00e9 ne cesse de s&rsquo;affirmer, de se renforcer.<\/p>\n<\/p>\n<p><p>\tNous ne sommes pas face \u00e0 une censure puissante qui nous emp\u00eacherait d&rsquo;agir, comme c&rsquo;\u00e9tait le cas dans les r\u00e9gimes totalitaires classiques. Nous n&rsquo;avons pas de r\u00e9f\u00e9rences fixes, y compris cette r\u00e9f\u00e9rence que serait une information officielle compl\u00e8tement dirig\u00e9e et qui constituerait un ennemi clair et \u00e9vident. Nous avons d\u00e9velopp\u00e9 \u00e0 plusieurs reprises notre appr\u00e9ciation selon laquelle la relativit\u00e9 de la perception, entre les multiples sources d&rsquo;information et de d\u00e9sinformation, au coeur de ce ph\u00e9nom\u00e8ne que nous nommons virtualisme, touche \u00e9galement les milieux officiels et les \u00e9lites. Voyez encore notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5098\" class=\"gen\">5 mai<\/a> \u00e0 propos de la perception de la situation am\u00e9ricaniste: <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Pr\u00e9cisons notre propos. L&rsquo;aveuglement dont nous parlons n&rsquo;est pas absolument celui de la m\u00e9connaissance par sottise ou du refus inconscient de la connaissance par r\u00e9flexe pavlovien d&rsquo;enfermement du jugement. Le cas existe \u00e9videmment car les caract\u00e8res faibles et les psychologies pauvres abondent. A c\u00f4t\u00e9, il existe de-\u00e7i de-l\u00e0, et de plus en plus, nous en avons l&rsquo;\u00e9cho assur\u00e9, des esprits plac\u00e9s dans les rouages des pouvoirs ou fort proches qui commencent \u00e0 r\u00e9aliser et \u00e0 mesurer la monstruosit\u00e9 de la crise US qui se d\u00e9veloppe (et des autres crises \u00e9galement, parall\u00e8lement) et l&rsquo;ab\u00eeme o\u00f9 ce mouvement convulsif conduit cette puissance. Leurs constats sont cr\u00e9pusculaires et leur conclusion d\u00e9sesp\u00e9r\u00e9e par l&rsquo;absence de r\u00e9ponse \u00e0 cette question: que faire?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A c\u00f4t\u00e9 de ces divers cas individuels existe une consigne g\u00e9n\u00e9rale non \u00e9crite, justifi\u00e9e par un r\u00e9flexe de refus du r\u00e9el, qui est celle de l&#8217;emprisonnement volontaire du jugement..<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEt nous terminions ce texte en sugg\u00e9rant <em>in fine<\/em> ce qui constitue aujourd&rsquo;hui la censure, ou l&rsquo;auto-censure du syst\u00e8me: une sorte d&rsquo;automatisme de refus de la r\u00e9alit\u00e9 par la conscience, nullement par intervention arbitraire mais pas faiblesse du caract\u00e8re et du jugement: \u00ab<em>Il reste que nous atteignons le coeur d&rsquo;une \u00e9poque d&rsquo;affreux d\u00e9s\u00e9quilibre psychologique entre une pens\u00e9e officielle qui s&rsquo;interdit le mode de pens\u00e9e eschatologique et une pens\u00e9e tout court qui n&rsquo;ose pas encore l&rsquo;aborder franchement, et une psychologie qui en est impr\u00e9gn\u00e9e chaque jour un peu plus. C&rsquo;est le dernier acte possible de censure, ou plut\u00f4t d&rsquo;auto-censure de cette civilisation.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous avons notre r\u00f4le \u00e0 jouer, qui ne d\u00e9pend ni de notre poids \u00e9conomique ni de notre position institutionnelle, ni de notre pouvoir politique. Dans cette curieuse \u00e9poque o\u00f9 la libert\u00e9 formelle est partout proclam\u00e9e et o\u00f9 la libert\u00e9 r\u00e9elle est volontairement ignor\u00e9e par les caract\u00e8res faibles et le r\u00e9flexe du conformisme qui composent une formule in\u00e9dite et postmoderne de servilit\u00e9 volontaire, nous disposons d&rsquo;instruments pour affirmer avec force et conduire sans faiblesse la recherche de v\u00e9rit\u00e9 de la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>\tEffectivement, nous pensons \u00eatre de ceux-l\u00e0 qui conduisent cette recherche. Nous avons la faiblesse de croire que nos lecteurs comprennent et appr\u00e9cient <em>dedefensa.org<\/em> de cette fa\u00e7on. Il n&rsquo;est pas n\u00e9cessaire de vous en dire plus pour vous pr\u00e9senter l&rsquo;argument central pour le soutien de <em>dedefensa.org<\/em>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vex\u00e9s? Non, peut-\u00eatre un moment d\u00e9senchant\u00e9s&#8230; 7 mai 2008 Rappellons ce rappel \u00e0 l&rsquo;ordre d&rsquo;un lecteur, le 24 avril, qui servira d&rsquo;introduction bienvenue \u00e0 notre message. (Ce texte est pr\u00e9sent\u00e9 temporairement en rubrique Faits &#038; Commentaires, pour attirer l&rsquo;attention et susciter d&rsquo;autant plus, nous l&rsquo;esp\u00e9rons, l&rsquo;int\u00e9r\u00eat de nos lecteurs. Il sera reclass\u00e9 dans notre rubrique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2631,3315,4854,6919],"class_list":["post-69878","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-de","tag-defensa","tag-donation","tag-message"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69878"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69878\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}