{"id":69915,"date":"2008-05-23T00:00:00","date_gmt":"2008-05-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/23\/tiens-il-se-passe-quelque-chose\/"},"modified":"2008-05-23T00:00:00","modified_gmt":"2008-05-23T00:00:00","slug":"tiens-il-se-passe-quelque-chose","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/23\/tiens-il-se-passe-quelque-chose\/","title":{"rendered":"Tiens, il se passe quelque chose\u2026"},"content":{"rendered":"<p><h2 class=\"common-article\">Tiens, il se passe quelque chose<\/h2>\n<\/p>\n<p><p>\t23 mai 2008  Il n&rsquo;est pas n\u00e9cessaire d&rsquo;aller bien loin. Deux articles successifs dans <em>Le Monde<\/em>, et voil\u00e0, on vous l&rsquo;assure, les couloirs de la Commission europ\u00e9enne boulevers\u00e9s. (Ce sont effectivement des textes qui circulent et qui font hocher les t\u00eates.) Il faut dire qu&rsquo;assembl\u00e9s, ils constituent une belle vol\u00e9e de bois vert contre la mondialisation. (Que nous <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1325\" class=\"gen\">persisterions<\/a> \u00e0 nommer plut\u00f4t globalisation, qui est un terme compl\u00e8tement diff\u00e9rent, et profitant ainsi de l&rsquo;antique vertu de la langue fran\u00e7aise,  elle qui dispose de ces deux mots, au contraire de l&rsquo;anglais par exemple.)<\/p>\n<\/p>\n<p><p>\tLes titres nous en disent beaucoup. \u00ab<em>La finance folle ne doit pas nous gouverner<\/em>\u00bb, publi\u00e9 le <a href=\"http:\/\/www.lemonde.fr\/web\/imprimer_element\/0,40-0@2-3232,50-1047738,0.html\" class=\"gen\">21 mai<\/a> ; \u00ab<em>21 sages pour une mondialisation moins sauvage<\/em>\u00bb, publi\u00e9 le <a href=\"http:\/\/www.lemonde.fr\/archives\/article\/2008\/05\/22\/21-sages-pour-une-mondialisation-moins-sauvage_1048251_0.html\" class=\"gen\">22 mai<\/a>. Le premier texte est sign\u00e9 de divers noms prestigieux et europ\u00e9ens (Jacques Delors, Jacques Santer, Helmut Schmidt, Massimo d&rsquo;Alema, Lionel Jospin, Pavvo Lipponen, Michel Rocard, Otto Graf Lambsdorff, etc.). Le second pr\u00e9sente le rapport d&rsquo;une Commission, dite des 21,  et l&rsquo;on nous pr\u00e9cise aussit\u00f4t: \u00ab<em>Cette commission ne peut \u00eatre suspect\u00e9e d&rsquo;altermondialisme: pr\u00e9sid\u00e9e par le Prix Nobel am\u00e9ricain Michael Spence, un lib\u00e9ral orthodoxe, elle compte vingt et une sommit\u00e9s, dont un autre Prix Nobel am\u00e9ricain, Robert Solow, d&rsquo;anciens chefs de l&rsquo;Etat ou premiers ministres, des ministres des finances, des repr\u00e9sentants de l&rsquo;ONU et de la Commission europ\u00e9enne, des gouverneurs de banques centrales, ainsi que le patron de la premi\u00e8re banque priv\u00e9e du monde, Citigroup.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIls ont envisag\u00e9 le cas historique (depuis 50 ans) de diff\u00e9rents succ\u00e8s \u00e9conomiques nationaux \u00e9tudi\u00e9s par la Commission \u00ab<em>Ils en tirent des conclusions qui vont \u00e0 l&rsquo;encontre du Consensus de Washington, cette th\u00e9orie adopt\u00e9e par les institutions internationales et \u00e9labor\u00e9e par l&rsquo;\u00e9conomiste John Williamson \u00e0 la fin des ann\u00e9es 1980, et qui pr\u00f4nait la r\u00e9duction des d\u00e9ficits, des imp\u00f4ts et des d\u00e9penses publiques, l&rsquo;acc\u00e9l\u00e9ration des privatisations et des d\u00e9r\u00e9glementations.<\/p>\n<\/p>\n<p><p>\tLe rapport de la Commission est sans ambigu\u00eft\u00e9. La principale de nos conclusions est que la croissance indispensable pour faire reculer la pauvret\u00e9 et assurer un d\u00e9veloppement durable r\u00e9clame un Etat fort, commente Kemal Dervis, administrateur du Programme des Nations unies pour le d\u00e9veloppement (PNUD) et ancien ministre des finances de Turquie.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa vision peu orthodoxe des orthodoxes membres de cette commission des 21 sages se poursuit au m\u00eame rythme endiabl\u00e9 et sacril\u00e8ge. \u00ab<em>Loin des certitudes des n\u00e9o-conservateurs am\u00e9ricains, qui refusent de dissocier d\u00e9veloppement et d\u00e9mocratie \u00e0 l&rsquo;occidentale, la commission se soucie peu du r\u00e9gime politique qui g\u00e8re la croissance. Que le pouvoir appartienne \u00e0 un parti unique, \u00e0 plusieurs partis ou \u00e0 des technocrates, l&rsquo;important est que le cap de la croissance soit maintenu, selon la m\u00e9thode de l&rsquo;ancien secr\u00e9taire du Parti communiste chinois, Deng Xiaoping, qui conseillait de traverser la rivi\u00e8re en t\u00e2tant les pierres.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cet appel \u00e0 une sorte de principe de pr\u00e9caution \u00e9conomique tranche avec la suffisance qui conduisait les \u00e9quipes de la Banque mondiale et du Fonds mon\u00e9taire international (FMI) \u00e0 imposer brutalement aux pays en d\u00e9veloppement l&rsquo;orthodoxie budg\u00e9taire, fiscale et mon\u00e9taire imagin\u00e9e \u00e0 Washington.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes prestigieuses et europ\u00e9ennes personnalit\u00e9s, elles, s&rsquo;attaquent \u00e0 la finance folle du syst\u00e8me de la globalisation, ce qui est une autre mani\u00e8re de poursuivre le m\u00eame but que les 21 sages. Elles d\u00e9noncent l&rsquo;irresponsabilit\u00e9 des march\u00e9s, l&rsquo;opacit\u00e9 des agissements des banques qui manipulent des risques financiers inconsid\u00e9r\u00e9s. Elles dressent un tableau alarmiste de la situation, europ\u00e9enne dans ce cas, mais nous comprenons que le mod\u00e8le est universel (globalis\u00e9?).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Les march\u00e9s libres ne peuvent faire fi de la morale sociale. Adam Smith, p\u00e8re du laisser-faire \u00e9conomique, a \u00e9galement \u00e9crit la Th\u00e9orie des sentiments moraux (PUF, 1999) et Max Weber a \u00e9tabli le lien entre le dur labeur et les valeurs morales d&rsquo;une part, et l&rsquo;avanc\u00e9e du capitalisme de l&rsquo;autre. Le capitalisme d\u00e9cent (soit un capitalisme respectueux de la dignit\u00e9 humaine, pour reprendre les propos d&rsquo;Amartya Sen) requiert une intervention publique efficace. La recherche du profit constitue l&rsquo;essence de l&rsquo;\u00e9conomie de march\u00e9. Mais lorsque tout est \u00e0 vendre, la coh\u00e9sion sociale s&rsquo;effrite et le syst\u00e8me s&rsquo;effondre. La crise financi\u00e8re actuelle r\u00e9duit la capacit\u00e9 de l&rsquo;Occident \u00e0 entamer un dialogue plus constructif avec le reste du monde sur les d\u00e9fis mondiaux, sur la gestion des effets de la mondialisation et du r\u00e9chauffement de la plan\u00e8te  alors que le boom \u00e9conomique extraordinaire de l&rsquo;Asie pose de nouveaux d\u00e9fis sans pr\u00e9c\u00e9dent.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Les augmentations spectaculaires des prix de l&rsquo;\u00e9nergie et des produits alimentaires viennent aggraver les effets de la crise financi\u00e8re et sont de mauvais augure. Il est tr\u00e8s significatif que les fonds sp\u00e9culatifs ont contribu\u00e9 \u00e0 la hausse des prix des denr\u00e9es de base. Les citoyens des pays les plus pauvres en seront les plus touch\u00e9s. Nous risquons de nous trouver face \u00e0 une mis\u00e8re sans pr\u00e9c\u00e9dent, \u00e0 une prolif\u00e9ration d&rsquo;Etats en faillite, \u00e0 des flux migratoires plus importants et \u00e0 davantage de conflits arm\u00e9s.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes personnalit\u00e9s prestigieuses lancent un appel \u00e0 la mobilisation g\u00e9n\u00e9rale. Elles apostrophent les dirigeants europ\u00e9ens,  leurs successeurs, en quelque sorte, leurs pi\u00e8tres successeurs \u00ab<em>Les d\u00e9cideurs europ\u00e9ens, tant au niveau de l&rsquo;Union qu&rsquo;au niveau national, doivent apporter une r\u00e9ponse ferme \u00e0 l&rsquo;actuelle crise financi\u00e8re.<\/em> [] <em>Il est temps de cr\u00e9er un comit\u00e9 de crise europ\u00e9en qui rassemble des repr\u00e9sentants politiques de haut niveau, d&rsquo;anciens chefs d&rsquo;Etat et de gouvernement ou des ministres des finances ainsi que des \u00e9conomistes renomm\u00e9s et des experts financiers de tous les continents<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl ne nous para\u00eet pas vraiment n\u00e9cessaire de poursuivre, ni les citations, ni l&rsquo;\u00e9nonc\u00e9 des mesures r\u00e9clam\u00e9es. Leur critique va de soi,  nous n&rsquo;aurions pas la cruaut\u00e9 gratuite de dire qu&rsquo;elle est ais\u00e9e. Bref, ces deux exemples rejoignent un sentiment g\u00e9n\u00e9ral, cit\u00e9 en introduction du texte sur le rapport des 21 sages: \u00ab<em>La publication du rapport de la Commission Croissance et d\u00e9veloppement, jeudi 22 mai, sonne la fin du tout-lib\u00e9ralisme en vogue depuis la fin du XXe si\u00e8cle en mati\u00e8re de politiques de d\u00e9veloppement \u00e9conomique. Elle annonce un nouveau consensus pour une mondialisation moins sauvage.<\/em>\u00bb<\/p>\n<h3>Vers la r\u00e9alisation de la crise syst\u00e9mique centrale, tr\u00e8s vite<\/h3>\n<\/p>\n<p><p>\tOn comprendra que ces deux textes sont appr\u00e9ci\u00e9s comme exemplaires plus qu&rsquo;exceptionnels. Ils refl\u00e8tent, directement ou indirectement, un sentiment montant de tr\u00e8s forte pr\u00e9occupation des \u00e9lites politico-\u00e9conomiques occidentales,  devant les crises syst\u00e9miques diverses et devant l&rsquo;inertie absolument <strong>extraordinaire<\/strong> qui caract\u00e9rise ce qui tient lieu de r\u00e9action de nos diff\u00e9rentes directions, politiques et autres, en place devant ces crises. La pression des \u00e9v\u00e9nements,  pour le court terme, de la crise des <em>subprimes<\/em> \u00e0 celle du prix du p\u00e9trole,  constitue \u00e9videmment un facteur fondamental pour entretenir et radicaliser cette pr\u00e9occupation.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, ces divers signes confirment qu&rsquo;il y a effectivement <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5129\" class=\"gen\">une perception<\/a> de plus en plus nette de la situation de crise syst\u00e9mique o\u00f9 nous nous trouvons. Nous sommes dans une phase d&rsquo;\u00e9volution acc\u00e9l\u00e9r\u00e9e, entre la perception qui s&rsquo;installe et la r\u00e9alisation de l&rsquo;ampleur du ph\u00e9nom\u00e8ne qui devrait suivre.<\/p>\n<\/p>\n<p><p>\tPr\u00e9cisons ici que tous ces constats n&rsquo;ont rien \u00e0 voir avec la pr\u00e9vision ou avec la prospective. Il y a longtemps que l&rsquo;on sait que les \u00e9l\u00e9ments d&rsquo;une crise syst\u00e9mique centrale sont rassembl\u00e9s, nous dirions <em>de facto<\/em> puisque notre syst\u00e8me est fond\u00e9 sur l&rsquo;exploitation de ressources finies et non renouvelables et qu&rsquo;il est caract\u00e9ris\u00e9 par une expansion continue sinon exponentielle; nous dirions m\u00eame que, d\u00e8s l&rsquo;origine, ce syst\u00e8me poss\u00e8de une nature potentielle de crise, qu&rsquo;il a fallu jusqu&rsquo;ici la croyance utopique ou id\u00e9ologique dans sa puissance progressiste \u00e0 r\u00e9soudre tous les probl\u00e8mes que son d\u00e9veloppement suscite pour \u00e9carter la r\u00e9alisation de cette nature.<\/p>\n<\/p>\n<p><p>\tIl ne s&rsquo;agit donc ni d&rsquo;une information nouvelle, ni d&rsquo;une d\u00e9couverte. Par perception, nous parlons effectivement de psychologie. Les \u00e9v\u00e9nements nous pressent et la psychologie int\u00e8gre ce que l&rsquo;esprit envisage depuis longtemps, ce que le bon sens intuitif devine comme in\u00e9luctable, \u00e9galement depuis longtemps. Pour autant, le ph\u00e9nom\u00e8ne est consid\u00e9rable. Il met le syst\u00e8me, et avec lui ses gardiens id\u00e9ologiques les plus vigilants, sur la d\u00e9fensive. C&rsquo;est une position qui ne lui sied gu\u00e8re, lui qui est fond\u00e9 sur une \u00ab<em>\u00e9conomie de force<\/em>\u00bb (voir <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=782\" class=\"gen\">Aron-Dandieu<\/a>) et sur une posture offensive, voire darwinienne.<\/p>\n<\/p>\n<p><p>\tS&rsquo;il est av\u00e9r\u00e9 aujourd&rsquo;hui que l&rsquo;inqui\u00e9tude ne cesse de grandir et ne cessera plus de grandir parce que les \u00e9v\u00e9nements y obligent, l&rsquo;\u00e9volution de la r\u00e9action devient le sujet le plus int\u00e9ressant. <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5089\" class=\"gen\">L\u00e0 aussi<\/a>, nous nous approchons d&rsquo;une situation de type <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5117\" class=\"gen\">gorbatch\u00e9vien<\/a> puisque nous sommes dans cette situation o\u00f9 la catastrophe syst\u00e9mique suscite des exigences r\u00e9formistes de plus en plus imp\u00e9ratives; en m\u00eame temps que ces exigences s&rsquo;affirment, l&rsquo;ampleur du probl\u00e8me se d\u00e9couvre et la question centrale devient: ce syst\u00e8me peut-il \u00eatre r\u00e9form\u00e9? L&rsquo;on sait que Gorbatchev fut lanc\u00e9 comme le r\u00e9formiste audacieux que les temps et l&rsquo;\u00e9tat \u00e9pouvantable du syst\u00e8me sovi\u00e9tique exigeaient, et que son action r\u00e9formiste aboutit involontairement, en un temps extr\u00eamement court, \u00e0 la rupture et \u00e0 la dislocation du syst\u00e8me. Il n&rsquo;est pas question de savoir ici si cela est possible dans le cas du syst\u00e8me plus vaste et globalis\u00e9 dont on parle; il est question d&rsquo;observer que, d\u00e8s lors que la situation est trop pressante dans un syst\u00e8me dont l&rsquo;\u00e9tat est \u00e9pouvantable et qu&rsquo;on est contraint \u00e0 envisager des r\u00e9formes, cette issue de la rupture est in\u00e9luctable. (Quant \u00e0 la forme qu&rsquo;elle prendra)<\/p>\n<\/p>\n<p><p>\tM\u00eame dans ces textes critiques, ou dans leur pr\u00e9sentation, l&rsquo;on sent bien les contraintes persistantes de la vision id\u00e9ologique sur le jugement. Lorsque les personnalit\u00e9s prestigieuses d\u00e9taillent les dangers qui menacent l&rsquo;Europe et qu&rsquo;elles appellent \u00e0 la mobilisation, et qu&rsquo;elles la justifient notamment par cette remarque : \u00ab<em>le boom \u00e9conomique extraordinaire de l&rsquo;Asie pose de nouveaux d\u00e9fis sans pr\u00e9c\u00e9dent<\/em>\u00bb,  elles semblent implicitement \u00e9tablir une situation de concurrence, l\u00e0 o\u00f9 l&rsquo;Europe serait faible et l&rsquo;Asie puissante, impliquant que le probl\u00e8me c&rsquo;est la fa\u00e7on dont l&rsquo;Europe se sert du syst\u00e8me et non le syst\u00e8me lui-m\u00eame, qu&rsquo;\u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me on peut r\u00e9ussir et donc que le syst\u00e8me est bon. Ces personnalit\u00e9s prestigieuses devraient savoir que le <em>boom<\/em> de la Chine n&rsquo;est pas une solution au probl\u00e8me (implicitement : l&rsquo;Europe devrait faire comme la Chine, tout irait bien pour elle) mais une partie essentielle du probl\u00e8me; que le <em>boom<\/em> est une cause \u00e9vidente non du succ\u00e8s du syst\u00e8me mais de sa crise. Le succ\u00e8s de la Chine est d&rsquo;ores et d\u00e9j\u00e0 une crise pour la Chine. Il n&rsquo;est plus temps de s\u00e9parer les diff\u00e9rents composants du syst\u00e8me en crise pour dire ici c&rsquo;est la crise et l\u00e0 c&rsquo;est le succ\u00e8s. Toutes ces choses sont les diverses manifestations de notre crise syst\u00e9mique centrale et universelle.<\/p>\n<\/p>\n<p><p>\tDe m\u00eame lorsqu&rsquo;on pr\u00e9sente la critique de la globalisation (<em>alias<\/em> mondialisation) en ces termes: \u00ab<em>la fin du tout-lib\u00e9ralisme en vogue depuis la fin du XXe si\u00e8cle en mati\u00e8re de politiques de d\u00e9veloppement \u00e9conomique. <\/em>[U]<em>n nouveau consensus pour une mondialisation moins sauvage.<\/em>\u00bb On dirait une aimable et acad\u00e9mique querelle de sp\u00e9cialistes, avec le temps devant soi pour prendre des d\u00e9cisions r\u00e9fl\u00e9chies et modifier \u00e0 mesure l&rsquo;orientation d&rsquo;une machine qui reste fondamentalement saine. Cette mesure-l\u00e0 contraste \u00e9videmment avec l&rsquo;urgence des temps et trace les limites de cette sorte d&rsquo;exercice.<\/p>\n<\/p>\n<p><p>\tMais tout \u00e9volue tr\u00e8s vite. Il faut prendre garde d&rsquo;appr\u00e9cier ces prises de position comme autant de facteurs fig\u00e9s et en rester \u00e0 la critique, s\u00e9v\u00e8re ou indulgente, de leurs insuffisances. Ces prises de position sont \u00e0 mettre dans le courant d&rsquo;une \u00e9volution tr\u00e8s rapide, autant de la crise que des appr\u00e9ciations de cette crise. Elles sont une \u00e9tape de plus dans cette tr\u00e8s rapide \u00e9volution et l&rsquo;on comprend bien qu&rsquo;il y a trois ans de telles positions eussent fait de leurs auteurs des extr\u00e9mistes dangereux. Le texte de pr\u00e9sentation du rapport des 21 sages le dit bien: \u00ab<em>Cette commission ne peut \u00eatre suspect\u00e9e d&rsquo;altermondialisme<\/em>\u00bb Il y a trois ans, elle aurait \u00e9t\u00e9 non seulement soup\u00e7onn\u00e9e, mais jug\u00e9e coupable du forfait et prestement exp\u00e9di\u00e9e. De m\u00eame, pour l&rsquo;affirmation de la n\u00e9cessit\u00e9 d&rsquo;un Etat fort pour les nations, face \u00e0 la globalisation; en 2005, une telle affirmation dans les c\u00e9nacles bien-pensants et dans les colonnes du <em>Monde<\/em> vous envoyaient directement au b\u00fbcher.<\/p>\n<\/p>\n<p><p>\tRien n&rsquo;est r\u00e9solu puisqu&rsquo;on sait l&rsquo;ampleur du cataclysme qui prend forme. On se contente ici d&rsquo;observer l&rsquo;\u00e9volution des choses et d&rsquo;offrir une interpr\u00e9tation. Les personnalit\u00e9s prestigieuses et les sages ne font pas autre chose, de leur c\u00f4t\u00e9, avec les caract\u00e9ristiques qu&rsquo;on a tent\u00e9es de mettre en \u00e9vidence. La puissance de la crise et des courants qui la suscitent poursuit son affirmation d\u00e9vastatrice et tout cela n&rsquo;a nul besoin de notre intervention pour accomplir l&rsquo;essentiel de la t\u00e2che. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiens, il se passe quelque chose 23 mai 2008 Il n&rsquo;est pas n\u00e9cessaire d&rsquo;aller bien loin. Deux articles successifs dans Le Monde, et voil\u00e0, on vous l&rsquo;assure, les couloirs de la Commission europ\u00e9enne boulevers\u00e9s. (Ce sont effectivement des textes qui circulent et qui font hocher les t\u00eates.) Il faut dire qu&rsquo;assembl\u00e9s, ils constituent une belle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3492,4568,398,2632,4405,5323,4505],"class_list":["post-69915","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-3492","tag-delors","tag-europe","tag-globalisation","tag-mondialisation","tag-sages","tag-schmidt"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69915"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69915\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}