{"id":69917,"date":"2008-05-23T00:00:00","date_gmt":"2008-05-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/23\/nuland-parlait-pour-elle-seule-et-encore\/"},"modified":"2008-05-23T00:00:00","modified_gmt":"2008-05-23T00:00:00","slug":"nuland-parlait-pour-elle-seule-et-encore","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/05\/23\/nuland-parlait-pour-elle-seule-et-encore\/","title":{"rendered":"Nuland parlait pour elle seule, et encore&#8230;"},"content":{"rendered":"<p><p>La France a proclam\u00e9 hautement, \u00e0 plusieurs reprises, qu&rsquo;elle \u00e9tait soutenue par les USA dans ses projets de d\u00e9fense europ\u00e9enne. Elle s&rsquo;appuie sur les <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4933\" class=\"gen\">d\u00e9clarations<\/a>, fin f\u00e9vrier, de l&rsquo;ambassadrice des USA \u00e0 l&rsquo;OTAN Victoria Nuland. Depuis, quelques mots de Bush au sommet de l&rsquo;OTAN \u00e0 Bucarest en avril, dont on fait fort grand cas, sont venus conforter les Fran\u00e7ais.<\/p>\n<\/p>\n<p><p>\tEnfin, pas tous&#8230; La repr\u00e9sentation diplomatique fran\u00e7aise \u00e0 Washington, dans ses d\u00e9p\u00eaches \u00e0 l&rsquo;intention du gouvernement fran\u00e7ais, a mis en \u00e9vidence \u00e0 plusieurs reprises, depuis fin f\u00e9vrier, combien ces d\u00e9clarations n&rsquo;avaient pas la moindre valeur d&rsquo;engagement. Ce qu&rsquo;a dit Bush ne vaut pas mieux.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Ce que disent les Fran\u00e7ais \u00e0 Washington, <\/em>explique une source \u00e0 l&rsquo;OTAN, <em>c&rsquo;est que ces d\u00e9clarations sont de simples circonstances. Nulle part \u00e0 Washington, on ne trouve la moindre indication que les initiatives fran\u00e7aises seront soutenues par les USA. Cette question n&rsquo;est nulle part abord\u00e9e, elle n&rsquo;existe pas.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes observations signifient que les Fran\u00e7ais n&rsquo;ont aucun soutien r\u00e9el des USA dans cette affaire, qu&rsquo;ils se retrouveront, lorsqu&rsquo;ils lanceront leur initiative (\u00e9ventuellement durant leur pr\u00e9sidence de l&rsquo;UE qui commence le 1er juillet), avec l&rsquo;habituel blocage US dans ce domaine. Ainsi se trouveront-ils devant la difficile perspective d&rsquo;\u00e9ventuellement devoir r\u00e9examiner leurs projets de r\u00e9int\u00e9gration de l&rsquo;OTAN, qui ne sont envisag\u00e9e qu&rsquo;en \u00e9change du soutien US sur la d\u00e9fense europ\u00e9enne.  <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 mai 2008 \u00e0 13H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La France a proclam\u00e9 hautement, \u00e0 plusieurs reprises, qu&rsquo;elle \u00e9tait soutenue par les USA dans ses projets de d\u00e9fense europ\u00e9enne. Elle s&rsquo;appuie sur les d\u00e9clarations, fin f\u00e9vrier, de l&rsquo;ambassadrice des USA \u00e0 l&rsquo;OTAN Victoria Nuland. Depuis, quelques mots de Bush au sommet de l&rsquo;OTAN \u00e0 Bucarest en avril, dont on fait fort grand cas, sont&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3019,3079,2687,5520],"class_list":["post-69917","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-defense","tag-europeenne","tag-france","tag-nuland"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69917"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69917\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}