{"id":69970,"date":"2008-06-16T00:00:00","date_gmt":"2008-06-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/16\/journal-de-bord-de-dedefensaorg-080616-temps-ultime\/"},"modified":"2008-06-16T00:00:00","modified_gmt":"2008-06-16T00:00:00","slug":"journal-de-bord-de-dedefensaorg-080616-temps-ultime","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/16\/journal-de-bord-de-dedefensaorg-080616-temps-ultime\/","title":{"rendered":"Journal de bord de dedefensa.org \u2014  080616, Temps ultime"},"content":{"rendered":"<p><p>16 juin 2008  Certes, il ne faut pas dramatiser. Cette campagne qui touche \u00e0 sa fin ne nous apportera pas toutes les satisfactions que nous en attendions. Ce n&rsquo;est pas pour autant que le ciel nous tombera sur la t\u00eate.  Pourtant, cela doit nous faire r\u00e9fl\u00e9chir et cela nous fera r\u00e9fl\u00e9chir.<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;heure, il reste sept jours pour influer sur les r\u00e9sultats de cette donation et les accorder mieux \u00e0 nos ambitions, dont nous esp\u00e9rons tant qu&rsquo;elles soient les v\u00f4tres \u00e9galement. Si c&rsquo;est le cas et si vous, lecteur, n&rsquo;avez pas encore contribu\u00e9, la logique autant que le sentiment devraient vous y <a href=\"http:\/\/www.dedefensa.org\/donation.php\" class=\"gen\">inviter<\/a> et vous ne devriez pas r\u00e9sister \u00e0 cette pression.<\/p>\n<\/p>\n<p><p>\tNous ne voudrions pas manquer de remercier ceux qui ont d\u00e9j\u00e0 particip\u00e9 \u00e0 cet effort de soutien de <em>dedefensa.org<\/em>. Certains nous ont fait des donations magnifiques, d&rsquo;autres ont renouvel\u00e9 leur donation initiale, devant le succ\u00e8s qu&rsquo;il jugeait mitig\u00e9 de la campagne, d&rsquo;autres encore nous ont fait des donations minimes, correspondant \u00e0 leurs tr\u00e8s faibles moyens, pour marquer leur volont\u00e9 de participer. Ce sont des exemples qui nous touchent bien fortement.<\/p>\n<\/p>\n<p><p>\tAu bout du compte, c&rsquo;est-\u00e0-dire quand nous serons oblig\u00e9s de faire les comptes, cette op\u00e9ration qui ne nous s\u00e9duit gu\u00e8re, nous commencerons \u00e0 avoir une id\u00e9e un peu plus pr\u00e9cise de ce que vaut cette formule d&rsquo;appel \u00e0 donation et ce que nous pouvons esp\u00e9rer avec elle. Pour l&rsquo;instant, les augures ne sont pas d\u00e9bordants d&rsquo;optimisme.<\/p>\n<\/p>\n<p><p>\tMais tout cela n&rsquo;a-t-il pas un \u00e9trange air d&rsquo;irr\u00e9alit\u00e9?  Nous d\u00e9battons dans nos colonnes de probl\u00e8mes si essentiels, dont vous savez bien qu&rsquo;il n&rsquo;en est plus rien dit de s\u00e9rieux, de loyal, d&rsquo;enrichissant, dans les canaux officiels si grassement entretenus. Jamais l&rsquo;argent n&rsquo;a \u00e9t\u00e9 autant d\u00e9vers\u00e9 \u00e0 flots pour entretenir la tromperie, la m\u00e9diocrit\u00e9, le nihilisme. Pendant ce temps, nous voici vous entretenant de ce soutien qui n&rsquo;arrive pas comme il faudrait, perdant notre temps et vous faisant perdre le v\u00f4tre, parce que nous avons besoin d&rsquo;un soutien minimum et que les \u00e9lans spontan\u00e9s de nos lecteurs ne suffisent pas jusqu&rsquo;ici \u00e0 le rencontrer. Est-ce bien raisonnable?<\/p>\n<\/p>\n<p><p>\tDoit-on continuer \u00e0 compter au bord de l&rsquo;apocalypse?<\/p>\n<\/p>\n<p><p>\tIl vous reste une semaine pour apporter les r\u00e9ponses qui importent \u00e0 ces questions. En un mot sans grande originalit\u00e9, <a href=\"http:\/\/www.dedefensa.org\/donation.php\" class=\"gen\">soutenez-nous<\/a>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>16 juin 2008 Certes, il ne faut pas dramatiser. Cette campagne qui touche \u00e0 sa fin ne nous apportera pas toutes les satisfactions que nous en attendions. Ce n&rsquo;est pas pour autant que le ciel nous tombera sur la t\u00eate. Pourtant, cela doit nous faire r\u00e9fl\u00e9chir et cela nous fera r\u00e9fl\u00e9chir. Pour l&rsquo;heure, il reste&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[6120,4854,6750,6775],"class_list":["post-69970","post","type-post","status-publish","format-standard","hentry","category-messagerie","tag-campagne","tag-donation","tag-temps","tag-ultime"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69970"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69970\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}