{"id":69975,"date":"2008-06-18T00:00:00","date_gmt":"2008-06-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/18\/parlons-dautre-chose\/"},"modified":"2008-06-18T00:00:00","modified_gmt":"2008-06-18T00:00:00","slug":"parlons-dautre-chose","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/18\/parlons-dautre-chose\/","title":{"rendered":"Parlons d&rsquo;autre chose"},"content":{"rendered":"<p><h2 class=\"common-article\">Parlons d&rsquo;autre chose<\/h2>\n<\/p>\n<p><p>\t18 juin 2008  On nous pardonnera d&rsquo;avoir, peut-\u00eatre curieusement pour certains, choisi de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5202\" class=\"gen\">parler<\/a> du Sarkozy d&rsquo;un autre jour (le 13 juin), \u00e0 un autre propos (son entregent avec GW), le jour (17 juin) o\u00f9 le pr\u00e9sident de la R\u00e9publique fran\u00e7aise parlait solennellement de la d\u00e9fense en France. C&rsquo;est une occurrence solennelle et r\u00e9volutionnaire classique pour un pr\u00e9sident, un tel discours. Peut-\u00eatre voulions-nous attendre le 18 juin (sans pr\u00e9cision d&rsquo;ann\u00e9e) pour en parler,  peut-\u00eatre<\/p>\n<\/p>\n<p><p>\tMais c&rsquo;est \u00e9galement, nous l&rsquo;avouons, parce qu&rsquo;il nous para\u00eet si difficile, aujourd&rsquo;hui, dans notre \u00e9poque, de parler d\u00e9fense,  comme on parle, par exemple, de cin\u00e9ma au Festival de Cannes. En effet, comment accepter de parler d\u00e9fense d&rsquo;une fa\u00e7on sp\u00e9cifique et limit\u00e9e aux seules caract\u00e8res du domaine, sans croire qu&rsquo;on dira <strong>n\u00e9cessairement<\/strong> des platitudes extraordinaires,  lorsque, par exemple mais bon exemple,  <em>BBC.News<\/em> peut titrer et pr\u00e9senter son texte sur le discours, le jour m\u00eame, le <a href=\"http:\/\/news.bbc.co.uk\/2\/hi\/europe\/7458650.stm\" class=\"gen\">17 juin<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>French defence to counter terror<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>President Nicolas Sarkozy wants a leaner fighting force. Terrorism is the main threat facing France and its defence system needs to change to reflect that, French President Nicolas Sarkozy has said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab [T]<em>error<\/em>\u00bb Terreur, c&rsquo;est-\u00e0-dire le terrorisme? La grande menace qui nous menace? <em>Are you kidding, Mr. Pr\u00e9sident<\/em>?  M\u00eame GW n&rsquo;ose plus dire cela et, de toutes les fa\u00e7ons, plus personne ne l&rsquo;\u00e9coute. Comment peut-on avancer une telle platitude d\u00e9risoire? Eh bien, il le peut.<\/p>\n<\/p>\n<p><p>\tInsistons sur notre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5200\" class=\"gen\">rengaine<\/a>. Nos dynamiques dirigeants sont aujourd&rsquo;hui saisis, sans encore s&rsquo;en aviser, d&rsquo;un vertige extraordinaire. Le soir d&rsquo;octobre 1917, ou du 7 novembre selon l&rsquo;autre calendrier, la R\u00e9volution r\u00e9ussie, c&rsquo;est-\u00e0-dire le coup d&rsquo;Etat bolch\u00e9vique qu&rsquo;Eisenstein immortalisera (<em>Octobre<\/em>) bien r\u00e9alis\u00e9, Vladimir lllitch Oulianov dit L\u00e9nine semble tituber, s&rsquo;assied sur un canap\u00e9 et dit, en allemand : \u00ab<em>Es Schwindle<\/em>\u00bb (J&rsquo;ai le vertige). L&rsquo;Histoire passe. Aujourd&rsquo;hui, nos dirigeants ont le vertige, mais 1) ils ne s&rsquo;en aper\u00e7oivent pas et ne s&rsquo;assoient sur aucun canap\u00e9, et 2) l&rsquo;Histoire ne passe pas par chez eux, occup\u00e9e de choses bien plus importantes.<\/p>\n<\/p>\n<p><p>\tPourtant, le pr\u00e9sident voulut sans aucun doute \u00eatre historique. Mais il parla de la d\u00e9fense en vieil homme ou bien en jeune homme \u00e9cervel\u00e9,  bref, en homme d&rsquo;un autre temps, en homme du temps de 9\/11 qui croit qu&rsquo;existe \u00ab<em>Mon Am\u00e9rique \u00e0 moi<\/em>\u00bb, que le terrorisme est le vrai danger contre la civilisation et que la civilisation existe, que \u00ab<em>Nous sommes tous Am\u00e9ricains<\/em>\u00bb et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tCela observ\u00e9 et sans que nous apportions instantan\u00e9ment le correctif esp\u00e9r\u00e9 (parlant de d\u00e9fense, au lieu de cette menace il aurait d\u00fb parler de telle autre), observons deux ou trois choses que nous croyons \u00e0 propos de nos dirigeants, des cercles qui les conseillent et des critiques qui les condamnent.<\/p>\n<h3>Deux ou trois choses que l&rsquo;on sait d&rsquo;eux<\/h3>\n<\/p>\n<p><p>\t Il est vrai que, d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale et sortis de la terreur (le terrorisme) et de l&rsquo;hypoth\u00e9tique et fantasmatique arme nucl\u00e9aire iranienne, les milieux de la d\u00e9fense en France, les services de renseignement, les militaires, n&rsquo;arrivent pas \u00e0 conceptualiser <strong>autre chose<\/strong> de vraiment s\u00e9rieux. Cela existe alors qu&rsquo;un sentiment g\u00e9n\u00e9ral mais extraordinairement diffus s&rsquo;installe de plus fermement selon lequel nous nous trouvons dans une \u00e9poque eschatologique, o\u00f9 les crises syst\u00e9miques ne cessent de s&rsquo;affirmer, de s&#8217;empiler, de s&rsquo;ajouter \u00e0 une tr\u00e8s grande rapidit\u00e9. Les experts et autres ne s&rsquo;attardent pas trop \u00e0 ce sentiment car lui opposer l&rsquo;affirmation que la principale menace est le terrorisme implique le risque inacceptable du ridicule. Simplement, parfois, l&rsquo;un d&rsquo;eux risque une remarque qui sugg\u00e8re que le roi est nu. (Javier Solana, devant la Commission sur le Livre blanc sur la D\u00e9fense et la S\u00e9curit\u00e9 nationale, le 4 octobre 2007 \u00e0 Paris,  ce Livre Blanc qui sert justement de support au discours de Sarkozy: \u00ab<em>La globalisation comporte autant de menaces que d&rsquo;atouts. J&rsquo;esp\u00e8re que vous saisissez la lourde responsabilit\u00e9 que je prends, dans ma position, en livrant un diagnostic aussi sombre.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t Le retour dans l&rsquo;OTAN et le rapprochement avec les USA qui va avec signifient-il une abdication? Il traduit dans tous les cas un \u00e9tat d&rsquo;esprit g\u00e9n\u00e9ral des \u00e9lites fran\u00e7aises. V\u00e9drine l&rsquo;observait justement dans son rapport de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4397\" class=\"gen\">septembre 2007<\/a>; parlant de la tentation de r\u00e9fr\u00e9ner une critique des USA au nom de valeurs communes et autre solidarit\u00e9, donc d&rsquo;affirmer un pro-am\u00e9ricanisme fondamental, il \u00e9crivait : \u00ab<em>Il est surprenant de constater que cette tentation est forte, comme pour l&rsquo;europ\u00e9isme, dans les \u00e9lites  mais quasiment pas dans la population<\/em>\u00bb; ou encore, toujours sur le m\u00eame sujet, et plus pr\u00e9cis\u00e9ment sur le retour dans l&rsquo;OTAN: \u00ab<em>N\u00e9anmoins, cette r\u00e9orientation fondamentale n&rsquo;est pas demand\u00e9e par l&rsquo;opinion fran\u00e7aise qui para\u00eet \u00e0 l&rsquo;aise dans la politique de la V\u00e8me R\u00e9publique dans la longue dur\u00e9e. Elle poserait d&rsquo;immenses probl\u00e8mes et comporterait des risques. Mais puisqu&rsquo;elle est souhait\u00e9e par une partie des \u00e9lites \u00e9conomiques et politiques, ce d\u00e9bat devrait \u00eatre men\u00e9 dans la clart\u00e9. Comme celui sur une \u00e9ventuelle zone de libre \u00e9change euro-am\u00e9ricaine.<\/em>\u00bb Donc, il s&rsquo;agirait simplement de l&rsquo;expression d&rsquo;une capitulation voulue par nos \u00e9lites? Cela n&rsquo;est pas nouveau (la d\u00e9cision de retrait de l&rsquo;OTAN a toujours \u00e9t\u00e9 impopulaire dans les \u00e9lites fran\u00e7aises, tout comme le d\u00e9veloppement d&rsquo;une force nucl\u00e9aire, tout comme bien d&rsquo;autres choses avant de Gaulle, en remontant le temps,  les \u00e9lites fran\u00e7aises ayant naturellement le go\u00fbt du parti de l&rsquo;\u00e9tranger). Mais cette abdication, justement, n&rsquo;est par per\u00e7ue comme une abdication, ce qui ouvre, ou plut\u00f4t poursuit la saison des quiproquos. Elle est curieusement per\u00e7ue,  la vanit\u00e9 n&rsquo;\u00e9tant jamais loin de l&rsquo;irresponsabilit\u00e9,  comme une affirmation (le fameux nous sommes sur un pied d&rsquo;\u00e9galit\u00e9 avec nos alli\u00e9s), ce qui renvoie \u00e0 l&rsquo;\u00e9trange psychologie fran\u00e7aise dont m\u00eame nos \u00e9lites ne sont pas quittes. En d&rsquo;autres mots, la France r\u00e9int\u00e9gr\u00e9e pourrait devenir encore plus insupportable \u00e0 ses alli\u00e9s; certains alli\u00e9s de la France le croient et, dans cette \u00e9poque de perception et de communication, c&rsquo;est l&rsquo;essentiel pour la concr\u00e9tisation de la chose. C&rsquo;est ce qui explique l&rsquo;enthousiasme assez ti\u00e8de de l&rsquo;OTAN et c&rsquo;est ce qu&rsquo;exprime encore mieux un autre texte de <em>BBC.News<\/em>, du m\u00eame <a href=\"http:\/\/news.bbc.co.uk\/2\/hi\/europe\/7459214.stm\" class=\"gen\">17 juillet<\/a>, de Jonathan Marcus, dont nous permettons de souligner quelques points importants: \u00ab<em>Moving back into Nato&rsquo;s military command structure undoes decades of French semi-detachment from the Atlantic alliance. But here too there should be<\/em> <strong><em>no illusions<\/em><\/strong><em>. Improving European defence capabilities is still very close to the president&rsquo;s heart. France will<\/em> <strong><em>remain<\/em><\/strong> <em>a Nato player with a<\/em> <strong><em>distinctive<\/em><\/strong> <em>accent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Sur l&rsquo;autonomie et sur la souverainet\u00e9, Sarko affirme des choses. Cela importe peu, ce qu&rsquo;il affirme. Le fait est que, depuis 15 ans, la France op\u00e8re en mode int\u00e9gr\u00e9, en coop\u00e9ration, etc., notamment au sein de l&rsquo;OTAN. (Marcus encore: \u00ab<em>It may mean less in practical terms. French forces operate and train alongside their Nato colleagues as a matter of course and despite the rows with Washington over Iraq, France remains an important military player in Afghanistan.<\/em>\u00bb) Le fait est qu&rsquo;elle (la France) n&rsquo;a perdu ni son autonomie ni sa souverainet\u00e9 parce que l&rsquo;OTAN plong\u00e9e dans des op\u00e9rations diverses a montr\u00e9 son impuissance \u00e0 int\u00e9grer et, par cons\u00e9quent, un r\u00e9flexe d&rsquo;autonomie chez tous ses membres,  ou bien est-ce ce r\u00e9flexe qui a provoqu\u00e9 l&rsquo;impuissance de l&rsquo;OTAN. (On se rappellera l&rsquo;incident fameux du 11 juin 1999 du g\u00e9n\u00e9ral anglais Jackson, commandant la force OTAN prenant possession du Kosovo, refusant purement et simplement l&rsquo;ordre de son chef, le SACEUR US, le g\u00e9n\u00e9ral Wesley Clark, qui le conduisait \u00e0 risquer d&rsquo;affronter les Russes sur l&rsquo;a\u00e9roport de Pristina, puis le m\u00eame Jackson recevant aussit\u00f4t l&rsquo;approbation de Blair suivie,  \u00f4 douloureuse surprise pour Clark,  de celle de Clinton.) Cet accent paradoxal sur la d\u00e9cision nationale en temps de coop\u00e9ration\/soi-disant int\u00e9gration, c&rsquo;est naturellement et plus encore le cas pour la France, dont toutes les structures y invitent. Aujourd&rsquo;hui, l&rsquo;OTAN op\u00e8re d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale selon l&rsquo;habituelle situation cauchemardesque des coalitions (Foch s&rsquo;en \u00e9tait aper\u00e7u en 1918), le grand chef ayant des subordonn\u00e9s de tr\u00e8s haut rang qui r\u00e9pondent en priorit\u00e9 \u00e0 leur autorit\u00e9 politique nationale. Le r\u00e9sultat, avec d&rsquo;autres facteurs dans ce sens, est l&rsquo;impuissance g\u00e9n\u00e9rale de l&rsquo;OTAN,  le mod\u00e8le afghan, si l&rsquo;on veut. Le retour de la France ne fera qu&rsquo;accentuer cette impuissance, d&rsquo;autant que \u00ab<em>France will<\/em> <strong><em>remain<\/em><\/strong> <em>a Nato player with a<\/em> <strong><em>distinctive<\/em><\/strong> <em>accent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Dans la logique de ce qui pr\u00e9c\u00e8de, il y a deux effets pervers \u00e0 esp\u00e9rer avec la plus grande ferveur, qui feraient du retour de la France dans l&rsquo;OTAN un ferment de division (m\u00eame, surtout involontaire et infond\u00e9,  le pire de tous les ferments). 1) La France, d\u00e9barrass\u00e9e du complexe insupportable pour ses \u00e9lites de l&rsquo;isolement, commen\u00e7ant \u00e0 parler haut et fort, en toute candeur, \u00e0-la-Kouchner et pour tenter de contenir les critiques des gardiens du dogme gaulliste, ce qui est la pire des situations pour l&rsquo;OTAN (Il vaut mieux parfois, souvent, un ind\u00e9pendant loyal qu&rsquo;un suiveur revendicateur.) 2). Le soup\u00e7on contre la France pourrait aussi bien cro\u00eetre. Les Britanniques, dans leur jugement si ambigu sur la France, ne croiront pas que la France revient, sans r\u00e9elle n\u00e9cessit\u00e9 puisque l&rsquo;essentiel de l&rsquo;int\u00e9gration est d\u00e9j\u00e0 fait, sans arri\u00e8res pens\u00e9es, comme eux-m\u00eames auraient s&rsquo;ils \u00e9taient \u00e0 la place des Fran\u00e7ais. D&rsquo;o\u00f9 une zizanie suppl\u00e9mentaire dans l&rsquo;OTAN, d&rsquo;autant plus probable que les Fran\u00e7ais ne feront pas de manuvre dans ce sens et seront d&rsquo;autant plus soup\u00e7onn\u00e9s (et secr\u00e8tement admir\u00e9s) pour leur jeu infiniment subtil (selon les Britanniques) pour dissimuler les manoeuvres. Tout ce qui am\u00e8ne la zizanie au sein de l&rsquo;OTAN, au travers des intentions et arri\u00e8res pens\u00e9es pr\u00eat\u00e9s aux uns et aux autres, est une tr\u00e8s bonne affaire. Est-ce cela que le brave Sarkozy \u00e9voquait en disant que sa d\u00e9cision est conforme \u00e0 la ligne de pens\u00e9e du g\u00e9n\u00e9ral?<\/p>\n<\/p>\n<p><p>\t Sur les mesures techniques prises par la France pour sa d\u00e9fense et expos\u00e9es par le discours, on ne peut que constater un signe de plus du mouvement g\u00e9n\u00e9ral des forces militaires selon les conceptions classiques (technologies, logistiques, protection des forces, etc.) vers une situation de d\u00e9sarmement structurel, rien de moins. Lorsqu&rsquo;on confronte l&rsquo;\u00e9tat r\u00e9el, catastrophique, de la situation militaire des Britanniques (les Fran\u00e7ais devraient fr\u00e9quenter plus souvent les s\u00e9minaires RISI, Chatam House, lire les articles de journaux et autres interviews, m\u00eame \u00e9crits en anglais, etc.), et qu&rsquo;un \u00e9ditorialiste fran\u00e7ais (Pierre Rousselin , du <em>Figaro<\/em>, le <a href=\"http:\/\/www.lefigaro.fr\/debats\/2008\/06\/17\/01005-20080617ARTFIG00276-la-mutation-necessaire-des-armees.php \" class=\"gen\">17 juin<\/a>) note : \u00ab<em>En Europe, les Britanniques sont les seuls avec qui nous pouvons nous mesurer. Ils disposent sur nous d&rsquo;une longueur d&rsquo;avance, qui se creuse et qu&rsquo;il faudrait combler<\/em>\u00bb,  on comprend (mais le comprend-il?) qu&rsquo;il s&rsquo;agit d&rsquo;une longueur d&rsquo;avance sur la voie du d\u00e9sarmement et de l&rsquo;impuissance. Lorsque Rousselin applaudit les Britanniques qui peuvent \u00ab<em>en Irak et en Afghanistan,<\/em> [] <em>mener deux conflits de front<\/em>\u00bb, on en a le souffle coup\u00e9: mener deux catastrophes de front, qui mettent les forces britanniques \u00e0 genoux, c&rsquo;est un exemple \u00e0 suivre? Les Fran\u00e7ais suivent la grande tendance de la sophistication de la technologie comme r\u00e8gle de l&rsquo;adaptation, simplement plaqu\u00e9e sur des types de guerre (la G4G) dont la r\u00e8gle essentielle est que la sophistication de la technologie doit \u00eatre un moyen \u00e9ventuel qui ne peut <strong>en aucun cas<\/strong> devenir la r\u00e8gle de l&rsquo;adaptation. Mais, de ce c\u00f4t\u00e9, on se heurte \u00e0 un mur, qui est celui d&rsquo;une crise syst\u00e9mique de la bureaucratisation de notre civilisation, les arm\u00e9es en premier, avec la technologie comme Dieu universel. Inutile de tenter de sugg\u00e9rer une alternative, que nous \u00e9voquons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5193\" class=\"gen\">par ailleurs<\/a> (partie <em>Addendum : les armements et la question des technologies<\/em>): d\u00e9grader les \u00e9quipements encombr\u00e9s de sophistication co\u00fbteuse et d\u00e9shumanisantes des forces terrestres, qui vouent toutes les exp\u00e9ditions lointaines \u00e0 l&rsquo;impossibilit\u00e9 de l&rsquo;apaisement et de la paix et gr\u00e8vent les budgets d&rsquo;une fa\u00e7on \u00e9pouvantable; nous aurions ainsi beaucoup moins de gaspillage et beaucoup plus d&rsquo;hommes, beaucoup plus efficaces. (Premi\u00e8re suggestion \u00e0 peine ironique et pas loin d&rsquo;\u00eatre s\u00e9rieuse: au lieu de fabriquer d&rsquo;impossibles merveilles qui tirent dans les coins par tous les temps, et m\u00eame sans appuyer sur la g\u00e2chette, et co\u00fbtent le double de leur poids en or, \u00e9quipez donc vos forces de l&rsquo;AK-47 qui est depuis un demi-si\u00e8cle la meilleure arme individuelle du monde.)<\/p>\n<h3>Critique de la d\u00e9raison pure<\/h3>\n<\/p>\n<p><p>\tDans tout cela, il n&rsquo;y a ni trahison, ni abdication, ni machiav\u00e9lisme asservissant, etc. Il y a l&rsquo;aveuglement propre \u00e0 toutes nos \u00e9lites occidentales, le d\u00e9passement d&rsquo;elles-m\u00eames par des circonstances qu&rsquo;elles ne comprennent pas tout en en entendant vaguement le grondement. La m\u00e9diocrit\u00e9 et le conformisme vont avec. Il y a aujourd&rsquo;hui une sorte de passion de l&rsquo;\u00e9galitarisme dans la pens\u00e9e occidentale, au sens de notre Grande R\u00e9volution, et que le professeur de Droit Christophe Boutin, de l&rsquo;Universit\u00e9 de Caen (chapitre <em>Le d\u00e9coupage r\u00e9volutionnaire du territoire<\/em>, dans <em>Le livre noir de la R\u00e9volution fran\u00e7aise<\/em>) d\u00e9finit d&rsquo;une fa\u00e7on incisive, o\u00f9 vous pourriez r\u00e9sumer le propos par conformisme comme r\u00e9sultat de la d\u00e9marche pour la pens\u00e9e:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La premi\u00e8re rel\u00e8ve, bien s\u00fbr, de la passion de l&rsquo;\u00e9galit\u00e9. Non pas l&rsquo;engouement pour cette \u00e9galit\u00e9 m\u00e2le que d\u00e9crira Alexandre de Tocqueville, qui pousse l&rsquo;homme \u00e0 tenter d&rsquo;\u00e9galer ceux qui lui sont sup\u00e9rieurs, mais cette passion qu&rsquo;\u00e9voque aussi le penseur normand, que nous nommerions \u00e9galitarisme, celle qui pousse \u00e0 tout rabaisser au niveau du plus petit d\u00e9nominateur commun.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCet \u00e9galitarisme de la pens\u00e9e occidentale, qui affecte \u00e9videmment les \u00e9lites fran\u00e7aises dont on sait l&rsquo;ascendant r\u00e9volutionnaire, interdit par d\u00e9finition toute pens\u00e9e d&rsquo;une quelconque hauteur. Une telle pens\u00e9e d\u00e9couvrirait bient\u00f4t qu&rsquo;en pr\u00e9sence des crises syst\u00e9miques dont nous sommes l&rsquo;objet, en pr\u00e9sence d&rsquo;un ph\u00e9nom\u00e8ne dont nous sommes les machinistes et qui engendre une d\u00e9structuration qui acc\u00e9l\u00e8re ces m\u00eames crises syst\u00e9miques, le seul domaine o\u00f9 l&rsquo;on peut envisager la probl\u00e9matique de la d\u00e9fense est celui de la consolidation de la structuration comme frein \u00e0 la d\u00e9structuration. Est-ce qu&rsquo;on r\u00e9alise une d\u00e9fense structurante en essayant de faire aussi bien que les Anglo-Saxons, qui ont mis l&rsquo;arc de crise \u00e0 feu et \u00e0 sang, ou en mena\u00e7ant l&rsquo;Iran d&rsquo;une attaque? (Il para\u00eet que GW, lors de sa tourn\u00e9e en Europe, a confi\u00e9 \u00e0 nos \u00e9minences que l&rsquo;attaque est pour septembre,  sans toutefois pr\u00e9ciser l&rsquo;heure.)<\/p>\n<\/p>\n<p><p>\t(Tentons de nous expliquer \u00e0 partir du mod\u00e8le d\u00e9j\u00e0  <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5193\" class=\"gen\">\u00e9voqu\u00e9<\/a>: une d\u00e9fense structurante est un m\u00e9lange d&rsquo;affirmation dans certaines missions,  les <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4703\" class=\"gen\">missions de souverainet\u00e9<\/a> structurantes,  qui manifestent la force l\u00e9gitime et renforcent les grands principes structurants comme la souverainet\u00e9; et, d&rsquo;autre part, d&rsquo;adoucissement et d&rsquo;humanisation dans les m\u00e9thodes, les \u00e9quipements et les comportements, dans les missions jug\u00e9es n\u00e9cessaires pour contenir le d\u00e9sordre mais qui sont potentiellement d\u00e9structurantes, les missions dont le risque d\u00e9structurant doit \u00eatre contenu en faisant la promotion de la souverainet\u00e9 et de la l\u00e9gitimit\u00e9 des forces sur place,  plus facile \u00e0 dire qu&rsquo;\u00e0 faire, mais qui les a fait roi et qui a suscit\u00e9 le d\u00e9sordre?  et puis dire cela c&rsquo;est d\u00e9j\u00e0 esquisser une approche d&rsquo;une d\u00e9fense structurante au lieu de rouler des m\u00e9caniques au son du choc des civilisations.)<\/p>\n<\/p>\n<p><p>\tPour ce qui est de nos dirigeants\/de nos \u00e9lites: essayons de penser leur m\u00e9diocrit\u00e9 en termes ironiques et emplis de d\u00e9rision, m\u00eame si certains lecteurs s&rsquo;en offusquent, parce que c&rsquo;est tout ce que les actes de ces personnages dans les mati\u00e8res o\u00f9 on les voit s&rsquo;agiter m\u00e9ritent comme attention d&rsquo;\u00e9valuation. Certes, il para\u00eet que certains d&rsquo;entre eux pourraient d\u00e9clencher l&rsquo;apocalypse, mais on se permettra un certain scepticisme pour l&rsquo;essentiel tant ils nous l&rsquo;ont promise sans avoir la volont\u00e9 de s&rsquo;y mettre, s&rsquo;arr\u00eatant au discours qui est leur raison d&rsquo;\u00eatre,  et s&rsquo;ils y r\u00e9ussissaient finalement, ils s&rsquo;arrangeraient pour que cette apocalypse les balaie d&rsquo;abord. <\/p>\n<\/p>\n<p><p>\tOn nous pardonnera par cons\u00e9quent de ne pas nous abandonner \u00e0 des critiques d\u00e9taill\u00e9es des interventions des dirigeants occidentaux, comme celle de Sarkozy hier, parce qu&rsquo;une telle d\u00e9marche serait leur accorder une l\u00e9gitimit\u00e9 qu&rsquo;ils n&rsquo;ont plus. Ils ne disent pas que des sottises, bien entendu, mais ils disent des choses <em>irrelevant<\/em>, \u00e0 mille lieues nautiques, les plus longs, du fracas du monde plong\u00e9 dans une \u00e9poque eschatologique. Ils manquent \u00e0 leur contrat. Ils sont ill\u00e9gitimes en essence, et cela suffit.<\/p>\n<\/p>\n<p><p>\tEn attendant, on peut \u00eatre s\u00fbr que le discours, pour de bonnes et de mauvaises raisons, et surtout parce qu&rsquo;il traduit un climat de plus en plus mal support\u00e9 d&rsquo;irresponsabilit\u00e9, a provoqu\u00e9 et va provoquer une sainte col\u00e8re dans les cadres militaires de la R\u00e9publique fran\u00e7aise. Allez donc jusqu&rsquo;\u00e0 envisager dans ce temps historique sans pareil des situations extr\u00eames,  comme l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5178\" class=\"gen\">U.S. Navy<\/a> elle-m\u00eame, pourtant arme de haute tradition s&rsquo;il en est, a montr\u00e9 la voie en faisant de l&rsquo;obstruction aux suggestions de son commandant en chef. Une sourde r\u00e9volte et peut-\u00eatre plus sont d\u00e9sormais dans le champ des possibles. Bling-bling devra souquer ferme dans la temp\u00eate. Cela nous permettra d&rsquo;appr\u00e9cier sa musculature. Sacr\u00e9 <em>people<\/em><\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parlons d&rsquo;autre chose 18 juin 2008 On nous pardonnera d&rsquo;avoir, peut-\u00eatre curieusement pour certains, choisi de parler du Sarkozy d&rsquo;un autre jour (le 13 juin), \u00e0 un autre propos (son entregent avec GW), le jour (17 juin) o\u00f9 le pr\u00e9sident de la R\u00e9publique fran\u00e7aise parlait solennellement de la d\u00e9fense en France. C&rsquo;est une occurrence solennelle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3228,3019,584,4590,3777,2746,6277],"class_list":["post-69975","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-crise","tag-defense","tag-otan","tag-sarkozy","tag-solana","tag-souverainete","tag-systemique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69975"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69975\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}