{"id":70008,"date":"2008-06-30T00:00:00","date_gmt":"2008-06-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/30\/que-faire\/"},"modified":"2008-06-30T00:00:00","modified_gmt":"2008-06-30T00:00:00","slug":"que-faire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/06\/30\/que-faire\/","title":{"rendered":"Que faire?"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Que faire?<\/h2>\n<\/p>\n<p><p>28 juin 2008 &mdash; Nous nous <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5225\">int\u00e9ressions<\/a> au <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5227\">Pentagone<\/a> ou aux <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5232\">relations<\/a> USA-Russie. Pendant ce temps, le temps, c&rsquo;est-\u00e0-dire l&rsquo;Histoire file vite. (En plus, notre site a manqu\u00e9 \u00e0 l&rsquo;appel pendant un temps ind\u00e9cent, du vendredi 27 \u00e0 samedi 28, pendant 15 heures. Vos messages de r\u00e9criminations \u00e9taient m\u00e9rit\u00e9s.)<\/p>\n<\/p>\n<p><p>Voyez, par exemple, &ndash; mais quels exemples, &ndash; dans ces deux domaines, ces \u00e9v\u00e9nements survenus la semaine derni\u00e8re.<\/p>\n<\/p>\n<p><p>&bull; Le 23 juin, le docteur David Hansen t\u00e9moigne devant le Congr\u00e8s. Il rappelle que vingt ans plus t\u00f4t, jour pour jour, il t\u00e9moignait devant le m\u00eame Congr\u00e8s. Les m\u00eames mots, la m\u00eame urgence, la m\u00eames alerte, grossis mille fois&#8230; Entre temps, le mal a prolif\u00e9r\u00e9, et l&rsquo;on d\u00e9couvre qu&rsquo;il prolif\u00e8re plus vite que pr\u00e9vu, ou plus vite que non-pr\u00e9vu. Si les USA, avec le nouveau pr\u00e9sident, ne prennent pas leurs responsabilit\u00e9s, dit <a class=\"gen\" href=\"http:\/\/www.commondreams.org\/archive\/2008\/06\/24\/9850\/\">Hansen<\/a>, &laquo;<em>&hellip;it will become impractical to constrain atmospheric carbon dioxide, the greenhouse gas produced in burning fossil fuels, to a level that prevents the climate system from passing tipping points that lead to disastrous climate changes that spiral dynamically out of humanity&rsquo;s control.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Nous sommes entr\u00e9s dans une nouvelle \u00e9poque\u00a0\u00bb, \u00e9crit Mike Davis, dans un article que publie <em>TomDispatch.com<\/em> le <a class=\"gen\" href=\"http:\/\/www.tomdispatch.com\/post\/174949\/mike_davis_welcome_to_the_next_epoch\">26 juin 2008<\/a>.<\/p>\n<\/p>\n<p><p>&laquo;<em>This February, while cranes were hoisting cladding to the 141st floor of the Burj Dubai tower (which will soon be twice the height of the Empire State Building), the Stratigraphy Commission of the Geological Society of London was adding the newest and highest story to the geological column.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>To the question \u00ab\u00a0Are we now living in the Anthropocene?\u00a0\u00bb the 21 members of the Commission unanimously answer \u00ab\u00a0yes.\u00a0\u00bb They adduce robust evidence that the Holocene epoch &ndash; the interglacial span of unusually stable climate that has allowed the rapid evolution of agriculture and urban civilization &ndash; has ended and that the Earth has entered \u00ab\u00a0a stratigraphic interval without close parallel in the last several million years.\u00a0\u00bb In addition to the buildup of greenhouse gases, the stratigraphers cite human landscape transformation which \u00a0\u00bbnow exceeds [annual] natural sediment production by an order of magnitude,\u00a0\u00bb the ominous acidification of the oceans, and the relentless destruction of biota.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>This new age, they explain, is defined both by the heating trend (whose closest analogue may be the catastrophe known as the Paleocene Eocene Thermal Maximum, 56 million years ago) and by the radical instability expected of future environments. In somber prose, they warn that \u00ab\u00a0the combination of extinctions, global species migrations and the widespread replacement of natural vegetation with agricultural monocultures is producing a distinctive contemporary biostratigraphic signal. These effects are permanent, as future evolution will take place from surviving (and frequently anthropogenically relocated) stocks.\u00a0\u00bb Evolution itself, in other words, has been forced into a new trajectory.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Que fait \u00ab\u00a0l&rsquo;homme\u00a0\u00bb, celui qui appartient \u00e0 l&rsquo;esp\u00e8ce humaine, celui qui se pare lui-m\u00eame de tant de vertus, tant morales que celle d&rsquo;une profonde sagesse, que fait-il pendant ce temps? Il regarde s&rsquo;accumuler les \u00ab\u00a0<em>worst since&hellip;<\/em>\u00ab\u00a0, &ndash; pour la crise du jour, l&rsquo;expression devient \u00ab\u00a0<em>worst since Great Depression<\/em>\u00ab\u00a0, le 26 juin, ou l&rsquo;\u00e9quivalent. Titre d&rsquo;une d\u00e9p\u00eache de <em>CNN.com<\/em> le <a class=\"gen\" href=\"http:\/\/money.cnn.com\/news\/newsfeeds\/articles\/djhighlights\/200806261857DOWJONESDJONLINE000793.htm\">26 juin<\/a>: &laquo;<em>Worst June For Dow Since 1930<\/em>&raquo;. Le site <em>WSWS.org<\/em>, \u00e0 c\u00f4t\u00e9 de la description de <a class=\"gen\" href=\"http:\/\/www.wsws.org\/articles\/2008\/jun2008\/econ-j27.shtml\">\u00ab\u00a0la crise du jour\u00a0\u00bb<\/a> \u00e0 Wall Street, observe le sort \u00e9trange de la puissante <em>Fed<\/em> devant ce ph\u00e9nom\u00e8ne qu&rsquo;elle pr\u00e9tend n\u00e9cessairement contr\u00f4ler, qui est le sort du syst\u00e8me financier du monde. Ecoutez cette histoire que <em>WSWS.org<\/em> nous rapporte le <a class=\"gen\" href=\"http:\/\/www.wsws.org\/articles\/2008\/jun2008\/fedr-j27.shtml<\/p>\n<p>&lt;\/p&gt;<\/p>\n<p>&lt;p&gt;<\/p>\n<p>\t\u00ab\u00a0>27 juin 2008<\/a> \u00e0 propos de la Federal Reserve: plac\u00e9e devant la n\u00e9cessit\u00e9 de r\u00e9duire ses taux d&rsquo;int\u00e9r\u00eat pour tenter de favoriser une reprise \u00e9conomique aux USA, et la n\u00e9cessit\u00e9 d&rsquo;augmenter ses taux d&rsquo;int\u00e9r\u00eat pour lutter contre l&rsquo;inflation en marche au sein de la globalisation&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>&hellip;the Fed decided to do nothing.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Announcing its decision, the Fed&rsquo;s open market committee tried to put the best face on the worsening US economy. \u00ab\u00a0Recent information,\u00a0\u00bb it stated, \u00ab\u00a0indicates that overall economic activity continues to expand, partly reflecting some firming in household spending &#8230; The substantial easing of monetary policy to date, combined with ongoing measures to foster market liquidity, should help promote moderate growth over time.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>These assertions prompted Business Week economics writer Michael Mandel to ask: \u00ab\u00a0Is the Fed living in a fairy-tale world? Unemployment is rising, housing prices and plunging and oil prices are sky-high. Oh, yes, and consumer expectations of their future economic prospects are at a record low, according to the Conference Board.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Nous n&rsquo;avons pas vraiment choisi parce que l&rsquo;actualit\u00e9 de la semaine, celle que les initi\u00e9s et les curieux peuvent d\u00e9couvrir sans grand effort l\u00e0 o&ugrave; on ne tente pas de l&rsquo;\u00e9touffer, s&rsquo;imposait \u00e0 nous. Pourtant, nous aurions pu nous tourner vers l&rsquo;Irak, ou rappeller les <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5223\">nouvelles<\/a> du dernier jeu \u00e0 la mode dans les chancelleries, qui se nomme: \u00ab\u00a0Quand taperons-nous sur l&rsquo;Iran?\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mais ce n&rsquo;est ni la place ni l&rsquo;heure des r\u00e9criminations faciles et du sarcasme sans difficult\u00e9. Il est plut\u00f4t question de s&rsquo;\u00e9tonner, de se surprendre soi-m\u00eame, au spectacle de la <strong>rapidit\u00e9<\/strong> extraordinaire de la marche de l&rsquo;Histoire hors de notre contr\u00f4le, &ndash; \u00ab\u00a0<em>out of humanity&rsquo;s control<\/em>\u00ab\u00a0, et que cette marche se fait \u00e0 l&rsquo;aide de \u00ab\u00a0crises syst\u00e9miques\u00a0\u00bb qui semblent porter le destin catastrophique du monde, &ndash; elles aussi hors de notre contr\u00f4le. Nous rappellerons ici, comme nous le faisons <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4787\">souvent<\/a>, que c&rsquo;est la d\u00e9finition m\u00eame d&rsquo;un temps eschatologique, qui se caract\u00e9rise par l&rsquo;absence de contr\u00f4le qu&rsquo;on peut exercer sur lui, \u00e9ventuellement par son issue catastrophique, et ceci expliquant cela.<\/p>\n<\/p>\n<p><p>Comme disait L\u00e9nine : \u00ab\u00a0Que faire?\u00a0\u00bb<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Marteau et rumination<\/h3>\n<\/p>\n<p><p>Nietzsche appelait \u00e7a \u00ab\u00a0la philosophie au marteau\u00a0\u00bb: r\u00e9p\u00e9ter, r\u00e9p\u00e9ter et r\u00e9p\u00e9ter encore la m\u00eame chose, jusque ce que la chose acquiert sa consistance, puis sa substance, et qu&rsquo;elle soit prise enfin pour ce qu&rsquo;elle est par ceux \u00e0 qui elle est pr\u00e9sent\u00e9e. (De m\u00eame disait-il, Nietzsche, qu&rsquo;il faut lire comme une vache rumine: lire, relire et relire le m\u00eame propos dont on devine l&rsquo;importance, dig\u00e9rer une fois, m\u00e2cher \u00e0 nouveau et ainsi de suite. Ainsi, l\u00e0 aussi, appara&icirc;tra sa substance profonde.) Aussi r\u00e9p\u00e9tons-nous et r\u00e9p\u00e9tons-nous encore cette affirmation ass\u00e9n\u00e9e comme \u00e0 coups de marteau: il faut &laquo;<em>envisager enfin<\/em> [&hellip; de] <em>constituer un tout autre type de rationalit\u00e9<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Comme on le sait, car nous r\u00e9p\u00e9tons cela comme avec un marteau, cette phrase, ou plut\u00f4t ce membre de phrase, est de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4787\">Ren\u00e9 Girard<\/a>. Nous ne tenons pas que Girard soit un g\u00e9nie ou pas, bien incapable d&rsquo;en d\u00e9cider, ni m\u00eame de statuer sur la signification du terme \u00ab\u00a0g\u00e9nie\u00a0\u00bb, voire de son existence, &ndash; tout cela n&rsquo;a gu\u00e8re d&rsquo;importance; mais cette phrase, ce mot, cette notion (n\u00e9cessit\u00e9 d&rsquo;&laquo;<em> un tout autre type de rationalit\u00e9<\/em>&raquo;) rel\u00e8ve de l&rsquo;illumination, quel que soit le m\u00e9dium qui nous la transmet, et ouvre aussit\u00f4t \u00e0 l&rsquo;esprit des champs de r\u00e9flexion nouveaux&hellip; C&rsquo;est \u00e9videmment ce qu&rsquo;il faut, aujourd&rsquo;hui, pour continuer \u00e0 avoir la force de penser notre temps, l&rsquo;esp\u00e8ce et son destin, avec une \u00e9nergie cr\u00e9atrice qui justifie de penser.<\/p>\n<\/p>\n<p><p>(Ou bien, faire comme tous les cr\u00e9tins du troupeau g\u00e9n\u00e9ral, les couverts de milliards et les couverts d&rsquo;honneurs, ne rien penser du tout; abdiquer devant la machine et la servir jusqu&rsquo;au bout du mensonge, qui a de si fortes probabilit\u00e9s d&rsquo;\u00eatre catastrophique&hellip; Impossible gymnastique si vous avez aper\u00e7u le trait de la lumi\u00e8re.)<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Illumination\u00a0\u00bb ne signifie pas que Girard ait compris, ou pes\u00e9, toute la puissance de son propos, ni non plus que ceux qui entendent son propos l&rsquo;entendent aussit\u00f4t dans le sens qui importe. Le propos est d&rsquo;une puissance sp\u00e9cifique et le fait d&rsquo;\u00eatre dit nous d\u00e9livre de la n\u00e9cessit\u00e9 de le rechercher. C&rsquo;est alors qu&rsquo;il faut commencer \u00e0 en peser les cons\u00e9quences. Chacun de ceux qui re\u00e7oivent cette lumi\u00e8re est libre d&rsquo;\u00e9clairer ce qu&rsquo;il lui pla&icirc;t&hellip; (Et, comme on dit, Dieu reconna&icirc;tra les siens.)<\/p>\n<\/p>\n<p><p>Nous ne pr\u00e9tendons pas ouvrir une voie ou tracer une perspective. Nous pr\u00e9tendons qu&rsquo;il faut se d\u00e9livrer des cha&icirc;nes de cette raison-l\u00e0, que nous nous sommes forg\u00e9e pour justifier <em>a posteriori<\/em> le destin que nous nous sommes choisi, et qui a ainsi montr\u00e9 ses limites tragiques, voire certains aspects faussaires de sa sp\u00e9cificit\u00e9. Lorsque le destin s&rsquo;av\u00e8re catastrophique, il faut r\u00e9volutionner la m\u00e9thode de la pens\u00e9e qui y a conduit. Nous sommes prisonniers du syst\u00e8me que nous avons construit puis d\u00e9cha&icirc;n\u00e9, mais bien plus de la raison que nous nous sommes fabriqu\u00e9e pour justifier ce syst\u00e8me et ne pas porter contre lui des attaques fondamentales.<\/p>\n<\/p>\n<p><p>Nous ne sommes pas les seuls et nous ne sommes pas les premiers \u00e0 observer la trag\u00e9die. Cette qu\u00eate de la compr\u00e9hension de la crise de notre monde et de la n\u00e9cessit\u00e9 de mettre en cause la forme que nous avons donn\u00e9e \u00e0 notre rationalit\u00e9 est d\u00e9j\u00e0 riche et vieille. Robert Aron et Arnaud Dandieu \u00e9crivaient en <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=782\">1931<\/a> ces phrases qui annoncent \u00e9videmment la crise de notre raison, suscit\u00e9e par la crise du monde que cette raison-l\u00e0, ce \u00ab\u00a0type de rationalit\u00e9\u00a0\u00bb d\u00e9pass\u00e9e ou faussaire, a enfant\u00e9e:<\/p>\n<\/p>\n<p><p>&laquo;<em>De Descartes \u00e0 Ford, cela veut dire : de l&rsquo;individu isol\u00e9 forgeant avec passion l&rsquo;outil rationnel de compr\u00e9hension et de conqu\u00eate, aux individus encasern\u00e9s, r\u00e9p\u00e9tant dans des usines rationalis\u00e9es les m\u00eames gestes machinaux d&rsquo;un labeur qui les d\u00e9passe. Cela veut dire que Descartes est \u00e0 l&rsquo;origine d&rsquo;une \u00e9pop\u00e9e humaine dont nous voyons l&rsquo;aboutissement gigantesque mais d\u00e9grad\u00e9. Cela veut dire que l&rsquo;esprit de conqu\u00eate, la volont\u00e9 r\u00e9volutionnaire qui permit et l\u00e9gitima la naissance des r\u00e8gles m\u00e9thodiques, a compl\u00e8tement disparu chez ceux qui en font maintenant une application intensive et routini\u00e8re. Descartes a pr\u00e9par\u00e9 lui-m\u00eame cette d\u00e9gradation de son &oelig;uvre, le jour o&ugrave;, formulant en r\u00e8gles abstraites et impersonnelles le r\u00e9sultat de ses angoisses et de ses efforts, il montra qu&rsquo;on pouvait en faire un outil, une m\u00e9thode, s\u00e9par\u00e9s de tout pouvoir d&rsquo;\u00e9motion et de toute facult\u00e9 cr\u00e9atrice. Cette g\u00e9niale \u00ab\u00a0\u00e9conomie de pens\u00e9e\u00a0\u00bb aurait d&ucirc; \u00eatre compens\u00e9e pour \u00eatre inoffensive, par une affirmation nouvelle de l&rsquo;essence affective de la cr\u00e9ation intellectuelle, &mdash; ce que Descartes ne fit pas, du moins express\u00e9ment. Ses successeurs ont achev\u00e9 cette trahison sentimentale le jour o&ugrave; ils appliqu\u00e8rent cette m\u00e9thode, d\u00e9sormais abstraite, aux domaines inhumains des sciences exp\u00e9rimentales, puis des sciences \u00e9conomiques. Enfin Descartes est descendu dans la rue avec l&rsquo;av\u00e8nement de l&rsquo;industrialisme et du taylorisme. Ainsi par un lent avilissement, la m\u00e9thode cart\u00e9sienne, perdant de plus en plus sa valeur individuelle et sa force r\u00e9volutionnaire, s\u00e9par\u00e9e de tout germe vivant, a pris un nom particulier. Elle s&rsquo;appelle Etats-Unis. Tant il est vrai que les conflits les plus profonds et les plus m\u00e9taphysiques doivent t\u00f4t ou tard s&rsquo;exprimer dans l&rsquo;imm\u00e9diat et le quotidien&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Nous n&rsquo;entendons certainement pas proposer un sch\u00e9ma, une r\u00e9ponse, une certitude rationnelle (!). Impossible puisque cette proposition s&rsquo;appuie sur l&rsquo;id\u00e9e de construire une autre rationalit\u00e9, donc sur la mise en cause de l&rsquo;instrument de la pens\u00e9e; elle porte sur l&rsquo;instrument et non sur ce que l&rsquo;instrument permettrait de d\u00e9terminer. Il y a quelque chose d&rsquo;\u00e9pouvantable dans cette n\u00e9cessit\u00e9 o&ugrave; nous nous trouvons de penser un temps historique qui ressemble d&rsquo;une fa\u00e7on de plus en plus irr\u00e9sistible \u00e0 \u00ab\u00a0la fin des temps\u00a0\u00bb, avec une rationalit\u00e9 qui repousse ontologiquement de telles possibilit\u00e9s. Notre bataille porte moins sur une cause qu&rsquo;il faut faire triompher que sur la possibilit\u00e9 de se battre.<\/p>\n<\/p>\n<p><p>Certes, nous avons nos id\u00e9es. Nous ne cachons pas que notre penchant d&rsquo;historien proph\u00e9tique, qui est une veine si fran\u00e7aise, notre penchant pour la conception \u00ab\u00a0maistrienne\u00a0\u00bb de l&rsquo;Histoire est un effort dans ce sens en m\u00eame temps qu&rsquo;un penchant de nature, &ndash; avec le d\u00e9fi intellectuel exaltant de concilier notre n\u00e9cessaire, notre imp\u00e9rative libert\u00e9 de penser et d&rsquo;agir avec un sch\u00e9ma historique dont la tendance d\u00e9terministe est \u00e9vidente, &ndash; mais nullement, \u00e0 notre sens, ennemie des am\u00e9nagements et des nuances fondamentales. Ce penchant pour la conception \u00ab\u00a0maistrienne\u00a0\u00bb, qui ne nous en fait pas le prisonnier, n&rsquo;est certainement pas une consigne pour les autres. Chacun se bat avec les armes dont il dispose et qu&rsquo;il privil\u00e9gie, et qu&rsquo;il a forg\u00e9es, selon la vision qu&rsquo;il entretient. Mais il s&rsquo;agit sans aucun doute du cas sp\u00e9cifique d&rsquo;un exemple intellectuel o&ugrave; l&rsquo;expos\u00e9 de l&rsquo;utilisation d&rsquo;une nouvelle logique doit devenir une incitation \u00e0 penser hardiment et sans s&rsquo;encombrer d&rsquo;interdits rationnels sugg\u00e9r\u00e9s par une raison elle-m\u00eame si mal en point, et qui s&rsquo;est discr\u00e9dit\u00e9e par le fait de la caricature nihiliste de civilisation qu&rsquo;elle nous a fabriqu\u00e9e.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que faire? 28 juin 2008 &mdash; Nous nous int\u00e9ressions au Pentagone ou aux relations USA-Russie. Pendant ce temps, le temps, c&rsquo;est-\u00e0-dire l&rsquo;Histoire file vite. (En plus, notre site a manqu\u00e9 \u00e0 l&rsquo;appel pendant un temps ind\u00e9cent, du vendredi 27 \u00e0 samedi 28, pendant 15 heures. Vos messages de r\u00e9criminations \u00e9taient m\u00e9rit\u00e9s.) Voyez, par exemple, &ndash;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4267,3280,3392,3228,4042,6063,5040,7336,7658,6277],"class_list":["post-70008","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-anthropocene","tag-aron","tag-climatique","tag-crise","tag-dandieu","tag-girard","tag-hansen","tag-rationalite","tag-rene","tag-systemique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70008"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70008\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}