{"id":70022,"date":"2008-07-05T00:00:00","date_gmt":"2008-07-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/05\/la-tchequie-de-plus-en-plus-incertaine\/"},"modified":"2008-07-05T00:00:00","modified_gmt":"2008-07-05T00:00:00","slug":"la-tchequie-de-plus-en-plus-incertaine","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/05\/la-tchequie-de-plus-en-plus-incertaine\/","title":{"rendered":"La Tch\u00e9quie de plus en plus incertaine?"},"content":{"rendered":"<p><p>Concernant la question du BMDE, les Polonais ont, ces derni\u00e8res semaines, fait passer le message insistant, jamais contredit par les Tch\u00e8ques, selon lequel les Tch\u00e8ques et eux-m\u00eames agissent 1) en parfaite coordination et en parfaite information r\u00e9ciproque les uns avec les autres, et 2) selon une analyse du fond du probl\u00e8me qui leur est commune. A partir de l\u00e0, on peut s&rsquo;interroger de savoir si la parfaite image d&rsquo;une Tch\u00e9quie particuli\u00e8rement anxieuse de signer son accord sur les deux bases radar du BMDE avec les USA est vraiment conforme \u00e0 la r\u00e9alit\u00e9. Ce sont les Am\u00e9ricains qui ne cessent de nous diffuser cette image idyllique, tandis que les Tch\u00e8ques, encore enthousiastes pour cette diffusion il y a quelques mois, tendent plut\u00f4t aujourd&rsquo;hui \u00e0 mettre en \u00e9vidence toutes les difficult\u00e9s restantes pour la signature de cet accord.<\/p>\n<\/p>\n<p><p>\tPourtant, Condi Rice s&rsquo;arr\u00eate le 8 juillet \u00e0 Prague, officiellement, selon Washington dans tous les cas, pour signer le susdit accord. Ce sera une journ\u00e9e int\u00e9ressante. (Il faut noter que, depuis f\u00e9vrier, la signature de l&rsquo;accord entre la Tch\u00e9quie et les USA, formellement fix\u00e9e, a \u00e9t\u00e9 repouss\u00e9e \u00e0 deux reprises. Dans tous les cas, l&rsquo;accord \u00e9ventuellement sign\u00e9 sera soumis \u00e0 la ratification du Parlement, ce qui est loin d&rsquo;\u00eatre chose acquise.) <\/p>\n<\/p>\n<p><p>\tEn Tch\u00e9quie, c&rsquo;est manifestement le m\u00e9contentement populaire anti-BMDE qui est l&rsquo;obstacle le plus ardu \u00e0 l&rsquo;installation des bases. Le mouvement anti-bases, dit <em>No Bases Initiative<\/em>, a pris des proportions et une dimensions tout \u00e0 fait inattendues. Selon la presse tch\u00e8que, ce mouvement populaire est le plus puissant depuis le mouvement populaire anti-communiste (la r\u00e9volution de velours) qui abattit le r\u00e9gime communiste \u00e0 l&rsquo;automne 1989.<\/p>\n<\/p>\n<p><p>\tLa pr\u00e9sentation officielle de la position du gouvernement dans la perspective d&rsquo;un \u00e9chec de l&rsquo;arrangement avec les USA s&rsquo;appuie sur une appr\u00e9ciation assez sentimentale, selon Jiri Pehe, un analyste politique tch\u00e8que. \u00ab<em>The Czech government went for this deal on the presumption that we owe the United States for what it did for us before the fall of communism. But a huge majority of Czechs are against the radar. They don&rsquo;t see why we should accept this at all, and if we do, why we shouldn&rsquo;t ask for something in return from the richest country in the world.<\/em>\u00bb Pour ce qui concerne cet aspect des choses, on sugg\u00e9rera une version un peu plus nuanc\u00e9e, \u00e9ventuellement moins bucolique, portant sur l&rsquo;all\u00e9geance automatique mais n\u00e9anmoins pas d\u00e9nu\u00e9e d&rsquo;int\u00e9r\u00eat des dirigeants de l&rsquo;Europe de l&rsquo;Est pour les USA depuis la chute du communisme. Les Polonais sont les premiers \u00e0 envisager de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5249\" class=\"gen\">s&rsquo;en d\u00e9gager<\/a> d&rsquo;une part \u00e0 cause de leur enthousiasme initial conduisant \u00e0 une d\u00e9ception \u00e0 mesure, d&rsquo;autre part \u00e0 cause de l&rsquo;importance du pays qui peut rechercher des rapprochements diff\u00e9rents et manifeste \u00e9galement un sens national beaucoup plus vite exc\u00e9d\u00e9 par le comportement US. Les dirigeants tch\u00e8ques actuels sont plut\u00f4t \u00e0 la taille de leur pays. Les citoyens tch\u00e8ques, par contre, avec un relais possible de la repr\u00e9sentation parlementaire, ont une autre id\u00e9e de leur ind\u00e9pendance et de leur souverainet\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 juillet 2008 \u00e0 15H21<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concernant la question du BMDE, les Polonais ont, ces derni\u00e8res semaines, fait passer le message insistant, jamais contredit par les Tch\u00e8ques, selon lequel les Tch\u00e8ques et eux-m\u00eames agissent 1) en parfaite coordination et en parfaite information r\u00e9ciproque les uns avec les autres, et 2) selon une analyse du fond du probl\u00e8me qui leur est commune.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4314,7666,2827,3306],"class_list":["post-70022","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bmde","tag-chequie","tag-pologne","tag-rice"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70022"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70022\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}