{"id":70027,"date":"2008-07-08T00:00:00","date_gmt":"2008-07-08T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/08\/journal-de-bord-de-dedefensaorg-080708-9405-et-nos-remerciements\/"},"modified":"2008-07-08T00:00:00","modified_gmt":"2008-07-08T00:00:00","slug":"journal-de-bord-de-dedefensaorg-080708-9405-et-nos-remerciements","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/08\/journal-de-bord-de-dedefensaorg-080708-9405-et-nos-remerciements\/","title":{"rendered":"Journal de bord de dedefensa.org \u2014  080708, \u20ac9405, et nos remerciements\u2026"},"content":{"rendered":"<p><p>8 juillet 2008  Apr\u00e8s avoir attendu le compl\u00e9ment des donations (envois postaux), nous avons pu faire nos comptes de cette deuxi\u00e8me campagne de donation, du 13 mai au 25 juin 2008. Nous atteignons un total de 9405. Nous vous soumettons quelques commentaires tr\u00e8s rapides, nous r\u00e9servant de revenir sur ce sujet plus au fond, tr\u00e8s rapidement.<\/p>\n<\/p>\n<p><p>\tMais d&rsquo;abord, nos remerciements, bien s\u00fbr. Notre reconnaissance va \u00e0 ces lecteurs qui ont tenu \u00e0 contribuer au soutien de notre site.<\/p>\n<\/p>\n<p><p>\tNous n&rsquo;avons pas atteint le but  que nous nous \u00e9tions fix\u00e9s (13.000), il s&rsquo;en faut d&rsquo;une partie non n\u00e9gligeable. Par contre, vos contributions sont notablement plus importantes que lors de la premi\u00e8re campagne de janvier-f\u00e9vrier (9.405 contre 6.570). Les d\u00e9buts de la campagne ont \u00e9t\u00e9 tr\u00e8s d\u00e9cevants, au point o\u00f9 nous pensions que nous allions vers un total inf\u00e9rieur \u00e0 celui de la premi\u00e8re campagne. Le redressement a \u00e9t\u00e9 spectaculaire. De ce point de vue, on pourrait juger la campagne plus encourageante qu&rsquo;ils n&rsquo;y para\u00eet.<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 pour nos r\u00e9flexions imm\u00e9diates. Nous reviendrons dans peu de temps sur cette donation, cette fois dans un cadre plus large, concernant bien entendu l&rsquo;organisation et le fonctionnement du site pour l&rsquo;avenir.<\/p>\n<\/p>\n<p><p>\tPour conclure ce message rapide, nous vous renouvelons nos remerciements.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 juillet 2008 Apr\u00e8s avoir attendu le compl\u00e9ment des donations (envois postaux), nous avons pu faire nos comptes de cette deuxi\u00e8me campagne de donation, du 13 mai au 25 juin 2008. Nous atteignons un total de 9405. Nous vous soumettons quelques commentaires tr\u00e8s rapides, nous r\u00e9servant de revenir sur ce sujet plus au fond, tr\u00e8s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[6120,4854,7667],"class_list":["post-70027","post","type-post","status-publish","format-standard","hentry","category-messagerie","tag-campagne","tag-donation","tag-remerciements"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70027"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70027\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}