{"id":70036,"date":"2008-07-11T00:00:00","date_gmt":"2008-07-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/11\/les-britanniques-et-laffaire-eadskc-45\/"},"modified":"2008-07-11T00:00:00","modified_gmt":"2008-07-11T00:00:00","slug":"les-britanniques-et-laffaire-eadskc-45","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/11\/les-britanniques-et-laffaire-eadskc-45\/","title":{"rendered":"Les Britanniques et l&rsquo;affaire EADS\/KC-45"},"content":{"rendered":"<p><p>Une surprise de plus dans la saga du programme de ravitailleurs en vol KC-45 de l&rsquo;USAF, c&rsquo;est de retrouver le Premier ministre britannique Gordon Brown engag\u00e9 \u00e0 fond derri\u00e8re EADS. La cause la plus imm\u00e9diate, c&rsquo;est l&rsquo;importance \u00e9conomique et sociale du programme,  si EADS l&#8217;emporte,  pour l&rsquo;\u00e9conomie britannique: \u00ab<em>If Airbus wins the tanker contract the wings will be made at its factory at Broughton, North Wales. The deal would secure the 11,000 jobs at Broughton and be worth more than \u00a34 billion to the British economy. A spokesman for the Prime Minister said yesterday: He will support the Airbus bid in whatever way he can.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le <em>Times<\/em> de Londres qui, <a href=\"http:\/\/business.timesonline.co.uk\/tol\/business\/industry_sectors\/engineering\/article4313136.ece\" class=\"gen\">aujourd&rsquo;hui<\/a>, rapporte la position de Brown dans cette affaire, notamment ses interventions politiques au plus haut niveau.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Mr Brown wrote to President Bush at the end of last year to promote the Airbus tanker, which has already been bought by the Royal Air Force. Mark Tami, the Labour MP for Alyn &#038; Deeside, which includes Broughton, said he expected the Prime Minister to take up the matter with Mr Bush again.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Brown will also have an opportunity to raise the issue with Barack Obama, the presumptive Democratic presidential nominee, when they meet in London next week. Mr Obama questioned the Pentagon&rsquo;s decision to award the tanker contract to a European company when the deal was initially announced in February.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t(Cette rencontrer avec Obama sera int\u00e9ressante et instructive puisque le candidat d\u00e9mocrate s&rsquo;est exprim\u00e9 sur l&rsquo;affaire, qu&rsquo;il a pris plut\u00f4t position pour un choix en faveur de Boeing, que Boeing est implant\u00e9 dans son Etat de l&rsquo;Illinois)<\/p>\n<\/p>\n<p><p>\tL&rsquo;article ne cache pas par ailleurs le mauvais climat (du point de vue europ\u00e9en) qui r\u00e8gne aux USA dans cette affaire, reprenant les accusations implicites ou explicites d&rsquo;isolationnisme et de manipulation du march\u00e9. Le d\u00e9put\u00e9 travailliste d\u00e9j\u00e0 cit\u00e9, Mark Tami, d\u00e9clare: \u00ab<em>It is obviously a pretty cynical political decision to recompete this contract. To many fair-minded people the Airbus offering was a superior product but we are in a US election year and this smacks of a cynical act.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;opinion que refl\u00e8te l&rsquo;article, opinion essentiellement recueillie dans les milieux politiques britanniques, semble nettement que les pressions politiques ont de fortes chances de conduire \u00e0 un choix en faveur de Boeing. Dans ces conditions, cette position des Britanniques est inhabituelle, eux qui ont peu l&rsquo;habitude de s&#8217;embarrasser de causes perdues. Les int\u00e9r\u00eats g\u00e9n\u00e9raux des Britanniques pour EADS sont d\u00e8s l&rsquo;origine tr\u00e8s secondaires sinon inexistants par rapport aux positions fran\u00e7aise et allemande.<\/p>\n<\/p>\n<p><p>\tOn chercherait plut\u00f4t dans la position des Britanniques la confirmation de la situation tr\u00e8s particuli\u00e8re d\u00e9crite <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5225\" class=\"gen\">ici<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5260\" class=\"gen\">l\u00e0<\/a> sur ce site, dans les milieux atlantistes et libre-\u00e9changistes o\u00f9 ces m\u00eames Britanniques sont \u00e9videmment tr\u00e8s pr\u00e9sents, sinon largement majoritaires. L&rsquo;affaire EADS et KC-45 est devenue subrepticement une cause nationale au Royaume Uni,  dans le sens d&rsquo;une cause qui rencontre les int\u00e9r\u00eats nationaux britanniques au travers de l&rsquo;engagement libre-\u00e9changiste (donc avec r\u00e9ciprocit\u00e9) avec les USA. Du coup, les Britanniques s&rsquo;engagent au niveau politique alors m\u00eame que les perspectives sont tr\u00e8s d\u00e9favorables.<\/p>\n<\/p>\n<p><p>\tQue conclure? Il est possible que les Britanniques, repr\u00e9sentant en ce sens les tendances atlantistes aient d\u00e9cid\u00e9 de s&rsquo;engager \u00e0 fond dans cette affaire pour prendre date avec les Am\u00e9ricains sur un point fondamental des relations transatlantiques. Une phrase de l&rsquo;article du <em>Times<\/em> m\u00e9rite de retenir l&rsquo;attention: \u00ab<em>If Boeing is able to use its enormous political influence in the US to get the tanker contract it could trigger calls in the UK to make it harder for American companies to win Ministry of Defence business.<\/em>\u00bb On retiendra dans cette phrase la menace \u00e9voqu\u00e9e mais, surtout, les circonstances tr\u00e8s pr\u00e9cis\u00e9ment caract\u00e9ris\u00e9es. Elles semblent indiquer que, pour les Britanniques, une s\u00e9lection de Boeing sera n\u00e9cessairement le produit d&rsquo;une pression politique, et sera par cons\u00e9quent interpr\u00e9t\u00e9 comme un choix politique hostile \u00e0 l&rsquo;Europe et \u00e0 eux-m\u00eames.<\/p>\n<\/p>\n<p><p>\tCertaines sources estiment que les Britanniques pourraient m\u00eame envisager de faire pression sur les Am\u00e9ricains par l&rsquo;interm\u00e9diaire de leurs engagements dans des programmes US, en mettant en question l&rsquo;un ou l&rsquo;autre de ces engagements. Le cas du JSF est \u00e9videmment cit\u00e9. On est \u00e9videmment tr\u00e8s loin de la coupe aux l\u00e8vres, jusqu&rsquo;\u00e0 envisager le s\u00e9rieux de telles hypoth\u00e8ses comme pr\u00e9sageant une r\u00e9elle action dans ce sens. Mais il ne faut pas perdre de vue que l&rsquo;affaire EADS\/KC-45 est vraiment en train de devenir une pol\u00e9mique fondamentale des relations transatlantiques \u00e0 un moment crucial de ces relations, avec l&rsquo;arriv\u00e9e du nouveau pr\u00e9sident.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 juillet 2008 \u00e0 20H14<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une surprise de plus dans la saga du programme de ravitailleurs en vol KC-45 de l&rsquo;USAF, c&rsquo;est de retrouver le Premier ministre britannique Gordon Brown engag\u00e9 \u00e0 fond derri\u00e8re EADS. La cause la plus imm\u00e9diate, c&rsquo;est l&rsquo;importance \u00e9conomique et sociale du programme, si EADS l&#8217;emporte, pour l&rsquo;\u00e9conomie britannique: \u00abIf Airbus wins the tanker contract the&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3192,4038,4215,4581,1097,1205,41],"class_list":["post-70036","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-boeing","tag-brown","tag-eads","tag-kc-45","tag-protectionnisme","tag-transatlantique","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70036"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70036\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}