{"id":70045,"date":"2008-07-15T00:00:00","date_gmt":"2008-07-15T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/15\/les-avis-contrastes-du-che\/"},"modified":"2008-07-15T00:00:00","modified_gmt":"2008-07-15T00:00:00","slug":"les-avis-contrastes-du-che","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/15\/les-avis-contrastes-du-che\/","title":{"rendered":"Les avis contrast\u00e9s du <strong>Che<\/strong>"},"content":{"rendered":"<p><p>Un avis int\u00e9ressant sur l&rsquo;UPM (Union Pour la M\u00e9diterran\u00e9e) qui vient d&rsquo;\u00eatre lanc\u00e9e \u00e0 Paris est celui, notablement favorable, de Jean-Pierre Chev\u00e8nement. L&rsquo;avis est int\u00e9ressant notamment parce que Chev\u00e8nement est souverainiste (de gauche) et sourcilleux sur le dogme national fran\u00e7ais (et gaulliste). Sa courte intervention du <a href=\"http:\/\/www.lejdd.fr\/cmc\/politique\/200828\/chevenement-il-faut-savoir-prendre-des-risques_132598.html\" class=\"gen\">13 juillet<\/a> (interview du 12 juillet) dans <em>Le Journal Du Dimanche<\/em> est int\u00e9ressante \u00e9galement parce que, \u00e0 c\u00f4t\u00e9 des f\u00e9licitations, le <em>Che<\/em> ne se g\u00eane pas pour critiquer, sinon condamner la position de Sarkozy vis-\u00e0-vis de l&rsquo;arm\u00e9e en France, comme sa politique vis-\u00e0-vis de l&rsquo;OTAN et des interventions ext\u00e9rieures. Il met ainsi en \u00e9vidence la dualit\u00e9 du personnage (Sarko), entre certains coups heureux et efficaces et certains engagements relevant d&rsquo;une pens\u00e9e basse et inconsistante.<\/p>\n<\/p>\n<p><p>\t(Chev\u00e8nement n&rsquo;a plus de poids politique aujourd&rsquo;hui, ce qui est une autre garantie qu&rsquo;il puisse dire quelque chose d&rsquo;int\u00e9ressant. Les hommes et femmes politiques et de quelque poids politique semblent \u00eatre frapp\u00e9s, hors de la bouillie pour chat de leur langage m\u00e9diatique et conformiste, d&rsquo;une nullit\u00e9 conceptuelle tr\u00e8s compl\u00e8te. Avec Villepin et quelques autres laiss\u00e9s sur le c\u00f4t\u00e9, Chev\u00e8nement est l&rsquo;un des rarissimes dont l&rsquo;avis importe.)<\/p>\n<\/p>\n<p><p>\tA une question sur la venue du pr\u00e9sident syrien \u00e0 Paris : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Je ne fais pas partie de ceux qui d\u00e9sapprouvent l&rsquo;invitation \u00e0 Paris de Bachar el-Assad. En politique, il faut savoir prendre des risques. En l&rsquo;occurrence, Nicolas Sarkozy a raison d&rsquo;en prendre. La Syrie est une pi\u00e8ce strat\u00e9gique du puzzle du Proche et du Moyen-Orient. Il est utile pour la France d&rsquo;avoir un contact avec ce pays. Si l&rsquo;on fait l&rsquo;Union pour la M\u00e9diterran\u00e9e, il faut le faire avec tous les pays riverains. Sans exception. Mener cette d\u00e9marche avec des crit\u00e8res uniquement \u00e9thiques nous aurait fait courir le risque de nous retrouver dans un cercle plut\u00f4t \u00e9troit. Et nous aurait conduit \u00e0 l&rsquo;impuissance.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur l&rsquo;UPM, Chev\u00e8nement est approbateur et r\u00e9serv\u00e9 (\u00ab<em> C&rsquo;\u00e9tait une bonne id\u00e9e au d\u00e9part. Elle est, h\u00e9las, largement vid\u00e9e de son contenu, en raison notamment des exigences de l&rsquo;Allemagne.<\/em>\u00bb). Il le fait justement, puisqu&rsquo;effectivement la bonne id\u00e9e tend \u00e0 \u00eatre phagocyt\u00e9e par la Commission, qui avait \u00e9t\u00e9 absolument catastroph\u00e9e par cette initiative, avec l&rsquo;Allemagne en flanc-garde. On assiste \u00e0 cet \u00e9gard \u00e0 un conflit classique entre des int\u00e9r\u00eats r\u00e9gionaux bas\u00e9s sur une logique de civilisation et les int\u00e9r\u00eats bureaucratique de l&rsquo;Europe institutionnalis\u00e9e. L&rsquo;affaire reste pendante, pour savoir qui imprimera sa marque, entre l&rsquo;orientation fran\u00e7aise soutenue par la logique r\u00e9gionale et historique, et la pesanteur bureaucratique de la bureaucratie europ\u00e9enne.<\/p>\n<\/p>\n<p><p>\tA la troisi\u00e8me question sur les rapports de Sarko et de l&rsquo;arm\u00e9e fran\u00e7aise, avec prolongement sur la politique fran\u00e7aise et de s\u00e9curit\u00e9 nationale (OTAN), Chev\u00e8nement est justement critique. (\u00ab<em>On est loin de l&rsquo;inspiration gaulliste de notre politique de d\u00e9fense. Un pays qui remet \u00e0 d&rsquo;autres, dans le cas qui nous occupe \u00e0 l&rsquo;organisation militaire int\u00e9gr\u00e9e de l&rsquo;Otan, le soin de sa d\u00e9fense, abandonne la ma\u00eetrise de sa politique \u00e9trang\u00e8re et de son destin. Je suis tr\u00e8s pr\u00e9occup\u00e9 par l&rsquo;abandon du consensus en mati\u00e8re de d\u00e9fense <\/em>\u00bb) <\/p>\n<\/p>\n<p><p>\tCe domaine de la politique de Sarkozy n&rsquo;a effectivement plus rien \u00e0 voir avec l&rsquo;inspiration gaulliste initiale et se place dans un courant de d\u00e9cadence auquel ses pr\u00e9d\u00e9cesseurs ont \u00e9galement contribu\u00e9 (participation \u00e0 la guerre du Golfe avec Mitterrand, rapprochement de l&rsquo;OTAN avec Chirac). Par ailleurs, les craintes de Chev\u00e8nement pour l&rsquo;ind\u00e9pendance de la France sont \u00e0 nuancer. L&rsquo;appareil occidental sous influence am\u00e9ricaniste est dans un tel \u00e9tat catastrophique de d\u00e9labrement et de d\u00e9sordre qu&rsquo;il a perdu l&rsquo;essentiel de sa force subversive d&rsquo;influence. Cela ne r\u00e9habilite pas Sarko, qui est d\u00e9pendant \u00e0 cet \u00e9gard d&rsquo;une pens\u00e9e politique primaire, \u00e0 hauteur de la fascination adolescente pour une Am\u00e9rique qui n&rsquo;a jamais exist\u00e9, mais cela pond\u00e8re notablement ses effets pervers. On peut m\u00eame envisager des occurrences o\u00f9 une improvisation fran\u00e7aise, si elle avait lieu, pourrait rapporter certains avantages \u00e0 la France sans compromission excessive.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 juillet 2008 \u00e0 09H10<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un avis int\u00e9ressant sur l&rsquo;UPM (Union Pour la M\u00e9diterran\u00e9e) qui vient d&rsquo;\u00eatre lanc\u00e9e \u00e0 Paris est celui, notablement favorable, de Jean-Pierre Chev\u00e8nement. L&rsquo;avis est int\u00e9ressant notamment parce que Chev\u00e8nement est souverainiste (de gauche) et sourcilleux sur le dogme national fran\u00e7ais (et gaulliste). Sa courte intervention du 13 juillet (interview du 12 juillet) dans Le Journal&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4902,3172,7170,584,4590,7682],"class_list":["post-70045","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-che","tag-chevenement","tag-mediterranee","tag-otan","tag-sarkozy","tag-upm"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70045"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70045\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}