{"id":70047,"date":"2008-07-16T00:00:00","date_gmt":"2008-07-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/16\/lattaque-contre-le-scandaleux-concurrent-du-jsf-et-il-est-americain\/"},"modified":"2008-07-16T00:00:00","modified_gmt":"2008-07-16T00:00:00","slug":"lattaque-contre-le-scandaleux-concurrent-du-jsf-et-il-est-americain","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/16\/lattaque-contre-le-scandaleux-concurrent-du-jsf-et-il-est-americain\/","title":{"rendered":"L&rsquo;attaque contre le scandaleux concurrent du JSF\u2026 et il est am\u00e9ricain"},"content":{"rendered":"<p><p>Le 14 juillet, le quotidien du Salon de Farnborough, le <em>Daily Flight Bulletin<\/em>, a publi\u00e9 un court <a href=\"http:\/\/www.flightglobal.com\/articles\/2008\/07\/14\/225330\/farnborough-2008-jsf-launches-extraordinary-attack-on-desperate-boeing.html\" class=\"gen\">article<\/a> rapportant une intervention stup\u00e9fiante de brutalit\u00e9 du Lieutenant G\u00e9n\u00e9ral Charles CR Davis, de l&rsquo;USAF, pr\u00e9sent\u00e9 comme <em>a JSF programme executive<\/em>. Le quotidien publi\u00e9 pour le Salon par le respectable hebdomadaire <em>Flight International<\/em> en est tout remu\u00e9. Il pr\u00e9sente cette intervention de cette fa\u00e7on: \u00ab<em>an unusually candid, exclusive interview on the eve of the Farnborough Air Show<\/em>\u00bb; que fait Davis? \u00ab<em>Davis blasted Boeing executives for making what he believes are grossly inappropriate statements about the health of his acquisition programme.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDavis attaque Boeing avec violence pour ce qu&rsquo;il juge \u00eatre des attaques scandaleuses de Boeing contre le JSF, essentiellement, suppose-t-on, parce que Boeing ose s&rsquo;imposer comme concurrent du JSF sur certains march\u00e9s \u00e9trangers (Danemark, Australie) que ce m\u00eame Davis juge p\u00e9remptoirement \u00eatre des march\u00e9s captifs par d\u00e9finition acquis au JSF. Il s&rsquo;agit, dans le chef de Boeing, de proposer le F\/A-18E\/F <em>Super Hornet<\/em>. (D&rsquo;autre part, le <em>Super Hornet<\/em> est utilis\u00e9 par la Navy comme alternative pr\u00e9ventive \u00e0 des manquements possibles du JSF. Cela ne renforce pas la popularit\u00e9 de Boeing dans la bureaucratie du JSF.)<\/p>\n<\/p>\n<p><p>\tDans le chef de Davis, si on le comprend bien, le <em>Super Hornet<\/em> appara\u00eet comme une sorte de casserole antique avec la pr\u00e9tention stup\u00e9fiante de concurrencer le JSF.Boeing attaque le JSF parce que le <em>Super Hornet<\/em> est un tocard en perdition. \u00ab<em>Boeing is spreading lies and half-truths about the F-35 Joint Strike Fighter (JSF) programme in a desperate and disgraceful effort to bolster domestic and foreign sales of its F\/A-18E\/F Super Hornet<\/em> [] <em>If Boeing has to say something negative about JSF to sell their aircraft, that tells me there is something wrong with their aircraft, Davis says.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl y a aussi cette intervention, \u00e9galement stup\u00e9fiante, qui semble avancer que Davis attend <em>illico presto<\/em> que Boeing vienne lui pr\u00e9senter ses excuses, un genoux en terre, pour ses affirmations pav\u00e9es de mensonges et de demi-v\u00e9rit\u00e9s: \u00ab<em>Davis says he has neither contacted Boeing executives about his accusations, nor does he intend to. Asked if he was waiting for Boeing to initiate contact, he quickly replied: Yes, I am.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 vient cette fureur du g\u00e9n\u00e9ral Davis? De la lecture de la presse, comme vous et moi, o\u00f9 l&rsquo;on imprime effectivement les calomnies de Boeing. \u00ab<em>Davis said he has read two recent articles  one in the US press and one in the foreign press  quoting Boeing executives saying the JSF programme would likely be delayed again and further exceed development costs by more than $10 billion.<\/em>\u00bb On comprend cette fureur, de la part d&rsquo;un d\u00e9fenseur d&rsquo;un programme qui a montr\u00e9 une si grande r\u00e9gularit\u00e9 dans le d\u00e9passement des pr\u00e9visions de co\u00fbt et de d\u00e9lais. La chose est cruellement rappel\u00e9e dans les articles, Boeing rappelant que les <em>Super Hornet<\/em> ont \u00e9t\u00e9 livr\u00e9s \u00e0 l&rsquo;heure dite et au co\u00fbt annonc\u00e9, tandis que le JSF a augment\u00e9 de 50% et a accumul\u00e9 un retard de 18 mois depuis les contrats sign\u00e9s en 2001-2002. Mais comment peut-on comparer l&rsquo;incomparable! hurle Davis; c&rsquo;est-\u00e0-dire, comment comparer quelque chose \u00e0 l&rsquo;incomparable JSF? On revient au jugement port\u00e9 plus haut sur le tocard antique qu&rsquo;est le F\/A-18E\/F. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Davis responded that the F-35&rsquo;s record cannot be compared to the F\/A-18E\/F. The F\/A-18E\/F is based on an existing airframe and re-used the avionics of the original aircraft. That&rsquo;s the baseline they&rsquo;re measured against. How hard is that? Davis asked.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tInterrog\u00e9 par le m\u00eame quotidien, Tom Bell, un dirigeant de Boeing pr\u00e9sent \u00e0 Farnborough, reste prudent m\u00eame si certains lui voient un sourire ironique. Des calomnies anti-JSF? Il n&rsquo;est pas au courant. Simplement, il musarde apr\u00e8s avoir rappel\u00e9 les cas australien et danois (l&rsquo;Australie a achet\u00e9 des <em>Super Hornet<\/em>, le Danemark l&rsquo;\u00e9value) : \u00ab<em>People with greater insight than I are looking at the offerings available. Let people draw their own conclusions about why.<\/em>\u00bb Quant \u00e0 la valeur du <em>Super Hornet<\/em>, si gravement mise en cause par Davis: \u00ab<em>I think characterizing the F\/A-18E\/F as a just a simple programme is maybe a little simplistic in and of itself. Boeing is very proud of delivering increased capability at decreased costs and delivering real capability to the warfighter now.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une fameuse passe d&rsquo;armes, du genre rarement vu dans le monde feutr\u00e9 du complexe militaro-industriel o\u00f9 les querelles se vident derri\u00e8re les murs \u00e9pais des conseils d&rsquo;administration et des bureaux des hauts fonctionnaires du Pentagone. Elle mesure la tension du climat qui r\u00e8gne dans ces milieux, pour diverses raisons pour le cas expos\u00e9 ici, qui s&rsquo;entrecroisent et s&rsquo;alimentent les unes les autres. Il n&rsquo;est pas indiff\u00e9rent, dans le cas pr\u00e9sent, que l&rsquo;affaire implique d&rsquo;un c\u00f4t\u00e9 l&rsquo;USAF en m\u00eame temps que le JSF, de l&rsquo;autre Boeing en m\u00eame temps qu&rsquo;un concurrent peut-\u00eatre ill\u00e9gal du JSF. Plusieurs points peuvent \u00eatre mis en \u00e9vidence \u00e0 cette lumi\u00e8re.<\/p>\n<\/p>\n<p><p>\t La nervosit\u00e9 de l&rsquo;USAF vis-\u00e0-vis du JSF, qui la pousse \u00e0 des positions extr\u00eames, y compris dans sa d\u00e9fense peut-\u00eatre paradoxale. L&rsquo;USAF est en crise et le JSF \u00e9galement. L&rsquo;USAF est aujourd&rsquo;hui contrainte (par la direction civile du Pentagone) de mettre une sourdine dans son soutien pour le prolongement du F-22 et de soutenir \u00e0 fond le JSF. L&rsquo;USAF ne peut faire autrement que s&rsquo;incliner car, si le F-22 est liquid\u00e9, il ne lui reste plus que le JSF. Elle n&rsquo;aime pas beaucoup le JSF mais elle est d\u00e9sormais oblig\u00e9e de le d\u00e9fendre pour la survie de son statut de premi\u00e8re force a\u00e9rienne du monde, et elle le fait d&rsquo;une fa\u00e7on d&rsquo;autant plus radicale. (L&rsquo;article sur le JSF dans Air Force <em>Magazine<\/em> de <a href=\"http:\/\/www.airforce-magazine.com\/MagazineArchive\/Pages\/2008\/July%202008\/0708lightning.aspx\" class=\"gen\">juillet 2008<\/a> est typique \u00e0 cet \u00e9gard. D&rsquo;un c\u00f4t\u00e9, on s&rsquo;acharne \u00e0 dire que le JSF ne vaut pas le F-22, pour continuer \u00e0 soutenir le F-22; de l&rsquo;autre, c&rsquo;est un pan\u00e9gyrique du JSF, pour soutenir le JSF si le F-22 est d\u00e9finitivement perdu)<\/p>\n<\/p>\n<p><p>\t Du point de vue de la bureaucratie du JSF, dont l&rsquo;USAF est partie prenante, Boeing a trahi une consigne non-dite mais imp\u00e9rative en intervenant comme <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4987\" class=\"gen\">concurrent<\/a> du JSF. Cette id\u00e9e s&rsquo;inscrit dans la parano\u00efa g\u00e9n\u00e9rale de la bureaucratie du JSF, t\u00e9tanis\u00e9e \u00e0 l&rsquo;id\u00e9e qu&rsquo;on puisse empi\u00e9ter sur le domaine sacr\u00e9e du JSF, qui couvre \u00e0 peu pr\u00e8s toute la plan\u00e8te, et, par ailleurs, inqui\u00e8te des probl\u00e8mes sans nombre du JSF. Face \u00e0 cela, Boeing ne veut pas c\u00e9der, se sachant soutenu par l&rsquo;U.S. Navy (le <em>Super Hornet<\/em> est l&rsquo;avion central de la Navy), qui n&rsquo;aime que moyennement le JSF et qui a pourtant d&rsquo;excellents rapports avec Gates (notamment l&rsquo;amiral Mullen, pr\u00e9sident du JCS, compl\u00e9ment indispensable de Gates dans l&rsquo;effort du Pentagone pour contr\u00f4ler la crise iranienne).<\/p>\n<\/p>\n<p><p>\t L&rsquo;hostilit\u00e9 de l&rsquo;USAF pour Boeing est aujourd&rsquo;hui palpable et extr\u00eame, depuis l&rsquo;affaire du programme KC-45 et de la <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5210\" class=\"gen\">victoire<\/a> de Boeing, par GAO interpos\u00e9. L&rsquo;USAF ne peut prendre Boeing de front dans ce domaine, \u00e0 cause du soutien de Boeing au Congr\u00e8s en g\u00e9n\u00e9ral, \u00e0 cause de la prudence de Gates qui ne veut plus rien faire contre Boeing dans ce domaine. Mais tous les moyens pour l&rsquo;USAF de mettre en cause Boeing dans d&rsquo;autres domaines sont bons. Il se trouve que l&rsquo;affaire JSF-<em>Super Hornet<\/em> est utilis\u00e9e dans ce sens, avec d&rsquo;autant plus d&rsquo;alacrit\u00e9 que le JSF est devenu le <em>darling<\/em> de Gates dans son opposition au F-22.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 juillet 2008 \u00e0 09H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 14 juillet, le quotidien du Salon de Farnborough, le Daily Flight Bulletin, a publi\u00e9 un court article rapportant une intervention stup\u00e9fiante de brutalit\u00e9 du Lieutenant G\u00e9n\u00e9ral Charles CR Davis, de l&rsquo;USAF, pr\u00e9sent\u00e9 comme a JSF programme executive. Le quotidien publi\u00e9 pour le Salon par le respectable hebdomadaire Flight International en est tout remu\u00e9. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3192,2990,464,7683,4711,250,3487,41],"class_list":["post-70047","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-boeing","tag-davis","tag-f","tag-f18e","tag-hornet","tag-jsf","tag-super","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70047"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70047\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}