{"id":70054,"date":"2008-07-18T00:00:00","date_gmt":"2008-07-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/18\/la-crise-pulverise-lamerican-dream\/"},"modified":"2008-07-18T00:00:00","modified_gmt":"2008-07-18T00:00:00","slug":"la-crise-pulverise-lamerican-dream","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/07\/18\/la-crise-pulverise-lamerican-dream\/","title":{"rendered":"La crise pulv\u00e9rise l&rsquo;<strong><em>American Dream<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La crise pulv\u00e9rise l&rsquo;<strong><em>American Dream<\/em><\/strong><\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t18 juillet 2008  Quelle est la valeur am\u00e9ricaniste supr\u00eame? Une expression la r\u00e9sume parce qu&rsquo;elle comporte tous les \u00e9l\u00e9ments, on dirait tout le bric-\u00e0-brac de la psychologie am\u00e9ricaniste : <em>the American way of life<\/em>. Le 27 septembre 2001, le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld, voulant galvaniser la population dans la bataille supr\u00eame contre la Terreur (on ne disait encore que contre le terrorisme), n&rsquo;avait trouv\u00e9 que cette r\u00e9f\u00e9rence : \u00ab<em>The American way of life is threatened<\/em> [] <em>We have no choice: either to change the way we live, which is unacceptable; or to change the way that they live. And we chose the latter.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est justement le th\u00e8me que choisit l&rsquo;EPA (Environmental Protection Agency) pour s&rsquo;engager, <strong>contre<\/strong> son pr\u00e9sident et toute la politique de l&rsquo;administration dont elle d\u00e9pend, dans la voie de jeter un cri d&rsquo;alarme face au r\u00e9chauffement climatique. (Une d\u00e9p\u00eache de Reuters, via <em>RAW Story<\/em> le <a href=\"http:\/\/rawstory.com\/\/printstory.php?story=11272\" class=\"gen\">17 juillet<\/a>, analyse le nouveau rapport de l&rsquo;EPA):<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The U.S. Environmental Protection Agency, under fire for apparently discounting the impact of climate change, on Thursday said global warming poses real risk to human health and the American way of life.<\/em> [] <em>Climate change poses real risk to human health and the human systems that support our way of life in the United States, the agency&rsquo;s Joel Scheraga said in a telephone briefing.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&#8217;emploi du qualificatif eschatologique est, dans ce cas, non seulement bienvenu mais imp\u00e9ratif. Il traduit moins une pr\u00e9tention de l&rsquo;esprit, un caprice de chroniqueur ou une volont\u00e9 de dramatisation artificielle, comme certains en font le reproche, qu&rsquo;une pr\u00e9cision n\u00e9cessaire devant ce qui est un changement de substance de la trag\u00e9die de la civilisation. L&rsquo;EPA d\u00e9crit les effets indirects, par cons\u00e9quences imm\u00e9diates et cons\u00e9quences induites, du r\u00e9chauffement climatique et tout ce qui l&rsquo;accompagne directement ou indirectement (crise de l&rsquo;\u00e9nergie, de l&rsquo;alimentation, etc.): bouleversements sociaux, maladies, restrictions, chocs psychologiques,  etc. Elle estime justement que ces \u00e9v\u00e9nements en acc\u00e9l\u00e9ration peuvent sinon doivent bouleverser le mode de vie (<em>way of life<\/em>) aux USA m\u00eame. Son rapport d\u00e9crit ainsi des effets sur les conditions sociales engendr\u00e9s par les ph\u00e9nom\u00e8nes climatiques dus au r\u00e9chauffement:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Risks include more heat-related deaths, more heart and lung diseases due to increased ozone and health problems related to hurricanes, extreme precipitation and wildfires, the agency said in a new report.<\/em>\u00bb Par d\u00e9finition, il s&rsquo;agit d&rsquo;effets dont la dynamique est insaisissable par sa complication et les forces qui la r\u00e9gissent, par cons\u00e9quent hors du contr\u00f4le humain. Cela rencontre parfaitement la d\u00e9finition temporelle et m\u00e9thodologique  assez simple que donne Roger Garaudy d&rsquo;eschatologie (\u00ab<em>L&rsquo;eschatologie ne consiste pas \u00e0 dire: voil\u00e0 o\u00f9 l&rsquo;on va aboutir, mais \u00e0 dire: demain peut \u00eatre diff\u00e9rent, c&rsquo;est-\u00e0-dire: tout ne peut pas \u00eatre r\u00e9duit \u00e0 ce qui existe aujourd&rsquo;hui<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tLa position de l&rsquo;EPA r\u00e9pond \u00e0 une \u00e9volution du Congr\u00e8s autant que du climat (!) politique \u00e0 Washington, qui devrait n\u00e9cessairement se transcrire par un bouleversement de la politique US face \u00e0 la crise climatique, avec le prochain pr\u00e9sident quel qu&rsquo;il soit (McCain et Obama sont dans le m\u00eame \u00e9tat d&rsquo;esprit \u00e0 cet \u00e9gard).  Elle r\u00e9pond \u00e0 la pr\u00e9tention de GW Bush de d\u00e9fendre l&rsquo;<em>American way of life<\/em>&lsquo; en refusant de lutter contre le mode de d\u00e9veloppement \u00e9conomique, en introduisant une logique dont le terme pose que c&rsquo;est justement ce mode de d\u00e9veloppement qui va d\u00e9truire l&rsquo; <em>American way of life<\/em>. La boucle est boucl\u00e9e et notre dilemme clairement expos\u00e9.<\/p>\n<\/p>\n<p><p>\tNous traitons \u00e0 part une autre intervention int\u00e9ressante, celle d&rsquo;Al Gore (voir notre <em>Bloc Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5281\" class=\"gen\">jour<\/a>). Elle a le m\u00e9rite de mettre en \u00e9vidence l&rsquo;interconnexion tr\u00e8s forte entre les diverses crises syst\u00e9miques sectorielles (\u00e9nergie, alimentation, etc.) et la crise climatique centrale. Cette d\u00e9marche est n\u00e9cessaire et d\u00e9cisive, elle est d&rsquo;abord d&rsquo;essence politique pour introduire une d\u00e9finition r\u00e9aliste et acceptable de notre crise g\u00e9n\u00e9rale.<\/p>\n<h3>La valeur am\u00e9ricaniste supr\u00eame menac\u00e9e<\/h3>\n<\/p>\n<p><p>\tRevenons, pour une rapide tentative de d\u00e9finition, sur ce que nous d\u00e9signions plus haut comme la valeur am\u00e9ricaniste supr\u00eame, <em>the American way of life<\/em>. On y trouve le caract\u00e8re domestique, presque petit-bourgeois, qu&rsquo;on retrouve par ailleurs dans la d\u00e9finition quasiment officielle de l&rsquo;<em>American Dream<\/em>, qui est une valeur rationalis\u00e9e par l&rsquo;\u00e9mergence d&rsquo;une classe moyenne apr\u00e8s la Deuxi\u00e8me Guerre mondiale, lorsque tout danger de rechute dans la Grande D\u00e9pression sembla \u00e9cart\u00e9e, et symbolis\u00e9e par la possibilit\u00e9 de l&rsquo;accession \u00e0 la propri\u00e9t\u00e9 de sa maison individuelle par chaque Am\u00e9ricain moyen. (C&rsquo;est un th\u00e8me central de l&rsquo;<em>American Dream<\/em>: \u00ab<em>The American dream of owning a home<\/em>\u00bb, comme l&rsquo;\u00e9crit Jim Cullen dans <em>American Dream<\/em>. Ce fut un th\u00e8me tr\u00e8s en vogue dans les ann\u00e9es 1945-1955, avec le succ\u00e8s foudroyant de l&rsquo;entrepreneur Abraham Levitt, qui d\u00e9veloppa la technique de construire en s\u00e9rie des maisons individuelles standardis\u00e9es sous contrats gouvernementaux portant sur des milliers de maisons individuelles toutes semblables. On cr\u00e9a ainsi de v\u00e9ritables villes, dont Levittown, \u00e0 partir du nom de Levitt, dans l&rsquo;Etat de New York,  le mot devenant usuel, les <em>levittowns<\/em>, pour d\u00e9signer ces villes standardis\u00e9es. Cette sorte de bonheur am\u00e9ricanis\u00e9 standardis\u00e9 peut aussi bien correspondre, pour les esprits critiques, c&rsquo;est-\u00e0-dire lucides, \u00e0 la description des USA faite par Henry Miller dans <em>Le cauchemar climatis\u00e9<\/em> [<em>Air-Conditoned Nightmare<\/em>].)<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de ces aspects mat\u00e9riels, on trouve bien entendu dans l&rsquo;expression <em>the American way of life<\/em> des r\u00e9f\u00e9rences extr\u00eamement fortes aux valeurs quasiment m\u00e9taphysiques caract\u00e9risant la pr\u00e9tention de l&rsquo;Am\u00e9rique \u00e0 \u00eatre le Nouveau Monde choisi de Dieu et rompant avec l&rsquo;ancien, en un complet contraste avec le caract\u00e8re petit-bourgeois signal\u00e9 plus haut. Ce m\u00e9lange surprenant, explosif en un sens, caract\u00e9rise effectivement la d\u00e9marche am\u00e9ricaniste, machin\u00e9 par la communication puis le virtualisme. Il s&rsquo;agit de maintenir le ph\u00e9nom\u00e8ne am\u00e9ricaniste dans les limites terrestres de l&rsquo;environnement social politiquement le plus mod\u00e9r\u00e9 possible, le plus apaisant, le plus anti-r\u00e9volutionnaire, avec le souci de contr\u00f4le des populations qui va avec, tout en lui offrant une vision quasiment m\u00e9taphysique qui doit servir de <em>substra<\/em> mobilisateur pour rassurer les \u00e2mes et les maintenir dans le droit chemin de l&rsquo;utopie originelle, \u00e0 la fois comme legs accompli et comme but inatteignable mais toujours renouvel\u00e9. <em>The American way of life<\/em> est une formule d\u00e9licate et complexe qu&rsquo;on ne peut manier qu&rsquo;avec pr\u00e9caution.<\/p>\n<\/p>\n<p><p>\tComme le montre la phrase de Rumsfeld, l&rsquo;appel \u00e0 la d\u00e9fense de l&rsquo;<em>American way of life<\/em>est le moyen le plus <strong>l\u00e9gitime<\/strong> (beaucoup plus que la d\u00e9fense de la nation, qui n&rsquo;a pas de fondement r\u00e9galien et historique aux USA) d&rsquo;appeler le peuple aux armes, donc de l\u00e9gitimer le combat qu&rsquo;on esp\u00e8re lancer. Pour cette raison, nous accordons une importance symbolique extr\u00eame au cri d&rsquo;alarme de l&rsquo;EPA, comme une r\u00e9ponse, sept ans plus tard, \u00e0 l&rsquo;exhortation de Rumsfeld: oui, <em>the American way of life<\/em> est menac\u00e9e,  mais pas par ceux qu&rsquo;on croit,  par elle-m\u00eame, par l&rsquo;Am\u00e9rique et ses exc\u00e8s, par la civilisation occidentale du progr\u00e8s technologique dont elle est l&rsquo;avanc\u00e9e extr\u00eame.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est pas indiff\u00e9rent, du point de vue symbolique, que la crise financi\u00e8re ait comme premier effet dans l&rsquo;\u00e9conomie r\u00e9elle la d\u00e9vastation du patrimoine immobilier des Am\u00e9ricains. C&rsquo;est effectivement le cur rationalis\u00e9 et petit-bourgeois de l&rsquo;<em>American way of life<\/em> et de l&rsquo;<em>American Dream<\/em> qui est ainsi mis en cause. Un lien s\u00e9mantique est ainsi fermement \u00e9tabli entre la crise financi\u00e8re et la crise du r\u00e9chauffement climatique, telle qu&rsquo;elle est ici d\u00e9finie par l&rsquo;EPA dans ses cons\u00e9quences \u00e9conomiques et sociales. Il s&rsquo;agit surtout d&rsquo;un pas de plus fait dans l&rsquo;int\u00e9gration des crises syst\u00e9miques sectorielles en une vaste crise syst\u00e9mique globale (comme le fait Al Gore), la crise du climat y tenant le r\u00f4le central, temporel et symbolique \u00e0 la fois, de m\u00e8re de toutes les crises.<\/p>\n<\/p>\n<p><p>\tEntre septembre 2001 (les d\u00e9clarations de Rumsfeld) et juillet 2008 avec ce rapport de l&rsquo;EPA, la chose a compl\u00e8tement chang\u00e9 de substance. L&rsquo;attaque contre l&rsquo;<em>American way of life<\/em> a chang\u00e9 de substance en devenant eschatologique. Le ph\u00e9nom\u00e8ne est surprenant par sa rapidit\u00e9. Nous sommes pass\u00e9s de l&rsquo;Ennemi terrestre symbolique, <strong>ext\u00e9rieur<\/strong> \u00e0 la vertu am\u00e9ricaniste, bien identifi\u00e9 quoique dans le mode symbolique absolument figuratif (la Terreur), dont les dirigeants du syst\u00e8me affirme qu&rsquo;ils ont tous les moyens pour le contr\u00f4ler, le r\u00e9duire et le d\u00e9truire (caract\u00e8re absolument non-eschatologique); \u00e0 l&rsquo;Ennemi eschatologique, <strong>int\u00e9rieur<\/strong>, incontr\u00f4lable par d\u00e9finition, dont le syst\u00e8me am\u00e9ricaniste est lui-m\u00eame la cause fondamentale et qui a \u00e9chapp\u00e9 au syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tLa logique est en route, d\u00e9sormais irr\u00e9sistible, de la mise en cause du syst\u00e8me lui-m\u00eame, de ses choix fondamentaux (le choix accidentel de la thermodynamique comme moteur de d\u00e9veloppement,  voir <em>Le choix du feu<\/em> d&rsquo;Alain Gras). Nous sommes bien loin du d\u00e9bat futile sur la r\u00e9alit\u00e9, puis sur la gravit\u00e9 et les origines de la crise climatique, c&rsquo;est-\u00e0-dire, dans la r\u00e9alit\u00e9 derri\u00e8re la rigueur scientifique, la bataille d\u00e9sesp\u00e9r\u00e9e pour la pr\u00e9servation du caract\u00e8re vertueux de la raison humaine pervertie,  car si la raison humaine accouche d&rsquo;un tel monstre, comment ne pas chanceler devant sa perversit\u00e9 dissimul\u00e9e? Cette crise est en train d&rsquo;acqu\u00e9rir toute sa puissance en entrant dans la psychologie am\u00e9ricanistes, avec des s\u00e9sames absolument irr\u00e9sistibles (l&rsquo;<em>American way of life<\/em> menac\u00e9e).<\/p>\n<\/p>\n<p><p>\tNous laisserons aux historiens du futur, s&rsquo;il y en a (mais il y en a d\u00e9j\u00e0, semble-t-il), install\u00e9s entre un ouragan et un incendie dont on cherche la cause r\u00e9elle, l&rsquo;int\u00e9ressant d\u00e9bat sur la r\u00e9alit\u00e9 des origines et des manifestations de cette crise. Comme dans toute crise, qui ne devient crise qu&rsquo;\u00e0 partir de ce moment, la crise devient elle-m\u00eame d\u00e8s lors que la psychologie l&rsquo;accepte. Le rapport de l&rsquo;EPA montre que la chose a touch\u00e9 la bureaucratie am\u00e9ricaniste, donc que la p\u00e9n\u00e9tration psychologique est, dans un pays aussi conformiste que les USA, assur\u00e9e. Tout cela se fait au milieu d&rsquo;un bric \u00e0 brac d&rsquo;arguments plus ou moins fond\u00e9s, qui choqueront les esprits \u00e9pris de rationalisme et qui entendent s&rsquo;int\u00e9resser au sexe des anges en mesurant les divers degr\u00e9s de responsabilit\u00e9 et de r\u00e9alit\u00e9 alors que souffle l&rsquo;ouragan. Ce qui nous importe est que souffle l&rsquo;ouragan et qu&rsquo;il d\u00e9signe d\u00e9sormais la cause humaine centrale de cet \u00e9pouvantable effondrement d&rsquo;un syst\u00e8me de civilisation: le syst\u00e8me lui-m\u00eame.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise pulv\u00e9rise l&rsquo;American Dream 18 juillet 2008 Quelle est la valeur am\u00e9ricaniste supr\u00eame? Une expression la r\u00e9sume parce qu&rsquo;elle comporte tous les \u00e9l\u00e9ments, on dirait tout le bric-\u00e0-brac de la psychologie am\u00e9ricaniste : the American way of life. Le 27 septembre 2001, le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld, voulant galvaniser la population dans la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3612,3392,3228,3613,4528,4328,4014,569,4260],"class_list":["post-70054","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-american","tag-climatique","tag-crise","tag-dream","tag-epa","tag-life","tag-of","tag-rumsfeld","tag-way"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70054"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70054\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}