{"id":70119,"date":"2008-08-18T13:50:47","date_gmt":"2008-08-18T13:50:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/08\/18\/crise-interceptee-le-bmde-marche\/"},"modified":"2008-08-18T13:50:47","modified_gmt":"2008-08-18T13:50:47","slug":"crise-interceptee-le-bmde-marche","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/08\/18\/crise-interceptee-le-bmde-marche\/","title":{"rendered":"Crise intercept\u00e9e: le BMDE marche"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Crise intercept\u00e9e: le BMDE marche<\/h2>\n<\/p>\n<p><p>18 ao&ucirc;t 2008 &mdash; La signature-express d&rsquo;un \u00ab\u00a0accord pr\u00e9liminaire\u00a0\u00bb entre les Etats-Unis et la Pologne le 14 ao&ucirc;t, concernant le stationnement de missiles anti-missiles (syst\u00e8me BMDE), peut \u00eatre interpr\u00e9t\u00e9e comme une r\u00e9action-\u00e9clair du syst\u00e8me face \u00e0 l&rsquo;invasion de la G\u00e9orgie. La chose pourrait para&icirc;tre compl\u00e8tement inattendue, ou impr\u00e9vue, et apr\u00e8s tout ce fut le cas car c&rsquo;\u00e9tait la logique m\u00eame, et nous dirions m\u00eame la sagesse, de pr\u00e9voir le retardement ou l&rsquo;abandon du syst\u00e8me &ndash; certes, logique et sagesse hors du th\u00e9\u00e2tre de la folie o&ugrave; \u00e9voluent les affaires du monde. Qu&rsquo;on en juge par ceci, sous la plume de plusieurs journalistes d&rsquo;un journal particuli\u00e8rement bien inform\u00e9 et proche de l&rsquo;administration Bush, Jay Solomon, Neil King Jr. et Marc Champion, du Wall Street <em>Journal<\/em> le <a class=\"gen\" href=\"http:\/\/online.wsj.com\/article\/SB121853033674533007.html?mod=2_1601_topbox&lt;D\">13 ao&ucirc;t<\/a>, qui nous annoncent que l&rsquo;accord BMDE est enterr\u00e9 pour longtemps:<\/p>\n<\/p>\n<p><p>&laquo;<em>Challenges seen as having died with the Soviet Union, such as access to Central Asian oil and gas supplies, have made a hasty return to Washington&rsquo;s foreign-policy agenda and will present new and unexpected challenges for America&rsquo;s next president. Other priorities, such as building a missile-defense shield in Eastern Europe and expanding the North Atlantic Treaty Organization to Russia&rsquo;s borders, now appear<\/em> <strong><em>troubled, if not dead, in the short term.<\/em><\/strong>&raquo;<\/p>\n<\/p>\n<p><p>Il semble manifeste que le Pentagone a fait un certain nombre de concessions significatives, rencontrant les exigences des Polonais pour signer cet accord. Ces concessions portent sur le d\u00e9ploiement de batteries sol-air <em>Patriot<\/em>, sur l&rsquo;installation d&rsquo;une base pour la gestion de ces syst\u00e8mes avant que l&rsquo;arm\u00e9e polonaise ne les prennent en charge, sur certaines \u00ab\u00a0garanties de s\u00e9curit\u00e9\u00a0\u00bb US pour la Pologne. L&rsquo;AFP rapporte le <a class=\"gen\" href=\"http:\/\/rawstory.com\/news\/afp\/Poland_US_clinch_missile_shield_dea_08142008.html\">14 ao&ucirc;t<\/a> les d\u00e9clarations du Premier ministre Tusk \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>&laquo;<em>Announcing the deal earlier Thursday, Polish Prime Minister Donald Tusk explained that Washington had accepted Warsaw&rsquo;s \u00ab\u00a0key demand, the presence of Patriots.\u00a0\u00bb \u00ab\u00a0We would start with a battery under US command, but made available to the Polish army. Then there would be a second phase, involving equipping the Polish army with missiles,\u00a0\u00bb he said. \u00ab\u00a0In five, seven or 10 years we want to be sufficiently well-equipped and well-trained to be ready, both with our allies but by ourselves, to defend ourselves at a critical moment.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Tusk said that the United States had also \u00ab\u00a0committed to close cooperation with Poland in the event of a danger from a third party.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Il est manifeste, y compris de fa\u00e7on indirecte dans les d\u00e9clarations du ministre des affaires \u00e9trang\u00e8res Sikorski et malgr\u00e9 ce qu&rsquo;il affirme, que les \u00e9v\u00e9nements de G\u00e9orgie ont jou\u00e9 un r\u00f4le majeur dans l&rsquo;accord. <em>BBC.News<\/em> rapporte le <a class=\"gen\" href=\"http:\/\/news.bbc.co.uk\/2\/hi\/europe\/7561926.stm\">15 ao&ucirc;t<\/a> les d\u00e9clarations de Sikorski.<\/p>\n<\/p>\n<p><p>&laquo;<em>Polish Foreign Minister Radoslaw Sikorski told the BBC&rsquo;s World Tonight programme that the timing of the deal had nothing to do with the hostilities. \u00ab\u00a0We agreed this negotiating phase a week ago, which was&#8230; before the events in Georgia, and because of the US calendar there was some urgency,\u00a0\u00bb he said. \u00ab\u00a0But, what is crucial, and what decided the success of the talks over the last couple of days, was that the US offered us new proposals.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9vidence de l&rsquo;effet-G\u00e9orgie est dans la pr\u00e9cision de Sikorski, du Pentagone pr\u00e9sentant soudain, il y a deux jours, de nouvelles propositions qui rencontraient nombre d&rsquo;exigences polonaises. La bureaucratie du Pentagone a jug\u00e9 l&rsquo;occasion opportune pour emporter l&rsquo;accord des Polonais, et elle a obtenu de sa direction politique et de la Maison-Blanche le feu vert pour ces concessions qui impliquent une forte implication financi\u00e8re US, et que les USA refusaient jusqu&rsquo;alors. Une cons\u00e9quence imm\u00e9diate de l&rsquo;accord a \u00e9t\u00e9 une r\u00e9action tr\u00e8s vive de la Russie, qui peut se d\u00e9tailler en plusieurs interventions.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;annulation d&rsquo;une visite du ministre russe des affaires \u00e9trang\u00e8res Lavrov en Pologne.<\/p>\n<\/p>\n<p><p>&bull; Des d\u00e9clarations <a class=\"gen\" href=\"http:\/\/www.guardian.co.uk\/world\/2008\/aug\/15\/russia.poland.nuclear.missiles.threat\">mena\u00e7antes<\/a> du vice-chef d&rsquo;\u00e9tat-major russe, le Colonel G\u00e9n\u00e9ral Nogovitsine. (&laquo;<em>\u00ab\u00a0By deploying, Poland is exposing itself to a strike &#8211; 100%,\u00a0\u00bb warned Colonel General Anatoly Nogovitsyn. He added that Russia&rsquo;s security doctrine allowed it to use nuclear weapons against an active ally of a nuclear power such as America.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>&bull; Des d\u00e9clarations plut\u00f4t ironique de l&rsquo;ambassadeur russe Rogozine, charg\u00e9 \u00e0 Bruxelles des relations avec l&rsquo;OTAN (Selon Novosti du <a class=\"gen\" href=\"http:\/\/fr.rian.ru\/world\/20080815\/116072240.html\">15 ao&ucirc;t<\/a>), comparant le syst\u00e8me BMDE \u00e0 un \u00ab\u00a0chat crev\u00e9\u00a0\u00bb (&laquo;<em>&hellip;Rogozine, a compar\u00e9 vendredi \u00e0 Bruxelles le bouclier antimissile am\u00e9ricain \u00e0 un &quot;chat crev\u00e9&quot;, car l&rsquo;efficacit\u00e9 d&rsquo;un tel syst\u00e8me ne pourrait \u00eatre v\u00e9rifi\u00e9e qu&rsquo;en cas d&rsquo;\u00e9change de coups nucl\u00e9aires balistiques<\/em>&raquo;); puis il pr\u00e9cise, de fa\u00e7on r\u00e9v\u00e9latrice : &laquo;<em>En acceptant d&rsquo;accueillir le bouclier antimissile am\u00e9ricain en pleine crise g\u00e9orgienne, la Pologne a confirm\u00e9 qu&rsquo;il \u00e9tait dirig\u00e9 contre la Russie. Il faut remercier les Polonais qui ont de facto d\u00e9voil\u00e9 la v\u00e9ritable orientation strat\u00e9gique du bouclier antimissile am\u00e9ricain.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;un des projets majeurs du nouveau (depuis novembre 2007) Premier ministre Tusk, qui \u00e9tait d&rsquo;am\u00e9liorer les relations de la Pologne avec la Russie, est pour l&rsquo;instant absolument compromis. C&rsquo;est \u00e0 une aggravation de ces relations qu&rsquo;on assiste maintenant tandis que l&rsquo;interpr\u00e9tation du BMDE comme \u00ab\u00a0r\u00e9ponse\u00a0\u00bb US \u00e0 la guerre avec la G\u00e9orgie se r\u00e9pand. Pour en rajouter dans ce sens, il y a une d\u00e9claration ukrainienne (de la pr\u00e9sidence ukrainienne, &ndash; on verra ce qu&rsquo;il en restera) annon\u00e7ant que l&rsquo;Ukraine est volontaire pour participer au BMDE. Dans cette zone, c&rsquo;est le d\u00e9veloppement rapide de la logique de la Guerre froide dans sa version la plus extr\u00eame de la course en avant, r\u00e9sultat de la grande peur enfant\u00e9e par l&rsquo;affaire g\u00e9orgienne.<\/p>\n<\/p>\n<p><p>Cet accord BMDE est du type \u00ab\u00a0pr\u00e9liminaire\u00a0\u00bb, ou transitoire si l&rsquo;on veut, marquant la h\u00e2te soudaine du Pentagone de verrouiller une signature. Il ne faut pas s&rsquo;y tromper: la perception du Pentagone est que les \u00e9v\u00e9nements de G\u00e9orgie sont une occasion de forcer les \u00e9v\u00e9nements pour obtenir l&rsquo;accord, et non pas un \u00e9l\u00e9ment d\u00e9terminant de l&rsquo;accord. Le but du Pentagone est bureaucratique: extension de ses installations, vente de quincaillerie, etc. Le but des Polonais est un renforcement de leur s\u00e9curit\u00e9 face \u00e0 la Russie. L&rsquo;esprit de l&rsquo;accord est donc tout \u00e0 fait rocambolesque. Le Pentagone continue \u00e0 psalmodier la fiction d&rsquo;un r\u00e9seau contre des missiles iraniens et ne songe qu&rsquo;\u00e0 sa propre extension bureaucratique et aux commandes pour l&rsquo;industrie d&rsquo;armement tandis que la Pologne le pr\u00e9sente ouvertement comme une garantie contre la Russie, avec toutes les implications qu&rsquo;on imagine.<\/p>\n<\/p>\n<p><p>Accord \u00ab\u00a0pr\u00e9liminaire\u00a0\u00bb, c&rsquo;est-\u00e0-dire coup de force du Pentagone, et coup de force \u00e9ventuellement d\u00e9sesp\u00e9r\u00e9 pour l&#8217;emporter avant l&rsquo;arriv\u00e9e d&rsquo;une nouvelle administration, d&rsquo;un Congr\u00e8s sourcilleux sur cette question. En r\u00e9alit\u00e9, rien n&rsquo;est fait. Il ne serait pas \u00e9tonnant que des obstacles inattendus surviennent lorsqu&rsquo;on passera au d\u00e9tail de l&rsquo;accord, lorsqu&rsquo;il sera question de le finaliser, lorsqu&rsquo;il sera temps de financer les syst\u00e8mes promis \u00e0 la Pologne, de discuter leur d\u00e9ploiement, etc. Certaines \u00ab\u00a0garanties de s\u00e9curit\u00e9\u00a0\u00bb pourraient \u00e9galement soulever bien des difficult\u00e9s. Le probl\u00e8me du Pentagone dans cette affaire est qu&rsquo;il ne peut pas plaider la bonne cause; il est pour l&rsquo;instant hors de question pour un homme comme Gates, particuli\u00e8rement prudent, de \u00ab\u00a0vendre\u00a0\u00bb l&rsquo;accord au Congr\u00e8s, ou \u00e0 la nouvelle administration, sous pr\u00e9texte de renforcer la s\u00e9curit\u00e9 de la Pologne face \u00e0 la Russie, &ndash; alors que cet argument pourrait trouver un fort soutien m\u00e9diatique et de communication par les temps qui courent, &ndash; simplement parce que la <em>narrative<\/em> du Pentagone est que le BMDE ne concerne que l&rsquo;Iran, et surtout pas la Russie.<\/p>\n<\/p>\n<p><p>D&rsquo;un autre c\u00f4t\u00e9, il ne faut pas \u00e9carter les comportements et initiatives contradictoires, &ndash; dans ce cas contradictoire de ce qui pr\u00e9c\u00e8de. Plus on est de fous&hellip; L&#8217;emportement m\u00e9diatique fi\u00e9vreux qui caract\u00e9rise le camp am\u00e9ricaniste, et aussi les int\u00e9r\u00eats de l&rsquo;industrie d&rsquo;armement, poussent \u00e0 l&rsquo;audace et au d\u00e9sint\u00e9r\u00eat pour la sagesse et la logique. A Washington m\u00eame, dans certains milieux r\u00e9publicains, on en vient effectivement \u00e0 affirmer que l&rsquo;engagement dans le MBDE repr\u00e9sente une riposte \u00e0 l&rsquo;invasion de la G\u00e9orgie. C&rsquo;est ce que nous signale le site <em>Spy Talk<\/em>, le <a class=\"gen\" href=\"http:\/\/blogs.cqpolitics.com\/spytalk\/2008\/08\/from-the-flames-of-georgia-the.html\">13 ao&ucirc;t<\/a> :<\/p>\n<\/p>\n<p><p>&laquo;<em>On Capitol Hill, some Republicans think they can use Russian aggression in Georgia to bludgeon the Democrats into supporting the deployment of an American \u00ab\u00a0missile shield\u00a0\u00bb in Eastern Europe, according to a story by CQ&rsquo;s enterprising Josh Rogin:<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>In September, lawmakers will resume their debate over the missile sites &ndash; this time amid fresh concerns over Russian threats to U.S. allies in eastern Europe. Though the administration has presented the missiles sites as a defense against Iranian attack, missile defense advocates say they now plan to cite the Russian threat as a way to get Democrats to let construction begin&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0Russia&rsquo;s actions represent compelling data that should be convincing to Democrats that we don&rsquo;t want to delay this thing,\u00a0\u00bb said Rep. Trent Franks, R-Ariz., a leading missile defense champion. \u00ab\u00a0This is not just about missile defense; this is about demonstrating to Russia that America is still a nation of resolve . . . and we&rsquo;re not going to let Russian expansionism intimidate everyone.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>John McCain lui-m\u00eame, toujours tr\u00e8s radical lorsqu&rsquo;il s&rsquo;agit de la Russie et avec les conseillers qu&rsquo;il faut (Randy Scheunemann, <em>neocon<\/em> notoire et principal lobbyiste appoint\u00e9 du gouvernement g\u00e9orgien jusqu&rsquo;en mars dernier), emprunte en partie cette voie de la justification du BMDE (voir <em>CQ Today<\/em> du <a class=\"gen\" href=\"http:\/\/www.cqpolitics.com\/wmspage.cfm?docID=news-000002937821\">13 ao&ucirc;t<\/a>). Justement, c&rsquo;est Scheunemann qui prend la parole: &laquo;<em>\u00ab\u00a0Russia&rsquo;s objections (to the sites) have never been based on anything more than trying to define a sphere of influence in Europe and on the territory of existing NATO members,\u00a0\u00bb said McCain&rsquo;s top foreign policy advisor Randy Scheunemann, \u00ab\u00a0Senator McCain believes that is unacceptable &mdash; especially in the aftermath of Russia&rsquo;s brutal invasion of Georgia.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Obama reste pour l&rsquo;instant (rien n&rsquo;est s&ucirc;r \u00e0 ce propos) sur ses positions d&rsquo;attentisme d\u00e9favorable au r\u00e9seau BMDE, en attendant des tests convaincants qu&rsquo;il situe pour 2010. Au Congr\u00e8s, les d\u00e9mocrates r\u00e9agissent plus fermement face \u00e0 cette pouss\u00e9e des r\u00e9publicains (&laquo;<em>Rep. Ellen O. Tauscher of California, chairwoman of the House Armed Services Strategic Forces Subcommittee, which oversees the missile defense program, denounced Republican efforts to \u00ab\u00a0conflate the &#8230; issue with Russia&rsquo;s provocation in the Caucasus,\u00a0\u00bb which were \u00ab\u00a0completely unrelated.\u00a0\u00bb<\/em>&raquo;)<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La ronde avec le BMDE et autour du BMDE<\/h2>\n<\/p>\n<p><p>Les choses deviennent-elles s\u00e9rieuses? Tous ces gens qui dansent en rond autour du syst\u00e8me BMDE sont-ils s\u00e9rieux quant au danger russe? Si c&rsquo;est le cas, Zogorine a compl\u00e8tement raison: que font-ils donc avec un syst\u00e8me BMDE anti-missiles?<\/p>\n<\/p>\n<p><p>Certes, nous ne partageons pas l&rsquo;alarme que manifestent ces diverses pr\u00e9cisions; mais en en acceptant la logique pour mieux examiner le cas, alors oui on se demande comment il est possible de pr\u00e9senter un r\u00e9seau anti-missiles encore au stade de d\u00e9veloppement pr\u00e9historique comme une parade efficace contre une menace russe. Les pr\u00e9cisions de Zogorine vont dans ce sens:<\/p>\n<\/p>\n<p><p>&laquo;<em>&hellip;Dans le m\u00eame temps, a poursuivi l&rsquo;ambassadeur, en acceptant d&rsquo;accueillir sur leur territoire le bouclier antimissile am\u00e9ricain, la Pologne et la R\u00e9publique tch\u00e8que deviennent potentiellement des cibles pour les terroristes, mais aussi pour les militaires russes. R\u00e9sultat, nul n&rsquo;a ajout\u00e9 \u00e0 sa s\u00e9curit\u00e9, alors que les relations internationales ont souffert, a constat\u00e9 M. Rogozine.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0Je pense que le pr\u00e9sident am\u00e9ricain George W. Bush ne comprend m\u00eame pas ce qu&rsquo;on lui a &lsquo;refil\u00e9&rsquo;. Il ne s&rsquo;agit en fait que des ambitions du complexe militaro-industriel convoitant de grosses commandes\u00a0\u00bb, a-t-il dit. Selon l&rsquo;ambassadeur russe, en priv\u00e9, m\u00eame les militaires otaniens qualifient d&rsquo;inefficace le syst\u00e8me ABM am\u00e9ricain.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est pourtant autour de l&rsquo;annonce de l&rsquo;engagement polonais que se pressent les strat\u00e8ges en chambre, pour pr\u00e9senter cet engagement comme le premier acte de la \u00ab\u00a0riposte\u00a0\u00bb US contre la Russie, apr\u00e8s la courte guerre avec la G\u00e9orgie. Le raisonnement est surprenant: l&rsquo;installation du syst\u00e8me fait monter la tension imm\u00e9diatement entre le pays-h\u00f4te et la Russie, comme le montre les consid\u00e9rations balistiques du Colonel G\u00e9n\u00e9ral. Le syst\u00e8me ne donne pourtant aucune garantie op\u00e9rationnelle concr\u00e8te au pays qui l&rsquo;accueille puisqu&rsquo;il n&rsquo;est cens\u00e9 intervenir que selon une logique globale d&rsquo;engagement nucl\u00e9aire, le plus haut \u00e9chelon de l&rsquo;affrontement arm\u00e9 o&ugrave; les particularismes polonais n&rsquo;ont rien \u00e0 faire. Le signe le plus \u00e9vident de cette inad\u00e9quation du syst\u00e8me aux besoins de s\u00e9curit\u00e9 du pays h\u00f4te, c&rsquo;est l&rsquo;exigence de la Pologne d&rsquo;\u00eatre \u00e9quip\u00e9e de batteries de missiles <em>Patriot<\/em>, contre une hypoth\u00e9tique attaque russe, &ndash; ce qui implique que le BMDE ne prot\u00e8ge la Pologne d&rsquo;aucune attaque russe, &ndash; ce qui est l&rsquo;\u00e9vidence puisqu&rsquo;il n&rsquo;op\u00e8re qu&rsquo;au niveau strat\u00e9gique. (L\u00e0 aussi, la l\u00e9gende publicitaire est sollicit\u00e9e pour alimenter la politique de s\u00e9curit\u00e9. Le <em>Patriot<\/em> est c\u00e9l\u00e8bre pour ses ratages et son impuissance presque grandiose dans la mission de protection qu&rsquo;il est cens\u00e9 accomplir.)<\/p>\n<\/p>\n<p><p>S&rsquo;il s&rsquo;agit de mesures de s\u00e9curit\u00e9 concr\u00e8te, le BMDE et tout ce qui l&rsquo;accompagne constituent un choix compl\u00e8tement contre-productif, pour une signification politique extr\u00eamement provocante et dangereuse. La mesure, op\u00e9rationnellement inad\u00e9quate par rapport \u00e0 la menace qu&rsquo;on d\u00e9duit de l&rsquo;affrontement russo-g\u00e9orgien, est symboliquement et politiquement aggravante. Un commentateur britannique particuli\u00e8rement inquiet, Michael Binyon, dans le <em>Times<\/em> du <a class=\"gen\" href=\"http:\/\/www.timesonline.co.uk\/tol\/comment\/columnists\/guest_contributors\/article4525885.ece\">15 ao&ucirc;t<\/a>, observe: &laquo;<em>Donald Tusk, Poland&rsquo;s Prime Minister, could not have chosen his words better when he told his countrymen: \u00ab\u00a0We have crossed the Rubicon.\u00a0\u00bb He was speaking after the signing of an agreement with America to base ten US interceptor missiles on Polish soil&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Si l&rsquo;on a \u00e0 l&rsquo;esprit une version diff\u00e9rente, savoir qu&rsquo;on n&rsquo;en est pas encore arriv\u00e9 \u00e0 une simple confrontation de mesures pr\u00e9ventives en pr\u00e9vision d&rsquo;un probable affrontement, si l&rsquo;on veut encore se m\u00e9nager de l&rsquo;espace pour man&oelig;uvrer entre pressions politico-militaires et arrangements acceptables, le choix du BMDE n&rsquo;est pas plus judicieux. Il n&rsquo;exerce aucune pression fructueuse puisque tout ce qu&rsquo;il obtient est de susciter la fureur russe et des mesures militaires en riposte sans rien apporter de r\u00e9elle s\u00e9curit\u00e9 suppl\u00e9mentaire aux Polonais. Le BMDE a d\u00e9pass\u00e9 le stade de la n\u00e9gociation et la querelle de ces deux derni\u00e8res ann\u00e9es a \u00e9puis\u00e9 toute possibilit\u00e9 de man&oelig;uvre. Avec la crise g\u00e9orgienne et l&#8217;emploi symbolique fait de l&rsquo;accord polonais, d\u00e9sormais les deux \u00ab\u00a0adversaires\u00a0\u00bb (USA et Russie) se rapprochent du stade o&ugrave; le maintien ou l&rsquo;abandon de la BMDE devient de plus en plus une question de perdre ou ne pas perdre la face; c&rsquo;est par excellence la mesure qui ne peut \u00eatre d&rsquo;aucune utilit\u00e9 pour une n\u00e9gociation puisque tant de valeur prestigieuse, radicale et symbolique lui est d\u00e9sormais attach\u00e9e. Ni utile op\u00e9rationnellement, ni utile pour une n\u00e9gociation, &ndash; avec le BMDE, on tourne d\u00e9sormais en rond.<\/p>\n<\/p>\n<p><p>&hellip;\u00a0\u00bbOn tourne en rond\u00a0\u00bb, simplement parce que le BMDE n&rsquo;a rien \u00e0 voir avec la question de la s\u00e9curit\u00e9, europ\u00e9enne ou polonaise, ni avec la situation nouvelle avec la crise g\u00e9orgienne. Zorogine ne dit rien d&rsquo;exceptionnel lorsqu&rsquo;il dit ce que tout le monde sait bien \u00e0 Bruxelles (&laquo;<em>&hellip;George W. Bush ne comprend m\u00eame pas ce qu&rsquo;on lui a &lsquo;refil\u00e9&rsquo;. Il ne s&rsquo;agit en fait que des ambitions du complexe militaro-industriel convoitant de grosses commandes<\/em>&raquo;). Le BMDE ne peut servir ni \u00e0 contribuer pleinement et assur\u00e9ment \u00e0 la s\u00e9curit\u00e9 de la Pologne (sans parler de l&rsquo;Europe), ni \u00e0 participer utilement \u00e0 une n\u00e9gociation comme outil de pression ou outil d&rsquo;\u00e9change. Sa logique n&rsquo;a rien \u00e0 voir avec ces subtilit\u00e9s diverses. Il est l\u00e0 effectivement pour grossir les commandes du complexe militaro-industriel; c&rsquo;est le produit d&rsquo;une dynamique syst\u00e9mique aveugle, qui n&rsquo;a aucune finalit\u00e9 stabilisatrice ou structurante mais qui acquiert, en cas de tension, des caract\u00e9ristiques d\u00e9structurantes et provocatrices consid\u00e9rables. Nous y sommes.<\/p>\n<\/p>\n<p><p>(Cela conduit \u00e0 la seule conclusion envisageable, que nous donnons en <em>post-scriptum<\/em> tant elle est \u00e9loign\u00e9e de la probl\u00e9matique de s\u00e9curit\u00e9 en Europe et de la crise g\u00e9orgienne. Le v\u00e9ritable sort du BMDE se jouera au niveau bureaucratique, dans les batailles internes de Washington, sans rapport avec nos crises du monde r\u00e9el. Certes, l&rsquo;argument de la s\u00e9curit\u00e9 europ\u00e9enne sera servi pour faire pression sur une nouvelle \u00e9quipe qui voudrait abandonner le programme, comme dans le cas du d\u00e9put\u00e9 Trent Franks, mais cela n&rsquo;aura rien \u00e0 voir avec la s\u00e9curit\u00e9 europ\u00e9enne et tout avec l&rsquo;argument du boutiquier et des relations publiques. A l&rsquo;inverse, ceux qui arriveraient \u00e0 d\u00e9truire le programme BMDE le feraient au nom d&rsquo;argument budg\u00e9taires et techniques ajout\u00e9s, l\u00e0 aussi rien \u00e0 voir avec la s\u00e9curit\u00e9 europ\u00e9enne. Elle sont absolument grotesque, les vaticinations strat\u00e9giques li\u00e9es \u00e0 la s\u00e9curit\u00e9 europ\u00e9ennes d\u00e9velopp\u00e9es par de nombreux strat\u00e8ges du syst\u00e8me oblig\u00e9s de justifier ces initiatives rocambolesques. Quant aux dirigeants politiques de tous bords \u00e0 \u00ab\u00a0l&rsquo;Ouest\u00a0\u00bb ils sont comme GW: on leur a \u00ab\u00a0refil\u00e9\u00a0\u00bb le BMDE, ils en discourent comme s&rsquo;ils y comprenaient quelque chose.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crise intercept\u00e9e: le BMDE marche 18 ao&ucirc;t 2008 &mdash; La signature-express d&rsquo;un \u00ab\u00a0accord pr\u00e9liminaire\u00a0\u00bb entre les Etats-Unis et la Pologne le 14 ao&ucirc;t, concernant le stationnement de missiles anti-missiles (syst\u00e8me BMDE), peut \u00eatre interpr\u00e9t\u00e9e comme une r\u00e9action-\u00e9clair du syst\u00e8me face \u00e0 l&rsquo;invasion de la G\u00e9orgie. La chose pourrait para&icirc;tre compl\u00e8tement inattendue, ou impr\u00e9vue, et apr\u00e8s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4056,4314,584,2827,2614,2730],"class_list":["post-70119","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antimissiles","tag-bmde","tag-otan","tag-pologne","tag-rogozine","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70119"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70119\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}