{"id":70172,"date":"2008-09-08T10:14:58","date_gmt":"2008-09-08T10:14:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/08\/et-si-mccain-etait-elu-grace-a-hurricane-sarah\/"},"modified":"2008-09-08T10:14:58","modified_gmt":"2008-09-08T10:14:58","slug":"et-si-mccain-etait-elu-grace-a-hurricane-sarah","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/08\/et-si-mccain-etait-elu-grace-a-hurricane-sarah\/","title":{"rendered":"Et si McCain \u00e9tait \u00e9lu gr\u00e2ce \u00e0 \u201c<em>Hurricane Sarah<\/em>\u201d?"},"content":{"rendered":"<p><p>La situation \u00e9lectorale US, malgr\u00e9 les fantastiques mesures sugg\u00e9r\u00e9es par le fonctionnement du <a href=\"http:\/\/www.dedefensa.org\/article-le_troisieme_larron_01_09_2008.html\" class=\"gen\">syst\u00e8me<\/a> pour la normaliser, nous a r\u00e9serv\u00e9 une surprise de plus. Le facteur humain est d\u00e9cid\u00e9ment incontr\u00f4lable, ou bien est-ce que la profondeur de la crise d&rsquo;identit\u00e9 des USA, au-dessus de toutes les autres crises du syst\u00e8me, est plus abyssale encore que l&rsquo;on ne le suppose. L&rsquo;intrusion de Sarah Palin, ex-Sarah <em>who<\/em>? pour notre compte, introduit en effet un facteur absolument insaisissable dans ses cons\u00e9quences.<\/p>\n<\/p>\n<p><p>\tPalin a connu \u00e0 la convention r\u00e9publicaine un triomphe sans pr\u00e9c\u00e9dent, bien d\u00e9crit ce <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/us_and_americas\/us_elections\/article4692458.ece\" class=\"gen\">7 septembre<\/a> par le <em>Sunday Times<\/em>,  qui boit du petit lait en bon conservateur, mais qui devrait se m\u00e9fier des arri\u00e8re-go\u00fbts amers pour ce qui concerne son pro-am\u00e9ricanisme. Palin est d\u00e9crite par cette expression intraduisible, mais que tous devrait comprendre: \u00ab<em>Palin, 44, a pistol-packing political powerhouse<\/em>\u00bb. (Si, d\u00e9cid\u00e9ment, vous avez du mal \u00e0 comprendre, reportez-vous \u00e0 cette autre expression : <em>Hurricane Sarah<\/em> et baptisez-l\u00e0 Annie du Grand Nord comme l&rsquo;on disait avant Annie du Far-West.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The enthusiasm generated by Sarah Palin, the Republican party&rsquo;s new northern star, on her first tour of Middle America this weekend has revived Senator John McCain&rsquo;s presidential campaign to such a remarkable extent that she is outshining her running mate.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is an unprecedented position of power for a vice-presidential candidate that carries great risks and rewards for McCain as he adjusts to operating in the shadow of a political phenomenon.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As the McCain-Palin road show took to the suburbs and small towns in the Republican party&rsquo;s target states, fans were running to see her rather than McCain, the 72-year-old former Vietnam prisoner of war.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I only found out half an hour ago that she was coming, said Brenda River, 45, a hairdresser, mother of four and grandmother, as she hurried to the Freedom Hill amphitheatre in a conservative suburb of Detroit, Michigan. I&rsquo;m in her shoes, totally. I love her.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, la conclusion \u00e9vidente vint aussit\u00f4t \u00e0 l&rsquo;esprit de nombreux militants r\u00e9publicains: c&rsquo;est <em>Hurricane Sarah<\/em> qui devrait \u00eatre candidate \u00e0 la pr\u00e9sidence. Cela n&rsquo;a pas du enchanter McCain<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Although he<\/em> [McCain] <em>revelled in the excitement, he seemed at times to be overwhelmed by the audience&rsquo;s passion.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By the end of the rally it was hard to tell whether this was still McCain&rsquo;s party. Matt Stath, a retired lorry driver, said: She should run for president. I&rsquo;d vote for her for president and McCain as vice-president. She&rsquo;s going to be the most beautiful vice-president in history<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tIl ne nous importe pas pour l&rsquo;instant de consid\u00e9rer l&rsquo;\u00e9v\u00e9nement de l&rsquo;apparition foudroyante de Sarah Palin du point de vue politique. (Elle est de l&rsquo;extr\u00eame droite chr\u00e9tienne du parti r\u00e9publicain; elle se croit men\u00e9e par Dieu et croit qu&rsquo;une attaque contre l&rsquo;Iran serait conforme \u00e0 la volont\u00e9 de Dieu; et ainsi de suite. Tout de m\u00eame une petite note sympathique pour pr\u00e9ciser que la seule mati\u00e8re de politique ext\u00e9rieure que connaisse Palin semble \u00eatre les anti-missiles comme ceux qu&rsquo;on promet \u00e0 la Pologne, et qu&rsquo;elle les adore,  ce qui nous promettrait des beaux jours si elle devenait vice-pr\u00e9sidente : \u00ab<em>John Bolton, the former US ambassador to the United Nations who met her briefly in Alaska, said: I thought she was very sharp. She was very knowledgeable about missile defence  Alaska has missile interceptor bases which are on a trajectory from North Korea.<\/em>\u00bb) Laissons ces r\u00e9flexions bien trop rationnelles pour la fi\u00e8vre de nos temps barbares. Ce qui nous importe, c&rsquo;est l&rsquo;extraordinaire facteur de d\u00e9stabilisation que pourrait devenir Palin.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, elle tend \u00e0 d\u00e9stabiliser la campagne en faisant basculer l&rsquo;aspect de nouveaut\u00e9 postmoderne, paradoxalement pour elle qui est ultra-conservatrice, de Obama vers l&rsquo;\u00e9quipe r\u00e9publicaine. On pourrait croire aujourd&rsquo;hui que la perspective d&rsquo;un pr\u00e9sident noir, \u00e0 c\u00f4t\u00e9 de celle d&rsquo;une p\u00e9tulante vice-pr\u00e9sident flanqu\u00e9e d&rsquo;un pr\u00e9sident de 72 ans en mauvaise sant\u00e9, a perdu toute cette originalit\u00e9 qui faisait frissonner nos salons postmodernes et r\u00e9volutionnaires au printemps dernier. Ensuite, elle tend \u00e0 d\u00e9stabiliser McCain lui-m\u00eame, en faisant d\u00e9pendre le destin du candidat McCain de sa propre popularit\u00e9. Elle place une \u00e9ventuelle pr\u00e9sidence McCain sous l&rsquo;ombre d&rsquo;une contribution importante et d&rsquo;une popularit\u00e9 affirm\u00e9e de sa vice-pr\u00e9sidence, alors que la fonction de vice-pr\u00e9sident a acquis un poids consid\u00e9rable avec l&rsquo;\u00e9quipe Bush-Cheney. Ses options extr\u00e9mistes et d\u00e9stabilisantes pourraient alors devenir un facteur d&rsquo;aggravation de la situation de l&rsquo;ex\u00e9cutif US, autant que de la politique US \u00e9videmment. Le d\u00e9sordre extr\u00e9miste de Bush serait poursuivi et accentu\u00e9; il pourrait m\u00eame p\u00e9n\u00e9trer \u00e0 la Maison Blanche puisque cet extr\u00e9misme-l\u00e0 ne rencontrerait pas n\u00e9cessairement toutes les options de McCain, beaucoup plus mod\u00e9r\u00e9 que Bush et Polin sur les questions culturelles, \u00e9thiques, etc.<\/p>\n<\/p>\n<p><p>\tCela pos\u00e9, reste \u00e0 voir si <em>Hurricane Sarah<\/em> va confirmer sa prestation de la convention sur la longueur de la campagne \u00e9lectorale. On verra, par ces temps d&rsquo;extr\u00eame volatilit\u00e9 politique, o\u00f9 les r\u00e9putations et les t\u00eates couronn\u00e9es d&rsquo;avance roulent plus vite que le vent.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 septembre 2008 \u00e0 10H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situation \u00e9lectorale US, malgr\u00e9 les fantastiques mesures sugg\u00e9r\u00e9es par le fonctionnement du syst\u00e8me pour la normaliser, nous a r\u00e9serv\u00e9 une surprise de plus. Le facteur humain est d\u00e9cid\u00e9ment incontr\u00f4lable, ou bien est-ce que la profondeur de la crise d&rsquo;identit\u00e9 des USA, au-dessus de toutes les autres crises du syst\u00e8me, est plus abyssale encore que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4623,4063,7763,3686,7749],"class_list":["post-70172","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-extremistes","tag-mccain","tag-polin","tag-republicain","tag-sarah"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70172"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70172\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}