{"id":70220,"date":"2008-09-23T09:50:48","date_gmt":"2008-09-23T09:50:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/23\/le-gouvernement-us-est-il-menace\/"},"modified":"2008-09-23T09:50:48","modified_gmt":"2008-09-23T09:50:48","slug":"le-gouvernement-us-est-il-menace","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/23\/le-gouvernement-us-est-il-menace\/","title":{"rendered":"Le gouvernement US est-il menac\u00e9?"},"content":{"rendered":"<p><p>David Walker est un homme s\u00e9rieux. Directeur du GAO jusqu&rsquo;en avril dernier, il est notamment fameux pour avoir compar\u00e9, dans une intervention en <a href=\"http:\/\/www.dedefensa.org\/article-la_reference_supreme_15_08_2007.html?\" class=\"gen\">ao\u00fbt 2007<\/a> les USA \u00e0 l&#8217;empire romain, <em>circa<\/em> d\u00e9cadence et chute. L&rsquo;article qu&rsquo;il publie <a href=\"http:\/\/www.ft.com\/cms\/s\/0\/85b5de5e-88b6-11dd-a179-0000779fd18c.html\" class=\"gen\">aujourd&rsquo;hui<\/a> dans le <em>Financial Times<\/em> est d&rsquo;un particulier int\u00e9r\u00eat.<\/p>\n<\/p>\n<p><p>\tOn retiendra les deux premiers paragraphes de son analyse, parce que cet expert de la comptabilit\u00e9 fiscale et budg\u00e9taire, qui ne manque pas de donner une dimension politique \u00e0 ses appr\u00e9ciations, y pose implicitement la question supr\u00eame et que la chose est bien suffisante En un mot, tout est dans son analogie: on disait que AIG, Bear Stearns, Fannie Mae, Freddie Mac, Lehman Brothers, Merrill Lynch \u00e9taient des titans de la finance et du cr\u00e9dit et, en cons\u00e9quence, trop gros pour s&rsquo;effondrer; ils se sont, d&rsquo;une mani\u00e8re ou d&rsquo;une autre, effondr\u00e9s. On dit aussi que vraiment, le gouvernement am\u00e9ricain est trop gros pour s&rsquo;effondrer&rsquo; Voulez-vous poursuivre l&rsquo;analogie?<\/p>\n<\/p>\n<p><p>\t\u00ab<em>What do AIG, Bear Stearns, Fannie Mae, Freddie Mac, Lehman Brothers and Merrill Lynch have in common? Some thought that these companies were too big to fail. They were wrong: all of these companies have either filed for bankruptcy, been bailed out by the government, or, owing to the sub-prime crisis, have been acquired. Over the weekend, the US government went one step further, with its proposals for an estimated $700bn (493bn, \u00a3391bn) bail-out to ease the credit crisis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The US government truly is too big to fail. However, there are disturbing parallels between the factors that led to the sub-prime crisis and the deteriorating financial condition and fiscal foundation of our federal government. These similarities ought to ring an alarm bell for Congress and the presidential candidates. The question is, will they hear it and wake up?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tWalker poursuit par diverses appr\u00e9ciations techniques, comptables et budg\u00e9taires. L&rsquo;important est \u00e9videmment qu&rsquo;il ait pos\u00e9 cette question, qu&rsquo;il \u00e9voque <em>in fine<\/em> cette hypoth\u00e8se qui \u00e9carte le tabou final de la croyance en l&rsquo;invincibilit\u00e9 du gouvernement am\u00e9ricaniste, per\u00e7ue comme une donn\u00e9e absolue. Cette croyance est \u00e9videmment un acte de foi, mais l&rsquo;acte de foi fondamental de la croyance dans le mod\u00e8le am\u00e9ricain, dans la structure anglo-saxonne qui tient tout le syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tLe cas du gouvernement US, par les diverses d\u00e9cisions d&rsquo;urgence qu&rsquo;il a \u00e9t\u00e9 conduit \u00e0 prendre, est qu&rsquo;il lie de plus en plus son sort \u00e0 la stabilit\u00e9, voire \u00e0 la survie du syst\u00e8me financier. On est de plus en plus conduit \u00e0 identifier le syst\u00e8me en perdition avec le gouvernement US, esp\u00e9rant que ce gouvernement saura redresser ce syst\u00e8me. Par l\u00e0, il \u00e9tablit un lien de responsabilit\u00e9 du gouvernement vis-\u00e0-vis du syst\u00e8me. On comprend \u00e9videmment la substance du lien ainsi \u00e9tabli, puisque tous nos vaillants id\u00e9ologues du n\u00e9o-lib\u00e9ralisme n&rsquo;ont plus peur d&rsquo;agir en bons vieux socialistes, en acceptant les nationalisations \u00e0 tour de bras. Mais cette action n&rsquo;est nullement constructive, bien entendu, mais une action d&rsquo;urgence entreprise sous l&#8217;empire de la n\u00e9cessit\u00e9; c&rsquo;est cette n\u00e9cessit\u00e9 qui \u00e9tablit un lien organique entre le gouvernement et le syst\u00e8me financier en p\u00e9ril. Un effondrement de ce syst\u00e8me ferait na\u00eetre aussit\u00f4t une menace vitale contre la stabilit\u00e9 et la structure du gouvernement des Etats-Unis, puisque la responsabilit\u00e9 de ce gouvernement serait engag\u00e9e. Avant m\u00eame d&rsquo;\u00e9voquer des hypoth\u00e8ses g\u00e9n\u00e9rales plus pr\u00e9cises, on peut envisager qu&rsquo;une telle situation conduirait imm\u00e9diatement \u00e0 des tensions centrifuges tr\u00e8s grandes dans la structure m\u00eame du syst\u00e8me am\u00e9ricaniste. (Pour illustrer ce propos, on rappellera que la derni\u00e8re tentative de s\u00e9cession d&rsquo;un Etat de l&rsquo;Union remonte \u00e0 1933, de la part de l&rsquo;Etat du Montana, qui fit voter son Congr\u00e8s sur une proposition de s\u00e9cession de la structure f\u00e9d\u00e9rale (proposition rejet\u00e9e), par des adversaires de la politique \u00e9conomique de Washington en pleine Grande D\u00e9pression.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 septembre 2008 \u00e0 09H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Walker est un homme s\u00e9rieux. Directeur du GAO jusqu&rsquo;en avril dernier, il est notamment fameux pour avoir compar\u00e9, dans une intervention en ao\u00fbt 2007 les USA \u00e0 l&#8217;empire romain, circa d\u00e9cadence et chute. L&rsquo;article qu&rsquo;il publie aujourd&rsquo;hui dans le Financial Times est d&rsquo;un particulier int\u00e9r\u00eat. On retiendra les deux premiers paragraphes de son analyse,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3228,2803,708,7709,5460,4225,2949,3014,2671,5168],"class_list":["post-70220","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-crise","tag-effondrement","tag-empire","tag-financier","tag-gouvernement","tag-romain","tag-secession","tag-systeme","tag-us","tag-walker"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70220"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70220\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}