{"id":70237,"date":"2008-09-30T09:00:05","date_gmt":"2008-09-30T09:00:05","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/30\/le-desordre-et-la-chambre\/"},"modified":"2008-09-30T09:00:05","modified_gmt":"2008-09-30T09:00:05","slug":"le-desordre-et-la-chambre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/09\/30\/le-desordre-et-la-chambre\/","title":{"rendered":"Le d\u00e9sordre et la Chambre"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Le d\u00e9sordre et la Chambre<\/h2>\n<\/p>\n<p><p>30 septembre 2008 &mdash; Il y a dix jours, Paulson apparaissait comme le sauveur du capitalisme, peut-\u00eatre une sorte de dictateur de l&rsquo;ombre, l&rsquo;homme qui allait disposer d&rsquo;un formidable pouvoir ($700 milliards \u00ab\u00a0<em>unchecked<\/em>\u00ab\u00a0, comme si l&rsquo;on vous mettait ce magot comme argent de poche, sans contr\u00f4le des parents). Aujourd&rsquo;hui, les g\u00e9monies lui sont promises et son autorit\u00e9 est dispers\u00e9e \u00e0 terre, en lambeaux.<\/p>\n<\/p>\n<p><p>En un court billet r\u00e9dig\u00e9 dans l&rsquo;urgence, <a class=\"gen\" href=\"http:\/\/business.timesonline.co.uk\/tol\/business\/industry_sectors\/banking_and_finance\/article4849789.ece\">ce matin<\/a> dans le <em>Times<\/em>, Anatole Kaletsky exp\u00e9die le secr\u00e9taire au tr\u00e9sor, &ndash; justement, aux g\u00e9monies. Les \u00e9v\u00e9nements montrent, c&rsquo;est l&rsquo;avis de Kaletsky, combien le \u00ab\u00a0<em>bailout<\/em>\u00a0\u00bb \u00e9tait inutile, combien il fut de bout en bout une man&oelig;uvre politique, combien l&rsquo;on va \u00eatre oblig\u00e9 de revenir \u00e0 l&rsquo;une ou l&rsquo;autre forme d&rsquo;intervention massive de la puissance publique (si cette expression a un sens \u00e0 Washington), cette fois aux conditions des d\u00e9mocrates (&laquo;<em>Now there seems to be only one option: for Mr Paulson and Mr Bush to plead for the Democrats to pass the bailout.<\/em>&raquo;). Description des manigances de Paulson, et de la crise qu&rsquo;il a contribu\u00e9 \u00e0 aggraver jusqu&rsquo;aux abysses.<\/p>\n<\/p>\n<p><p>&laquo;<em>The interesting questions raised by last night&rsquo;s fiasco are: how did the US Government get into such an appalling mess; and what will be the consequences of this disaster for US politics? The answers to both these questions come back to Hank Paulson, the former Wall Street banker and incompetent US Treasury Secretary. Had it not been for Mr Paulson the bailout would probably never have been needed. What made it necessary was a three-stage sequence of blunders. The first began when Mr Paulson decided, for largely political reasons, to wipe out the private shareholders in Fannie Mae and Freddie Mac, two businesses which he and many Republican politicians regarded as crypto-socialist incubi in the American body politic. The enormous &ndash; and unnecessary &ndash; losses suffered by shareholders of Fannie Mae triggered the first stage of the financial crisis, starting on September 8. He then aggravated the crisis by deliberately bankrupting Lehman and then seizing the assets of AIG.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>These unnecessary decisions spread the crisis to every other financial institution. Even worse was Mr Paulson&rsquo;s second set of political blunders, starting with his sudden announcement last week of a $700 billion bailout on which he had consulted no one. The arrogance of his assumption that the Congress would write him a cheque was matched by his failure to come up with any coherent description of how he planned to use this money to help the banks. Under these circumstances, it was hardly surprising that he faced congressional opposition, which led to his third blunder. Mr Paulson&rsquo;s only hope of getting his money was to give unequivocal support to the Democratic Party leaders in Congress who were willing to write a plan themselves. But just as this was nearing completion, Mr Paulson allowed John McCain to parachute himself into the negotiations and attempt to take credit for saving the economy. Had Mr Paulson warned Mr McCain away, the package would probably have been passed already. But by bowing to party-political demands for a Republican say in the package, Mr Paulson opened himself to last night&rsquo;s sabotage.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Autre commentaire qui nous int\u00e9resse, celui de Rupert Cornwell, dans <em>The Independent<\/em>, \u00e9galement de <a class=\"gen\" href=\"http:\/\/www.independent.co.uk\/opinion\/commentators\/rupert-cornwell\/rupert-cornwell-stunning-defeat-of-bill-exposes-failures-of-the-us-political-system-946159.html\">ce matin<\/a>. Cornwell ne s&rsquo;int\u00e9resse pas \u00e0 l&rsquo;aspect technique, aux man&oelig;uvres de Paulson, \u00e0 la com\u00e9die de McCain. Il va plus au c&oelig;ur du probl\u00e8me, qui est le fonctionnement du syst\u00e8me politique US. Ce \u00ab\u00a0<em>black Monday<\/em>\u00ab\u00a0-l\u00e0 n&rsquo;est pas en manque de reconnaissances en paternit\u00e9, mais il ne fait aucun doute pour nous que l&rsquo;inspirateur irresponsable de la chose est bien le syst\u00e8me tel qu&rsquo;il est devenu, le c&oelig;ur politique de cette puissance auto-proclam\u00e9e, le mod\u00e8le de \u00ab\u00a0gouvernance\u00a0\u00bb US, la perfection du \u00ab\u00a0<em>check &#038; balance<\/em>\u00a0\u00bb adul\u00e9e dans le <em>Rest Of the World<\/em> aux jours heureux des illusions. Le mod\u00e8le est en faillite, et plut\u00f4t du genre frauduleux.<\/p>\n<\/p>\n<p><p>&laquo;<em>Yesterday was not only a black Monday for markets. It was the blackest of Mondays too for the US political system, saddled with a discredited president who has completely lost control of his own party and a Congress that responds to a national emergency with little except snarling partisanship.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The stunning defeat of the financial bailout bill has exposed the weakness of the system at its moment of maximum vulnerability, in the quasi-interregnum of the weeks immediately before and after a presidential election. Even so, had a similar crisis erupted at the same stage of the second term of Bill Clinton or Ronald Reagan it is hard to imagine Congress staging a similar rebellion. For George W Bush, alas, it is a different story.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>His lack of clout was first exposed last Thursday when the bailout summit he convened at the White House degenerated into a blazing row. But that humiliation paled beside yesterday&rsquo;s. The President went on TV at 7.30am to plead for the measure that had been thrashed out over the weekend, to no avail. Then he called two dozen recalcitrant House Republicans, begging them to hold their noses and do their patriotic duty &ndash; but again to no avail.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>When the vote came, his own party voted almost two to one against the bill, more than cancelling out the 140-95 majority of Democrats who did hold their noses to support the wishes of a President most of them despise.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Thus did US politics enter the world of Alice Through the Looking Glass. A president who prided himself on being a champion of free markets was urging the biggest state intervention in the economy in more than 50 years.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le vote de la Chambre lui-m\u00eame eut lieu dans des conditions presque irr\u00e9elles. Le d\u00e9sordre s&rsquo;\u00e9tait install\u00e9 au c&oelig;ur du pouvoir, les uns et les autres dissimulant leurs intentions de vote, coinc\u00e9s entre les consignes de la direction et les torrents d&rsquo;<em>e-mails<\/em> (merci aux technologies avanc\u00e9es) des futurs \u00e9lecteurs d&rsquo;ores et d\u00e9j\u00e0 furieux; l&rsquo;ensemble donne cette impression de bateau ivre, le USS <em>Washington D.C.<\/em>, cahotant sur les flots de la temp\u00eate qu&rsquo;il alimente. Le vote \u00e9tait forc\u00e9 mais personne ne voulait plus c\u00e9der \u00e0 la force d&rsquo;un syst\u00e8me dont la direction est d&rsquo;une telle faiblesse, quels que soient les qualit\u00e9s des uns et des autres. Plus qu&rsquo;une r\u00e9volte, la Chambre des Repr\u00e9sentants a montr\u00e9 le visage du d\u00e9sordre. Tous, y compris ceux qui avaient vot\u00e9 contre, tous furent stup\u00e9fi\u00e9s du r\u00e9sultat collectif, &ndash; comme si la Chambre \u00e9tait devenus autonome, avait \u00e9chapp\u00e9 aux parlementaires qui votaient pour exprimer \u00e0 elle seule une d\u00e9cision dont aucun n&rsquo;\u00e9tait comptable, &ndash; tous coupables, pas de responsable. Le New York <em>Times<\/em> eut, <a class=\"gen\" href=\"http:\/\/www.nytimes.com\/2008\/09\/30\/business\/30bailout.html?_r=1&#038;hp&#038;oref=slogin\">hier soir<\/a>, quelques phrases \u00e9voquant implicitement cette atmosph\u00e8re: &laquo;<em>Immediately after the vote, many House members appeared stunned. Some Republicans blamed Ms. Pelosi for a speech before the vote that disdained President Bush&rsquo;s economic policies, and did so, in the opinion of the speaker&rsquo;s critics, in too partisan a way. \u00ab\u00a0Clearly, there was something lacking in the leadership here,\u00a0\u00bb said Representative Eric Cantor, Republican of Virginia.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le syst\u00e8me empoisonn\u00e9 par lui-m\u00eame<\/h3>\n<\/p>\n<p><p>Pour Kaletsky, il y a une certaine artificialit\u00e9 n\u00e9e des man&oelig;uvres politiciennes dans la monstrueuse crise qui secoue le syst\u00e8me. En ce sens, ce 9\/11-l\u00e0 (le \u00ab\u00a09\/11 financier\u00a0\u00bb) serait <strong>aussi<\/strong> un complot, une fois de plus mont\u00e9 par des comploteurs type-Pieds Nickel\u00e9s qui se prennent pour des g\u00e9ants, les ma&icirc;tres aux petits pieds de l&rsquo;univers globalis\u00e9. Kaletsky n&rsquo;en oublie pas la consid\u00e9ration essentielle : &laquo;<em>&hellip;how did the US Government get into such an appalling mess; and what will be the consequences of this disaster for US politics?<\/em>&raquo; Pour Cornwell, le syst\u00e8me politique est comme Alice au Pays des Merveilles, au milieu des miroirs d\u00e9formants; il ne sait plus ce qu&rsquo;il fait, il se cogne ici et l\u00e0, ayant perdu son sens de l&rsquo;orientation (le sens de son int\u00e9r\u00eat commun). Toutes les images ont leur valeur. Elles sugg\u00e8rent d&rsquo;une fa\u00e7on ou l&rsquo;autre ce qui nous semble essentiel.<\/p>\n<\/p>\n<p><p>La crise financi\u00e8re, dont on voyait <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_habits_divers_de_la_crise_24_09_2008.html\">l&rsquo;\u00e9largissement<\/a> depuis quelques jours, s&rsquo;est d\u00e9finitivement transform\u00e9e en une crise fondamentale du syst\u00e8me politique en allant au c&oelig;ur de la chose, &ndash; la politique, certes. Le ph\u00e9nom\u00e8ne syst\u00e9mique poursuit sa diffusion de crise sectorielle en crise sectorielle, chacune continuant \u00e0 br&ucirc;ler une fois qu&rsquo;on est pass\u00e9 \u00e0 la suivante. Mais l&rsquo;on admettra qu&rsquo;on se trouve ici au c&oelig;ur de l&rsquo;incendie: les hommes confront\u00e9s au monstre qu&rsquo;ils ont cr\u00e9\u00e9, victimes de ce monstre, incapables de servir ce monstre jusqu&rsquo;o&ugrave; ils devraient le faire parce qu&rsquo;ils sont eux-m\u00eames au bout de leur capacit\u00e9 de le faire.<\/p>\n<\/p>\n<p><p>Ecartons ici, par piti\u00e9, toute consid\u00e9ration technique, &ndash; sur ce que valent le plan de sauvetage, l&rsquo;action et les manigances de Paulson, les formules de sauvetage d&rsquo;un syst\u00e8me financier d\u00e9vor\u00e9 par les termites, les justifications \u00e9videntes de ceux qui se sont r\u00e9volt\u00e9s en d\u00e9sordre pour le repousser, les perspectives des bourses ajoutant chaque jour un \u00ab\u00a0jour noir\u00a0\u00bb, les faillites \u00e0 venir, les nationalisations, etc. Observons simplement l&rsquo;absence compl\u00e8te de force commune, de solidarit\u00e9, de sens et d&rsquo;\u00e9lan collectifs par quoi un tel syst\u00e8me tient, quelles que soient la vanit\u00e9 et la malignit\u00e9 des motifs. Nous ne cessons de rappeler les pr\u00e9c\u00e9dents, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-un_pearl_harbor_economique_bien_vu_25_09_2008.html\">Pearl Harbor<\/a> mais aussi l&rsquo;entr\u00e9e en fonction de FDR, o&ugrave; un Congr\u00e8s pourtant hostile vota (le 9 mars 1933) la premi\u00e8re mesure d&rsquo;urgence (la fermeture des banques pour 30 jours) d\u00e9cid\u00e9e le lendemain de son installation (le 5 mars 1933) par le pr\u00e9sident. (Quelle importance, cette mesure qui fut par ailleurs d\u00e9cri\u00e9e justement, comme l&rsquo;est le plan Paulson? Seul importe l&rsquo;acte dans ces circonstances, comme celles que nous connaissons. L&rsquo;humoriste Will Rogers l&rsquo;avait justement dit : &laquo;<em>The whole country is with him, just so he does something. If he burned down the Capitol, we would all cheer and say, well, we at least got a fire started anyhow.<\/em>&raquo;) Ces r\u00e9f\u00e9rences mesurent par contraste la d\u00e9cadence du syst\u00e8me, qui passe par la d\u00e9mobilisation de ses soldats, la perte du sens commun, l&rsquo;amertume et les consid\u00e9rations \u00e9lectorales. Le syst\u00e8me meurt du poison qu&rsquo;il a lui-m\u00eame instill\u00e9 dans le temps et l&rsquo;espace qu&rsquo;il a eus sous sa domination; d\u00e9structurant du reste, il l&rsquo;est devenu de lui-m\u00eame.<\/p>\n<\/p>\n<p><p>Nous autres, \u00e0 <em>dedefensa.org<\/em> avons \u00e9t\u00e9 stup\u00e9faits par le vote de la Chambre des Repr\u00e9sentants US hier. Nous ne pouvions imaginer que ce syst\u00e8me, cette machinerie, en arrivent l\u00e0 dans le vaste domaine de l&rsquo;irresponsabilit\u00e9 politique. Nous ne pensions pas que la d\u00e9cr\u00e9pitude du syst\u00e8me serait telle que quelques-uns de ses principaux serviteurs oseraient, dans ce moment de solidarit\u00e9 n\u00e9cessaire pour le bien du syst\u00e8me lui-m\u00eame, se r\u00e9volter sans la moindre concertation. On comprend compl\u00e8tement que les Repr\u00e9sentants l&rsquo;aient fait, quand on consid\u00e8re les conditions du \u00ab\u00a0<em>bailout<\/em>\u00ab\u00a0, le cas inconsistant qu&rsquo;il faisait des convictions et des int\u00e9r\u00eats de chacun. Mais qu&rsquo;ils l&rsquo;aient fait dans cet instant tragique et vital repousse les consid\u00e9rations les plus cr\u00e9pusculaires que nous entretenions sur l&rsquo;\u00e9tat de cette chose, &ndash; leur syst\u00e8me. Nous croyions \u00e9videmment qu&rsquo;avec eux, le pire est toujours possible; mais la d\u00e9cadence extraordinaire de ce syst\u00e8me conduit \u00e0 l&rsquo;invention du \u00ab\u00a0pire du pire\u00a0\u00bb. Fid\u00e8le \u00e0 la mont\u00e9e aux extr\u00eames, d\u00e9cid\u00e9ment.<\/p>\n<\/p>\n<p><p>Que fait-on maintenant? On attaque l&rsquo;Iran? (M\u00eame \u00e7a, il ne peut plus, les amiraux n&rsquo;ob\u00e9iront pas, &ndash; rappel de la remarque venimeuse du <em>Sunday Times<\/em> : &laquo;<em>There was no bombing to be done &mdash; banks were doing enough of that by themselves. All<\/em> [Bush] <em>could do was warn: \u00ab\u00a0If money isn&rsquo;t loosened up, this sucker could go down.\u00a0\u00bb<\/em>&raquo;)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9sordre et la Chambre 30 septembre 2008 &mdash; Il y a dix jours, Paulson apparaissait comme le sauveur du capitalisme, peut-\u00eatre une sorte de dictateur de l&rsquo;ombre, l&rsquo;homme qui allait disposer d&rsquo;un formidable pouvoir ($700 milliards \u00ab\u00a0unchecked\u00ab\u00a0, comme si l&rsquo;on vous mettait ce magot comme argent de poche, sans contr\u00f4le des parents). Aujourd&rsquo;hui, les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3359,5615,3228,3184,7819,7024,3372,3014,6097,3132,3248],"class_list":["post-70237","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chambre","tag-cornwell","tag-crise","tag-fdr","tag-kaltsky","tag-paulson","tag-street","tag-systeme","tag-vote","tag-wall","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70237"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70237\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}