{"id":70286,"date":"2008-10-20T06:14:06","date_gmt":"2008-10-20T06:14:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/10\/20\/leurope-et-son-avenir-incertain\/"},"modified":"2008-10-20T06:14:06","modified_gmt":"2008-10-20T06:14:06","slug":"leurope-et-son-avenir-incertain","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/10\/20\/leurope-et-son-avenir-incertain\/","title":{"rendered":"L&rsquo;Europe et son avenir incertain"},"content":{"rendered":"<p><p>Dans l&#8217;emportement tragique de l&rsquo;automne 2008 apparaissent d&rsquo;ores et d\u00e9j\u00e0 des sp\u00e9culations pour le d\u00e9but de l&rsquo;ann\u00e9e 2009, dans la perspective d&rsquo;une crise qui commence \u00e0 entrer dans le domaine p\u00e9rilleux pour la stabilit\u00e9 politique de l&rsquo;\u00e9conomie r\u00e9elle. William Pfaff met en \u00e9vidence, dans un article dat\u00e9 du <a href=\"http:\/\/www.williampfaff.com\/modules\/news\/article.php?storyid=348\" class=\"gen\">16 octobre<\/a>, le changement consid\u00e9rable effectu\u00e9 entre l&rsquo;\u00e9t\u00e9 et cet automne, du point de vue de la perception du <em>leadership<\/em> occidental.<\/p>\n<\/p>\n<p><p>\tPfaff rappelle l&rsquo;inexistence US durant la crise g\u00e9orgienne, puis ce m\u00eame effacement face \u00e0 la crise financi\u00e8re, avec cette image d\u00e9risoire d&rsquo;un Bush faisant sa d\u00e9claration quotidienne comme le coucou d&rsquo;une horloge, sans que personne ne lui pr\u00eate attention \u00ab<em>Treasury Secretary Henry Paulson, recently of Goldman Sachs, appeared to have been placed in charge of the U.S. government.<\/em> [] <em> Congressional insurrection stopped that.<\/em> [] <em>The Federal Reserve Chairman seemed out of the loop. President Bush (I believe it was Gail Collins of the New York Times who said this first) popped out of the White House once a day, as from a cuckoo-clock, to make an announcement no one paid attention to.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe r\u00e9sultat, observe Pfaff, est que l&rsquo;Europe d\u00e9cida de se passer du <em>leadership<\/em> US. La chose fut prestement exp\u00e9di\u00e9e. \u00ab<em>In these circumstances, some Europeans seem to have decided that the postwar era of American leadership is over. British Prime Minister Gordon Brown temporarily nationalized British banks, took control of them, fired some of their executives, and refinanced them. Nicolas Sarkozy immediately invited Brown (not a member of the Eurogroup), Angela Merkel, and the other European chiefs who are Eurogroup members, to Paris to agree to more or less the same policy, thus creating the framework for a (hitherto unthinkable) European economic government.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMais les choses vont vite. Cette nouvelle situation est elle-m\u00eame mise en question par les perspectives d&rsquo;incertitude dues au fonctionnement normal des institutions, d&rsquo;ailleurs tant en Europe qu&rsquo;aux USA. (Il s&rsquo;agit d&rsquo;une nouvelle pr\u00e9sidence UE et de l&rsquo;\u00e9lection pr\u00e9sidentielle US.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The factor of uncertainty in Europe is that in January the Czech Republic takes over the EU presidency, and the Czech president and prime minister dislike the European Union.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Some have suggested that the EU somehow contrive to keep Sarkozy on, with him and Merkel in charge. Perhaps the Irish could be persuaded to take back their veto of a European constitution so that a permanent president could be elected before January. But that is unlikely. At least a year of leaderless Euro-American drift seems ahead.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa sp\u00e9culation centrale est de savoir si les \u00e9v\u00e9nements, et notamment le d\u00e9veloppement de la crise \u00e9conomique, permettront une telle perspective. Cette interrogation vaut essentiellement pour l&rsquo;Europe, o\u00f9 vont se poser conjointement et d&rsquo;une mani\u00e8re antagoniste les questions de la continuit\u00e9 du pouvoir et de la forme de l&rsquo;organisation du pouvoir. Il est vrai que la pr\u00e9sidence de l&rsquo;UE a acquis une grande importance durant la crise; il est vrai qu&rsquo;elle risque de se trouver devant une crise d&rsquo;autorit\u00e9 et de repr\u00e9sentativit\u00e9 \u00e0 partir du 1er janvier 2009. Les deux faits ont une cause unique: l&rsquo;importance de la pr\u00e9sidence UE existe aujourd&rsquo;hui parce que cette pr\u00e9sidence est assur\u00e9e par une des grandes nations fondatrices, avec un pr\u00e9sident qui joue sans restriction sur cette position; les difficult\u00e9s possibles de la pr\u00e9sidence de l&rsquo;UE \u00e0 partir du 1er janvier 2009 viendront de ce que la succession se fera dans les pires conditions de contraste possibles, passant \u00e0 un petit pays (la Tch\u00e9quie), nouvellement membre de l&rsquo;UE, avec un Premier ministre peu connu et de convictions tr\u00e8s eurosceptique (et son pr\u00e9sident \u00e0 mesure), avec une politique nationale largement discr\u00e9dit\u00e9e par une orientation pro-am\u00e9ricaniste bien connue.<\/p>\n<\/p>\n<p><p>\tLa pr\u00e9vision qui est d&rsquo;ores et d\u00e9j\u00e0 faite de cette circonstance tr\u00e8s difficile tend \u00e0 rajouter une perspective suppl\u00e9mentaire de crise avant m\u00eame que la chose soit r\u00e9alis\u00e9e. La probabilit\u00e9 est tr\u00e8s grande de voir mise en lumi\u00e8re d&rsquo;une fa\u00e7on explosive la faiblesse dramatique des conceptions et des m\u00e9canismes europ\u00e9ens et leur absence compl\u00e8te de l\u00e9gitimit\u00e9. Si la crise g\u00e9n\u00e9rale (financi\u00e8re et \u00e9conomique) se poursuit et s&rsquo;aggrave, des circonstances explosives peuvent rapidement appara\u00eetre \u00e0 nouveau. Les grands pays europ\u00e9ens n&rsquo;accepteraient pas une direction r\u00e9duite, soit en capacit\u00e9s, soit en conceptions ou les deux \u00e0 la fois. L&rsquo;urgence est l\u00e0, avec des dirigeants (Sarkozy, Brown, Merkel) qui ont appris cet automne que l&rsquo;urgence requiert imp\u00e9rativement des r\u00e9actions et des d\u00e9cisions tr\u00e8s rapides. Dans certaines circonstances, des hypoth\u00e8ses d&rsquo;insurrection par rapport aux normes institutionnelles de fonctionnement de l&rsquo;Europe ne peuvent \u00eatre \u00e9cart\u00e9es, notamment les grands pays europ\u00e9ens d\u00e9cidant d&rsquo;agir ensemble, hors des canaux de la pr\u00e9sidence de l&rsquo;UE, si cette pr\u00e9sidence ne pouvait ou ne voulait pas r\u00e9agir comme ces pays le veulent. Le sch\u00e9ma qui appara\u00eetrait constituerait n\u00e9cessairement une rupture des normes institutionnelles. Apr\u00e8s un automne o\u00f9 l&rsquo;on voit combien l&rsquo;Europe des nations tient un r\u00f4le essentiel sinon exclusif aux d\u00e9pens d&rsquo;une l&rsquo;Europe institutionnelle inexistante, on pourrait voir une situation o\u00f9 une insurrection des nations contre l&rsquo;Europe institutionnelle ach\u00e8verait de fixer le sort de l&rsquo;Europe telle qu&rsquo;elle est actuellement constitu\u00e9e.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 20 octobre 2008 \u00e0 06H12<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans l&#8217;emportement tragique de l&rsquo;automne 2008 apparaissent d&rsquo;ores et d\u00e9j\u00e0 des sp\u00e9culations pour le d\u00e9but de l&rsquo;ann\u00e9e 2009, dans la perspective d&rsquo;une crise qui commence \u00e0 entrer dans le domaine p\u00e9rilleux pour la stabilit\u00e9 politique de l&rsquo;\u00e9conomie r\u00e9elle. William Pfaff met en \u00e9vidence, dans un article dat\u00e9 du 16 octobre, le changement consid\u00e9rable effectu\u00e9 entre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4038,398,4590,5551,2609],"class_list":["post-70286","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-brown","tag-europe","tag-sarkozy","tag-tchequie","tag-ue"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70286"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70286\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}