{"id":70303,"date":"2008-10-28T09:22:10","date_gmt":"2008-10-28T09:22:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/10\/28\/obama-et-lurgence-des-temps\/"},"modified":"2008-10-28T09:22:10","modified_gmt":"2008-10-28T09:22:10","slug":"obama-et-lurgence-des-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/10\/28\/obama-et-lurgence-des-temps\/","title":{"rendered":"Obama et l&rsquo;urgence des temps"},"content":{"rendered":"<p><p>A une semaine de l&rsquo;\u00e9lection, Obama change de sujet. Il aborde indirectement mais publiquement, la situation d&rsquo;apr\u00e8s l&rsquo;\u00e9lection, c&rsquo;est-\u00e0-dire apr\u00e8s sa victoire. Cela est implicite et m\u00eame presque explicite dans ce discours fait \u00e0 Canton, dans l&rsquo;Ohio, et dont le <em>Times<\/em> se fait l&rsquo;\u00e9cho <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/us_and_americas\/us_elections\/article5025935.ece\" class=\"gen\">aujourd&rsquo;hui<\/a>.<\/p>\n<\/p>\n<p><p>\t(L&rsquo;id\u00e9e de la victoire irr\u00e9sistible d&rsquo;Obama et des d\u00e9mocrates est m\u00eame pr\u00e9sente chez McCain, qui vient de faire un discours o\u00f9 il d\u00e9nonce le danger de voir s&rsquo;\u00e9tablir un pouvoir absolu des d\u00e9mocrates, avec la victoire d&rsquo;Obama, une victoire \u00e0 la Chambre [Pelosi] et au S\u00e9bat [Reid]: \u00ab[McCain] <em>has described the prospect of unfettered Democratic power across Washington  with Mr Obama alongside Congressional leaders Nancy Pelosi and Harry Reid  as a dangerous threesome<\/em>\u00bb. Les r\u00e9publicains luttent d\u00e9sormais pour tenter d&#8217;emp\u00eacher un pouvoir d\u00e9mocrate absolu, les emp\u00eachant m\u00eame d&rsquo;avoir la moindre capacit\u00e9 d&rsquo;action au Congr\u00e8s,  par exemple, si la majorit\u00e9 d\u00e9mocrate est telle qu&rsquo;elle leur interdirait l&rsquo;usage de la proc\u00e9dure dite du <em>filibuster<\/em> qui donne \u00e0 une minorit\u00e9 suffisante la capacit\u00e9 d&rsquo;interf\u00e9rer sur la proc\u00e9dure de la majorit\u00e9 dans les d\u00e9bats parlementaires.)<\/p>\n<\/p>\n<p><p>\tLe discours d&rsquo;Obama, dans l&rsquo;Ohio, est pr\u00e9sent\u00e9 dans ce texte du <em>Times<\/em>, comme un dernier effort avant l&rsquo;\u00e9lection, avec le th\u00e8me nouveau, ou plut\u00f4t retrouv\u00e9 du d\u00e9but de la campagne des primaires d&rsquo;Obama, d&rsquo;un rassemblement national autour de lui.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Barack Obama sought to close the deal with American voters yesterday as he heralded the dawn of a new politics that will heal divisions, appeal to our better angels and restore a sense of higher purpose.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>His speech in Canton, Ohio, was designed to frame the final days of an often bitterly fought presidential contest around the uplifting themes he had emphasised at the outset of his campaign. While he was at pains to tell supporters that they cannot afford to let up for one day, one minute or one second, Mr Obama told an exultant crowd: In one week, we can come together as one nation, and one people, and once more choose our better history.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He declared: If you will stand with me, and fight with me, and give me your vote, then I promise you this  we will not just win Ohio, we will not just win this general election, but together we will change this country and we will change the world.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, une premi\u00e8re approche est effectivement de placer ce discours dans le cadre de la campagne \u00e9lectorale, comme le fait le <em>Times<\/em>. Nous serions plut\u00f4t tent\u00e9s de le placer dans un cadre qui d\u00e9passe cette campagne, qui tient pour acquise la victoire d&rsquo;Obama, et qui pose le probl\u00e8me de la n\u00e9cessit\u00e9 d&rsquo;un rassemblement national aussit\u00f4t apr\u00e8s l&rsquo;\u00e9lection pour soutenir la nouvelle administration plac\u00e9e devant des t\u00e2ches extr\u00eamement difficiles, voire dangereuses.<\/p>\n<\/p>\n<p><p>\tIl est concevable que la campagne et l&rsquo;\u00e9quipe Obama, approchant du terme, avec l&rsquo;id\u00e9e d&rsquo;une victoire certaine et sans doute m\u00eame tr\u00e8s importante, commencent \u00e0 prendre en compte les r\u00e9alit\u00e9s politiques et \u00e9conomiques qui l&rsquo;attendent. La perspective est per\u00e7ue comme tr\u00e8s difficile, et la n\u00e9cessit\u00e9 d&rsquo;un soutien populaire devient un \u00e9l\u00e9ment de la situation politique d&rsquo;apr\u00e8s l&rsquo;\u00e9lection.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 octobre 2008 \u00e0  09H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A une semaine de l&rsquo;\u00e9lection, Obama change de sujet. Il aborde indirectement mais publiquement, la situation d&rsquo;apr\u00e8s l&rsquo;\u00e9lection, c&rsquo;est-\u00e0-dire apr\u00e8s sa victoire. Cela est implicite et m\u00eame presque explicite dans ce discours fait \u00e0 Canton, dans l&rsquo;Ohio, et dont le Times se fait l&rsquo;\u00e9cho aujourd&rsquo;hui. (L&rsquo;id\u00e9e de la victoire irr\u00e9sistible d&rsquo;Obama et des d\u00e9mocrates est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6120,4063,3890,6208,7870,6210],"class_list":["post-70303","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-campagne","tag-mccain","tag-national","tag-obama","tag-rassemblement","tag-urgence"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70303"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70303\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}