{"id":70372,"date":"2008-12-01T07:58:20","date_gmt":"2008-12-01T07:58:20","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/01\/il-faut-savoir-tenir-les-promesses-que-lon-na-pas-faites\/"},"modified":"2008-12-01T07:58:20","modified_gmt":"2008-12-01T07:58:20","slug":"il-faut-savoir-tenir-les-promesses-que-lon-na-pas-faites","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/01\/il-faut-savoir-tenir-les-promesses-que-lon-na-pas-faites\/","title":{"rendered":"Il faut savoir tenir les promesses que l&rsquo;on n&rsquo;a pas faites"},"content":{"rendered":"<p><h2 class=\"common-article\">Il faut savoir tenir les promesses que l&rsquo;on n&rsquo;a pas faites<\/h2>\n<\/p>\n<p><p>\t1er d\u00e9cembre 2008  La controverse g\u00e9n\u00e9rale est d\u00e9j\u00e0 bien engag\u00e9e autour du pr\u00e9sident Obama,  alors que, comme chacun sait, il se trouve encore \u00e0 sept semaines de son entr\u00e9e en fonction, qu&rsquo;il n&rsquo;est encore que <em>the President-elect<\/em>. Il est vrai qu&rsquo;Obama agit comme pr\u00e9sident d&rsquo;ores et d\u00e9j\u00e0, avec une promptitude extraordinaire, ce qui est \u00e0 la fois c\u00e9l\u00e9br\u00e9 comme une des vertus extraordinaires de cet homme aux multiples vertus extraordinaires,  \u00e0 la fois utilis\u00e9 pour lancer contre lui des attaques d\u00e9j\u00e0 furieuses et presque venimeuses, et contre la tournure que prend sa pr\u00e9sidence qui n&rsquo;est-m\u00eame-pas-encore-install\u00e9e.<\/p>\n<\/p>\n<p><p>\tOn a <a href=\"http:\/\/www.dedefensa.org\/article-deja_le_desamour_pointe_27_11_2008.html\" class=\"gen\">d\u00e9j\u00e0<\/a> signal\u00e9 cette tendance mais elle ne fait que se confirmer et s&rsquo;amplifier. Le paradoxe est double:<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, cette tendance grandit \u00e0 mesure qu&rsquo;Obama s&rsquo;affirme, c&rsquo;est-\u00e0-dire qu&rsquo;elle est effectivement li\u00e9e \u00e0 l&rsquo;affirmation de ses capacit\u00e9s, de ses qualit\u00e9s \u00e9videntes. Obama agit comme s&rsquo;il \u00e9tait d\u00e9j\u00e0 pr\u00e9sident, d\u00e9barrassant la sc\u00e8ne politicienne washingtonienne de cet avorton-pr\u00e9sident qu&rsquo;\u00e9tait (le pass\u00e9 est de rigueur) GW Bush. Soupir de soulagement g\u00e9n\u00e9ral, mont\u00e9e de l&rsquo;adr\u00e9naline admirative sans condition,  aussit\u00f4t bloqu\u00e9e par le constat: tout cet activisme puissant pour <strong>\u00e7a<\/strong>?  c&rsquo;est-\u00e0-dire le retour au premier plan des t\u00e9nors des ann\u00e9es 1990, qui nous avaient pr\u00e9par\u00e9s aux petits oignons la pr\u00e9sidence Bush, en machinant une globalisation catastrophique, en lan\u00e7ant le capitalisme sauvage \u00e0 travers le monde (rappelez-vous la Russie ravag\u00e9e), en lan\u00e7ant Wall Street dans les \u00e9toiles, avec les bulles sans nombre, les patrons surpay\u00e9s, les <em>bonus<\/em> douteux, l&rsquo;argent qui n&rsquo;existe pas, les <em>oxyd assets<\/em>, etc. Dr\u00f4le de dilemme pour <em>the President-elect<\/em>. \u00ab<em>Fifty days before President George W Bush packs his bags for Texas, Obama has already usurped much of his predecessor&rsquo;s authority<\/em>, \u00e9crivait le <em>Sunday Times<\/em> <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/us_and_americas\/article5258056.ece\" class=\"gen\">hier<\/a>, 30 novembre. <em>Yet in doing so he has exposed himself to early controversy that may seriously shorten the presidential honeymoon that most new incumbents enjoy. There are already stirrings of confusion and dismay among Democratic faithful perturbed by some of Obama&rsquo;s early appointments.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPlus loin, le m\u00eame: \u00ab<em>While Obama&rsquo;s bold moves have been broadly welcomed, they have also posed headaches for Democratic activists who have been surprised by the caution and moderation reflected in some of Obama&rsquo;s cabinet picks. It&rsquo;s very hard for even leaders of the left to poke holes, because many of their followers will say give the guy a break &#8211; 29he hasn&rsquo;t even been in the White house yet&rsquo;, said Steven Clemons, a liberal analyst at the New America Foundation. Clemons added: We are in an Obama bubble now. And it&rsquo;s tough to step out and be the first to deflate the bubble.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Trade union leaders who spent millions of dollars campaigning for Obama have nonetheless been shocked that nobody overtly sympathetic to the union movement has been appointed to the incoming economic team. Obama has not yet named a secretary of labour, which some activists interpreted as a worrying sign that bankers and employers have become higher priorities. If we believe this election was about rebuilding the middle class and reclaiming the American Dream, the next secretary of labour should be somebody who is passionate about workers, warned Anna Burger, who as secretary-treasurer of a big services union was a key Obama supporter during the election campaign.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama&rsquo;s eye-catching national security appointments have stunned many antiwar protesters who were convinced that Obama would stick to his pledges to close Guantanamo Bay and bring an early end to the war in Iraq. The Nation, a liberal Washington weekly, complained that the candidates for Obama&rsquo;s national security team had been drawn exclusively from conservative, centrist and pro-military circles without even a single one chosen to represent the antiwar wing of the Democratic party. A coalition of liberal groups is planning to set up tents in January near Obama&rsquo;s home in Hyde Park, Chicago, in the hope that their presence will remind the president-elect of his promises.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While many Democrats hope that Obama will reassure them once he gets into office, Jodie Evans, a well-known activist, told the Politico website last week that the president-elect was already violating the people&rsquo;s mandate. Nor have Democrats been encouraged by Republican applause for the president-elect&rsquo;s appointments. Max Boot, a foreign policy adviser to Senator John McCain, said last week he had previously been sceptical of Obama&rsquo;s moderate posturing, but had been gob-smacked by an Obama team that was stunning in its moderation. Boot added: Most of these appointments could just as easily have come from a President McCain.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t En portant aussit\u00f4t son action contre la crise \u00e9conomique et sur la situation int\u00e9rieure qui l&rsquo;accompagne et qu&rsquo;elle aggrave de plus en plus nettement, ce qui est parfaitement comprendre le sens de son \u00e9lection et la pression de ses \u00e9lecteurs qui demandent que l&rsquo;action int\u00e9rieure prenne le pas sur l&rsquo;accent mis jusqu&rsquo;ici sur une folle politique ext\u00e9rieure, Obama s&rsquo;expose exactement d&rsquo;un m\u00eame mouvement aux plus cruelles critiques. Il se trouve, ce qu&rsquo;on savait depuis longtemps mais qui prend \u00e0 la lumi\u00e8re de son activisme une tournure bien mis\u00e9rable, que l&rsquo;essentiel de son \u00e9quipe a une tournure Wall Street, souvent une tournure Goldman Sachs, dans tous les cas une tournure toute enti\u00e8re marqu\u00e9e par la patte et l&rsquo;influence du ma\u00eetre d&rsquo;uvre de la politique financi\u00e8re de l&rsquo;administration Clinton, qui pr\u00e9para (<em>bis retetitat<\/em>) dans les ann\u00e9es 1990, les catastrophiques ann\u00e9es 2000 jusqu&rsquo;\u00e0 la catastrophe de 2008. On parle de Robert Rubin, \u00e2g\u00e9 de 70 ans mais toujours actif,  devinez o\u00f9? A la t\u00eate de <em>Citigroup<\/em>, nouveau symbole, avec le record battu de l&rsquo;aide promise de Washington \u00e0 une banque ($305 milliards), et donc le record de l&rsquo;obsc\u00e8ne entourloupette ainsi \u00e9tabli. D&rsquo;o\u00f9 les exclamations feutr\u00e9es mais s\u00e9v\u00e8res de l&rsquo;<em>Observer<\/em>, <a href=\"http:\/\/www.guardian.co.uk\/world\/2008\/nov\/30\/obama-white-house-barackobama\" class=\"gen\">hier<\/a><\/p>\n<\/p>\n<p><p>\t\u00ab<em>As Barack Obama prepares to announce the appointment of Hillary Clinton as Secretary of State this week, the first notes of dissent over the President-elect&rsquo;s choices are being heard across America. The loudest complaints concern his economic team&rsquo;s ties to Citigroup, the banking behemoth that all but collapsed last weekend. In particular, criticisms are mounting over the role to be played by Robert Rubin, a director at Citigroup and President Clinton&rsquo;s former treasury secretary.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama, who last week called for a massive stimulus package to prevent the US economy from &lsquo;falling into a deflationary spiral&rsquo;, has taken several prot\u00e9g\u00e9s of 70-year-old Rubin as advisers, among them Timothy Geithner as treasury secretary, Lawrence Summers as senior White House economics adviser and Peter Orszag as budget director, even as Rubin himself has been defending his key role in deregulating the financial markets and steering Citigroup towards taking greater trading risks to expand its business and reap higher profits.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>But with criticism of Rubin and loyal &lsquo;Rubinistas&rsquo; threatening Obama&rsquo;s Washington debut, there is increasing concern that the President-elect&rsquo;s emphasis on appointing Clinton-era officials &#8211; a shadow Clinton term, as it has been called  could backfire as the very people who undertook financial deregulation in the Nineties are now directed to re-regulate a decade later. Where&rsquo;s the diversity on the economic team? It&rsquo;s not only all from the same small club, but from the club that brought us the deregulation that has a lot to do with the economic collapse, said Robert Kuttner, the co-founder of the liberal-leaning American Prospect magazine.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;attaque la plus s\u00e9v\u00e8re, la plus lumineuse par l&rsquo;analogie ainsi propos\u00e9e, pr\u00e9cis\u00e9ment sur cette \u00e9quipe de lutte contre la crise \u00e9conomique, vient de Michael Hudson, dans <em>CounterPunch<\/em> le <a href=\"http:\/\/www.counterpunch.org\/hudson11262008.html\" class=\"gen\">26 novembre<\/a>, sous le titre incendiaire de <em>The Neo-Yeltsin Administration?<\/em> Alors que tout le monde attend un nouveau Gorbatchev, \u00e9crit Hudson, voil\u00e0 que nous avons un nouvel Eltsine. Le rappel du r\u00f4le que joua dans la mise \u00e0 sac de la Russie sous la pr\u00e9sidence Eltsine la direction financi\u00e8re et \u00e9conomique des ann\u00e9es Clinton, qu&rsquo;on retrouve presque enti\u00e8rement reconstitu\u00e9e dans l&rsquo;\u00e9quipe Obama, est particuli\u00e8rement frappant. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Instead, after resembling President Carter by running a brilliant presidential primary campaign to win the nomination (will a similarly disappointing administration be about to come?), Obama is looking more like Boris Yeltsin  a political umbrella for the kleptocrats to whom the public domain and decades of public wealth were given with no quid pro quo.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama&rsquo;s ties with the Yeltsin administration are as direct as could be. He has appointed as his economic advisors the same anti-labor, pro-financial team that brought the kleptocrats to power in Russia in the mid-1990s. His advisor Robert Rubin has managed to put his prot\u00e9g\u00e9s in key Obama administration posts: Larry Summers, who as head of the World Bank forced privatization at give-away prices to kleptocrats; Geithner of the New York Fed; and a monetarist economist from Berkeley, as right-wing a university as Chicago. These are the protective guard-dogs of America&rsquo;s vested interests.<\/em>\u00bb<\/p>\n<h3>Tout le monde trompe tout le monde<\/h3>\n<\/p>\n<p><p>\tLe cas est \u00e9clairant. Obama a d\u00e9roul\u00e9 au long d&rsquo;une campagne septembre-octobre 2008 ennuyeuse \u00e0 p\u00e9rir un programme mod\u00e9r\u00e9, tout en assurant les piliers financiers et \u00e9conomiques du capitalisme am\u00e9ricaniste qu&rsquo;il ferait tout ce qui serait en son pouvoir pour les renforcer. Le 25 septembre 2008, au sommet de la Maison-Blanche qui, \u00e0 notre sens, vit sous la pression de la crise le v\u00e9ritable transmission du pouvoir entre un Bush aux abois et le futur pr\u00e9sident (McCain ou Obama,  mais d\u00e9j\u00e0 Obama presque assur\u00e9), Obama soutint \u00e0 fond le plan Paulson. Ce plan \u00e9tait pr\u00e9sent\u00e9 comme une urgence pour, para\u00eet-il, \u00e9viter le pire du fond de l&rsquo;ab\u00eeme, mais il n&rsquo;en \u00e9tait pas moins un scandale obsc\u00e8ne de plus en couvrant d&rsquo;or les copains et les coquins de Wall Street. Obama le prit compl\u00e8tement \u00e0 son compte, se faisant bien plus r\u00e9publicain que les r\u00e9publicains. Dans les jours qui suivirent, ce sont les d\u00e9mocrates, sous la pression imp\u00e9rative d&rsquo;Obama, qui firent adopter le plan par le Congr\u00e8s. Obama n&rsquo;a pas cach\u00e9 son jeu. Pour le reste, la tactique d&rsquo;Obama fut de constamment tenter de montrer qu&rsquo;il avait la capacit\u00e9 de gouverner, qu&rsquo;il avait plus d&rsquo;exp\u00e9rience qu&rsquo;on ne croyait, etc., c&rsquo;est-\u00e0-dire promettre implicitement un gouvernement qui s&rsquo;inscrirait absolument dans la continuit\u00e9 de l&rsquo;habituel gouvernement de Washington,  GW except\u00e9. (Ce qu&rsquo;on lui reproche aujourd&rsquo;hui vient d&rsquo;une activit\u00e9 qui, depuis le 4 novembre, prouve qu&rsquo;il agit aussi bien, sinon mieux qu&rsquo;un homme d&rsquo;exp\u00e9rience. Il tient donc cette promesse \u00e9lectorale-l\u00e0, jug\u00e9e si essentielle. C&rsquo;est l&rsquo;occasion de lui reprocher de ne pas tenir ses autres promesses \u00e9lectorales, celles qu&rsquo;il n&rsquo;a pas faites&#8230;)<\/p>\n<\/p>\n<p><p>\t[U]ne campagne septembre-octobre 2008 ennuyeuse \u00e0 p\u00e9rir, \u00e9crivons-nous. Ce n&rsquo;est pas une coquille. La campagne elle-m\u00eame fut exactement cela. La tension extraordinaire monta <strong>autour<\/strong> de la campagne \u00e0 cause de la crise catastrophique qu&rsquo;on sait, qui engendrait angoisse profonde et panique; la campagne ennuyeuse et la tension de la crise sembl\u00e8rent \u00e9voluer parall\u00e8lement, comme dans deux univers parall\u00e8les qui, selon Euclide lui-m\u00eame, ne se rencontrent jamais; enfin, tant pis pour Euclide, la rencontre se fit; assez naturellement, sur la fin de la p\u00e9riode, cette tension envahit la campagne par l&rsquo;ext\u00e9rieur, un peu comme Gorbatchev avait fait vis-\u00e0-vis du syst\u00e8me sovi\u00e9tique, enfin pour se substituer \u00e0 la campagne pour sa signification, comme on fait un <em>kidnapping<\/em>.<\/p>\n<\/p>\n<p><p>\tLa pression de la crise \u00e9tait telle qu&rsquo;on ignora absolument les promesses r\u00e9elles du candidat Obama, pour le charger de promesses suppos\u00e9es et en r\u00e9alit\u00e9 fictives. Il fut proclam\u00e9 l&rsquo;homme du changement en r\u00e9f\u00e9rence aux vagues slogans des primaires (<em>Change we can believe in<\/em>, <em>Yes, we can<\/em>,  tout cela qui ne mange pas de pain mais qui fixa le climat des primaires). Cette exigence s\u00e9mantique, sinon de pure communication dans l&rsquo;interpr\u00e9tation qu&rsquo;on eut d&rsquo;Obama, pouvait, devait m\u00eame signifier en l&rsquo;occurrence: l&rsquo;homme d&rsquo;un changement peut-\u00eatre r\u00e9volutionnaire. Obama ne d\u00e9mentit pas cette ambiance extraordinaire, qui n&rsquo;avait rien \u00e0 voir avec ce qu&rsquo;il disait sur le fond, qui le servait grandement dans les sondages, sauf sur la fin o\u00f9 il devint vraiment inquiet de toutes les obligations dont ces promesses qu&rsquo;il ne faisait pas le chargeaient. Peut-\u00eatre est-ce \u00e0 ce moment, <a href=\"http:\/\/www.dedefensa.org\/article-obama_et_l_urgence_des_temps_28_10_2008.html\" class=\"gen\">fin octobre<\/a>, juste avant l&rsquo;\u00e9lection, qu&rsquo;Obama s&rsquo;aper\u00e7ut du danger: on allait \u00e9lire un homme,  lui, en l&rsquo;occurrence,  au nom de promesses d&rsquo;un changement consid\u00e9rable qu&rsquo;il ne faisait pas. Ce fut sans doute fugitif car l&rsquo;ivresse du 4 novembre balaya tout cela.<\/p>\n<\/p>\n<p><p>\tDepuis, la disparition de GW Bush de la vie politique et la pression de la crise ont conduit Obama \u00e0 se manifester comme quasi-pr\u00e9sident, mais sans le pouvoir d&rsquo;imposer les mesures n\u00e9cessaires. Toute l&rsquo;attention est orient\u00e9e vers la constitution de son cabinet, avec la cons\u00e9quence de commentaires de plus en plus n\u00e9gatifs dus aux personnalit\u00e9s dont la caract\u00e9ristique n&rsquo;est certes pas le changement. Pour le changement, s&rsquo;il y a changement, il faudrait attendre l&rsquo;entr\u00e9e en fonction d&rsquo;Obama et sa prise de pouvoir effective. Mais on n&rsquo;attend pas.<\/p>\n<\/p>\n<p><p>\tEn attendant, les questions des journalistes le pressent de se justifier de ne pas manifester le grand changement qu&rsquo;il a promis et il se juge oblig\u00e9 de r\u00e9pondre, et il r\u00e9pond sur la d\u00e9fensive en cr\u00e9ant des concepts paradoxaux (il explique qu&rsquo;il fait appel \u00e0 des hommes d&rsquo;exp\u00e9rience \u00e9prouv\u00e9e et chenue pour pouvoir mieux accoucher de pens\u00e9es nouvelles,  <em>fresh thinking<\/em>). Curieusement, les questions des journalistes, autant que les r\u00e9ponses d&rsquo;Obama sont d\u00e9plac\u00e9es puisqu&rsquo;elles s&rsquo;appuient sur l&rsquo;id\u00e9e qu&rsquo;Obama a promis un changement r\u00e9volutionnaire pendant la campagne, alors qu&rsquo;il ne l&rsquo;a pas fait.<\/p>\n<\/p>\n<p><p>\tMais la tension est tellement grande, la tension de la crise si forte, la tension au niveau du gouvernement apr\u00e8s la p\u00e9riode catastrophique qui se termine, que l&rsquo;id\u00e9e du changement promis (non-promis) devient une exigence in\u00e9vitable, quelque chose que tout le monde tient pour acquis,  Obama a promis la changement, l&rsquo;apportera-t-il? Lui-m\u00eame s&rsquo;interroge l\u00e0-dessus, pour s&rsquo;excuser que le changement ne soit pas an rendez-vous aussit\u00f4t, pour garantir qu&rsquo;il sera l\u00e0 bient\u00f4t, dans la pens\u00e9e autant que dans l&rsquo;action politiques, et ainsi de suite. Lui-m\u00eame accr\u00e9dite la version des faits qui permet sa mise en accusation.<\/p>\n<\/p>\n<p><p>\tObama est prisonnier d&rsquo;une image de r\u00e9formiste quasi-r\u00e9volutionnaire qu&rsquo;il a contribu\u00e9e largement \u00e0 forger \u00e0 ses d\u00e9buts, avant de l&rsquo;abandonner prestement; qu&rsquo;il n&rsquo;a certainement pas combattue quand elle est ressortie comme le fait une g\u00e9n\u00e9ration spontan\u00e9e, \u00e0 cause de la crise financi\u00e8re, <strong>autour<\/strong> de la campagne \u00e9lectorale bien plus que dans cette campagne. (Le fait qu&rsquo;il soit Africain-Am\u00e9ricain, \u00e9videmment, a accentu\u00e9 cette image de l&rsquo;homme du changement dans le monde de la communication o\u00f9 nous vivons, sans doute d&rsquo;une fa\u00e7on tr\u00e8s puissante. Le tableau est complet.) On dira qu&rsquo;une image, on peut s&rsquo;en d\u00e9barrasser, ou bien s&rsquo;en accommoder c&rsquo;est selon. Ce n&rsquo;est pas faux en temps normal. Mais nous ne sommes pas dans des temps normaux, comme Obama lui-m\u00eame ne cesse de le dire; nous sommes dans des temps d&rsquo;une crise extraordinairement grave, qui ne cesse de s&rsquo;aggraver, surtout aux Etats-Unis m\u00eame. L&rsquo;inqui\u00e9tude et bient\u00f4t la rancoeur de l&rsquo;aile lib\u00e9rale du parti d\u00e9mocrate, qui a pes\u00e9 de tout son poids pour le faire \u00e9lire, sont d\u00e9j\u00e0 <a href=\"http:\/\/hosted.ap.org\/dynamic\/stories\/O\/OBAMA_LEFT_OR_CENTER?SITE=AP&#038;SECTION=HOME&#038;TEMPLATE=DEFAULT\" class=\"gen\">tr\u00e8s fortes<\/a> et ne cesseront de s&rsquo;exacerber \u00e0 mesure que la crise transformera l&rsquo;enthousiasme \u00e9ph\u00e9m\u00e8re du 4 novembre en une revendication am\u00e8re et bient\u00f4t furieuse. La satisfaction visible des r\u00e9publicains devant les nominations du gouvernement Obama rajoute de l&rsquo;huile sur le feu.<\/p>\n<\/p>\n<p><p>\tLe tr\u00e8s brillant <em>President-elect<\/em> est d\u00e9j\u00e0 sur la d\u00e9fensive avant d&rsquo;\u00eatre pr\u00e9sident. On avait coutume de mettre en doute ses capacit\u00e9s de r\u00e9forme parce qu&rsquo;on le jugeait prisonnier de l&rsquo;<em>establishment<\/em>. Mais il appara\u00eet d&rsquo;ores et d\u00e9j\u00e0 comme complice de l&rsquo;<em>establishment<\/em>, sinon partie prenante. Qu&rsquo;il le soit ou pas n&rsquo;a qu&rsquo;une importance minime en l&rsquo;occurrence puisqu&rsquo;on peut ais\u00e9ment comprendre qu&rsquo;un pr\u00e9sident \u00e9lu, dans le syst\u00e8me tel qu&rsquo;il l&rsquo;est, l&rsquo;est toujours plus ou moins. L&rsquo;important est bien qu&rsquo;il le paraisse d&rsquo;une fa\u00e7on si visible, on dirait presque provocatrice, alors qu&rsquo;il assoit plus que jamais sa popularit\u00e9 sur son image d&rsquo;homme de changement. Cette situation fait qu&rsquo;au contraire de s&rsquo;en d\u00e9barrasser, Obama, pour se d\u00e9fendre contre les risques de l&rsquo;impopularit\u00e9, va devoir de plus en plus prot\u00e9ger et renforcer cette image qui devient de plus en plus sa sauvegarde,  mais qui est aussi l&rsquo;image de sa trahison suppos\u00e9e. La pression de la crise et les nouvelles malheureuses de la population US ne lui laisseront aucun r\u00e9pit \u00e0 cet \u00e9gard et vont aggraver la contradiction. La tension entre la r\u00e9alit\u00e9 apparente de son pouvoir et les n\u00e9cessit\u00e9s de son gouvernement face \u00e0 la crise a toutes les chances de pendre, d\u00e8s les d\u00e9buts de sa pr\u00e9sidence, des allures de crise personnelle. Comment Obama d\u00e9nouera-t-il cette crise? La d\u00e9nouera-t-il seulement?  Est-il prisonnier de l&rsquo;<em>establishment<\/em> ou bien est-il prisonnier de la crise qu&rsquo;il est en train de cr\u00e9er en paraissant complice de l&rsquo;<em>establishment<\/em>? Est-il habit\u00e9 de pens\u00e9es secr\u00e8tes qui pourraient le pousser \u00e0 d\u00e9nouer cette crise personnelle, en r\u00e9f\u00e9rence \u00e0 la crise g\u00e9n\u00e9rale du pays, d&rsquo;une fa\u00e7on radicale (<LIEN=http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html>hypoth\u00e8se Gorbatchev)? <\/p>\n<\/p>\n<p><p>\tQuelle vitesse! Nous voil\u00e0 en train de parler de crise de la pr\u00e9sidence Obama alors qu&rsquo;il n&rsquo;est pas encore en fonction. C&rsquo;est qu&rsquo;en v\u00e9rit\u00e9 la crise de la pr\u00e9sidence Obama a commenc\u00e9 le 15 septembre, lorsqu&rsquo;a \u00e9clat\u00e9 la crise financi\u00e8re. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il faut savoir tenir les promesses que l&rsquo;on n&rsquo;a pas faites 1er d\u00e9cembre 2008 La controverse g\u00e9n\u00e9rale est d\u00e9j\u00e0 bien engag\u00e9e autour du pr\u00e9sident Obama, alors que, comme chacun sait, il se trouve encore \u00e0 sept semaines de son entr\u00e9e en fonction, qu&rsquo;il n&rsquo;est encore que the President-elect. Il est vrai qu&rsquo;Obama agit comme pr\u00e9sident&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[934,3228,5212,3483,3773,6208,4600,4301],"class_list":["post-70372","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-clinton","tag-crise","tag-eltsine","tag-gorbatchev","tag-image","tag-obama","tag-reformiste","tag-rubin"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70372"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70372\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}