{"id":70378,"date":"2008-12-03T13:44:16","date_gmt":"2008-12-03T13:44:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/03\/la-france-confirme-sa-mefiance-hostile-au-bmde\/"},"modified":"2008-12-03T13:44:16","modified_gmt":"2008-12-03T13:44:16","slug":"la-france-confirme-sa-mefiance-hostile-au-bmde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/03\/la-france-confirme-sa-mefiance-hostile-au-bmde\/","title":{"rendered":"La France confirme sa m\u00e9fiance hostile au BMDE"},"content":{"rendered":"<p><p>Apr\u00e8s l&rsquo;intervention tonitruante de Sarkozy contre le r\u00e9seau anti-missile US en Europe (BMDE), le 14 novembre <a href=\"http:\/\/www.dedefensa.org\/article-sarko_sur_la_breche_et_dans_la_breche_medvedev_en_bandouliere_15_11_2008.html\" class=\"gen\">\u00e0 Nice<\/a>, la politique fran\u00e7aise dans ce domaine est confirm\u00e9e par une intervention du ministre fran\u00e7ais de la d\u00e9fense devant le Parlement Europ\u00e9en, le 1er d\u00e9cembre. (M\u00eame s&rsquo;il parle au nom de la pr\u00e9sidence fran\u00e7aise de l&rsquo;UE, il est \u00e9vident qu&rsquo;il s&rsquo;agit de la politique fran\u00e7aise en l&rsquo;esp\u00e8ce,  mais dont on pourrait dire que la France en fait b\u00e9n\u00e9ficier l&rsquo;Europe, par g\u00e9n\u00e9rosit\u00e9 sans doute.)<\/p>\n<\/p>\n<p><p>\tIl y avait eu un certain flottement, le lendemain de ce sommet UE-Russie de Nice, lorsque Sarkozy, alors \u00e0 Washington pour le sommet du G20, avait temp\u00e9r\u00e9 ses propos de la veille,  selon une d\u00e9p\u00eache AP du <a href=\"http:\/\/fr.news.yahoo.com\/3\/20081116\/r_t_ap_wl_amnord\/twl-usa-france-missiles-224d7fb_1.html?printer=1\" class=\"gen\">16 novembre<\/a>. (La m\u00eame d\u00e9p\u00eache faisait \u00e9tat d&rsquo;une r\u00e9action du Premier ministre polonais, implicitement tr\u00e8s critique de la position frn\u00e7aise.)<\/p>\n<\/p>\n<p><p>\t\u00ab[A] <em>l&rsquo;issue du G-20, le pr\u00e9sident fran\u00e7ais a mod\u00e9r\u00e9 ses propos <\/em>[du 14 novembre]<em>, estimant que le dispositif<\/em> [BMDE] <em>pourrait constituer un compl\u00e9ment contre la menace de missiles venant d&rsquo;ailleurs, d&rsquo;Iran par exemple. Le premier ministre polonais a estim\u00e9 pour sa part que la question du d\u00e9ploiement en Pologne ne concernait que son pays et les Etats-Unis. Sur la question du bouclier, je n&rsquo;attends pas de commentaires ni d&rsquo;actes de tiers parties a estim\u00e9 le premier polonais, Donald Tusk.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl semble que ces d\u00e9clarations polonaises n&rsquo;aient nullement d\u00e9courag\u00e9 les Fran\u00e7ais, si l&rsquo;on en juge d&rsquo;apr\u00e8s la d\u00e9claration de Morin. <em>Defense News<\/em> rapporte, le <a href=\"http:\/\/www.defensenews.com\/story.php?i=3846066&#038;c=AME\" class=\"gen\">2 d\u00e9cembre<\/a>, l&rsquo;essentiel de cette intervention.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Speaking to members of the European Parliament here Dec. 1, Herv\u00e9 Morin asked what funds Europe would have left for other things if it committed to the huge cost of such defenses.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Morin raised other questions as well. Who would hold the key to their use? What threat would they tackle? There are risks, yes, but to say that there is a threat today would need to be checked, he said. He also said the decision on such defenses would need to be made in the context of relations with Russia.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMorin apporte la touche technique du ministre de la d\u00e9fense contre le BMDE, apr\u00e8s la prise de position politique de Sarko, le 14 novembre \u00e0 Nice. Il ne rejette pas le projet,  ce n&rsquo;est ni le propos ni son domaine de comp\u00e9tence,  mais lui trouve implicitement un nombre consid\u00e9rable de d\u00e9fauts qui, tous, p\u00e8sent d&rsquo;un grand poids sur la situation strat\u00e9gique de l&rsquo;Europe et la s\u00e9curit\u00e9 paneurop\u00e9enne. L&rsquo;int\u00e9r\u00eat des Fran\u00e7ais pour le BMDE est effectivement justifi\u00e9 par l&rsquo;implication directe et massive de ce syst\u00e8me dans l&rsquo;\u00e9quilibre de la s\u00e9curit\u00e9 pan-europ\u00e9enne, et le caract\u00e8re bilat\u00e9ral (Pologne-USA) de l&rsquo;accord qui l&rsquo;installe n&rsquo;a gu\u00e8re de valeur face \u00e0 cette r\u00e9alit\u00e9,  d&rsquo;autant moins lorsqu&rsquo;on sait les conditions de cet accord.<\/p>\n<\/p>\n<p><p>\tAinsi se compl\u00e8te et se renforce la nouvelle orientation par Sarkozy lors du sommet de Nice, et son initiative, avec Medvedev, d\u00e9clar\u00e9e \u00e0 cette occasion. (Cette initiative implique la mise en question du BMDE dans le cadre de la recherche d&rsquo;une nouvelle architecture europ\u00e9enne de s\u00e9curit\u00e9, avec une ou plusieurs proposition de conf\u00e9rence, \u00e9ventuellement dans le cadre de l&rsquo;OSCE, sur ce sujet.). Il faut remarquer qu&rsquo;il y a une acceptation <em>de facto<\/em> grandissante, dans les milieux europ\u00e9ens, de l&rsquo;existence et de la validit\u00e9 de cette initiative. Un signe bureaucratique \u00e0 cet \u00e9gard est que le travail politique int\u00e9rieur de la Commission europ\u00e9enne actuellement en cours, portant notamment sur les relations avec la Russie, int\u00e8gre cette initiative et la d\u00e9signe formellement comme <em>the Evian proposal<\/em>, r\u00e9f\u00e9rence \u00e0 la proposition commune Sarkozy-Medvedev qui sortit du s\u00e9minaire d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-les_accords_d_evian_09_10_2008.html\" class=\"gen\">Evian<\/a> le 8 octobre dernier.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 d\u00e9cembre 2008 \u00e0 13H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s l&rsquo;intervention tonitruante de Sarkozy contre le r\u00e9seau anti-missile US en Europe (BMDE), le 14 novembre \u00e0 Nice, la politique fran\u00e7aise dans ce domaine est confirm\u00e9e par une intervention du ministre fran\u00e7ais de la d\u00e9fense devant le Parlement Europ\u00e9en, le 1er d\u00e9cembre. (M\u00eame s&rsquo;il parle au nom de la pr\u00e9sidence fran\u00e7aise de l&rsquo;UE, il est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4314,2858,7060,7910,7688,4590],"class_list":["post-70378","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bmde","tag-medvedev","tag-morin","tag-nice","tag-paneuropeen","tag-sarkozy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70378"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70378\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}