{"id":70380,"date":"2008-12-04T15:11:13","date_gmt":"2008-12-04T15:11:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/04\/confusions-europeennes-et-revelatrices\/"},"modified":"2008-12-04T15:11:13","modified_gmt":"2008-12-04T15:11:13","slug":"confusions-europeennes-et-revelatrices","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/04\/confusions-europeennes-et-revelatrices\/","title":{"rendered":"Confusions europ\u00e9ennes et r\u00e9v\u00e9latrices"},"content":{"rendered":"<p><h2 class=\"common-article\">Confusions europ\u00e9ennes et r\u00e9v\u00e9latrices<\/h2>\n<\/p>\n<p><p>\t4 d\u00e9cembre 2008  Les ministres des affaires \u00e9trang\u00e8res des pays de l&rsquo;OTAN viennent de se rencontrer (les 2 et 3 d\u00e9cembre) \u00e0 Bruxelles. L&rsquo;OSCE se r\u00e9unit \u00e0 partir d&rsquo;aujourd&rsquo;hui \u00e0 Helsinki. Autour de ces r\u00e9unions \u00e9voluent divers probl\u00e8mes importants, sinon centraux, qui concernent la s\u00e9curit\u00e9 europ\u00e9enne, qui ont \u00e9t\u00e9 fortement r\u00e9activ\u00e9s par les diverses crises en cours, notamment apr\u00e8s le paroxysme de l&rsquo;\u00e9t\u00e9 (crise g\u00e9orgienne, crise du syst\u00e8me anti-missile BMDE) et les \u00e9volutions qui ont suivi cet automne.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est surtout autour de la r\u00e9union de l&rsquo;OTAN qu&rsquo;on a pu appr\u00e9cier l&rsquo;\u00e9volution des choses, essentiellement au niveau de l&rsquo;information et de la d\u00e9sinformation, ou, mieux encore, de l&rsquo;existence parall\u00e8le de mondes diff\u00e9rent pr\u00e9tendant dispenser leurs informations. C&rsquo;est effectivement \u00e0 ce niveau de l&rsquo;information que les derniers \u00e9v\u00e9nements sont int\u00e9ressants,  charge \u00e0 nous, au-del\u00e0, d&rsquo;en tirer des conclusions sur l&rsquo;orientation des \u00e9v\u00e9nements eux-m\u00eames.<\/p>\n<\/p>\n<p><p>\t Sur la question de l&rsquo;adh\u00e9sion de la G\u00e9orgie et de l&rsquo;Ukraine, l&rsquo;orientation MAP n&rsquo;a pas \u00e9t\u00e9 retenue. Par contre, l&rsquo;orientation d&rsquo;\u00e9changes renforc\u00e9s entre les deux pays et l&rsquo;OTAN a \u00e9t\u00e9 annonc\u00e9e. D&rsquo;une fa\u00e7on apparemment neutre et s&rsquo;en tenant \u00e0 la lettre sollicit\u00e9e des choses, cette \u00e9volution a \u00e9t\u00e9 pr\u00e9sent\u00e9e comme un compromis entre les partisans (essentiellement les USA) et les adversaires de l&rsquo;adh\u00e9sion. Mais il s&rsquo;agit bien s\u00fbr d&rsquo;un revers des partisans de l&rsquo;adh\u00e9sion, le bon sens ne laisse pas de doute \u00e0 ce propos et c&rsquo;est dans ce sens qu&rsquo;on retiendra ces r\u00e9unions de d\u00e9cembre. La presse britannique, la plus r\u00e9aliste et la plus ouverte \u00e0 ce propos, expose clairement une analyse dans ce sens. A titre d&rsquo;exemple, citons <em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/europe\/setback-for-georgia-after-nato-rejection-1049064.html\" class=\"gen\">3 d\u00e9cembre<\/a>, parlant clairement d&rsquo;un \u00ab<em>Setback for Georgia after Nato rejection<\/em>\u00bb: \u00ab<em>Georgia&rsquo;s hopes of joining Nato were dealt a blow last night, when Western European countries blocked a bid to offer it a path to membership.<\/em>\u00bb Le quotidien londonien va jusqu&rsquo;\u00e0 donner une pr\u00e9cision touchante sur les petits G\u00e9orgiens, qui re\u00e7oivent le pr\u00e9nom de Map (et sans doute de Nato \u00e9galement?), et que voil\u00e0 fort d\u00e9\u00e7us de porter d\u00e9sormais le nom d&rsquo;une esp\u00e9rance d\u00e9\u00e7ue:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The measures are a major disappointment for Tbilisi. It will be hard to explain this to our people back home, Georgia&rsquo;s Foreign Minister, Ekaterine Tkeshelashvili, said. The Prime Minister, Grigol Mgaloblishvili, added: MAP has taken on such huge symbolism in Georgia that I have even met people who have named their children Map. But of course, we do realise that what matters most is that we are on a steady road to membership.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Dans l&rsquo;affaire du syst\u00e8me anti-missiles US BMDE, les ministres ont r\u00e9affirm\u00e9 une position d\u00e9j\u00e0 affirm\u00e9e en avril dernier au sommet de Bucarest. Selon des sources \u00e0 l&rsquo;OTAN, la discussion sur le BMDE est pass\u00e9e pratiquement inaper\u00e7ue,  si l&rsquo;on peut m\u00eame parler de discussion. Manifestement, la chose a \u00e9t\u00e9 vue comme une simple formalit\u00e9, figurant dans le communiqu\u00e9 comme un paragraphe standard (chercher entre le n\u00b030 et le n\u00b040). Le probl\u00e8me est que, depuis avril, il y a eu des prolongements importants dans cette affaire. Cela permet \u00e0 Associated Press de publier cette d\u00e9p\u00eache du <a href=\"http:\/\/www.sfgate.com\/cgi-bin\/article.cgi?f=\/n\/a\/2008\/12\/03\/international\/i034741S93.DTL\" class=\"gen\">3 d\u00e9cembre<\/a>, pr\u00e9sentant cette position sur le BMDE comme un fait important de la r\u00e9union, et pla\u00e7ant la chose en situation, ou selon une situation arrangeante, de fa\u00e7on \u00e0 ce qu&rsquo;elle apparaisse effectivement comme importante,  \u00e9ventuellement, m\u00eame, comme s&rsquo;il s&rsquo;agissait d&rsquo;une premi\u00e8re d\u00e9cision dans ce sens (quitte \u00e0 nuancer implicitement dans le texte, lorsqu&rsquo;il est fait allusion aux d\u00e9cisions de Bucarest):<\/p>\n<\/p>\n<p><p>\t\u00ab<em>NATO foreign ministers on Wednesday affirmed their support for U.S. plans to install anti-missile defenses in Europe despite Russia&rsquo;s strong opposition. The ministers said the planned U.S. defenses in Poland and the Czech Republic will make a substantial contribution to protecting allies from the threat of long-range ballistic missiles.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>All 26 NATO allies signed the statement backing the deployment of interceptor missiles in Poland and an advanced radar station in the Czech Republic.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Doubts about allied support for the plan were raised last month when French President Nicolas Sarkozy said the missile defenses would bring nothing to security &#8230; it would complicate things, and would make them move backward. Sarkozy&rsquo;s statement at a meeting in France with Russian President Dmitry Medvedev appeared to contradict his early support for the missile plans at a NATO summit in April. But in Washington a few days later, the French leader changed tack again, saying that the anti-missile shield could compl\u00e9ment Western defenses against a threat from Iran.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le <em>All 26 NATO allies<\/em> s&rsquo;adresse \u00e9videmment \u00e0 la France, suivi du d\u00e9veloppement sur la position fran\u00e7aise sur le BMDE, avec le rappel que la France avait d\u00e9j\u00e0 sign\u00e9 en avril \u00e0 Bucarest un texte de soutien, que la France a sembl\u00e9 d\u00e9savouer lorsque Sarkozy a pr\u00e9sent\u00e9 une nouvelle position \u00e0 Nice le 14 novembre, nouvelle position que Sarkozy a sembl\u00e9 d\u00e9savouer (mais le jugement implicite est un peu fort) le 15 novembre \u00e0 Washington, et puis les Fran\u00e7ais semblent \u00e0 nouveau re-confirmer \u00e0 Bruxelles le 3 d\u00e9cembre leur position d&rsquo;avril de Bucarest. Encore Paul Ames, de AP, rate-t-il l&rsquo;essentiel, ou dans tous les cas le plus r\u00e9cent, qui est que le ministre fran\u00e7ais de la d\u00e9fense Herv\u00e9 Morin, deux jours plus t\u00f4t \u00e0 Bruxelles, devant le Parlement europ\u00e9en, avait exprim\u00e9 au travers de graves questions non r\u00e9solues, y compris la validit\u00e9 de la menace, la question de la d\u00e9cision d&#8217;emploi, etc., <a href=\"http:\/\/www.dedefensa.org\/article-la_france_confirme_sa_mefiance_hostile_au_bmde_03_12_2008.html\" class=\"gen\">toute la m\u00e9fiance<\/a> que lui inspire, et qu&rsquo;inspire \u00e0 la France pourrait-on \u00eatre conduit \u00e0 conclure, le syst\u00e8me BMDE. O\u00f9 est, dans ce cas, la <em>substantial contribution<\/em> du BMDE \u00e0 la s\u00e9curit\u00e9 europ\u00e9enne?<\/p>\n<\/p>\n<p><p>\t Sans doute le fleuron revient-il \u00e0 des d\u00e9clarations faites par le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, concernant la proposition Medvedev sur une nouvelle architecture de la s\u00e9curit\u00e9 en Europe. Le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN remarque sur un ton condescendant que les 26 pays de l&rsquo;OTAN sont tr\u00e8s heureux avec l&rsquo;architecture existante et s&rsquo;ils accueillent avec sympathie, aujourd&rsquo;hui et d\u00e9sormais, tout ce qui vient des Russes, ils voient mal l&rsquo;utilit\u00e9 d&rsquo;une conf\u00e9rence pour cette \u00e9trange nouvelle architecture. Vingt-quatre heures plus tard (aujourd&rsquo;hui) s&rsquo;ouvre \u00e0 Helsinki la conf\u00e9rence annuelle de l&rsquo;OSCE, \u00e0 l&rsquo;agenda de laquelle il y a notamment la proposition de Sarkozy pour une conf\u00e9rence sur une nouvelle architecture de la s\u00e9curit\u00e9 en Europe; Sarkozy, c&rsquo;est semble-t-il la France, qui est semble-t-il un des 26 membres de l&rsquo;OTAN, dont les 26 membres n&rsquo;ont rien \u00e0 faire d&rsquo;une nouvelle architecture de la s\u00e9curit\u00e9 en Europe selon le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, et ainsi de suite. La chose est joliment mise en valeur par le simple encha\u00eenement des choses, dans cette d\u00e9p\u00eache AFP du <a href=\"http:\/\/www.spacewar.com\/reports\/NATO_Russia_agree_return_to_top_level_talks_999.html\" class=\"gen\">3 d\u00e9cembre<\/a>: <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The alliance is also concerned that proposals by Russian President Dmitry Medvedev for a new security pact in Europe are aimed at doing away with NATO, which Moscow fears is closing in on its borders. Russia has called for a new, legally binding security pact to replace what it says are outdated arms control treaties from the Cold War and to help avoid crises such as the brief war in Georgia.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At an EU-Russia summit in France last month, French President Nicolas Sarkozy called for a security summit with Russia under the auspices of the Organisation for Security and Cooperation in Europe (OSCE). The proposals are on the agenda of OSCE talks in Helsinki starting Thursday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But<\/em> [<em>NATO&rsquo;s Secretary General<\/em>] <em>Scheffer said NATO&rsquo;s 26 nations were satisfied with Europe&rsquo;s security structures and that he could not imagine them agreeing to anything that would undermine institutions including the European Union, OSCE and NATO. We are quite happy with the security structure as it exists in Europe, said Scheffer, at a press conference with Georgian Foreign Minister Eka Tkeshelashvili.<\/em>\u00bb<\/p>\n<h3>La valse postmoderne de l&rsquo;information<\/h3>\n<\/p>\n<p><p>\til est vrai qu&rsquo;aujourd&rsquo;hui, en Europe, se croisent et se m\u00e9langent des situations bien contrast\u00e9es, avec les commentaires officiels et les informations d\u00e9form\u00e9es \u00e0 mesure; entre les roucoulades furieuses des G\u00e9orgiens d\u00e9\u00e7us que le pr\u00e9nom Tar n&rsquo;ait pas convaincu leurs parrains occidentaux, l&rsquo;immobilisme plein de mouvements et presque hyst\u00e9rique de l&rsquo;OTAN, l&rsquo;absence am\u00e9ricaine avec un <em>President-elect<\/em> dont l&rsquo;activisme forcen\u00e9 ne concerne que la crise US, l&rsquo;activisme forcen\u00e9 avec les diverses propositions et d\u00e9clarations qui vont avec des Russes et des Fran\u00e7ais,  avec tout cela, la relativit\u00e9 parfois grotesque et souvent amusante de l&rsquo;information refl\u00e8te apr\u00e8s tout le d\u00e9rangement des choses et l&rsquo;impr\u00e9cision des lieux. L&rsquo;OTAN est plus que jamais le domaine du langage convenu et du double langage du conformisme. Il semble parfois qu&rsquo;on signe le communiqu\u00e9 d&rsquo;usage, qui ne semble \u00eatre qu&rsquo;un copi\u00e9-coll\u00e9 du pr\u00e9c\u00e9dent, sans se donner la peine de vraiment le lire. Le jeu des autorit\u00e9s otaniennes est de faire prendre ces convenances entre alli\u00e9s pour la r\u00e9alit\u00e9 de la politique. Les \u00e9v\u00e9nements sont si pressants qu&rsquo;on en arrive \u00e0 d&rsquo;amusantes contradictions, comme celle du secr\u00e9taire g\u00e9n\u00e9ral parlant au nom des 26 pour sembler ridiculiser, \u00e0 l&rsquo;ombre vertueuse de l&rsquo;ordre otanien et idyllique, une proposition dont l&rsquo;un des 26 est le parrain empress\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;OTAN est effectivement au centre du jeu, parce que c&rsquo;est sa place et qu&rsquo;elle ne sert plus \u00e0 rien, s&rsquo;agitant un peu d\u00e9sesp\u00e9r\u00e9ment pour faires savoir qu&rsquo;elle existe vraiment, et pour croire elle-m\u00eame qu&rsquo;elle existe toujours. La Commission europ\u00e9enne est actuellement l&rsquo;objet de sollicitations diverses en provenance de correspondants otaniens tout aussi divers, au niveau des relations bureaucratiques courantes, pour sugg\u00e9rer toutes les collaborations possibles dans le but \u00e9vident que l&rsquo;OTAN phagocyte des activit\u00e9s non-militaires qui lui donneraient une raison d&rsquo;exister autre qu&rsquo;une culott\u00e9e monumentale en Afghanistan ou un agrandissement rat\u00e9 en collaboration avec l&rsquo;ineffable Saakachvili. La consigne, \u00e0 la Commission, est d&rsquo;\u00e9carter de toute force ces sollicitations qui empi\u00e8tent sur son territoire; au moins la Commission a-t-elle ainsi, elle, le sentiment d&rsquo;exister et de compter.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une situation typique de l&rsquo;\u00e8re postmoderne, quand des forces importantes de changement, d\u00e9clench\u00e9es par des crises irr\u00e9sistibles, se manifestent alors qu&rsquo;on suppose que la consigne officielle est de repousser de toutes ses forces quelque changement que ce soit. Le r\u00e9sultat est cacophonique et contradictoire. Il s&rsquo;agit alors, pour tenter de saisir la r\u00e9alit\u00e9 de la situation, de s\u00e9parer l&rsquo;essentiel de l&rsquo;accessoire; cela n&rsquo;est finalement pas impossible, m\u00eame si la difficult\u00e9 est r\u00e9elle, dans la mesure o\u00f9 l&rsquo;accessoire, pour ne pas \u00eatre \u00e9limin\u00e9, entend poser des gestes essentiels qui, \u00e0 un moment ou l&rsquo;autre, se heurtant \u00e0 des refus polis mais fermes qui fixent les choses, apparaissent alors pour ce qu&rsquo;ils sont,  c&rsquo;est-\u00e0-dire accessoires. Ainsi en a-t-il \u00e9t\u00e9 de l&rsquo;adh\u00e9sion de la G\u00e9orgie et de l&rsquo;Ukraine. Les partisans de l&rsquo;\u00e9largissement auraient pu s&rsquo;\u00e9pargner cette piteuse mise en \u00e9vidence de l&rsquo;aspect bien accessoire de leurs propositions, en ne pressant pas les autres, en avril dernier \u00e0 Bucarest, pour qu&rsquo;on revienne sur la question en d\u00e9cembre. Ils le firent pourtant, sous l&rsquo;impulsion des Am\u00e9ricains de Bush, parce que les Am\u00e9ricains de Bush, comme d&rsquo;habitude, ne doutaient pas de l&#8217;emporter. Ils avaient oubli\u00e9 qu&rsquo;ils ne seraient plus tr\u00e8s influents \u00e0 cette \u00e9poque, puisqu&rsquo;en fin de mandat, et qu&rsquo;en attendant Saakachvili se serait employ\u00e9 \u00e0 cochonner son dossier en lan\u00e7ant une attaque qu&rsquo;il annon\u00e7ait \u00e0 ses parrains washingtoniens depuis longtemps, et qu&rsquo;il n&rsquo;avait plus l&rsquo;opportunit\u00e9 de lancer qu&rsquo;avant les \u00e9lections US, donc avant ce sommet de d\u00e9cembre. <\/p>\n<\/p>\n<p><p>\tLes autres affaires sont de la m\u00eame eau. En cherchant \u00e0 chaque occasion \u00e0 faire r\u00e9affirmer sous l&#8217;emprise du conformisme de l&rsquo;unanimit\u00e9 otanienne des positions qui contredisent totalement les politiques de certains des membres de ladite Organisation, le parti des immobilistes finit par provoquer des tensions trop importantes entre ce conformisme et la r\u00e9alit\u00e9. Ainsi pousse-t-il, non pas \u00e0 la faute, mais \u00e0 des prises de position qui constituent des attaques d\u00e9structurantes contre le syst\u00e8me conformiste qui p\u00e8se sur l&rsquo;Europe. Ainsi provoque-t-on des incidents qui peuvent engendrer des ruptures.<\/p>\n<\/p>\n<p><p>\tCes constats renforcent la perception d&rsquo;une situation o\u00f9 la difficult\u00e9 est moins de disposer d&rsquo;informations \u00e0 son propos, que de distinguer dans la masse d&rsquo;informations disponibles lesquelles sont essentielles et lesquelles sont accessoires. Il n&rsquo;y a aucun cr\u00e9dit particulier \u00e0 accorder aux sources officielles, y compris les plus hautes, tant ces sources ont pris l&rsquo;habitude de consid\u00e9rer l&rsquo;information comme une partie de leur politique ou, plus g\u00e9n\u00e9ralement, d&rsquo;ignorer elles-m\u00eames quelles sont les informations essentielles et les informations accessoires. Il y a m\u00eame tout lieu de consid\u00e9rer les sources officielles comme les moins cr\u00e9dibles, les moins \u00e9clair\u00e9es, les moins int\u00e9ressantes parmi les sources disponibles, sinon pour nous informer sur les faiblesses et les erreurs de ceux qui les utilisent. Les organismes les plus puissants sont aujourd&rsquo;hui prisonniers de leur pesanteur et de leur conformisme et s&rsquo;aventurent dans des interpr\u00e9tations ou des appr\u00e9ciations totalement d\u00e9nu\u00e9es de fondement, et qui p\u00e2lissent de ridicule par rapport aux \u00e9valuations et analyses de r\u00e9seaux priv\u00e9s qui ont la vertu essentielle de l&rsquo;ind\u00e9pendance. La fonction de l&rsquo;information est aujourd&rsquo;hui bien plus difficile qu&rsquo;elle n&rsquo;a jamais \u00e9t\u00e9 mais aussi bien plus lib\u00e9r\u00e9e qu&rsquo;elle n&rsquo;a jamais \u00e9t\u00e9; pour autant, cela ne signifie pas que l&rsquo;information soit libre (d\u00e9nu\u00e9e de pressions et de pesanteurs), ni juste d&rsquo;elle-m\u00eame par cons\u00e9quent, mais qu&rsquo;elle est assez multiple et assez complexe pour \u00eatre lib\u00e9r\u00e9e, quand elle est bien conduite, de ses pressions et de ses pesanteurs. Il suffit de le savoir et d&rsquo;agir en cons\u00e9quence. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confusions europ\u00e9ennes et r\u00e9v\u00e9latrices 4 d\u00e9cembre 2008 Les ministres des affaires \u00e9trang\u00e8res des pays de l&rsquo;OTAN viennent de se rencontrer (les 2 et 3 d\u00e9cembre) \u00e0 Bruxelles. L&rsquo;OSCE se r\u00e9unit \u00e0 partir d&rsquo;aujourd&rsquo;hui \u00e0 Helsinki. Autour de ces r\u00e9unions \u00e9voluent divers probl\u00e8mes importants, sinon centraux, qui concernent la s\u00e9curit\u00e9 europ\u00e9enne, qui ont \u00e9t\u00e9 fortement r\u00e9activ\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[7767,7769,4314,2631,3662,3329,398,5519,3100,7940,584,4205,4299],"class_list":["post-70380","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-adhesion","tag-architecture","tag-bmde","tag-de","tag-desinformation","tag-elargissement","tag-europe","tag-georgie","tag-information","tag-officielles","tag-otan","tag-securite","tag-sources"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70380"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70380\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}