{"id":70435,"date":"2008-12-31T11:34:56","date_gmt":"2008-12-31T11:34:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/31\/staline-homme-de-lannee\/"},"modified":"2008-12-31T11:34:56","modified_gmt":"2008-12-31T11:34:56","slug":"staline-homme-de-lannee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/12\/31\/staline-homme-de-lannee\/","title":{"rendered":"Staline, homme de l&rsquo;ann\u00e9e?"},"content":{"rendered":"<p><h2 class=\"common-article\">Staline, homme de l&rsquo;ann\u00e9e?<\/h2>\n<\/p>\n<p><p>\t31 d\u00e9cembre 2008  C&rsquo;est avec une grande d\u00e9solation que la station de t\u00e9l\u00e9vision russe <em>Rossiya<\/em>, l&rsquo;une des plus grandes de ce grand pays, a donn\u00e9 les r\u00e9sultats d&rsquo;une grande enqu\u00eate effectu\u00e9e sur plusieurs mois en 2008, et qui a touch\u00e9 plus de 50 millions de citoyens par tous les moyens de communication possibles. L&rsquo;enqu\u00eate, dont <em>BBC.News<\/em> donne quelques d\u00e9tails le <a href=\"http:\/\/news.bbc.co.uk\/go\/pr\/fr\/-\/2\/hi\/europe\/7802485.stm\" class=\"gen\">28 d\u00e9cembre<\/a> portait sur la d\u00e9termination du plus grand Russe de tous les temps. Cinq cents noms avaient \u00e9t\u00e9 s\u00e9lectionn\u00e9s, qui aboutirent \u00e0 une pr\u00e9-s\u00e9lection finale de douze, puis de huit. Le r\u00e9sultat est que nous avons \u00e9vit\u00e9 de justesse que Joseph Staline soit ce Russe-l\u00e0,  bien qu&rsquo;il f\u00fbt G\u00e9orgien de pure souche, ce qui a sa signification en ce moment. Il arrive finalement troisi\u00e8me apr\u00e8s, semble-t-il, d&rsquo;\u00e9tranges interventions des promoteurs de cette vaste initiative de recensement du sentiment russe actuel. (On est d\u00e9mocrate ou on ne l&rsquo;est pas.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Stalin  born an ethnic Georgian  was riding high for many months and was in the number one slot at one point until the show&rsquo;s producer appealed to viewers to vote for someone else, says the BBC&rsquo;s Richard Galpin in Moscow.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe vainqueur, le plus grand Russe de tous les temps, est honorablement le grand Alexander Nevsky, le chevalier du XIII\u00e8me si\u00e8cle qui repoussa les envahisseurs venus de l&rsquo;Occident et pr\u00e9serva l&rsquo;unit\u00e9 de la Sainte Russie; le second, \u00e9galement fort honorable mais cette fois pour nos consciences d\u00e9mocratiques, est le Premier ministre Piotr Arkadievitch Stolypine, homme politique r\u00e9formiste, assassin\u00e9 en 1911; et le troisi\u00e8me, enfin, est Joseph Staline. Quelle affreuse surprise, pour cette troisi\u00e8me place,  qui aurait pu \u00eatre la premi\u00e8re! (Parmi les autres class\u00e9s imm\u00e9diatement derri\u00e8re Staline, la grande Catherine, Dosto\u00efevski, Pierre le Grand, Ivan le Terrible)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Former Soviet dictator Joseph Stalin was beaten by medieval prince Alexander Nevsky in a poll held by a TV station to find the greatest Russian. Stalin came third, despite being responsible for the deaths of millions of Soviets in labour camps and purges. Alexander Nevsky fought off European invaders in the 13th century to preserve a united Russia. In second place was reformist Prime Minister Pyotr Stolypin, who was assassinated in 1911.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>More than 50 million people voted by phone, the internet or via text messages in the poll held by Rossiya, one of Russia&rsquo;s biggest television stations. The voting took place over six months as 500 original candidates were whittled down to a final 12.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement, les promoteurs et animateurs de cette immense enqu\u00eate sont perplexes, sinon angoiss\u00e9s et inquiets. La troisi\u00e8me place donn\u00e9e \u00e0 l&rsquo;un des plus terribles et sanglants dictateurs de l&rsquo;Histoire semble une sorte de myst\u00e8re effrayant. La chose appara\u00eet comme un symbole de la situation russe et, plus gravement encore, un symbole de la situation de notre temps historique.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Many in Russia do still revere Stalin for his role during World War II when the Soviet Union defeated the forces of Nazi Germany. But now there is a much broader campaign to rehabilitate Stalin and it seems to be coming from the highest levels of government, says our correspondent.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We now have to think very seriously, why the nation chooses to put<\/em> [Joseph]<em> Stalin in third place, said actor and film director Nikita Mikhalkov, one of the contest&rsquo;s judges, after the results were released.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette enqu\u00eate et ce choix si perturbateurs pour l&rsquo;esprit interviennent dans les nouvelles courantes \u00e0 un moment \u00e9videmment important, pour la Russie et pour le reste, et ils sont un bon reflet de l&rsquo;importance de ce moment. L&rsquo;ann\u00e9e 2008 a \u00e9t\u00e9 importante pour la Russie elle-m\u00eame d&rsquo;un double point de vue: d&rsquo;un c\u00f4t\u00e9, il y a eu une affirmation tonitruante de la puissance retrouv\u00e9e de la Russie (la crise g\u00e9orgienne en ao\u00fbt) et, dans tous les cas, au travers du soutien qu&rsquo;a re\u00e7u le gouvernement russe dans cette crise, l&rsquo;affirmation populaire de la fiert\u00e9 russe retrouv\u00e9e, de la puissance russe, de l&rsquo;identit\u00e9 nationale, etc.; d&rsquo;un autre c\u00f4t\u00e9, presque en m\u00eame temps, \u00e0 partir de septembre, les effets de la crise accompagnant la chute brutale du prix du p\u00e9trole apr\u00e8s une hausse tout aussi brutale, qui ont plac\u00e9 la Russie dans une situation pr\u00e9caire, avec la possibilit\u00e9, largement \u00e9voqu\u00e9e par les commentateurs occidentaux, de troubles sociaux devant des conditions sociales rendues plus difficiles. C&rsquo;est justement pendant ces six mois que Joseph Staline a failli \u00eatre \u00e9lu selon un processus d\u00e9mocratique qui l&rsquo;aurait \u00e9moustill\u00e9, et qu&rsquo;il s&rsquo;est impos\u00e9 tout de m\u00eame comme le troisi\u00e8me plus grand Russe de tous les temps. Il est difficile d&rsquo;\u00e9carter le constat qu&rsquo;il y a un rapport entre les \u00e9v\u00e9nements et les r\u00e9sultats de l&rsquo;enqu\u00eate de <em>Rossiya<\/em>.<\/p>\n<\/p>\n<p><p>\tApr\u00e8s la chute du communisme et la p\u00e9riode d&rsquo;anarchie \u00e9conomique et sociale qui a suivi l&rsquo;arriv\u00e9e au pouvoir d&rsquo;Eltsine, p\u00e9riode activ\u00e9e par l&rsquo;interventionnisme \u00e9conomique des USA pour imposer un syst\u00e8me dont le monde entier peut aujourd&rsquo;hui go\u00fbter les fruits dans la crise syst\u00e9mique g\u00e9n\u00e9rale, le communisme, plus encore que Staline bien s\u00fbr, avait connu un certain regain de popularit\u00e9 dans la population. Ce regain correspondait \u00e0 un r\u00e9flexe de survivance, une nostalgie pour un syst\u00e8me qui, malgr\u00e9 ses travers et ses vices, assurait une certaine stabilit\u00e9 et une certaine s\u00e9curit\u00e9 sociales. Le regain de popularit\u00e9 de Staline ajoute une nouvelle dimension, plus proche de la r\u00e9alit\u00e9; il correspond \u00e0 la perception de la r\u00e9affirmation de l&rsquo;identit\u00e9 nationale au travers de l&rsquo;id\u00e9e de puissance attach\u00e9e \u00e0 Staline. Outre son r\u00f4le dans la conduite de la guerre contre l&rsquo;Allemagne (r\u00f4le un peu forc\u00e9 au d\u00e9part, et sans gloire excessive, par contre avec une cruaut\u00e9 extr\u00eame et des qualit\u00e9s strat\u00e9giques approximatives dans l&#8217;emploi des troupes russes), une appr\u00e9ciation assez r\u00e9pandue \u00e0 cet \u00e9gard est celle-ci: Malgr\u00e9 toutes les souffrances qu&rsquo;il a caus\u00e9es, Staline reste l&rsquo;homme qui a fait passer la Russie au niveau de la super-puissance qu&rsquo;elle occupe depuis 1945. Une telle appr\u00e9ciation m\u00e9riterait \u00e9videmment d&rsquo;\u00eatre plac\u00e9e dans son contexte, qui est que Staline, et le communisme avec lui, ont r\u00e9ussi cet exploit,  et \u00e0 quel prix!  apr\u00e8s avoir tr\u00e8s largement contribu\u00e9 \u00e0 la destruction de la puissance russe, jusque dans la p\u00e9riode qui suivit la r\u00e9volution de f\u00e9vrier 1917 (ferment r\u00e9volutionnaire dans l&rsquo;arm\u00e9e russe, capitulation <em>de facto<\/em> avec le trait\u00e9 de Brest-Litovsk de mars 1918, d\u00e9structuration g\u00e9n\u00e9rale et destructions avec la guerre civile, etc.). Mais cette sorte de sentiment populaire qu&rsquo;on examine ici ne pr\u00e9tend certainement pas \u00eatre une le\u00e7on d&rsquo;histoire; elle est plut\u00f4t l&rsquo;expression d&rsquo;une psychologie dans une situation politique pr\u00e9sente, et la popularit\u00e9 de Staline exprime autant un r\u00e9flexe de fiert\u00e9 russe, d&rsquo;affirmation de puissance (la super-puissance), qu&rsquo;un r\u00e9flexe d\u00e9fensif national contre les pressions ext\u00e9rieures (la d\u00e9fense contre l&rsquo;Allemagne jusqu&rsquo;\u00e0 la victoire). <\/p>\n<\/p>\n<p><p>\tMais on ne peut s&rsquo;en tenir l\u00e0 pour le commentaire.<\/p>\n<h3>Qu&rsquo;avons-nous fait de la chute du Mur?<\/h3>\n<\/p>\n<p><p>\tCe choix de Staline \u00e0 cette position, dans une enqu\u00eate si significative par son caract\u00e8re massif, est un fait symbolique bien significatif. Staline est bien ce qu&rsquo;il est,  un homme exceptionnel par sa cruaut\u00e9 autant personnelle que politique, son absence totale de sensibilit\u00e9 et d&rsquo;intelligence humaine dans sa politique, sa capacit\u00e9 vicieuse d&rsquo;\u00e9liminer ses compagnons soup\u00e7onn\u00e9s d&rsquo;un jour devenir des rivaux, sa brutalit\u00e9 bureaucratique dans l&rsquo;organisation du totalitarisme, sa responsabilit\u00e9 directe et av\u00e9r\u00e9e dans la mise en place d&rsquo;un syst\u00e8me sans exemple de s\u00e9lection et de contrainte id\u00e9ologiques et bureaucratiques par la contrainte psychologique et l&rsquo;\u00e9limination syst\u00e9matique de la personne physique au nom de principes \u00e9galement id\u00e9ologiques et bureaucratiques dont la vacuit\u00e9 permettait d&rsquo;inclure \u00e0 peu pr\u00e8s n&rsquo;importe qui dans les accusations et l&rsquo;\u00e9limination. (L&rsquo;un des traits caract\u00e9ristiques du syst\u00e8me policier stalinien est que personne ne pouvait se croire \u00e0 l&rsquo;abri de son action d&rsquo;\u00e9limination, tant les accusations que portait ce syst\u00e8me \u00e9taient vagues et adaptables \u00e0 n&rsquo;importe qui et \u00e0 n&rsquo;importe quelle situation. M\u00eame les membres de l&rsquo;\u00e9quipe Staline, comme l&rsquo;a rapport\u00e9 Krouchtchev, allaient \u00e0 une invitation \u00e0 d\u00eener du chef avec la peur au ventre d&rsquo;\u00eatre soudainement arr\u00eat\u00e9 durant le d\u00eener sur un ordre de Staline.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;ampleur de la liquidation et de l&rsquo;\u00e9puration permanentes, en m\u00eame temps que la force de la pression de communication de d\u00e9ification du chef (sorte de pression formidable de la communication de propagande), \u00e9taient telles qu&rsquo;on en arrivait \u00e0 concevoir qu&rsquo;il s&rsquo;agissait de l&rsquo;initiative de subordonn\u00e9s \u00e9chappant au contr\u00f4le de Staline. C&rsquo;\u00e9tait une remarque courante durant la <em>Iejotchina<\/em> (la p\u00e9riode de I\u00e9jov, du nom du chef du NKVD de l&rsquo;\u00e9poque, Nicolas I\u00e9jov, entre 1936 et 1939), notamment chez les intellectuels du r\u00e9gime menac\u00e9s d&rsquo;\u00e9limination, d&rsquo;affirmer que Staline n&rsquo;\u00e9tait pas au courant, et qu&rsquo;il suffirait de l&rsquo;en aviser pour faire cesser la Grande Terreur de 1936-39. Les fun\u00e9railles de Staline, en mars 1953, montr\u00e8rent \u00e9galement cette stup\u00e9fiante ambivalence, de voir une population victime d&rsquo;une telle oppression, sous la pression inou\u00efe et contradictoire de la terreur polici\u00e8re permanente et de la sacralisation du chef, montrer un tel d\u00e9sespoir, proche de l&rsquo;absolu, de la mort du dictateur qui avait ordonn\u00e9, aux deux sens du mot, cette oppression. M\u00eame dans les camps de l&rsquo;\u00e9limination sans fin du <em>Goulag<\/em>, nombre de d\u00e9tenus exon\u00e9rait Staline de toute responsabilit\u00e9 dans leur sort atroce. De ce point de vue d&rsquo;une situation de plusieurs d\u00e9cennies de la psychologie collective tortur\u00e9e et absolument d\u00e9form\u00e9e, en plus de l&rsquo;\u00e9limination physique, Staline et le stalinisme pr\u00e9sentent un cas unique dans l&rsquo;Histoire. A la terreur polici\u00e8re absolue s&rsquo;ajoutait une terreur tout aussi absolue de la communication, de d\u00e9ification paradoxale du dictateur impitoyable. Dans un tel univers g\u00e9n\u00e9ral o\u00f9 les r\u00e9f\u00e9rences normales d&rsquo;un \u00eatre \u00e9taient absolument saccag\u00e9es, l&rsquo;univers mental est effectivement totalement d\u00e9form\u00e9.<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de cela, Staline montra des qualit\u00e9s politiques de force sans contr\u00f4le, de cynisme et de duret\u00e9, qui donn\u00e8rent effectivement des r\u00e9sultats au niveau de la puissance d&rsquo;apparence de l&rsquo;URSS. (Le cas de la Deuxi\u00e8me Guerre mondiale est compl\u00e8tement \u00e0 part. Staline, pour se sauver et sauver son pouvoir et le pays par cons\u00e9quent, dut capituler en abandonnant toute la communication dialectique sur le communisme, et en le rempla\u00e7ant par une communication dialectique sur la nation et la d\u00e9fense de la Sainte Russie, et ainsi susciter un formidable \u00e9lan patriotique russe. Cela ne l&#8217;emp\u00eacha pas de mener la guerre avec son habituelle cruaut\u00e9, notamment pour ses propres soldats russes, et de montrer, semble-t-il, de pi\u00e8tres qualit\u00e9s strat\u00e9giques.) On ne sait si cette d\u00e9marche o\u00f9 l&rsquo;on pourrait trouver des qualit\u00e9s politiques \u00e0 Staline doit \u00eatre jug\u00e9e politiquement, ou s&rsquo;il ne faut y voir qu&rsquo;une retomb\u00e9e in\u00e9vitable du syst\u00e8me g\u00e9n\u00e9ral de terreur polici\u00e8re et de terreur de la communication que Staline avait mis en place, assurant par sa contrainte m\u00eame des opportunit\u00e9s politiques. Quoi qu&rsquo;il en soit, ce sont ces derniers points,  ses soi disant qualit\u00e9s politiques et patriotiques,  que la m\u00e9moire historique de nombreux Russes retient aujourd&rsquo;hui de Staline, comme le montre l&rsquo;enqu\u00eate. Cette attitude psychologique des Russes est explicable en tr\u00e8s grande partie, sinon exclusivement, par le traitement absurde, injuste et stupide que l&rsquo;Occident soi disant victorieuse a appliqu\u00e9 \u00e0 la Russie depuis 1989 (l&rsquo;Occident soi disant victorieuse&rsquo;,  alors que la chute du communisme est essentiellement due \u00e0 Gorbatchev, comme on ne doit cesser de le r\u00e9p\u00e9ter, au contraire de la pieuse <a href=\"http:\/\/www.dedefensa.org\/article-le_role_de_reagan_dans_l_effondrement_du_communisme_07_06_2004.html?admin=1\" class=\"gen\">l\u00e9gende<\/a> sur le r\u00f4le de Reagan et du sacro-saint militarisme US).<\/p>\n<\/p>\n<p><p>\tL&rsquo;aveuglement complet et l&rsquo;injustice fondamentale de l&rsquo;Occident, pour cette s\u00e9quence, sont \u00e0 dater de la chute du Mur de novembre 1989. Nous cr\u00fbmes que l&rsquo;Europe de l&rsquo;Est se lib\u00e9rait du joug du communisme (cette croyance, \u00e9vident transfert psychologique d&rsquo;un Occident, particuli\u00e8rement les USA en 1956 et en 1968, qui n&rsquo;a jamais rien fait pour pour venir en aide \u00e0 l&rsquo;Europe de l&rsquo;Est durant la Guerre froide apr\u00e8s s&rsquo;\u00eatre abstenu de la d\u00e9fendre \u00e0 la fin de la Seconde Guerre mondiale). La r\u00e9alit\u00e9 se d\u00e9cline en deux parties: 1) l&rsquo;Europe de l&rsquo;Est ne se lib\u00e9rait pas <em>stricto sensu<\/em>, c&rsquo;est Gorbatchev qui avait d\u00e9cid\u00e9 qu&rsquo;on ne ferait rien contre les mouvements de lib\u00e9ration qui se d\u00e9veloppaient; 2) ce n&rsquo;est pas l&rsquo;Europe de l&rsquo;Est seulement qui \u00e9tait lib\u00e9r\u00e9e du joug communiste, mais aussi et d&rsquo;abord la Russie. Quand on rappelle ce que Staline a <strong>impos\u00e9<\/strong> d&rsquo;une fa\u00e7on dictatoriale \u00e0 la Russie, sous les applaudissements contemporains de la foule des idiots utiles occidentaux, innombrables chez les intellectuels dont les fils et h\u00e9ritiers spirituels d\u00e9noncent la Russie aujourd&rsquo;hui, comment ne pas comprendre que la Russie fut \u00e9videmment <strong>victime<\/strong> du communisme, encore plus que l&rsquo;Europe de l&rsquo;Est elle-m\u00eame? Qu&rsquo;elle avait autant sinon plus droit \u00e0 la sollicitude, \u00e0 l&rsquo;attention et au respect de l&rsquo;Occident que l&rsquo;Europe de l&rsquo;Est? Au contraire, on la traita comme on le sait, comme une pestif\u00e9r\u00e9e et une vaincue, autant \u00e0 cause de la d\u00e9formation historique de l&rsquo;hostilit\u00e9 n\u00e9e de la Guerre froide et de la vanit\u00e9 du syst\u00e8me lib\u00e9ral occidental croyant \u00e0 sa sup\u00e9riorit\u00e9 historique, que selon les lignes habituelles de <a href=\"http:\/\/www.dedefensa.org\/article-de_la_mediocrite_des_origines_de_la_crise_05_09_2008.html\" class=\"gen\">la m\u00e9diocrit\u00e9 barbare<\/a> d&rsquo;un syst\u00e8me (le n\u00f4tre) incapable de suivre autre chose que les instincts pr\u00e9dateurs et cupides de sa logique corrompue. Les qualificatifs nous manquent<\/p>\n<\/p>\n<p><p>\tAlors, puisqu&rsquo;il le faut, l&rsquo;esprit russe se replie, dans un r\u00e9flexe de d\u00e9fi et de fiert\u00e9 nationale, sur le souvenir du seul homme qui effraya et trompa l&rsquo;Occident, qui mena la lutte contre l&rsquo;Allemagne hitl\u00e9rienne, malgr\u00e9 les souffrances inou\u00efe que la Russie endura de son fait. En fait de g\u00e2chis, on ne fait pas mieux. Cela dit, nous pouvons commencer \u00e0 g\u00e9mir sur le manque de sens d\u00e9mocratique, \u00e0 l&rsquo;image de notre superbe exemple, dont font preuve les Russes en s\u00e9lectionnant Staline. G\u00e9missons, g\u00e9missons, puisqu&rsquo;il ne nous reste que cela pour justifier notre civilisation. Quel pi\u00e8tre temps historique. Comment peut-on \u00eatre civilis\u00e9?, aurait demand\u00e9 Montesquieu. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Staline, homme de l&rsquo;ann\u00e9e? 31 d\u00e9cembre 2008 C&rsquo;est avec une grande d\u00e9solation que la station de t\u00e9l\u00e9vision russe Rossiya, l&rsquo;une des plus grandes de ce grand pays, a donn\u00e9 les r\u00e9sultats d&rsquo;une grande enqu\u00eate effectu\u00e9e sur plusieurs mois en 2008, et qui a touch\u00e9 plus de 50 millions de citoyens par tous les moyens de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3670,4034,2631,4739,398,4852,8017,3574,8015,8016,8014,2730,4561,3744],"class_list":["post-70435","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-berlin","tag-communisme","tag-de","tag-enquete","tag-europe","tag-goulag","tag-iejov","tag-lest","tag-mur","tag-nkvd","tag-policiere","tag-russie","tag-staline","tag-terreur"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70435"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70435\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}