{"id":70453,"date":"2009-01-09T12:46:32","date_gmt":"2009-01-09T12:46:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/09\/la-turbo-crise-accelere-comme-cest-son-role\/"},"modified":"2009-01-09T12:46:32","modified_gmt":"2009-01-09T12:46:32","slug":"la-turbo-crise-accelere-comme-cest-son-role","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/09\/la-turbo-crise-accelere-comme-cest-son-role\/","title":{"rendered":"La \u201cturbo-crise\u201d acc\u00e9l\u00e8re (comme c&rsquo;est son r\u00f4le)"},"content":{"rendered":"<p><h2 class=\"common-article\">La turbo-crise acc\u00e9l\u00e8re (comme c&rsquo;est son r\u00f4le)<\/h2>\n<\/p>\n<p><p>\t9 janvier 2009  Les occasions sont rares (mais de moins en moins, apr\u00e8s tout) o\u00f9 l&rsquo;on peut voir simultan\u00e9ment les \u00e9v\u00e9nements se presser sur des fronts diff\u00e9rents, en une occurrence qui semble \u00eatre l&rsquo;Histoire m\u00eame en train de se faire. Un jour comme ce 9 janvier 2009, avec les nouvelles qui sont publi\u00e9es, ressemble \u00e0 une telle occasion, illustrant d&rsquo;ailleurs une p\u00e9riode d&rsquo;une intensit\u00e9 extraordinaire,  mais l&rsquo;extraordinaire tendant \u00e0 devenir notre ordinaire, apr\u00e8s tout (<em>bis<\/em>). La p\u00e9riode de la transition entre deux pr\u00e9sidents aux USA, qui est actuellement l&rsquo;\u00e9v\u00e9nement qui borne la p\u00e9riode et qui impliquait traditionnellement une pause dans la progression des affaires, \u00e9chappe compl\u00e8tement au contr\u00f4le du calendrier humain. (Curiosit\u00e9 de la chose: on annon\u00e7ait une grande crise internationale pour tester Obama devenu pr\u00e9sident. D\u00e9sormais, on teste avant&#8230; Ou bien, cela n&rsquo;a rien \u00e0 voir avec un test? Toutes les hypoth\u00e8ses sont accept\u00e9es&#8230;)<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, 9 janvier 2009, on voit donc l&rsquo;acc\u00e9l\u00e9ration des \u00e9v\u00e9nements sur trois fronts diff\u00e9rents, dont on sait pourtant qu&rsquo;ils sont li\u00e9s entre eux par une extraordinaire intensit\u00e9 et par un rythme insens\u00e9 des \u00e9v\u00e9nements qui les caract\u00e9risent. (C&rsquo;est dans tous les cas, ce on sait, notre hypoth\u00e8se \u00e0 nous.)<\/p>\n<\/p>\n<p><p>\t La crise de Gaza entre dans une phase chaotique, entre les \u00e9v\u00e9nements sur le terrain et les \u00e9v\u00e9nements autour des \u00e9v\u00e9nements sur le terrain. Le constat du jour est que les USA se trouvent dans l&rsquo;obligation d&rsquo;accepter une certaine implication \u00e0 laquelle ils se sont refus\u00e9s jusqu&rsquo;ici. Par cons\u00e9quent, leur action est indirecte, fragment\u00e9e, faite de r\u00e9actions officielles improvis\u00e9es ou d&rsquo;informations officieuses pressantes. Le vote du Conseil de S\u00e9curit\u00e9 de l&rsquo;ONU demandant un cessez-le-feu \u00e0 Gaza, par 14 voix et l&rsquo;abstention des USA est une illustration de cette situation. M\u00eame si les Fran\u00e7ais et les Britanniques esp\u00e9raient un vote positif (Rice ayant elle-m\u00eame particip\u00e9 \u00e0 l&rsquo;\u00e9laboration du texte), la chose est ainsi d\u00e9crite par le <em>Times<\/em> <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/middle_east\/article5479673.ece\" class=\"gen\">aujourd&rsquo;hui<\/a>: \u00ab<em>The US decision to allow the Security Council to call for a ceasefire in a formal resolution undercuts the Israelis&rsquo; continued military operations in Gaza and left Israeli officials fuming.<\/em> [..] <em>The abstention, nevertheless, marked an about-face by the United States just days after it blocked any Security Council action to bring the fighting to an end.<\/em> [] <em>It represents a rare break between Israel and the United States<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Parall\u00e8lement, le <em>Guardian<\/em> annonce, <a href=\"http:\/\/www.guardian.co.uk\/world\/2009\/jan\/08\/barack-obama-gaza-hamas\" class=\"gen\">aujourd&rsquo;hui<\/a> encore, tenir de bonnes sources que l&rsquo;administration Obama devrait entreprendre des contacts avec le Hamas \u00e0 un niveau moyen, chose jusqu&rsquo;ici absolument proscrite de la politique US. D&rsquo;une fa\u00e7on tr\u00e8s caract\u00e9ristique, le processus est d\u00e9crit comme devant se faire selon des normes l&rsquo;apparentant \u00e0 un processus secret, mais il est annonc\u00e9, par l&rsquo;interm\u00e9diaire du <em>Guardian<\/em>, avec un luxe de d\u00e9tails et de pr\u00e9cisions qui fait s&rsquo;interroger sur la signification du secret en question. (Peu importe puisque ce qui importe est qu&rsquo;on diffuse au moins la nouvelle de l&rsquo;intention.) Les causes avanc\u00e9es concernent autant une volont\u00e9 de tenter de d\u00e9bloquer la situation que celle de faire rentrer les USA dans une crise dont ils ont \u00e9t\u00e9 compl\u00e8tement absents.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The incoming Obama administration is prepared to abandon George Bush&rsquo;s doctrine of isolating Hamas by establishing a channel to the Islamist organisation, sources close to the transition team say.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The move to open contacts with Hamas, which could be initiated through the US intelligence services, would represent a definitive break with the Bush presidency&rsquo;s ostracising of the group. The state department has designated Hamas a terrorist organisation, and in 2006 Congress passed a law banning US financial aid to the group.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Guardian has spoken to three people with knowledge of the discussions in the Obama camp. There is no talk of Obama approving direct diplomatic negotiations with Hamas early on, but he is being urged by advisers to initiate low-level or clandestine approaches, and there is growing recognition in Washington that the policy of ostracising Hamas is counter-productive. A tested course would be to start contacts through Hamas and the US intelligence services, similar to the secret process through which the US engaged with the PLO in the 1970s. Israel did not become aware of the contacts until much later.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Mais il y a sans doute, ou bien \u00e9videmment, une autre raison dans cette \u00e9volution US. Il s&rsquo;agit de la situation aux USA, qu&rsquo;Obama et ses conseillers <a href=\"http:\/\/www.independent.co.uk\/news\/world\/americas\/obama-us-faces-economic-ruin-if-you-donrsquot-back-me-1242612.html\" class=\"gen\">jugent<\/a> de plus en plus dramatique, et qui n\u00e9cessite une mobilisation extr\u00eame. Cette mobilisation passe par la n\u00e9cessit\u00e9 de tenter de contenir les crises ext\u00e9rieures trop pressantes, notamment celle de Gaza; et l&rsquo;\u00e9quation actuelle, notamment les positions internationales de plus en plus affirm\u00e9es de malaise ou d&rsquo;hostilit\u00e9 devant l&rsquo;action d&rsquo;Isra\u00ebl, implique \u00e9ventuellement les ouvertures qu&rsquo;on a vues. Quoi qu&rsquo;il en soit, il y a aussi, aux USA, dans l&rsquo;\u00e9valuation qu&rsquo;on fait de la crise \u00e9conomique, une acc\u00e9l\u00e9ration et une dramatisation sans pr\u00e9c\u00e9dent. Obama parle d\u00e9sormais d&rsquo;une catastrophe \u00e9conomique si des d\u00e9cisions ne sont pas prises dans les semaines qui viennent, voire dans les jours qui suivront son inauguration. L&rsquo;atmosph\u00e8re commence \u00e0 ressembler effectivement \u00e0 celle de l&rsquo;inauguration de FDR le 5 mars 1933.<\/p>\n<\/p>\n<p><p>\t La crise du gaz en Europe, entre l&rsquo;Ukraine et la Russie avec des effets directs extr\u00eamement s\u00e9v\u00e8res en Europe devient, elle aussi, dramatique et pressante, quelles qu&rsquo;en soient les orientations (l\u00e0 aussi, on parle du climat de la chose). La Russie et l&rsquo;Ukraine \u00e9tant en d\u00e9saccord commercial (dans l&rsquo;atmosph\u00e8re qu&rsquo;on imagine, vues les relations politiques), le gaz russe vers l&rsquo;Europe passant notamment par l&rsquo;Ukraine, la Russie accusant l&rsquo;Ukraine de pr\u00e9lever du gaz pour elle-m\u00eame alors que la Russie ne veut plus lui en livrer,  tout cela a conduit \u00e0 la d\u00e9cision russe de couper tous leurs envois \u00e0 et par l&rsquo;Ukraine (dont ceux pour l&rsquo;Europe). Il fait froid et nombre de pays europ\u00e9ens sont en difficult\u00e9s. La Commission europ\u00e9enne va envoyer des observateurs en Ukraine (avec <a href=\"http:\/\/fr.rian.ru\/world\/20090109\/119401172.html\" class=\"gen\">accord<\/a> des Russes) pour enqu\u00eater sur la situation et d\u00e9terminer les responsabilit\u00e9s. L&rsquo;OTAN se r\u00e9unit et annonce qu&rsquo;il faut faire quelque chose, qu&rsquo;elle va faire quelque chose Un lecteur, commentant l&rsquo;article du <em>Times<\/em> <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/europe\/article5477684.ece\" class=\"gen\">de ce jour<\/a> sur la r\u00e9action de l&rsquo;OTAN, observe sarcastiquement: \u00ab<em>Let&rsquo;s see NATO soldiers coming to rescue by cutting some wood for their allies. How else are they going to help, go to war over unpaid bills of a country which is not even a NATO member? In that case at least they won&rsquo;t face the questions about WMDs.<\/em>\u00bb<\/p>\n<h3>On bouche les voies d&rsquo;eau comme on peut<\/h3>\n<\/p>\n<p><p>\tNous utilisons cette expression de turbo-crise (dans notre titre) dans la rubrique <em>de defensa<\/em> de notre Lettre d&rsquo;Analyse <em>dd&#038;e<\/em>, dans le num\u00e9ro du 10 janvier 2009. Pour rendre \u00e0 C\u00e9sar ce dont C\u00e9sar a la paternit\u00e9 indirecte, nous y pr\u00e9cisons ceci:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>En 1996, pour d\u00e9signer le nouveau capitalisme lanc\u00e9 par l&rsquo;\u00e9quipe Clinton (la chose vient de loin&#8230;), Edward Lutwak inventa le terme de turbo-capitalisme. On comprend ce qu&rsquo;il veut dire, et on le comprit encore mieux en 1997 et en 1998 lorsqu&rsquo;une crise n\u00e9e de cette pression am\u00e9ricaniste et clintonienne balaya divers pays (de la Tha\u00eflande \u00e0 la Russie, \u00e0 l&rsquo;Argentine, etc.). Nous avons donc, en plus de la crise syst\u00e9mique qui est aussi une crise de civilisation, qui est peut-\u00eatre et m\u00eame sans doute une crise de l&rsquo;esp\u00e8ce,  nous avons donc la turbo-crise en r\u00e9ponse au turbo-capitalisme. Car l&rsquo;une de ses caract\u00e9ristiques est \u00e9galement la surprise et la vitesse, c&rsquo;est-\u00e0-dire son rythme infernal, son tempo, son beat comme disent les musiciens de jazz et ceux dont le surnom lui doit tout (les beatniks).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEh bien, le <em>beat<\/em> acc\u00e9l\u00e8re, la turbo-crise avec Tous ces \u00e9v\u00e9nements (Gaza, Obama, le gaz russe) pourraient \u00eatre per\u00e7us comme n&rsquo;ayant gu\u00e8re de liens directs entre eux, sauf qu&rsquo;ils ont l&rsquo;essentiel en commun, qui est le rythme justement, qui nous est impos\u00e9. On peut s&rsquo;acharner \u00e0 tenter de comprendre ces crises, c&rsquo;est-\u00e0-dire les causes profondes, les intentions cach\u00e9es, les manigances; y arriverait-on, gr\u00e2ce \u00e0 notre imagination prolixe pour trouver des plans et des manigances diverses, qu&rsquo;on n&rsquo;y aurait encore rien compris du tout. Ce qu&rsquo;il importe de saisir et de mesurer, c&rsquo;est le rythme des choses, qui passe par ce qui est commun \u00e0 toutes ces crises, qui est la d\u00e9stabilisation g\u00e9n\u00e9rale et commune, intervenue avec les \u00e9v\u00e9nements de l&rsquo;automne 2008, de situations diverses d\u00e9j\u00e0 tr\u00e8s d\u00e9stabilis\u00e9es elles-m\u00eames. A ce moment-l\u00e0, seulement, touche-t-on la substance de la chose, qui fait que ces crises sont diff\u00e9rentes de ce qu&rsquo;elles sont en g\u00e9n\u00e9ral,  disons de ce qu&rsquo;elles sont d&rsquo;habitude, si ce terme d&rsquo;habitude n&rsquo;\u00e9tait un peu contradictoire avec ce qu&rsquo;est une crise en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est pourtant le cas. La turbo-crise rend toutes les autres crises, les crises sectorielles, r\u00e9gionales, etc., compl\u00e8tement inhabituelles. Pour cette raison, il est vain de vouloir les comprendre pour ce qu&rsquo;elles sont d&rsquo;habitude, avec le risque en plus de partir sur des chemins de traverse passant par les sp\u00e9culations si tentantes pour l&rsquo;esprit \u00e0 propos des manigances, des manuvres secr\u00e8tes, des plans myst\u00e9rieux et grandioses qui ne se r\u00e9alisent jamais l\u00e0 o\u00f9 on les attend, etc. Si les USA font ce qui semble \u00eatre des concessions par rapport \u00e0 leur politique rigide pro-isra\u00e9lienne, c&rsquo;est moins parce qu&rsquo;ils ont des intentions, voire un plan quelconque, que parce qu&rsquo;ils sentent, Obama et Bush unis \u00e0 cet \u00e9gard, que la situation leur \u00e9chappe compl\u00e8tement. Les projets d&rsquo;Obama de parler au Hamas font partie de la s\u00e9quence: on lance un ballon d&rsquo;essai pour tenter de reprendre la main,  mais moins, beaucoup moins, pour un but r\u00e9gional pr\u00e9cis (disons offensif) que pour tenter de stabiliser le front du Moyen-Orient en paraissant y \u00eatre \u00e0 nouveau pr\u00e9sent, et ainsi r\u00e9duire cette pression ext\u00e9rieure; parce que, pour ce cas pr\u00e9cis, ce qui importe est la situation int\u00e9rieure US, la crise \u00e9conomique et psychologique catastrophique, et qu&rsquo;Obama veut y disposer du maximum de libert\u00e9 d&rsquo;action. M\u00eame si parler avec le Hamas para\u00eet r\u00e9volutionnaire par rapport au courant habituel, c&rsquo;est en fait une mesure plut\u00f4t stabilisatrice pour sortir d&rsquo;une position radicale pro-isra\u00e9lienne qui tend \u00e0 devenir intenable pour les USA, par rapport \u00e0 leur statut g\u00e9n\u00e9ral dans le monde et \u00e0 leur situation de crise int\u00e9rieure. On conviendra aussi et surtout que c&rsquo;est mettre un \u00e9vidence le lien entre tous ces \u00e9v\u00e9nements, et ce lien est le rythme de la turbo-crise.<\/p>\n<\/p>\n<p><p>\tOn raisonne trop, en raisonnant de fa\u00e7on compartiment\u00e9 pour chaque crise, comme si les acteurs avaient les mains libres, pour notamment suivre leur plan secret,  puisqu&rsquo;il para\u00eet qu&rsquo;ils en ont. La r\u00e9alit\u00e9 est que nous sommes tous sur la d\u00e9fensive, press\u00e9s, bouscul\u00e9s, balad\u00e9s par la turbo-crise. Le temps des <em>neocons<\/em> et de leur d\u00e9lire hallucin\u00e9 est pass\u00e9. Nous en sommes, aujourd&rsquo;hui, \u00e0 tenter de boucher les voies d&rsquo;eau qui se d\u00e9clarent partout, prisonniers du rythme de la turbo-crise que notre syst\u00e8me a enfant\u00e9e.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La turbo-crise acc\u00e9l\u00e8re (comme c&rsquo;est son r\u00f4le) 9 janvier 2009 Les occasions sont rares (mais de moins en moins, apr\u00e8s tout) o\u00f9 l&rsquo;on peut voir simultan\u00e9ment les \u00e9v\u00e9nements se presser sur des fronts diff\u00e9rents, en une occurrence qui semble \u00eatre l&rsquo;Histoire m\u00eame en train de se faire. Un jour comme ce 9 janvier 2009, avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3228,4751,4967,3955,2774,2730,8034,1296],"class_list":["post-70453","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-crise","tag-economique","tag-gaz","tag-gaza","tag-israel","tag-russie","tag-turbo-crise","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70453"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70453\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}