{"id":70459,"date":"2009-01-12T14:45:34","date_gmt":"2009-01-12T14:45:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/12\/premiere-rencontre-exterieure-de-bho-le-voisin-du-sud\/"},"modified":"2009-01-12T14:45:34","modified_gmt":"2009-01-12T14:45:34","slug":"premiere-rencontre-exterieure-de-bho-le-voisin-du-sud","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/12\/premiere-rencontre-exterieure-de-bho-le-voisin-du-sud\/","title":{"rendered":"Premi\u00e8re rencontre ext\u00e9rieure de BHO: le voisin du Sud"},"content":{"rendered":"<p><p>C&rsquo;est une tradition nous assure Barack Obama, dit BHO. Quoi qu&rsquo;il en soit, le premier dirigeant \u00e9tranger que le <em>President-elect<\/em> rencontre de fa\u00e7on tout \u00e0 fait officielle, aujourd&rsquo;hui m\u00eame, une semaine avant son inauguration, est bien le pr\u00e9sident mexicain Felipe Calderon. Reuters nous pr\u00e9sente, <a href=\"http:\/\/www.reuters.com\/article\/politicsNews\/idUSTRE50A1QB20090112\" class=\"gen\">ce jour<\/a>, la rencontre qui aura lieu dans quelques heures. Il n&rsquo;est nullement dissimul\u00e9, bien entendu, que sera prioritairement abord\u00e9e la question de la guerre de la drogue, ou de la guerre int\u00e9rieure mexicaine qui d\u00e9borde \u00e9videmment sur les USA, telle que nous l&rsquo;avons \u00e9voqu\u00e9e le <a href=\"http:\/\/www.dedefensa.org\/article-le_desordre_par_le_sud_10_01_2009.html\" class=\"gen\">10 janvier 2009<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>U.S. President-elect Barack Obama will discuss the drug war and trade issues with Mexican President Felipe Calderon on Monday, in Obama&rsquo;s first meeting with a foreign leader since his November election.<\/em>[] <em>Obama aides said the Calderon meeting was part of a long tradition of U.S. presidents meeting with the Mexican leader before their inauguration.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>One of Calderon&rsquo;s priorities is to press Obama to follow through on a U.S. aid program launched by Bush in 2007 to help Mexico combat the drug trade. The Mexican president is battling drug traffickers blamed for killing 5,650 people last year. Mexican Foreign Minister Patricia Espinosa told a news conference on Friday that it was vital to push ahead with the $1.4 billion drug aid package known as the Merida Initiative. So far nearly $300 million of aid has been freed up, but the first equipment is unlikely to arrive until late this year.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Obama adviser, who spoke on condition of anonymity, said Obama viewed the effort to combat drug trafficking as a shared challenge for both our countries. As worried as we are about the northbound drug trade, we&rsquo;re also worried about the southbound weapons and cash flows that impact the drug war, the adviser said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the May speech in Miami, Obama praised Calderon&rsquo;s tough stance against drug trafficking and vowed to support his efforts. We need tougher border security, and a renewed focus on busting up gangs and traffickers crossing our border. But we must address the material heading south as well, Obama said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes autres sujets des entretiens sont li\u00e9s, eux aussi,\u00e0 l&rsquo;\u00e9tat g\u00e9n\u00e9ral de tension qui se d\u00e9veloppe sur la fronti\u00e8re commune  et en fonction des conditions \u00e9conomiques et sociales sp\u00e9cifiques, y compris bien s\u00fbr cette omnipr\u00e9sente guerre de la drogue. Les Mexicains sont inquiets des \u00e9ventuelles pressions de l&rsquo;administration Obama pour modifier l&rsquo;accord ALENA, pour r\u00e9duire l&rsquo;acc\u00e8s au march\u00e9 US; ils sont inquiets des retomb\u00e9es de la crise \u00e9conomique aux USA, qui touche particuli\u00e8rement la communaut\u00e9 mexicaine-am\u00e9ricaine, qui r\u00e9duit l&rsquo;apport d&rsquo;argent de cette communaut\u00e9 vers le Mexique (par le biais des liens familiaux et autres), qui implique par cons\u00e9quent un accroissement des difficult\u00e9s au Mexique et une pression renouvel\u00e9e pour l&rsquo;immigration ill\u00e9gale vers les USA.<\/p>\n<\/p>\n<p><p>\tTout en d\u00e9plorant cette immigration ill\u00e9gale, dont ils chargent les USA d&rsquo;une bonne part de responsabilit\u00e9, les Mexicains veulent que les USA r\u00e9duisent certaines barri\u00e8res et contraintes l\u00e9gales pour l&rsquo;int\u00e9gration de ces immigrants ill\u00e9gaux; ils veulent que des facilit\u00e9s soient accord\u00e9es au franchissement des biens et autres exportations, c&rsquo;est-\u00e0-dire en \u00e9largissant certaines disposition d&rsquo;ALENA au contraire de ce qu&rsquo;Obama a promis \u00e0 certains de ses \u00e9lecteurs, et qu&rsquo;en m\u00eame temps l&rsquo;immigration soit mieux contr\u00f4l\u00e9e, mais sans des restrictions humiliantes,  et ainsi de suite, puisque les relations entre les USA et le Mexique, quels que soient les hommes en place et les soup\u00e7ons qu&rsquo;on porte contre eux, sont d&rsquo;abord un tissu complexe de contradictions quasiment inconciliables et insolubles.<\/p>\n<\/p>\n<p><p>\tQuoi qu&rsquo;il en soit et quoi que dise la tradition, cette rencontre Obama-Calderon a une forte signification politique. Il n&rsquo;est pas question, au menu, du terrorisme plus ou moins mythique, de l&rsquo;\u00e9poque 9\/11-GW, mais bel et bien d&rsquo;une guerre en cours, qui fait rage tous les jours, et menace de d\u00e9stabiliser jusqu&rsquo;\u00e0 l&rsquo;effondrement l&rsquo;Etat mexicain. Il n&rsquo;est pas question de mobilisation strat\u00e9gique dans le style Cheney-<em>neocon<\/em> mais bien de relations tendues et d\u00e9licates, dans le cadre de l&rsquo;effondrement de la globalisation et de la crise syst\u00e9mique qui fait rage et d\u00e9vaste l&rsquo;\u00e9conomie aux USA. Les relations entre les USA et le Mexique abordent r\u00e9solument la nouvelle \u00e9poque, post-bushiste.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 12 janvier 2009 \u00e0 14H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une tradition nous assure Barack Obama, dit BHO. Quoi qu&rsquo;il en soit, le premier dirigeant \u00e9tranger que le President-elect rencontre de fa\u00e7on tout \u00e0 fait officielle, aujourd&rsquo;hui m\u00eame, une semaine avant son inauguration, est bien le pr\u00e9sident mexicain Felipe Calderon. Reuters nous pr\u00e9sente, ce jour, la rencontre qui aura lieu dans quelques heures. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3760,5561,2631,4019,5217,2645,3330,2622,2943,8042,6208,3300,2804],"class_list":["post-70459","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alena","tag-calderon","tag-de","tag-drogue","tag-frontiere","tag-guerre","tag-immigration","tag-la","tag-mexique","tag-narco-trafiquants","tag-obama","tag-sud","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70459"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70459\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}