{"id":70463,"date":"2009-01-14T16:07:01","date_gmt":"2009-01-14T16:07:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/14\/anatomie-de-la-depression\/"},"modified":"2009-01-14T16:07:01","modified_gmt":"2009-01-14T16:07:01","slug":"anatomie-de-la-depression","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/14\/anatomie-de-la-depression\/","title":{"rendered":"Anatomie de la d\u00e9pression"},"content":{"rendered":"<p><p>Il est \u00e9videmment int\u00e9ressant de rapporter cette remarque, et mesurant aussit\u00f4t sa justesse,  qu&rsquo;il y a un an, le monde des experts d\u00e9battait avec gravit\u00e9 de savoir si les USA \u00e9taient ou non en r\u00e9cession, avec nombre de sceptiques s\u00fbrs d&rsquo;une Am\u00e9rique assez puissante pour \u00e9viter cet avatar,  et qu&rsquo;aujourd&rsquo;hui on d\u00e9bat de savoir <strong>quand<\/strong> il faudra bien admettre que nous sommes entr\u00e9s dans une d\u00e9pression. C&rsquo;est le commentateur de UPI Martin Walker qui, le <a href=\"http:\/\/www.terradaily.com\/reports\/Walkers_World_Depression_looms_999.html\" class=\"gen\">11 janvier 2009<\/a>, fait cette remarque: \u00ab<em>This time last year, many economists were still debating whether the United States was entering or already experiencing a recession. That debate is over. The question now is whether we are entering a depression and how great or modest it will be.<\/em>\u00bb  <\/p>\n<\/p>\n<p><p>\tLa formulation est int\u00e9ressante, soit dit en passant. Effectivement, on s&rsquo;interrogeait l&rsquo;ann\u00e9e derni\u00e8re, \u00e0 propos de la r\u00e9cession, sur le sort des USA en particulier, et fort peu du <em>Rest Of the World<\/em>. Le propos \u00e9tait en g\u00e9n\u00e9ral plein de jactance, comme si l&rsquo;aspect assez b\u00e9nin de la chose (une r\u00e9cession) permettait effectivement de d\u00e9velopper la r\u00e9flexion \u00e0 propos des USA, \u00e9tant sous entendu que cette b\u00e9nignit\u00e9 impliquait par contraste que la puissance de ces m\u00eames USA les mettait \u00e0 l&rsquo;abri d&rsquo;un accident plus grave. Aujourd&rsquo;hui qu&rsquo;il est question de d\u00e9pression, il est question d&rsquo;un \u00e9v\u00e9nement mondial, ce qui permet de sortir de la singularit\u00e9 US pour un diagnostic qui met en cause le syst\u00e8me lui-m\u00eame, att\u00e9nuant d&rsquo;autant la responsabilit\u00e9 US bien que le syst\u00e8me soit 100% <em>made in USA<\/em>.<\/p>\n<\/p>\n<p><p>\tPour autant et par contraste avec la tendance pr\u00e9c\u00e9dente, le texte de Walker confirme un autre aspect de la r\u00e9flexion qu&rsquo;on retrouve de plus en plus souvent chez les commentateurs US. La fiction du ch\u00f4mage US r\u00e9duit gr\u00e2ce \u00e0 des artifices de m\u00e9thodologie est maintenant syst\u00e9matiquement mise \u00e0 jour et \u00e9cart\u00e9e, avec la pr\u00e9cision du v\u00e9ritable taux de ch\u00f4mage,  non plus un peu plus de 7% mais quelque part entre 12% et 15%. (\u00ab<em>In the United States, 524,000 payroll jobs were lost in December, having lost 2.6 million jobs in the year. The conventional unemployment rate has risen to 7.2 percent, but includes workers who are now off the rolls and forced part-time work, and the true jobless rate is already in double digits, with the economy contracting at about 5 percent annual rate in the fourth quarter.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tL&rsquo;aspect le plus int\u00e9ressant du billet de Walker concerne la d\u00e9finition de la d\u00e9pression. Walker cite un \u00e9conomiste, le professeur Peter Morici, ancien chef de l&rsquo;analyse \u00e9conomique au d\u00e9partement du commerce.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Does this mean we are heading into a depression? Professor Peter Morici of the University of Maryland, formerly the chief economist for the U.S. trade representative and one of the best forecasters in the business, has an interesting definition of the difference between recession and depression.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Recessions, he maintains, are self-correcting, like stock market corrections that eventually rebound without government intervention. Federal Reserve interest rate cuts and stimulus tax rebates and spending have shortened the lives and eased the impact of post-World War II recessions, but those policies did not end them. The economy self-corrected.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By contrast, he argues, A depression is not self-correcting. Roosevelt administration stimulus packages  huge deficit spending  eased the pain but failed to end the Great Depression. Similarly, President-elect Obama&rsquo;s massive stimulus package, alone, won&rsquo;t fix the U.S. economy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Morici identifies three structural problems of the current crisis that are not self-correcting and will require robust government intervention. The first is bad management practices at the large money center banks. The second is the huge foreign trade deficit, and the third is part of the second: the dependence on imported energy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The economy will not recover without fundamental changes in banking and trade policy, Morici believes. A large stimulus package, though necessary, will only give the economy a temporary lift, but then unemployment will rise again and continue at unacceptable levels indefinitely without successively larger stimulus packages and huge federal budget deficits. The economy is in a depression, not a recession.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes, la r\u00e9cession est un accident temporaire \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un syst\u00e8me qui fonctionne bien en g\u00e9n\u00e9ral alors que la d\u00e9pression est une maladie grave, sinon irr\u00e9versible, qui indique un vice fondamental du syst\u00e8me. La question qui se pose alors est de savoir quel \u00e9v\u00e9nement, selon la d\u00e9finition du professeur Morici, a repr\u00e9sent\u00e9 vraiment une d\u00e9pression dans l&rsquo;histoire \u00e9conomique de la modernit\u00e9 (de l&rsquo;industrialisation), mis \u00e0 part ce qui se passe actuellement. Si l&rsquo;on s&rsquo;en tient \u00e0 la r\u00e9f\u00e9rence US, le seul \u00e9v\u00e9nement de cette sorte est la Grande D\u00e9pression, et l&rsquo;on constate alors qu&rsquo;il n&rsquo;y a pas eu de rem\u00e8de fondamental appliqu\u00e9 \u00e0 cette maladie mortelle; l&rsquo;\u00e9conomie US s&rsquo;est poursuivie avec des exp\u00e9dients, le premier \u00e9tant la Deuxi\u00e8me Guerre mondiale, le second \u00e9tant la re-mobilisation pour la Guerre froide (notamment avec le <a href=\"http:\/\/www.dedefensa.org\/article-quelques_elements_de_reflexions_sur_le_complexe_militaro-industriel_son_passe_son_present_et_son_avenir_radieux_12_02_2003.html\" class=\"gen\">montage<\/a> de la panique anti-sovi\u00e9tique de 1948 qui permit le sauvetage de l&rsquo;industrie a\u00e9ronautique encha\u00eenant sur la mobilisation de l&rsquo;industrie de l&rsquo;armement de 1949-1950,  bombe atomique sovi\u00e9tique et guerre de Cor\u00e9e); le reste de la p\u00e9riode, l&rsquo;\u00e9conomie soutenue par la position du dollar, l&rsquo;endettement US, l&rsquo;expansionnisme militaire comme moyen de pression et\/ou de chantage, aboutissant \u00e0 l&rsquo;aggravation de ces derni\u00e8res ann\u00e9es jusqu&rsquo;au paroxysme de 2008.<\/p>\n<\/p>\n<p><p>\tBien entendu, le terme de d\u00e9pression ajoute, par l&rsquo;une de ses significations parall\u00e8les, la dimension psychologique qui tend \u00e0 faire sortir le ph\u00e9nom\u00e8ne du seul domaine \u00e9conomique (nous avons beaucoup \u00e9crit l\u00e0-dessus <a href=\"http:\/\/www.dedefensa.org\/article-precisions_sur_fdr_et_la_grande_depression_20_09_2008.html\" class=\"gen\">\u00e0 propos<\/a> de la Grande D\u00e9pression). De ce point de vue, il faut revenir sur l&rsquo;excellente trouvaille de Niall Ferguson, que nous signalions le <a href=\"http:\/\/www.dedefensa.org\/article-chronique_de_l_appointe_du_systeme_31_12_2008.html\" class=\"gen\">31 d\u00e9cembre 2008<\/a>, du terme de <em>Great Repression<\/em>. Ferguson \u00e9crivait notamment, \u00e0 partir d&rsquo;un texte de politique-fiction \u00e9crit comme si l&rsquo;on \u00e9tait en d\u00e9cembre 2009:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Great Repression began in August 2007 and reached its nadir in 2009. It was clearly not a Great Depression on the scale of the 1930s, when output in the US declined by as much as a third and unemployment reached 25 per cent. Nor was it merely a Big Recession. As output in the developed world continued to decline throughout 2009  despite the best efforts of central banks and finance ministries  the tag Great Repression seemed more and more apt: though this was the worst economic crisis in 70 years, many people remained in deep denial about it.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNotre commentaire \u00e9tait le suivant: \u00ab<em>La trouvaille est excellente. Outre l&rsquo;explication<\/em> [] <em>que donne Ferguson, et qui est tr\u00e8s juste (une majorit\u00e9 d\u00e9niant la crise), nous y ajouterions que le mot Depression repr\u00e9sente une composition harmonieuse de recession et de depression; qu&rsquo;il signifie en anglais refoulement (sens que sugg\u00e8re Ferguson), mais aussi et plus directement r\u00e9pression (sens qui laisserait pas mal \u00e0 penser, notamment que la crise fut machin\u00e9e par Washington, involontairement ou pas, pour torpiller le reste de l&rsquo;\u00e9conomie du monde?) Bref, le prince de l&rsquo;Ambigu\u00eft\u00e9.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement se pose la question de savoir si nous ne nous trouvons pas dans une d\u00e9pression refoul\u00e9e, donc le terme de <em>repression<\/em> (refoulement) convenant \u00e0 merveille; dans ce cas, la dimension psychologique est d&rsquo;autant plus pr\u00e9sente et prend l&rsquo;allure d&rsquo;un d\u00e9ni virtualiste de la r\u00e9alit\u00e9 de la d\u00e9pression, qui est aussi le signe de la maladie mortelle du syst\u00e8me, de son effondrement in\u00e9luctable et ainsi de suite. Ce refoulement serait d&rsquo;ailleurs aussi bien le cas des \u00e9lites que des opinions publiques, ces \u00e9lites n&rsquo;ayant aucune capacit\u00e9 s\u00e9rieuse de freiner ou de r\u00e9soudre la crise et pratiquant souvent le refoulement par cons\u00e9quent; quant aux opinions publiques, on parlerait aussi bien de r\u00e9serve, voire d&rsquo;indiff\u00e9rence aux \u00e9v\u00e9nements dans leur signification ontologique, voire de satisfaction dans certains cas pour les perspectives de destruction du syst\u00e8me qu&rsquo;implique cette signification ontologique.<\/p>\n<\/p>\n<p><p>\tLa d\u00e9finition de la d\u00e9pression par Morici ouvre d&rsquo;ailleurs la perspective supr\u00eame. Que sont ces <em>fundamental changes in banking and trade Policy<\/em> dont parle Morici? Encore s&rsquo;en tient-il \u00e0 ces seuls aspects, rendant compte de sympt\u00f4mes US de la crise, qui ne sont manifestement pas suffisants pour d\u00e9finir et expliquer la crise. Que se passe-t-il si les <em>fundamental changes<\/em> n\u00e9cessaires d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale ne peuvent \u00eatre faits, s&rsquo;il n&rsquo;y a pas d&rsquo;accord pour les faire, ou bien, plus radicalement, si l&rsquo;on ne r\u00e9ussit pas \u00e0 les d\u00e9terminer? C&rsquo;est la question de l&rsquo;apr\u00e8s-crise; c&rsquo;est l&rsquo;hypoth\u00e8se de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-comment_une_crise_peut_en_cacher_beaucoup_beaucoup_d_autres_08_12_2008.html\" class=\"gen\">il n&rsquo;y a plus d&rsquo;apr\u00e8s<\/a> (la crise) Cette question de l&rsquo;il n&rsquo;y a plus d&rsquo;apr\u00e8s prolonge d&rsquo;une fa\u00e7on implacablement logique l&rsquo;interpr\u00e9tation que les USA ne sont jamais <a href=\"http:\/\/www.dedefensa.org\/article-1929_jusqu_au_bout_19_12_2008.html\" class=\"gen\">vraiment sortis<\/a> de la Grande D\u00e9pression, et que cette Grande Crise qui est entr\u00e9e dans sa p\u00e9riode paroxystique le 15 septembre 2008,  qui en serait alors le moment de v\u00e9rit\u00e9 jusqu&rsquo;ici repouss\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 janvier 2009 \u00e0 16H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est \u00e9videmment int\u00e9ressant de rapporter cette remarque, et mesurant aussit\u00f4t sa justesse, qu&rsquo;il y a un an, le monde des experts d\u00e9battait avec gravit\u00e9 de savoir si les USA \u00e9taient ou non en r\u00e9cession, avec nombre de sceptiques s\u00fbrs d&rsquo;une Am\u00e9rique assez puissante pour \u00e9viter cet avatar, et qu&rsquo;aujourd&rsquo;hui on d\u00e9bat de savoir quand&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3083,4048,2891,8047,3725,8046,5168],"class_list":["post-70463","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-depression","tag-ferguson","tag-grande","tag-morici","tag-recession","tag-repression","tag-walker"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70463"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70463\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}