{"id":70474,"date":"2009-01-20T09:51:54","date_gmt":"2009-01-20T09:51:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/20\/la-russie-et-leurope-premier-enjeu-dobama\/"},"modified":"2009-01-20T09:51:54","modified_gmt":"2009-01-20T09:51:54","slug":"la-russie-et-leurope-premier-enjeu-dobama","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/20\/la-russie-et-leurope-premier-enjeu-dobama\/","title":{"rendered":"La Russie (et l&rsquo;Europe), premier enjeu d&rsquo;Obama"},"content":{"rendered":"<p><p>Nous sommes alternativement en accord et en d\u00e9saccord avec les analyses de George Friedman, de <em>Stratfor.com<\/em>, selon les sujets, selon le mode de traitement des sujets, voire selon l&rsquo;humeur des choses. Cette fois, ce serait plut\u00f4t un accord, sur le sujet du premier grand enjeu de politique ext\u00e9rieure de BHO, le nouveau pr\u00e9sident US. \u00ab<em>Obama Enters the Great Game<\/em>\u00bb, nous dit Friedman ce <a href=\"http:\/\/www.stratfor.com\/weekly\/20090119_obama_enters_great_game\" class=\"gen\">19 janvier 2009<\/a>. Le th\u00e8me est une question: mises \u00e0 part les surprises, sur quoi on ne peut par d\u00e9finition supputer, quel est le premier grand dossier qui attend BHO \u00e0 la Maison Blanche?<\/p>\n<\/p>\n<p><p>\tLa r\u00e9ponse est : la Russie,  mise \u00e0 part la crise \u00e9conomique US, qui est \u00e9videmment la premi\u00e8re priorit\u00e9 des priorit\u00e9s, cela va de soi, et donc hors cat\u00e9gorie de classement. (Pour cette crise, Friedman rappelle, comme il est bon de le faire \u00e0 chaque fois que l&rsquo;on analyse son importance,  soulign\u00e9 en gras par nous: \u00ab<em>The most important issue Obama will face will be the economy, something he<\/em> <strong><em>did not anticipate<\/em><\/strong> <em>through most of his campaign.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t&#8230;La Russie, c&rsquo;est-\u00e0-dire le point central d&rsquo;un ensemble de tensions ou de crises prioritaires pour le nouveau pr\u00e9sident. D&rsquo;une part, l&rsquo;Afghanistan, o\u00f9 une nouvelle strat\u00e9gie (si l&rsquo;on admet qu&rsquo;il y en une en cours) doit \u00eatre d\u00e9velopp\u00e9e, impliquant notamment des arrangements nouveaux avec les pays europ\u00e9ens engag\u00e9s dans le conflit; surtout, impliquant de r\u00e9gler en priorit\u00e9 le probl\u00e8me du ravitaillement des forces en ouvrant une nouvelle ligne de ravitaillement, ce qui implique d&rsquo;une fa\u00e7on ou l&rsquo;autre la Russie (soit en obtenant sa coop\u00e9ration avec la ligne passant par la Russie, soit en suscitant son opposition et d&rsquo;\u00e9normes difficult\u00e9s avec la ligne contournant la Russie par le Sud). D&rsquo;autre part, les relations de la Russie avec l&rsquo;Europe, notamment \u00e0 la suite de la courte et int\u00e9ressante <a href=\"http:\/\/www.dedefensa.org\/article-la_guerre_du_gaz_a_bien_eu_lieu_18_01_2009.html \" class=\"gen\">guerre du gaz<\/a> mais aussi avec d&rsquo;autres questions en suspens comme le r\u00e9seau anti-missiles BMDE, tout cela impliquant un r\u00e9ajustement des relations USA-Russie, et d&rsquo;une certaine fa\u00e7on des relations des USA avec l&rsquo;Europe.<\/p>\n<\/p>\n<p><p>\tAyant pass\u00e9 en revue ces diff\u00e9rents points puis envisag\u00e9 les concessions que demanderont les Russes, notamment pour la question strat\u00e9gique centrale du ravitaillement de l&rsquo;OTAN en Afghanistan, Friedman conclut qu&rsquo;il faudra que l&rsquo;administration Obama refonde ses relations avec la Russie dans le sens d&rsquo;un accommodement<\/p>\n<\/p>\n<p><p>\t\u00ab<em>We expect the Russians to make variations on all these demands in exchange for cooperation in creating a supply line to Afghanistan. Simply put, the Russians will demand that the United States acknowledge a Russian sphere of influence in the former Soviet Union. The Americans will not want to concede this  or at least will want to make it implicit rather than explicit. But the Russians will want this explicit, because an explicit guarantee will create a crisis of confidence over U.S. guarantees in the countries that emerged from the Soviet Union, serving as a lever to draw these countries into the Russian orbit. U.S. acquiescence on the point potentially would have ripple effects in the rest of Europe, too.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Therefore, regardless of the global financial crisis, Obama has an immediate problem on his hands in Afghanistan. He has troops fighting there, and they must be supplied. The Pakistani supply line is no longer a sure thing. The only other options either directly challenge Russia (and ineffectively at that) or require Russian help. Russia&rsquo;s price will be high, particularly because Washington&rsquo;s European allies will not back a challenge to Russia in Georgia, and all options require Russian cooperation anyway. Obama&rsquo;s plan to recruit the Europeans on behalf of American initiatives won&rsquo;t work in this case. Obama does not want to start his administration with making a massive concession to Russia, but he cannot afford to leave U.S. forces in Afghanistan without supplies. He can hope that nothing happens in Pakistan, but that is up to the Taliban and other Islamist groups more than anyone else  and betting on their goodwill is not a good idea.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Whatever Obama is planning to do, he will have to deal with this problem fast, before Afghanistan becomes a crisis. And there are no good solutions. But unlike with the Israelis and Palestinians, Obama can&rsquo;t solve this by sending a special envoy who appears to be doing something. He will have to make a very tough decision. Between the economy and this crisis, we will find out what kind of president Obama is.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And we will find out very soon.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tFriedman a, nous semble-t-il, raison d&rsquo;envisager cette question de politique ext\u00e9rieure comme une urgence, plut\u00f4t que la question isra\u00e9lo-palestinienne \u00e0 la suite de la crise de Gaza. (\u00ab<em>The major challenge he faces is not Gaza; the Israeli-Palestinian dispute is not one any U.S. president intervenes in unless he wants to experience pain. As we have explained, that is an intractable conflict to which there is no real solution.<\/em>\u00bb.) Le cas de la Russie (avec l&rsquo;Europe et l&rsquo;Afghanistan) est une question en pleine \u00e9volution, dans laquelle Obama ne peut prendre le risque de ne pas \u00eatre pr\u00e9sent, d&rsquo;une fa\u00e7on active et, si possible, novatrice; Obama ne peut d&rsquo;autre part risquer de se charger d&rsquo;une crise avec la Russie, qui p\u00e8serait lourd alors qu&rsquo;il est si occup\u00e9 au niveau int\u00e9rieur. Dans le cas isra\u00e9lo-palestinien, il s&rsquo;agit d&rsquo;une crise enferm\u00e9e, d&rsquo;une crise paralys\u00e9e si l&rsquo;on veut, o\u00f9 m\u00eame l&rsquo;implication directe ne requiert de la part des USA aucune mobilisation particuli\u00e8re.<\/p>\n<\/p>\n<p><p>\tCette priorit\u00e9 euro-asiatique d&rsquo;Obama correspond \u00e0 l&rsquo;analyse que nous avons faite, depuis la crise g\u00e9orgienne et \u00e0 cause d&rsquo;elle, d&rsquo;un <a href=\"http:\/\/www.dedefensa.org\/article-du_sud_au_nord_la_crise_bascule.html\" class=\"gen\">basculement<\/a> du Sud vers le Nord des tensions prioritaires. La Russie est d\u00e9sormais pour les USA une affaire qui ne peut attendre, et l&rsquo;Europe et l&rsquo;Afghanistan non plus par cons\u00e9quent. (Et chacun de ces deux probl\u00e8mes compl\u00e9mentaires,  l&rsquo;Afghanistan et l&rsquo;Europe,  est \u00e0 consid\u00e9rer d\u00e9sormais prioritairement, pour les USA, en fonction des rapports qu&rsquo;il a avec la Russie et, d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, avec le Nord.) <\/p>\n<\/p>\n<p><p>\tL\u00e0-dessus vont s&rsquo;encha\u00eener d&rsquo;autres questions qui sont li\u00e9es \u00e0 cette probl\u00e9matique, notamment celle du d\u00e9ploiement du r\u00e9seau BMDE. Effectivement, diverses <a href=\"http:\/\/www.spacewar.com\/reports\/New_US_president_could_order_missile_shield_review_official_999.html\" class=\"gen\">indications<\/a> montrent que la question du BMDE est prioritaire pour l&rsquo;administration Obama,  plut\u00f4t, elles le confirment puisque cet int\u00e9r\u00eat a d\u00e9j\u00e0 \u00e9t\u00e9 mis <a href=\"http:\/\/www.dedefensa.org\/article-intuitions_polonaises_generalites_moscovites_serieux_doutes_washingtoniens_le_bmde_tremble_13_11_2008.html\" class=\"gen\">en \u00e9vidence<\/a> depuis l&rsquo;\u00e9lection du 4 novembre 2008.<\/p>\n<\/p>\n<p><p>\tLa logique implique effectivement une recherche de l&rsquo;apaisement. Cela correspond \u00e0 la tendance r\u00e9volutionnaire de la p\u00e9riode, o\u00f9 il faut rassembler ses forces pour la d\u00e9fensive; o\u00f9 nous passons de l&rsquo;\u00e9poque de la d\u00e9structuration g\u00e9opolitique, offensive et ext\u00e9rieure,  l&rsquo;\u00e9poque Bush\/<em>neocon<\/em>,  \u00e0 l&rsquo;\u00e9poque fondamentale de l&rsquo;affrontement de la crise syst\u00e9mique avec toutes ses cons\u00e9quences. Cela implique un renversement des tendances. Aujourd&rsquo;hui, c&rsquo;est la force hier d\u00e9structurante (les USA, ou plut\u00f4t le syst\u00e8me de l&rsquo;am\u00e9ricanisme), qui est elle-m\u00eame menac\u00e9e de d\u00e9structuration et se trouve compl\u00e8tement sur la d\u00e9fensive.  <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 20 janvier 2009 \u00e0 09H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes alternativement en accord et en d\u00e9saccord avec les analyses de George Friedman, de Stratfor.com, selon les sujets, selon le mode de traitement des sujets, voire selon l&rsquo;humeur des choses. Cette fois, ce serait plut\u00f4t un accord, sur le sujet du premier grand enjeu de politique ext\u00e9rieure de BHO, le nouveau pr\u00e9sident US. \u00abObama&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,4314,3907,398,1268,3349,6208,8053,2730,3160,3300],"class_list":["post-70474","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-bmde","tag-destructuration","tag-europe","tag-friedman","tag-nord","tag-obama","tag-renversement","tag-russie","tag-stratfor","tag-sud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70474"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70474\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}