{"id":70489,"date":"2009-01-27T17:00:52","date_gmt":"2009-01-27T17:00:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/27\/le-grand-jeu-ou-pourquoi-faire-simple-quand-on-peut-faire-complique\/"},"modified":"2009-01-27T17:00:52","modified_gmt":"2009-01-27T17:00:52","slug":"le-grand-jeu-ou-pourquoi-faire-simple-quand-on-peut-faire-complique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/01\/27\/le-grand-jeu-ou-pourquoi-faire-simple-quand-on-peut-faire-complique\/","title":{"rendered":"Le \u201cGrand Jeu\u201d, ou pourquoi faire simple quand on peut faire compliqu\u00e9"},"content":{"rendered":"<p><p>Certes, l&rsquo;administration Obama a choisi de d\u00e9placer le pion Afghanistan, d&rsquo;accentuer <a href=\"http:\/\/www.dedefensa.org\/article-l_afghanistan_et_les_contradictions_d_obama__26_01_2009.html\" class=\"gen\">son effort<\/a> dans le cur de cette crise. Non seulement trouve-t-on sur cette voie sp\u00e9culative l&rsquo;interrogation de la capacit\u00e9 des USA \u00e0 faire \u00e9voluer cette crise, m\u00eame au travers de cet effort et particuli\u00e8rement par le biais de cet effort, mais on observe \u00e9galement que cette orientation repr\u00e9sente elle-m\u00eame l&rsquo;apport d&rsquo;une consid\u00e9rable capacit\u00e9 d\u00e9tonante de plusieurs autres d\u00e9veloppements contradictoires de l&rsquo;effort US. Tout cela, sans surprise excessive.<\/p>\n<\/p>\n<p><p>\tL&rsquo;excellent M K Bhadrakumar, ancien diplomate indien devenu commentateur, et l&rsquo;un des meilleurs des affaires de la r\u00e9gion caucasienne et du sous-continent indien, nous livre un aper\u00e7u de l&rsquo;imbroglio o\u00f9 risquent de s&rsquo;engager les USA. M K Bhadrakumar  n&rsquo;a pas son pareil pour \u00e9clairer les imbroglios d&rsquo;une r\u00e9gion tr\u00e8s propice \u00e0 la chose. Son article se trouve sur <em>Atimes.com<\/em>, mis en ligne ce <a href=\"http:\/\/www.atimes.com\/atimes\/South_Asia\/KA27Df01.html\" class=\"gen\">27 janvier<\/a>. <\/p>\n<\/p>\n<p><p>\t M K Bhadrakumar d\u00e9marre sur la r\u00e9cente d\u00e9claration du g\u00e9n\u00e9ral David Petraeus, commandant Central Command, concernant un accord avec la Russie pour une voie de passage des approvisionnement vers l&rsquo;Afghanistan, par le Nord et la Russie. Un accord? Premi\u00e8re nouvelle, disent les Russes,  tout en pr\u00e9cisant qu&rsquo;ils ne sont pas contre<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia&rsquo;s ambassador to NATO, Dmitry Rogozin, added from Brussels, We know nothing of Russia&rsquo;s alleged agreement of military transit of Americans or NATO at large. There had been suggestions of the sort, but they were not formalized. And, with a touch of irony, Rogozin insisted Russia wanted the military alliance to succeed in Afghanistan.  I can responsibly say that in the event of NATO&rsquo;s defeat in Afghanistan, fundamentalists who are inspired by this victory will set their eyes on the north. First they will hit Tajikistan, then they will try to break into Uzbekistan &#8230; If things turn out badly, in about 10 years, our boys will have to fight well-armed and well-organized Islamists somewhere in Kazakhstan,<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Ce qui nous permet, au passage, d&rsquo;avoir quelques pr\u00e9cisions suppl\u00e9mentaires sur la situation, absolument surr\u00e9aliste reconnaissons-le, du ravitaillement des forces US par le Pakistan. Les pertes par emprunt, vol, pression, rachat, entourloupe, etc., sont colossales puisqu&rsquo;elles approchent 50% du volume des diverses mati\u00e8res, syst\u00e8mes, munitions, ravitaillement, etc., transport\u00e9s. Tout cela constitue la manne d&rsquo;une quasi-\u00e9conomie de march\u00e9 noir autour de la route de ravitaillement.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The shocking intelligence assessment shared by Moscow reveals that almost half of the US supplies passing through Pakistan is pilfered by motley groups of Taliban militants, petty traders and plain thieves. The US Army is getting burgled in broad daylight and can&rsquo;t do much about it. Almost 80% of all supplies for Afghanistan pass through Pakistan. The Peshawar bazaar is doing a roaring business hawking stolen US military ware, as in the 1980s during the Afghan jihad against the Soviet Union. This volume of business will register a quantum jump following the doubling of the US troop level in Afghanistan to 60,000. Wars are essentially tragedies, but can be comical, too.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t La question des voies d&rsquo;approvisionnement nouvelles \u00e0 \u00e9tablir, pour les forces US et de l&rsquo;OTAN, reste un sujet d\u00e9licat. S&rsquo;il y a certes celle du Nord, passant par la Russie, et dont on constate que le sort reste \u00e0 \u00eatre fix\u00e9, il y a aussi celle qui est plus m\u00e9ridionale, passant au Sud de la Russie, donc hors des fronti\u00e8res russes, qui est l&rsquo;objet d&rsquo;une f\u00e9roce bataille d&rsquo;influence entre Washington et Moscou. Les Russes per\u00e7oivent que la recherche d&rsquo;une telle route alternative de ravitaillement peut aussi ouvrir la voie \u00e0 d&rsquo;autres initiatives, celles-l\u00e0 beaucoup plus strat\u00e9giques et inqui\u00e9tantes pour Moscou. \u00ab<em>Russian experts estimate that the proposed Caspian transit route could eventually become an energy transportation route in reverse direction, which would mean a strategic setback for Russia in the decade-long struggle for the region&rsquo;s hydrocarbon reserves.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t D&rsquo;o\u00f9 un branle-bas des Russes dans diverses directions nouvelles. Par exemple mais exemple qu&rsquo;on appr\u00e9ciera comme singuli\u00e8rement r\u00e9jouissant, les Russes se rapprochent de Karza\u00ef, le pr\u00e9sident afghan.  Karza\u00ef ne dit pas non du tout, sentant \u00e9videmment son impopularit\u00e9 grandissante \u00e0 Washington, avant de rencontrer un Holbrooke qui ne devrait pas tarder \u00e0 d\u00e9bouler dans une quasi-mission d&rsquo;<em>Exterminator<\/em>, avec le r\u00e9gime afghan en place comme cible \u00e0 exterminer. Le rapprochement Moscou-Kaboul se fait souvent en contravention des accords secrets Kaboul-Washington, notamment pour la livraison d&rsquo;armes russes \u00e0 l&rsquo;Afghanistan qui serait une des voies explor\u00e9es. Karza\u00ef n&rsquo;en a pas vraiment cure, qui sent de plus en plus qu&rsquo;il n&rsquo;a plus grand&rsquo;chose \u00e0 perdre. Cette situation d\u00e9clenche par contrecoup des cons\u00e9quences en cha\u00eene. Moscou, pour verrouiller son initiative, a propos\u00e9 une conf\u00e9rence du SCO (Shangha\u00ef Cooperation Organization) sur l&rsquo;Afghanistan. Le SCO, cette chose terrible sino-russe, c&rsquo;est un peu le diable pour Washington. La conf\u00e9rence int\u00e9resse l&rsquo;Iran (diable!) et l&rsquo;Inde (allons!), qui y participeront comme observateurs atentifs,  c&rsquo;est-\u00e0-dire la puissance avec laquelle Washington voudrait parler et la puissance dont Washington juge qu&rsquo;elle est un nouvel alli\u00e9 s\u00fbr dans la r\u00e9gion La premi\u00e8re question \u00e9tant de savoir si Karza\u00ef va accepter l&rsquo;ouverture du SCO et participer \u00e0 la r\u00e9union au grand dam apoplectique de Washington, la seconde question,  assez \u00e9trange au demeurant,  devient de savoir et si Washington va parvenir \u00e0 l&rsquo;\u00e9liminer avant. (Eliminer sa marionnette mise en place il y a 7 ans pour contr\u00f4ler l&rsquo;Afghanistan au nom des USA? <em>Well, well<\/em>, excellente manuvre)<\/p>\n<\/p>\n<p><p>\t\u00ab<em> Moscow has stepped up its efforts to hold an international conference on Afghanistan under the aegis of the SCO. The US doesn&rsquo;t want Karzai to legitimize a SCO role in the Afghan problem. Now a flashpoint arises.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A meeting of deputy foreign ministers from the SCO member countries (China, Kazakhstan, Kyrgyzstan, Russia, Tajikistan and Uzbekistan) met in Moscow on January 14. The Russian Foreign Ministry subsequently announced that a conference would take place in late March. The Russian initiative received a big boost with Iran and India&rsquo;s decision to participate in the conference. <\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The big question is whether Karzai will seize these regional trends and respond to the SCO overture, which will enable Kabul to get out of Washington&rsquo;s stranglehold? To be sure, Washington is racing against time in bringing about a regime change in Kabul.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t A quoi se r\u00e9sume la situation, finalement? Peut-\u00eatre cette remarque de M K Bhadrakumar , gliss\u00e9e au coin d&rsquo;un paragraphe, fait-elle l&rsquo;affaire: \u00ab<em>The point is, more and more countries in the region are finding it difficult to accept the US monopoly on conflict-resolution in Afghanistan.<\/em>\u00bb Elle caract\u00e9rise une situation qui va prochainement changer grandement puisque Washington va encore plus <strong>accentuer<\/strong> son monopole de contr\u00f4le des affaires en Afghanistan, si n\u00e9cessaire, et si possible, en \u00e9liminant la marionnette servile devenue lion rameutant peu ou prou la r\u00e9sistance anti-US <em>soft<\/em>. Notre point de vue est que le brave Obama a encore un long, long chemin \u00e0 faire avant de parvenir dans des eaux nouvelles, internationalistes, ouvertes \u00e0 la coop\u00e9ration et ainsi de suite. Il est vrai qu&rsquo;il commence les affaires en Afghanistan en frappant du poing sur la table et en annon\u00e7ant qu&rsquo;il prend les choses en main, en plus, par l&rsquo;interm\u00e9diaire de ce monstre de la diplomatie-<em>blitzkrieg<\/em> qu&rsquo;est Holbrooke. Appr\u00e9ci\u00e9e de ce point de vue, l&rsquo;Afghanistan semble avoir, sur le Vietnam et sur l&rsquo;Irak, l&rsquo;avantage de plusieurs cercles concentriques d&rsquo;imbroglios et de complications possibles, c&rsquo;est-\u00e0-dire l&rsquo;occasion, pour les USA, d&rsquo;ajouter plusieurs volets d&rsquo;incompr\u00e9hension et d&rsquo;erreurs. Pourquoi faire simple quand on peut faire compliqu\u00e9?, interroge le sage.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en lmigne le 27 janvier 2009 \u00e0 17H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certes, l&rsquo;administration Obama a choisi de d\u00e9placer le pion Afghanistan, d&rsquo;accentuer son effort dans le cur de cette crise. Non seulement trouve-t-on sur cette voie sp\u00e9culative l&rsquo;interrogation de la capacit\u00e9 des USA \u00e0 faire \u00e9voluer cette crise, m\u00eame au travers de cet effort et particuli\u00e8rement par le biais de cet effort, mais on observe \u00e9galement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,5474,4300,5949,4575,5509],"class_list":["post-70489","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-bhadrakumar","tag-holbrooke","tag-kaboul","tag-karzai","tag-sco"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70489"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70489\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}