{"id":70511,"date":"2009-02-05T19:11:51","date_gmt":"2009-02-05T19:11:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/02\/05\/le-roi-jsf-est-nu\/"},"modified":"2009-02-05T19:11:51","modified_gmt":"2009-02-05T19:11:51","slug":"le-roi-jsf-est-nu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/02\/05\/le-roi-jsf-est-nu\/","title":{"rendered":"Le roi-JSF est nu"},"content":{"rendered":"<p><h2 class=\"common-article\">Le roi-JSF est nu<\/h2>\n<\/p>\n<p><p>\t5 f\u00e9vrier 2009  Un document parvenu \u00e0 la connaissance du public par des voies officieuses, d\u00e9tourn\u00e9es sans doute et bienvenues d&rsquo;autre part, permet de bien fixer les conditions historiques et fondamentales du programme JSF, et surtout de ses vices structurels de conception et de r\u00e9alisation. Il s&rsquo;agit d&rsquo;un m\u00e9morandum interne dit Info-Memo de John Young, sous-secr\u00e9taire \u00e0 la d\u00e9fense pour les acquisitions, la technologie et la logistique, adress\u00e9 le 16 janvier 2009 au secr\u00e9taire \u00e0 la d\u00e9fense Robert Gates.<\/p>\n<\/p>\n<p><p>\tLe document a \u00e9t\u00e9 notamment r\u00e9percut\u00e9, d&rsquo;abord par l&rsquo;excellent site hollandais d&rsquo;information critique sur le d\u00e9veloppement du programme JSF, <em>JSF Nieuws<\/em> (en date du <a href=\"http:\/\/translate.google.com\/translate?u=http%3A%2F%2Fwww.jsfnieuws.nl&#038;hl=en&#038;ie=UTF-8&#038;sl=nl&#038;tl=en\" class=\"gen\">4 f\u00e9vrier<\/a>, accessible dans une version de traduction anglais Google n\u00e9cessairement approximative mais qui permet de comprendre le sens de l&rsquo;information); \u00e9galement par le quotidien de Fort Worth <em>Star Telegram<\/em> (en date du <a href=\"http:\/\/www.star-telegram.com\/business\/story\/1183080.html\" class=\"gen\">4 f\u00e9vrier<\/a>).<\/p>\n<\/p>\n<p><p>\tCe m\u00e9morandum donne un r\u00e9sum\u00e9 de l&rsquo;appr\u00e9ciation du programme JSF \u00e0 l&rsquo;heure o\u00f9 celui-ci est officiellement d\u00e9clar\u00e9 l\u00e9galement <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_attaque_par_la_verite_officielle_des_prix_circa-obama_et_gao_24_01_2009.html\" class=\"gen\">en infraction<\/a> \u00e0 la loi Nunn-McCurdy, qui vise tous les programmes du DoD ayant d\u00e9pass\u00e9 leur devis de d\u00e9veloppement et de production de 30%.<\/p>\n<\/p>\n<p><p>\t(Young pr\u00e9cise dans son m\u00e9mo que le programme a d\u00e9pass\u00e9 son devis de 2001  il s&rsquo;agit l\u00e0 des chiffres officiels, connus et d&rsquo;ores et d\u00e9j\u00e0 contest\u00e9s,  \u00e0 partir d&rsquo;un programme estim\u00e9 \u00e0 $229 milliards en 2001 jusqu&rsquo;\u00e0 un programme de $298 milliards aujourd&rsquo;hui, soit $69 milliards de d\u00e9passement; cela fait exactement les 30% et un poil de d\u00e9passement; \u00e9tonnante occurrence math\u00e9matique et comptable, n&rsquo;est-il pas? Effectivement et par ailleurs, ce dernier chiffre de $298 milliards largement contest\u00e9, notamment par le GAO. Le <em>Star Telegram<\/em> indique: \u00ab<em>New estimates, expected to be released soon, are expected to show further cost growth.<\/em>\u00bb. Certaines sources affirment que le GAO annoncerait un programme JSF \u00e0 au moins $339 milliards dans son prochain rapport sur le JSF, sans doute en mars.)<\/p>\n<\/p>\n<p><p>\tLe m\u00e9mo-Young trace donc un rapide portrait de ce qui peut \u00eatre d\u00e9sormais consid\u00e9r\u00e9 comme une catastrophe annonc\u00e9e, r\u00e9pertori\u00e9e, mesur\u00e9e, etc. Young met en cause la m\u00e9thodologie suivie dans le d\u00e9veloppement du programme.<\/p>\n<\/p>\n<p><p>\t Le principal probl\u00e8me que le sous-secr\u00e9taire \u00e0 la d\u00e9fense rel\u00e8ve, d\u00e8s l&rsquo;origine de la phase actuelle, c&rsquo;est-\u00e0-dire 2001, c&rsquo;est que la structure du JSF n&rsquo;\u00e9tait pas ad\u00e9quate par rapport \u00e0 ce que serait finalement le JSF. On a d\u00e9velopp\u00e9 une structure d&rsquo;avion pour un autre avion que ce que le JSF est devenu. (Effectivement, nous e\u00fbmes donc un JSF virtuel, qui devait \u00eatre ce formidable programme qui conquerrait le monde, et puis le JSF r\u00e9el) \u00ab<em>JSF technology demonstrators were not adequately robust, leading to optimistic estimates of the structural weight of the aircraft.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t La m\u00e9thodologie, donc: le tout fut de n&rsquo;avoir pas inclus dans le programme de vrais prototypes, exp\u00e9rimentant en vrai, en temps r\u00e9el, dans des conditions r\u00e9elles, etc., la structure  fondamentale de l&rsquo;avion pour d\u00e9couvrir les probl\u00e8mes qui se r\u00e9v\u00e8lent lors de l&rsquo;exp\u00e9rimentation. Peut-\u00eatre croirait-on r\u00eaver, si on ne se pin\u00e7ait pas, car constater qu&rsquo;il aurait fallu de <strong>vrais<\/strong> prototypes, alors que la chose se pratique depuis les origines de l&rsquo;aviation, comme de toute activit\u00e9 industrielle s\u00e9rieuse, c&rsquo;est un constat qui semble nous dire: Le probl\u00e8me est que nous avons oubli\u00e9 de r\u00e9inventer la roue, attentif comme nous \u00e9tions \u00e0 inventer le fil \u00e0 couper le beurre,  et, par cons\u00e9quent, nous ne pouvions que nous planter d\u00e8s le d\u00e9part puisque nous avons d\u00e9cid\u00e9 \u00e0 partir d&rsquo;une connaissance fauss\u00e9e de l&rsquo;avion \u00ab<em>Most importantly, we should have built quality prototypes in the 1996-2001 time frame.<\/em> [] <em>JSF did not built true prototypes built as was done in the YF-22 and YF-23 fly off. To be clear, the future of the JSF cost growth was largely written in 2001 when an budget pricing decisions were made in 2001 based on the inadequate knowledge gained from the JSF technology demonstrators.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Mis \u00e0 part ce travers fondamental, qui est un travers de m\u00e9thode, d&rsquo;autres causes sont cit\u00e9es pour l&rsquo;augmentation de co\u00fbt de l&rsquo;avion (augmentation des mat\u00e9riaux, co\u00fbt des d\u00e9lais pour modifications structurelles, r\u00e9duction de la commande de la Navy, etc.) Une derni\u00e8re cause, assez curieusement r\u00e9dig\u00e9e: \u00ab<em>Lockheed Martin&rsquo;s performance is adequate, but not great.<\/em>\u00bb C&rsquo;est une fa\u00e7on paradoxale de faire figurer le constructeur dans les causes puisqu&rsquo;on lui reproche simplement d&rsquo;avoir \u00e9t\u00e9 bon mais de n&rsquo;avoir pas \u00e9t\u00e9 exceptionnel; paradoxalement, parce que cela revient \u00e0 exon\u00e9rer Lockheed Martin (LM) d&rsquo;une r\u00e9elle responsabilit\u00e9, ce qui se comprend lorsqu&rsquo;on sait que Young \u00e9tait chez LM avant de passer au Pentagone. <\/p>\n<\/p>\n<p><p>\t Des pr\u00e9cisions sur l&rsquo;information du d\u00e9roulement du programme (passage soulign\u00e9 en gras par nous) confirment l&rsquo;importance dramatique de l&rsquo;information pour le programme JSF, et sa r\u00e9tention, son contr\u00f4le syst\u00e9matiques y compris \u00e0 l&rsquo;int\u00e9rieur du Pentagone puisque Young affirme que le d\u00e9partement n&rsquo;\u00e9tait pas inform\u00e9: \u00ab<em>However, the JSF costs were already higher than estimated because inadequacies in the technology demonstrators led to underestimating the weight of the JSF aircraft <\/em> <strong><em>the Department did not know this at the time.<\/em><\/strong>\u00bb Il n&rsquo;est d&rsquo;ailleurs pas assur\u00e9 qu&rsquo;il y ait eu syst\u00e9matiquement et volontairement contr\u00f4le et r\u00e9tention de l&rsquo;information, par exemple de la part de Lockheed Martin (LM) ou du JSF Program Office (JPO), vis-\u00e0-vis de la direction du Pentagone. Il est tr\u00e8s possible que <strong>personne<\/strong> ne se soit, \u00e0 l&rsquo;origine, rendu compte de rien dans la fa\u00e7on dont les choses \u00e9taient machin\u00e9es pour lancer le destin compl\u00e8tement faussaire et pervers du JSF; le programme a baign\u00e9 pendant toutes ces ann\u00e9es dans le plus complet virtualisme, c&rsquo;est-\u00e0-dire dans un montage auquel tout le monde a contribu\u00e9 chacun pour son compte, et auquel tout le monde \u00e9tait inclin\u00e9 \u00e0 croire.<\/p>\n<\/p>\n<p><p>\tCe document est particuli\u00e8rement int\u00e9ressant, r\u00e9v\u00e9lateur, significatif. Il ne nous apprend rien que nous ne sachions d\u00e9j\u00e0, nous qui sommes en dehors de la cha\u00eene de montage (de communication) du virtualisme-JSF, mais il nous permet d&rsquo;avoir confirmation de la substance m\u00eame du programme JSF, et aussi d&rsquo;avoir une vision int\u00e9ressante sur la situation au Pentagone \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\tSur ce dernier point, en effet Pourquoi John Young \u00e9crit-il ce m\u00e9mo qui met en cause si profond\u00e9ment, c&rsquo;est-\u00e0-dire structurellement, le programme JSF? On a \u00e0 l&rsquo;esprit que Young est un partisan convaincu du JSF au sein du DoD. (Au sein du DoD? Est-il toujours \u00e0 son poste avec l&rsquo;administration Obama? Sa <a href=\"http:\/\/www.defenselink.mil\/bios\/biographydetail.aspx?biographyid=142\" class=\"gen\">biographie<\/a> dit que oui.) Cet automne 2008, il moulina dur contre le F-22 et pour le F-35 (JSF) <a href=\"http:\/\/www.dedefensa.org\/article-le_meilleur_ami_du_jsf_s_en_va_03_12_2008.html\" class=\"gen\">au c\u00f4t\u00e9<\/a> de son sup\u00e9rieur hi\u00e9rarchique, Gordon England (lui-m\u00eame ayant quitt\u00e9 son poste, au contraire de Young). Il y a des hypoth\u00e8ses, et nous allons nous attarder au moins \u00e0 l&rsquo;une d&rsquo;entre elles.<\/p>\n<\/p>\n<p><p>\t Mentionnons par charit\u00e9 pentagonesque l&rsquo;hypoth\u00e8se humanitaire d&rsquo;un Young d\u00e9couvrant l&rsquo;horreur du monde-JSF et d\u00e9non\u00e7ant aussit\u00f4t, de sa propre initiative, l&rsquo;\u00e9pouvantable v\u00e9rit\u00e9. L&rsquo;\u00e9motion nous emp\u00eache d&rsquo;aller plus avant.<\/p>\n<\/p>\n<p><p>\t Attardons-nous \u00e0 l&rsquo;hypoth\u00e8se bureaucratique. Celle-ci nous dit que l&rsquo;on vient d&rsquo;apprendre que le programme JSF est mis en accusation par la loi Nunn-McCurdy. La chose atteint \u00e9videmment le plus haut \u00e9chelon, Gates lui-m\u00eame. Gates demande des explications. Young lui en fournit, en se d\u00e9faussant diversement. Il n&rsquo;\u00e9tait lui-m\u00eame pas au courant, puisque \u00ab<em>the Department did not know this at the time<\/em>\u00bb. (Notons la vague de la chose : <em>the Department<\/em>; qui pr\u00e9cis\u00e9ment? OSD [Office of the Secretary of Defense]? Le Pentagone dans son ensemble?) D&rsquo;autre part, si Young reste au Pentagone ou pour toute autre raison, il doit pour \u00e9carter les soup\u00e7ons de partialit\u00e9 jouer partiellement franc jeu dans son appr\u00e9ciation de la situation du JSF, d&rsquo;autant que la catastrophe est d\u00e9sormais officiellement act\u00e9e par Nunn-McDurby.<\/p>\n<\/p>\n<p><p>\t Cette hypoth\u00e8se correspond bien \u00e0 ce que nous pensons des positions des uns et des autres. Le couple England-Young, venu de LM, est (\u00e9tait puisqu&rsquo;England est parti) une courroie de transmission directe pour soutenir et favoriser le programme JSF, y compris au d\u00e9triment du F-22 (\u00e9galement de LM) qui ne fera plus beaucoup d&rsquo;argent, m\u00eame si l&rsquo;on en fait une nouvelle (petite) s\u00e9rie. Gates, lui, a une position diff\u00e9rente, m\u00eame s&rsquo;il a paru anti-F-22 et pro-JSF. Au d\u00e9part (arriv\u00e9 en novembre 2006), Gates veut affirmer son autorit\u00e9, tenter de r\u00e9tablir un peu d&rsquo;ordre au Pentagone, etc. Le premier service auquel il se heurte est l&rsquo;USAF, qui rencontre nombre de d\u00e9boires, a de gros probl\u00e8mes de cr\u00e9dit, de discipline, de contr\u00f4le de ses forces (notamment nucl\u00e9aires, avec notamment l&rsquo;affaire du <a href=\"http:\/\/www.dedefensa.org\/article-le_b-52_on_the_road_de_minot_a_barksdale_avec_six_cruise_missiles_a_tetes_nucleaires_07_09_2007.html\" class=\"gen\">B-52<\/a> de Minot AFB, en septembre 2007). L&rsquo;affaire prend des dimensions de crise, avec la mise \u00e0 pied de la direction de l&rsquo;USAF, en <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_de_l_usaf_confirmation_de_l_affrontement_bureaucratique_10_06_2008.html?admin=1\" class=\"gen\">juin 2008<\/a>, pour s&rsquo;aggraver encore, avec l&rsquo;affaire du KC-45 <a href=\"http:\/\/www.dedefensa.org\/article-_et_gates_entre_dans_la_fosse_aux_lions_ultimately_he_s_the_boss__27_06_2008.html\" class=\"gen\">fin juin 2008<\/a>. C&rsquo;est bien assez pour que Gates regarde avec un agacement consid\u00e9rable, sinon de l&rsquo;hostilit\u00e9 syst\u00e9matique, toute demande de l&rsquo;USAF sortant de la programmation courante. Pour cette raison, Gates a \u00e9t\u00e9, \u00e0 l&rsquo;automne 2008, <a href=\"http:\/\/www.dedefensa.org\/article-dogfight_pas_furtif_du_tout.html\" class=\"gen\">contre<\/a> la demande de l&rsquo;USAF de plus de F-22, par cons\u00e9quent, \u00e0 cause des manuvres England-Young, class\u00e9 comme partisan du JSF. Mais il appara\u00eet improbable que Gates soit partisan dans le cas du JSF, dont il n&rsquo;est pas assur\u00e9 qu&rsquo;il soit bien inform\u00e9.<\/p>\n<\/p>\n<p><p>\tUn passage de m\u00e9mo-Young nous para\u00eet tout \u00e0 fait extraordinaire par son extraordinaire incongruit\u00e9, nous faisant effectivement penser \u00e0 une position tr\u00e8s \u00e9loign\u00e9e de la connaissance du programme JSF de Gates, et \u00e0 une attitude manipulatrice syst\u00e9matique de Young m\u00eame quand il est oblig\u00e9 de reconna\u00eetre quelques d\u00e9fauts au JSF. A l&rsquo;avant dernier paragraphe du m\u00e9mo, Young \u00e9crit:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>JSF is essentially developing three unique fighter aircraft as well as export version, through a joint international development program, for $44 billion of development costs. By comparison, in FY 09 dollars, B-2 development costs $36.2 billion, and final F-22development will cost $43.2 billion. JSF is the most advanced fighter in the world in terms of signature, sensors, and combined delivery of air-to-air and air-to-ground modes.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQu&rsquo;est-ce qui distingue ce passage, sinon, justement son extr\u00eame platitude, \u00e0 peu pr\u00e8s aussi int\u00e9ressant qu&rsquo;un communiqu\u00e9 de LM sur le JSF? Mais il s&rsquo;agit d&rsquo;un m\u00e9mo interne, d&rsquo;un sous-secr\u00e9taire \u00e0 la d\u00e9fense pour un secr\u00e9taire \u00e0 la d\u00e9fense qui n&rsquo;est pas tomb\u00e9 de la derni\u00e8re pluie (ancien directeur de la CIA, notamment), concernant le premier programme en co\u00fbt du Pentagone, dans une phase extr\u00eamement d\u00e9licate. Dans ce cas-l\u00e0, on fait pr\u00e9cis, rapide, sur l&rsquo;essentiel,  ce qui est le cas du reste du m\u00e9mo. (Ajoutons-y l&rsquo;habituelle touche de propagande sur les capacit\u00e9s air-air du JSF, qui sont tout sauf av\u00e9r\u00e9es et prouv\u00e9es.) Sans que nous puissions avancer d&rsquo;hypoth\u00e8se pr\u00e9cise \u00e0 ce propos, sinon la croyance de Young en l&rsquo;ignorance av\u00e9r\u00e9 de Gates \u00e0 propos du JSF et la confirmation qu&rsquo;il (Young) reste un propagandiste du JSF malgr\u00e9 tout, tout cela laisse beaucoup \u00e0 penser \u00e0 propos des manuvres et de la bataille autour du JSF au sein du Pentagone.<\/p>\n<h3>Le JSF, artefact de l&rsquo;am\u00e9ricanisme en chute libre<\/h3>\n<\/p>\n<p><p>\tYoung termine par les le\u00e7ons des erreurs du programme JSF \u00e0 son stade initial, et sert effectivement une le\u00e7on principale qui est un contresens absolument av\u00e9r\u00e9, d&rsquo;une pens\u00e9e sophistique cherchant, plus inconsciemment que machiav\u00e9liquement, \u00e0 finalement pr\u00e9senter le JSF comme victime de forces ext\u00e9rieures (en g\u00e9n\u00e9ral, le Congr\u00e8s qui ne donne pas assez d&rsquo;argent au Pentagone): \u00ab<em>I think the fundamental lesson in JSF is the critical importance of robust funding in the early, prototype phase of development<\/em>\u00bb. Il s&rsquo;agit d&rsquo;un mensonge av\u00e9r\u00e9 ou, plut\u00f4t, d&rsquo;une non-v\u00e9rit\u00e9 issue d&rsquo;une pens\u00e9e sophistique par virtualisme.<\/p>\n<\/p>\n<p><p>\tLe JSF n&rsquo;a jamais souffert d&rsquo;un sous-financement. Il y a eu au d\u00e9part la d\u00e9cision qu&rsquo;il n&rsquo;y aurait pas de prototype pur, tant le travail virtuel de conception \u00e9tait jug\u00e9 assez s\u00fbr, voire irr\u00e9sistible pour se passer d&rsquo;exp\u00e9rimentation. Il n&rsquo;y a donc pas eu de sous-financement pour un \u00e9quipement (des prototypes) dont on avait d\u00e9cid\u00e9 de se passer en raison de leur compl\u00e8te inutilit\u00e9 proclam\u00e9e. La non-v\u00e9rit\u00e9 ou la v\u00e9rit\u00e9 virtualiste de Young, d&rsquo;ailleurs m\u00eame pas d\u00e9lib\u00e9r\u00e9e quoi qu&rsquo;elle fasse du coupable (le programme JSF lui-m\u00eame) une victime, nous \u00e9claire, ou plut\u00f4t nous confirme \u00e0, propos de la philosophie du programme. C&rsquo;est aussi la philosophie de l&rsquo;am\u00e9ricanisme dans sa phase virtualiste et exub\u00e9rante maximale. (Cette p\u00e9riode, \u00e0 peu pr\u00e8s commenc\u00e9e en <a href=\"http:\/\/www.dedefensa.org\/article-de_atlanta-1996_a_new_orleans-2005_02_09_2005.html\" class=\"gen\">1996<\/a>, \u00e9tait \u00e0 pleine vapeur jusqu&rsquo;\u00e0 9\/11, pour se transformer en folie conqu\u00e9rante accouchant de l&rsquo;une ou l&rsquo;autre souris en bien mauvais \u00e9tat, les bordels irakien et afghan.)<\/p>\n<\/p>\n<p><p>\tOn n&rsquo;a pas fait de phase prototype parce que la sup\u00e9riorit\u00e9 des USA \u00e9tait jug\u00e9e telle qu&rsquo;elle ne se calculait plus par rapport aux concurrents \u00e9ventuels (chose devenue inconcevable, la concurrence), mais par rapport \u00e0 la domination, et m\u00eame la ma\u00eetrise des grandes forces naturelles ou manufacturi\u00e8res par l&rsquo;am\u00e9ricanisme. La <a href=\"http:\/\/www.dedefensa.org\/article-de_beyond_history_a_beyond_hegemony__17_01_2007.html?admin=1\" class=\"gen\">phrase fameuse<\/a> de Greenspan en juin 1998 selon laquelle certains concevaient, non sans raison(s), que l&rsquo;\u00e9conomie US \u00e9tait \u00ab<em>beyond history<\/em>\u00bb valait \u00e9galement pour le JSF, lui aussi \u00ab<em>beyond history<\/em>\u00bb, donc lui aussi \u00e9chappant aux lois terrestres habituelles de l&rsquo;industrie a\u00e9ronautique et de l&rsquo;industrie manufacturi\u00e8re en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>\tL&rsquo;exp\u00e9rimentation, la technique du prototype (\u00ab<em>mod\u00e8le premier<\/em>\u00bb) n&rsquo;avait pas de raison d&rsquo;\u00eatre, puisque tout \u00e9tait cr\u00e9\u00e9 en un monde virtuel, que le monde-JSF \u00e9tait cr\u00e9\u00e9 o\u00f9 le JSF \u00e9voluerait en pays de connaissance \u00e9videmment ma\u00eetris\u00e9 (inutilit\u00e9 du prototype), cela aboutissant \u00e0 l&rsquo;annexion automatique de tous les march\u00e9s (les USA ont pratiquement choisi les pays qui participeraient au programme JSF), avec les valeurs \u00e9tablis avant m\u00eame que l&rsquo;avion n&rsquo;existe,  excellence technologique sans \u00e9gale pour le XXI\u00e8me si\u00e8cle, sup\u00e9riorit\u00e9 op\u00e9rationnelle sans besoin de d\u00e9monstration, prix \u00e9videmment ma\u00eetris\u00e9 et choisi selon les param\u00e8tres imp\u00e9riaux US, annexion politique des pays-JSF et ainsi de suite. Le JSF est une aventure sans \u00e9gale, une exp\u00e9rimentation en temps r\u00e9volutionn\u00e9 plut\u00f4t qu&rsquo;en temps r\u00e9el, de la folie am\u00e9ricaniste. Nous ne sommes pas au bout de nos surprises, car ce programme est totalement artificiel, du d\u00e9but \u00e0 la fin, compl\u00e8tement d\u00e9tach\u00e9 du r\u00e9el, compl\u00e8tement suspendu dans l&rsquo;\u00e9ther, dans le vide des conceptions am\u00e9ricanistes du Pentagone aussi bien que de l&rsquo;industrie (LM). <\/p>\n<\/p>\n<p><p>\tLe programme JSF est un arch\u00e9type fondamental de l&rsquo;am\u00e9ricanisme et, bien s\u00fbr, un artefact virtualiste complet. Il nous permet de suivre, symbolis\u00e9e autant que concr\u00e9tis\u00e9e dans un formidable programme industriel et militaire, la chute de l&#8217;empire am\u00e9ricaniste et des conceptions qui vont avec. Le m\u00e9mo-Young est une \u00e9tape int\u00e9ressante de la chute, nous permettant d&rsquo;avoir un aper\u00e7u de ce que les petits soldats de l&rsquo;am\u00e9ricanisme, avec leurs habituelles pratiques de corruption et de manipulation, r\u00e9alisent exactement de la situation en cours. L&rsquo;int\u00e9r\u00eat du document est alors de d\u00e9couvrir que m\u00eame eux, eux-m\u00eames per\u00e7ant le cuir \u00e9pais qui leur sert de technologie <em>stealth<\/em> personnelle, commencent \u00e0 se douter de quelque chose; \u00e9tape int\u00e9ressante, ils en sont \u00e0 commencer \u00e0 \u00e9crire l&rsquo;histoire falsifi\u00e9e des vices fondamentaux et d&rsquo;origine du programme. Il est bien possible que le programme JSF nous offre un de ces jours une de ces chutes finales,  industrielle, technologique et militaire dans ce cas,  dont le syst\u00e8me a le secret, comme on l&rsquo;a vu avec l&rsquo;aventure Lehman Brothers et le reste. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le roi-JSF est nu 5 f\u00e9vrier 2009 Un document parvenu \u00e0 la connaissance du public par des voies officieuses, d\u00e9tourn\u00e9es sans doute et bienvenues d&rsquo;autre part, permet de bien fixer les conditions historiques et fondamentales du programme JSF, et surtout de ses vices structurels de conception et de r\u00e9alisation. Il s&rsquo;agit d&rsquo;un m\u00e9morandum interne dit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4526,3984,250,8083,3194,7255,610,7670],"class_list":["post-70511","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-england","tag-gates","tag-jsf","tag-memo-young","tag-pentagone","tag-prototype","tag-virtualisme","tag-young"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70511"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70511\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}