{"id":70530,"date":"2009-02-13T05:55:06","date_gmt":"2009-02-13T05:55:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/02\/13\/buy-american-a-survecu-et-se-porte-bien\/"},"modified":"2009-02-13T05:55:06","modified_gmt":"2009-02-13T05:55:06","slug":"buy-american-a-survecu-et-se-porte-bien","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/02\/13\/buy-american-a-survecu-et-se-porte-bien\/","title":{"rendered":"<em>Buy American<\/em> a surv\u00e9cu et se porte bien"},"content":{"rendered":"<p><p>Le plan de stimulation de l&rsquo;\u00e9conomie US vot\u00e9 par le Congr\u00e8s le 11 f\u00e9vrier, apr\u00e8s la rencontre classique de compromis entre la Chambre et le S\u00e9nat pour concilier les deux textes vot\u00e9s par les deux chambres, comprend bien la clause dite <em>Buy American<\/em>. On trouve dans la r\u00e9daction de la chose les quelques am\u00e9nagements de forme introduits \u00e0 la demande du pr\u00e9sident Obama. <\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.defensenews.com\/story.php?i=3946283&#038;c=AME\" class=\"gen\">12 f\u00e9vrier<\/a>, <em>Defense News<\/em> rend compte de la nouvelle:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Buy-American requirements survived in the giant economic stimulus bill that the U.S. House and Senate agreed to Feb. 11, to the chagrin of U.S. business associations. Lawmakers agreed to retain the Senate&rsquo;s version of the protectionist provision that requires U.S.-made products to be used in projects funded by the $790 billion stimulus bill.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The provision says that iron, steel and manufactured goods used in projects funded by the economic stimulus bill must be produced in the United States. After an outcry by U.S. business associations and foreign ambassadors, who feared the language might trigger trade wars, the Senate added that the provision must be applied in a manner consistent with United States obligations under international agreements.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Even with the modification, U.S. defense companies worry that foreign governments may retaliate by refusing to buy U.S.-made weapons. Nevertheless, the buy-American provision remains in compromise legislation worked out between the House and Senate on Feb. 11, said a spokeswoman for the House Appropriations Committee.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>U.S. business organizations aren&rsquo;t happy about it.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;affaire s&rsquo;est d\u00e9roul\u00e9e, comme on disait selon le langage standard de la bureaucratie sovi\u00e9tique, selon le plan pr\u00e9vu. L&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-panique_a_downing_street_04_02_2009.html\" class=\"gen\">intervention<\/a> du pr\u00e9sident Obama a abouti \u00e0 un am\u00e9nagement de langage qui, dirait-on, va de soi. Il semble en effet aller de soi qu&rsquo;un pays qui a sign\u00e9 des engagements internationaux entende les respecter tant qu&rsquo;il ne les a pas explicitement d\u00e9nonc\u00e9s. Cela confirme l&rsquo;interpr\u00e9tation que nous avions donn\u00e9e de l&rsquo;intervention d&rsquo;Obama: \u00ab<em>Cette prise de position du pr\u00e9sident US, notons-le bien, concerne le langage de la clause Buy American, pour que les USA n&rsquo;envoient pas au monde un message qui ferait croire qu&rsquo;ils sont pr\u00e9occup\u00e9s d&rsquo;eux-m\u00eames seulement, et pas du Rest Of the World.<\/em>\u00bb Dans la pratique de la chose, il reste que les soumissionnaires des contrats pass\u00e9s dans le cadre du plan sont dans l&rsquo;obligation d&rsquo;utiliser du fer et de l&rsquo;acier produits aux Etats-Unis; ils pourraient, pour bien faire, agr\u00e9menter leurs commandes et leurs contrats d&rsquo;une appr\u00e9ciation qu&rsquo;il ne s&rsquo;agit en rien un acte de protectionnisme.<\/p>\n<\/p>\n<p><p>\t<em>In illo tempore<\/em>, lorsque l&rsquo;influence US existait \u00e0 son standard de haut niveau que l&rsquo;on connaissait, \u00e0 l&rsquo;abri de toute critique et de toute concurrence, une telle aventure e\u00fbt \u00e9t\u00e9 une p\u00e9rip\u00e9tie sans importance puisque tout acte de la puissance tut\u00e9laire \u00e9tait accept\u00e9 sans murmure. Aujourd&rsquo;hui, elle constitue un acte important et s\u00e9rieux parce que pos\u00e9 dans le cadre de la crise g\u00e9n\u00e9rale, en fonction de cette crise, par une puissance dont l&rsquo;influence fortement d\u00e9clinante permet aux int\u00e9r\u00eats des autres nations de s&rsquo;exprimer de fa\u00e7on beaucoup plus ouverte. D\u00e9sormais, les autres pays qui entendent suivre une politique de protection se trouvent confort\u00e9s dans leur d\u00e9marche, d&rsquo;autant qu&rsquo;il s&rsquo;agit d&rsquo;une loi officielle et non d&rsquo;une pratique dont on peut toujours arguer de la r\u00e9alit\u00e9 et du fondement. On parlera par cons\u00e9quent d&rsquo;un pas non n\u00e9gligeable qui a \u00e9t\u00e9 franchi dans la structure de crise qui se met en place.<\/p>\n<\/p>\n<p><p>\tAu reste et sur le fondement de la chose, on se gardera de condamner les l\u00e9gislateurs US, de la m\u00eame fa\u00e7on que la question du protectionnisme avec toutes ses nuances nous para\u00eet largement ouverte dans le contexte d&rsquo;un syst\u00e8me qui s&rsquo;appuie sur une hostilit\u00e9 mortelle au protectionnisme et qui se trouve dans une crise si profonde que tous les principes et options de son fonctionnement ont tout lieu d&rsquo;\u00eatre soumis \u00e0 la critique la plus vive. La d\u00e9cision US a ceci de bon, r\u00e9p\u00e9tons-le, qu&rsquo;elle dit tout haut et de fa\u00e7on l\u00e9gale ce que les autres et m\u00eame tout le monde (y compris les USA dans d&rsquo;autres domaines) pratiquent tout bas. Elle force effectivement, d&rsquo;une fa\u00e7on ou l&rsquo;autre, \u00e0 mettre en question l&rsquo;un des <em>diktat<\/em> du syst\u00e8me; elle conduit par cons\u00e9quent \u00e0 faire progresser le d\u00e9bat sur la validit\u00e9 d&rsquo;un syst\u00e8me omnipr\u00e9sent et qui a suscit\u00e9, par ses pratiques dont celle de tenir dans la plus compl\u00e8te excommunication le protectionnisme et de fa\u00e7on plus g\u00e9n\u00e9rale toute pratique de protection av\u00e9r\u00e9e des int\u00e9r\u00eats \u00e9conomiques nationaux, une crise de la dimension de celle qu&rsquo;on subit. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 f\u00e9vrier 2009 \u00e0 05H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le plan de stimulation de l&rsquo;\u00e9conomie US vot\u00e9 par le Congr\u00e8s le 11 f\u00e9vrier, apr\u00e8s la rencontre classique de compromis entre la Chambre et le S\u00e9nat pour concilier les deux textes vot\u00e9s par les deux chambres, comprend bien la clause dite Buy American. On trouve dans la r\u00e9daction de la chose les quelques am\u00e9nagements de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5688,3612,6079,1097,8074],"class_list":["post-70530","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-act","tag-american","tag-buy","tag-protectionnisme","tag-stimulus"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70530"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70530\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}