{"id":70583,"date":"2009-03-05T07:00:49","date_gmt":"2009-03-05T07:00:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/05\/fin-de-lamerican-dream-limagination-un-peu-courte\/"},"modified":"2009-03-05T07:00:49","modified_gmt":"2009-03-05T07:00:49","slug":"fin-de-lamerican-dream-limagination-un-peu-courte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/05\/fin-de-lamerican-dream-limagination-un-peu-courte\/","title":{"rendered":"Fin de l&rsquo;<em>American Dream<\/em>, l&rsquo;imagination un peu courte"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Fin de l&rsquo;<em>American Dream<\/em>, l&rsquo;imagination un peu courte<\/h2>\n<\/p>\n<p><p>Il y a, depuis quelques mois, sur les r\u00e9seaux officiels am\u00e9ricanistes d&rsquo;information, un sujet particuli\u00e8rement d\u00e9licat qui commence \u00e0 \u00eatre abord\u00e9 avec r\u00e9ticence et hostilit\u00e9, alors qu&rsquo;il \u00e9tait jusqu&rsquo;alors implicitement <em>off-limits<\/em> et tout simplement ignor\u00e9. (L&rsquo;auto-censure de l&rsquo;information marche bien, y compris comme r\u00e9v\u00e9lateur: lorsqu&rsquo;elle commence \u00e0 le c\u00e9der sur un point pr\u00e9cis, c&rsquo;est qu&rsquo;il existe une inqui\u00e9tude diffuse \u00e0 cet \u00e9gard.) Le sujet est la dislocation des Etats-Unis, ou \u00ab\u00a0la fin des USA\u00a0\u00bb. Un des acteurs favoris de ce sujet, c&rsquo;est le russe <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-_et_l_option_de_l_eclatement_26_11_2008.html\">Igor Panarine<\/a>, ex-analyste du FSB (ex-KGB), pass\u00e9 tr\u00e8s officiellement dans une fonction que chapeaute le minist\u00e8re russe des affaires \u00e9trang\u00e8res.<\/p>\n<\/p>\n<p><p>Un texte de l&rsquo;agence US et am\u00e9ricaniste AP rapporte une tr\u00e8s r\u00e9cente intervention de Panarine, dans une d\u00e9p\u00eache du <a class=\"gen\" href=\"http:\/\/news.yahoo.com\/s\/ap\/20090304\/ap_on_re_eu\/eu_russia_us_the_end_is_near;_ylt=AiXfQglF2OCbdDB725vHSvGs0NUE;_ylu=X3oDMTFpNTQyZmEwBHBvcwMyNARzZWMDYWNjb3JkaW9uX21vc3RfcG9wdWxhcgRzbGsDcnVzc2lhbnNjaG9s\">4 mars<\/a>. Elle pr\u00e9sente la chose d&rsquo;une fa\u00e7on mi-figue mi-raisin, non sans une r\u00e9elle condescendance, non sans une vague inqui\u00e9tude affleurant par instant.<\/p>\n<\/p>\n<p><p>&laquo;<em>If you&rsquo;re inclined to believe Igor Panarin, and the Kremlin wouldn&rsquo;t mind if you did, then President Barack Obama will order martial law this year, the U.S. will split into six rump-states before 2011, and Russia and China will become the backbones of a new world order.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Panarin might be easy to ignore but for the fact that he is a dean at the Foreign Ministry&rsquo;s school for future diplomats and a regular on Russia&rsquo;s state-guided TV channels. And his predictions fit into the anti-American story line of the Kremlin leadership. \u00ab\u00a0There is a high probability that the collapse of the United States will occur by 2010,\u00a0\u00bb Panarin told dozens of students, professors and diplomats Tuesday at the Diplomatic Academy &mdash; a lecture the ministry pointedly invited The Associated Press and other foreign media to attend.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Manifestement, l&rsquo;auteur de la d\u00e9p\u00eache, le journaliste Mike Ekel, est stup\u00e9fait qu&rsquo;une telle intervention se fasse dans un cadre officiel, qu&rsquo;elle soit soutenue et organis\u00e9e par le minist\u00e8re des affaires \u00e9trang\u00e8res, que le conf\u00e9rencier avec de telles id\u00e9es si \u00e9tranges soit lui-m\u00eame employ\u00e9 par ces services officiels. Ekel pr\u00e9cise qu&rsquo;il a \u00e9t\u00e9 demand\u00e9 \u00e0 des officiels du minist\u00e8re pr\u00e9sents si ce minist\u00e8re partageait cette analyse (il lui fut r\u00e9pondu qu&rsquo;une r\u00e9ponse \u00e9crite lui serait communiqu\u00e9e, &ndash; ce qui serait int\u00e9ressant \u00e0 lire). Il y a une r\u00e9elle condescendance dans la fa\u00e7on dont Panarine est pr\u00e9sent\u00e9 (&laquo;<em>If you&rsquo;re inclined to believe Igor Panarin, and the Kremlin wouldn&rsquo;t mind if you did&hellip;<\/em> [&hellip;] <em>Panarin might be easy to ignore but for the fact that he is a dean at the Foreign Ministry&rsquo;s school for future diplomats&hellip;<\/em>&raquo;). On sent qu&rsquo;il y a une consid\u00e9ration de sacril\u00e8ge dans le jugement port\u00e9 sur certaines affirmations de l&rsquo;orateur (&laquo;<em>I was there recently and things are far from good. What&rsquo;s happened is the collapse of the American dream<\/em>&raquo;).<\/p>\n<\/p>\n<p><p>Aussi ne s&rsquo;\u00e9tonne-t-on pas que la derni\u00e8re partie de la d\u00e9p\u00eache soit consacr\u00e9e \u00e0 une r\u00e9futation implicite de la th\u00e8se de Panarine, comme d&rsquo;habitude camoufl\u00e9e derri\u00e8re la r\u00e9f\u00e9rence \u00e0 l&rsquo;opportun expert qui va bien, et cors\u00e9e de l&rsquo;implicite et habituelle contre-attaque (\u00ab\u00a0ce que vous dites qui va nous arriver, cela va vous arriver \u00e0 vous!\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>&laquo;<em>It wasn&rsquo;t clear how persuasive the 20-minute lecture was. One instructor asked Panarin whether his predictions more accurately describe Russia, which is undergoing its worst economic crisis in a decade as well as a demographic collapse that has led some scholars to predict the country&rsquo;s d\u00e9mise. Panarin dismissed that idea: \u00ab\u00a0The collapse of Russia will not occur.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>But Alexei Malashenko, a scholar-in-residence at the Carnegie Moscow Center who did not attend the lecture, sided with the skeptical instructor, saying Russia is the country that is on the verge of disintegration. \u00ab\u00a0I can&rsquo;t imagine at all how the United States could ever fall apart,\u00a0\u00bb Malashenko told the AP.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;expert convoqu\u00e9, Alexei Malachenko, opportun\u00e9ment employ\u00e9 par la fondation Carnegie dans son antenne de Moscou (on conna&icirc;t le r\u00f4le des fondations US en Russie), a l&rsquo;esprit un peu court et la m\u00e9moire \u00e0 mesure. Juger \u00ab\u00a0inimaginable\u00a0\u00bb l&rsquo;hypoth\u00e8se que les USA puissent se disloquer est tout de m\u00eame un peu gros, &ndash; mais non, \u00e7a passe dans la d\u00e9p\u00eache, malgr\u00e9 la grossi\u00e8ret\u00e9 historique du propos, et ainsi les lecteurs am\u00e9ricanistes de la d\u00e9p\u00eache sont-ils rassur\u00e9s. Malachenko n&rsquo;a sans doute pas encore atteint le chapitre \u00ab\u00a0Guerre de S\u00e9cession\u00a0\u00bb dans ses \u00e9tudes historiques sur les USA, ou bien s&rsquo;en est-il tenu \u00e0 la pieuse version qui en fait une \u00ab\u00a0<em>Civil War<\/em>\u00a0\u00bb seulement pr\u00e9occup\u00e9e de faire cesser l&rsquo;esclavage sur la terre de la libert\u00e9.<\/p>\n<\/p>\n<p><p>Cette pr\u00e9sentation est r\u00e9v\u00e9latrice des r\u00e9actions des experts US, en g\u00e9n\u00e9ral, devant les hypoth\u00e8ses de dislocation des USA. Les hypoth\u00e8ses de troubles aux USA, de conflits sur les fronti\u00e8res (Mexique) pouvant avoir des effets int\u00e9rieurs ne manquent pas, mais l&rsquo;hypoth\u00e8se fondamentale de la dislocation est en g\u00e9n\u00e9ral \u00e9cart\u00e9e des \u00e9valuations des risques et des menaces. Son d\u00e9faut est tout simplement celui du sacril\u00e8ge. L&rsquo;attitude d&rsquo;auto-censure rel\u00e8ve de l&rsquo;exorcisme.<\/p>\n<\/p>\n<p><p>L&rsquo;allusion \u00e0 la possibilit\u00e9 de l&rsquo;\u00e9clatement de la Russie renvoie au contre-argument dialectique habituel, bas\u00e9 sur la perception de la puissance \u00e9conomique et militaire, du \u00ab\u00a0poids\u00a0\u00bb, seule chose que les experts US comprennent. La r\u00e9f\u00e9rence historique et m\u00eame m\u00e9tahistorique, et la r\u00e9f\u00e9rence psychologique, sont ignor\u00e9es. Nous dirions au contraire que la Russie n&rsquo;est pas tant \u00ab\u00a0menac\u00e9e d&rsquo;\u00e9clatement\u00a0\u00bb parce que c&rsquo;est une vieille nation qui a connu beaucoup d&rsquo;avatars, et qui renvoie \u00e0 une \u00ab\u00a0\u00e2me russe\u00a0\u00bb tr\u00e8s puissante. La Russie peut \u00eatre r\u00e9duite, perdre des territoires, conna&icirc;tre des crises, \u00eatre vaincue, occup\u00e9e, etc., mais l&rsquo;identit\u00e9 russe est quelque chose qui d\u00e9passe et m\u00eame transcende ces trag\u00e9dies. Il n&rsquo;y a pas de situation US \u00e9quivalent, ce qui renvoie effectivement \u00e0 un grand probl\u00e8me qui passionnait moralistes et historiens juste avant la Grande D\u00e9pression, &ndash; et qu&rsquo;on s&rsquo;interdit depuis d&rsquo;\u00e9voquer d&rsquo;une fa\u00e7on trop voyante: existe-t-il une \u00ab\u00a0\u00e2me am\u00e9ricaine\u00a0\u00bb, un \u00ab\u00a0caract\u00e8re am\u00e9ricain\u00a0\u00bb, ou bien ce pays est-il toujours fait d&rsquo;un assemblage artificiel de caract\u00e8res et d&rsquo;\u00e2mes diff\u00e9rents, et ne risque-t-il pas de se rompre comme il faillit faire en 1861? La r\u00e9ponse est \u00e9videmment positive: le risque existe, ce pourquoi les analyses de Panarine, sur le fond et sans s&rsquo;attacher pour ce cas aux pr\u00e9cisions de date et aux d\u00e9tails du processus, ne sont pas simples loufoqueries dans ces temps de tension extr\u00eame et de d\u00e9cadence acc\u00e9l\u00e9r\u00e9e de la puissance US. Le refus en g\u00e9n\u00e9ral des milieux officiels US, de planification et d&rsquo;information, de prendre en compte l&rsquo;hypoth\u00e8se de l&rsquo;\u00e9clatement, en dit long \u00e0 ce propos, <em>a contrario<\/em>, sur les risques effectivement r\u00e9els aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>Mis en ligne le 5 mars 2009 \u00e0 07H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin de l&rsquo;American Dream, l&rsquo;imagination un peu courte Il y a, depuis quelques mois, sur les r\u00e9seaux officiels am\u00e9ricanistes d&rsquo;information, un sujet particuli\u00e8rement d\u00e9licat qui commence \u00e0 \u00eatre abord\u00e9 avec r\u00e9ticence et hostilit\u00e9, alors qu&rsquo;il \u00e9tait jusqu&rsquo;alors implicitement off-limits et tout simplement ignor\u00e9. (L&rsquo;auto-censure de l&rsquo;information marche bien, y compris comme r\u00e9v\u00e9lateur: lorsqu&rsquo;elle commence \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3612,3613,7021,7930,2949,2804],"class_list":["post-70583","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-american","tag-dream","tag-eclatement","tag-panarine","tag-secession","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70583"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70583\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}