{"id":70605,"date":"2009-03-14T09:30:01","date_gmt":"2009-03-14T09:30:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/14\/apres-lambassadeur-freeman-lamiral-blair\/"},"modified":"2009-03-14T09:30:01","modified_gmt":"2009-03-14T09:30:01","slug":"apres-lambassadeur-freeman-lamiral-blair","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/14\/apres-lambassadeur-freeman-lamiral-blair\/","title":{"rendered":"Apr\u00e8s l&rsquo;ambassadeur Freeman, l&rsquo;amiral Blair?"},"content":{"rendered":"<p><p>Dans les suites de l&rsquo;affaire de la d\u00e9cision de retrait du poste de pr\u00e9sident du National Intelligence Council de Charles Freeman, la th\u00e8se d&rsquo;une victoire \u00e0 la Pyrrhus du <em>Lobby<\/em> (l&rsquo;AIPAC pro-isra\u00e9lien) fait de plus en plus d&rsquo;adeptes. <a href=\"http:\/\/www.antiwar.com\/ips\/lubanlobe.php?articleid=14400\" class=\"gen\">Aujourd&rsquo;hui<\/a>, sur <em>Antiwar.com<\/em> (et sur IPS), ce sont Daniel Luban et Jim Lobe qui y souscrivent, \u00e0 partir d&rsquo;une observation minutieuse des r\u00e9actions diverses du monde de la communication US.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Although the successful campaign to keep Amb. Charles \u00ab\u00a0Chas\u00a0\u00bb Freeman out of a top intelligence post marked a surface victory for the pro-Israel hardliners who opposed him, the long-term political implications of the Freeman affair appear far more ambiguous.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Freeman&rsquo;s withdrawal has provoked growing  if belated  media scrutiny of the operations of the so-called Israel Lobby, and aroused protests from a number of prominent mainstream political commentators who allege that he was the target of a dishonest and underhanded smear campaign that, among other things, accused him of shilling for the governments of Saudi Arabia and China.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For the neoconservatives who led the charge against Freeman&rsquo;s appointment, his withdrawal may therefore prove to be both a tactical victory and a strategic defeat.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe point le plus int\u00e9ressant de ce texte nous appara\u00eet \u00eatre celui qui est mis en conclusion, \u00e0 partir d&rsquo;une interview faite avec un ancien analyste de la Defense Intellegence Agency (DIA), le colonel Lang.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Col. Pat Lang, the former top Middle East analyst at the Defense Intelligence Agency who signed a letter of support for Freeman, told IPS that the saga had caused a tentative feeling of disappointment about the new administration within the intelligence community. It&rsquo;s very disheartening for people who viewed Freeman&rsquo;s appointment as the return to some standard of intellectual excellence or integrity, he said, adding that Director of National Intelligence (DNI) Adm. Dennis Blair, who went to the Senate and strongly defended his appointee, may be the next target for Freeman&rsquo;s antagonists as they push for alarmist intelligence on Iran.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I&rsquo;m concerned about what these characters are going to do about Blair, because Blair really stood up to them, and their general reaction to that is to wage a war of annihilation against people who do that, Lang said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement, l&rsquo;amiral Dennis Blair a soutenu avec force l&rsquo;ambassadeur Freeman, qu&rsquo;il avait personnellement et express\u00e9ment recrut\u00e9 pour ce poste de haut niveau. Blair a affirm\u00e9 son soutien d&rsquo;une mani\u00e8re tr\u00e8s officielle, par lettre et lors d&rsquo;une audition au S\u00e9nat, notamment face au s\u00e9nateur Lieberman. Ce n&rsquo;est pas une hypoth\u00e8se sollicit\u00e9e que de penser que Blair, en tant que DNI (Director of National Intelligence), va \u00eatre l&rsquo;objet des m\u00eames soup\u00e7ons que Freeman de la part du <em>Lobby<\/em> et de ses soutiens. Il est possible que des mises en cause et des pol\u00e9miques \u00e9clatent, \u00e0 l&rsquo;occasion d&rsquo;\u00e9valuations des services de renseignement. Les premi\u00e8res \u00e9valuations connues sous la responsabilit\u00e9 de Blair, le rapport annuel des services de renseignement, ont conduit \u00e0 des conclusions qui ont beaucoup <a href=\"http:\/\/www.dedefensa.org\/article-apocalypse_psychologique_16_02_2009.html\" class=\"gen\">\u00e9tonn\u00e9<\/a> certains, dans la mesure o\u00f9 ce rapport est une <a href=\"http:\/\/www.dedefensa.org\/article-deconstruction_de_9_11_13_02_2009.html\" class=\"gen\">d\u00e9construction<\/a> de 9\/11 et une mise en cause implicite de la sacro-sainte guerre contre la terreur, laquelle est le fondement de toute la pens\u00e9e et de la strat\u00e9gie des n\u00e9o-conservateurs, du <em>Lobby<\/em> et d&rsquo;Isra\u00ebl. On comprend, dans cette perspective, la validit\u00e9 de l&rsquo;hypoth\u00e8se de Pat Lang, d&rsquo;autant que le <em>Lobby<\/em> ne semble gu\u00e8re montrer de mesure ni de prudence actuellement pour lancer ses campagnes de pression et de diffamation, ce qui est clairement la cons\u00e9quence d&rsquo;une crainte de voir la politique US \u00e9voluer (d\u00e9favorablement pour Isra\u00ebl).<\/p>\n<\/p>\n<p><p>\tUn autre point doit \u00eatre mis en \u00e9vidence \u00e0 cette occasion, qui permet de mettre en doute les analyses trop sch\u00e9matiques, ou trop attach\u00e9es aux \u00e9tiquettes vite interpr\u00e9t\u00e9es. La pr\u00e9sence de Blair \u00e0 ce poste de responsabilit\u00e9, avec deux autres militaires ayant un rang \u00e9lev\u00e9 dans l&rsquo;administration Obama (le g\u00e9n\u00e9ral James Jones \u00e0 la t\u00eate du NSC et le g\u00e9n\u00e9ral Shinseki comme secr\u00e9taire aux V\u00e9t\u00e9rans), a fait dire \u00e0 certains commentateurs qu&rsquo;il s&rsquo;agissait d&rsquo;un noyautage, ou d&rsquo;une amorce de prise de contr\u00f4le, bref d&rsquo;une militarisation de l&rsquo;administration Obama dans le sens d&rsquo;un courant belliciste affirm\u00e9.<\/p>\n<\/p>\n<p><p>\tOn constate en fait, au contraire, que nombre de militaires ont des positions mod\u00e9r\u00e9es, beaucoup plus mod\u00e9r\u00e9es que les civils des milieux <em>neocons<\/em>, du <em>Lobby<\/em>, et des parlementaires compl\u00e8tement corrompus par le <em>Lobby<\/em> et les groupes d&rsquo;int\u00e9r\u00eat qui sont autour. Luban et Lobe mettent en \u00e9vidence la l\u00e2chet\u00e9 et la corruption du monde politique dans cette affaire Freeman, au contraire de la communaut\u00e9 de s\u00e9curit\u00e9 nationale (\u00ab[T]<em>he Freeman affair has highlighted the yawning disconnect between the career professionals in the intelligence and diplomatic communities, from whom Freeman enjoyed strong support, and political leaders in Congress and the White House, none of whom came to his defense publicly.<\/em> [] <em>While the Freeman affair may have shifted the parameters of debate on Israel policy, it has also exposed fissures and resentments between the national security bureaucracy and the U.S. political leadership<\/em>\u00bb). La lettre d&rsquo;information tr\u00e8s influente <em>Nelson Report<\/em> a compar\u00e9 l&rsquo;attaque contre Freeman aux pratiques du maccarthysme, avec l&rsquo;id\u00e9e implicite de rappeler que McCarthy s&rsquo;\u00e9tait effondr\u00e9 \u00e0 la suite d&rsquo;une attaque contre l&rsquo;U.S. Army, qui avait vu une violente riposte des militaires. Dans le cas consid\u00e9r\u00e9, si une attaque \u00e9tait effectivement lanc\u00e9e contre l&rsquo;amiral Dennis Blair, celui-ci devrait effectivement avoir le soutien des militaires et, surtout bien entendu, de l&rsquo;U.S. Navy, qui occupe une position tr\u00e8s puissante aujourd&rsquo;hui. Tout cela devrait, d&rsquo;autre part, tendre encore plus des rapports d\u00e9j\u00e0 d\u00e9licats entre la hi\u00e9rarchie militaire US, notamment et encore l&rsquo;U.S. Navy (l&rsquo;amiral <a href=\"http:\/\/www.dedefensa.org\/article-mullen_aux_israeliens_pas_de_nouveau_liberty_05_08_2008.html\" class=\"gen\">Mullen<\/a>, pr\u00e9sident du JCS), et la direction isra\u00e9lienne \u00e0 cause de ses projets bellicistes contre l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\tDans ce contexte, si une attaque type maccarthyste contre Blair est possible, elle risquerait de provoquer des \u00e9v\u00e9nements extr\u00eamement int\u00e9ressants, avec la possible confrontation du <em>Lobby<\/em> avec une parie importante de la communaut\u00e9 de s\u00e9curit\u00e9 nationale. Ce serait une \u00e9volution riche de cons\u00e9quences.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 mars 2009 \u00e0 09H37<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les suites de l&rsquo;affaire de la d\u00e9cision de retrait du poste de pr\u00e9sident du National Intelligence Council de Charles Freeman, la th\u00e8se d&rsquo;une victoire \u00e0 la Pyrrhus du Lobby (l&rsquo;AIPAC pro-isra\u00e9lien) fait de plus en plus d&rsquo;adeptes. Aujourd&rsquo;hui, sur Antiwar.com (et sur IPS), ce sont Daniel Luban et Jim Lobe qui y souscrivent, \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[831,705,8109,3003,3090,2774,2622,4883,3816,1094,3506,8178,2860],"class_list":["post-70605","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-a","tag-blair","tag-dennis","tag-freeman","tag-influence","tag-israel","tag-la","tag-lieberman","tag-lobby","tag-lobe","tag-maccarthysme","tag-pyrrhus","tag-victoire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70605"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70605\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}