{"id":70613,"date":"2009-03-17T06:47:26","date_gmt":"2009-03-17T06:47:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/17\/la-marche-des-patriot\/"},"modified":"2009-03-17T06:47:26","modified_gmt":"2009-03-17T06:47:26","slug":"la-marche-des-patriot","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/17\/la-marche-des-patriot\/","title":{"rendered":"La marche des <em>Patriot<\/em>"},"content":{"rendered":"<p><p>Les USA sont engag\u00e9s dans une op\u00e9ration dite, selon le jargon militaro-bureaucratique US,  de <em>damage control<\/em> vis-\u00e0-vis des pays d&rsquo;Europe de l&rsquo;Est. Il s&rsquo;agit essentiellement de la Pologne et de l&rsquo;affaire des syst\u00e8mes anti-missiles en Europe (BMDE) que l&rsquo;administration Obama veut abandonner. Une interview de Zbgniew Brzezinski au journal polonais <em>Gazeta Wyborcza<\/em> illustre clairement cette op\u00e9ration.<\/p>\n<\/p>\n<p><p>\tBrzezinski a tous les avantages pour cette sorte d&rsquo;intervention. Il a la r\u00e9putation d&rsquo;\u00eatre proche de l&rsquo;administration Obama, de jouer un r\u00f4le de conseiller occulte, type vieux sage, aupr\u00e8s du pr\u00e9sident pour les mati\u00e8res de s\u00e9curit\u00e9 nationale. Il est d&rsquo;origine polonaise. Sa  m\u00e9fiance, voire son hostilit\u00e9 \u00e0 la Russie constitue une garantie implicite qu&rsquo;il ne souscrirait pas \u00e0 une op\u00e9ration de l\u00e2chage des pays d&rsquo;Europe de l&rsquo;Est, surtout pas son pays d&rsquo;origine; son argumentation en faveur de ce qu&rsquo;il d\u00e9clare \u00eatre une \u00e9volution vers l&rsquo;abandon du BMDE peut \u00eatre prise pour rassurante \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\tL&rsquo;agence Novosti rapporte, le <a href=\"http:\/\/fr.rian.ru\/world\/20090316\/120588919.html\" class=\"gen\">16 mars<\/a>, des extraits de cet interview.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La coop\u00e9ration entre Moscou et Washington sur le probl\u00e8me nucl\u00e9aire iranien pourrait rendre inutile le d\u00e9ploiement d&rsquo;\u00e9l\u00e9ments du bouclier antimissile am\u00e9ricain en Pologne, a estime lundi Zbigniew Brzezinski, ex-conseiller \u00e0 la S\u00e9curit\u00e9 du pr\u00e9sident US, dans une interview au journal polonais Gazeta Wyborcza. Personne ne garantira aujourd&rsquo;hui que des \u00e9l\u00e9ments du syst\u00e8me ABM seront d\u00e9ploy\u00e9s en Pologne, a estim\u00e9 M. Brzezinski.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il n&rsquo;est pas \u00e0 exclure qu&rsquo;\u00e0 l&rsquo;issue des n\u00e9gociations entre les Etats-Unis et la Russie et suite aux pressions contre l&rsquo;Iran, une nouvelle situation apparaisse quand la n\u00e9cessit\u00e9 du d\u00e9ploiement du bouclier antimissile diminue ou m\u00eame disparaisse compl\u00e8tement, a expliqu\u00e9 l&rsquo;ancien conseiller de la pr\u00e9sidence am\u00e9ricaine.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn point important, qui signale l&rsquo;\u00e9volution de la dialectique am\u00e9ricaniste dans cette affaire, est mis en \u00e9vidence par Brzezinski lorsqu&rsquo;il estime que \u00ab<em>les missiles antimissiles am\u00e9ricains Patriot sont beaucoup plus importants pour la s\u00e9curit\u00e9 de la Pologne que le syst\u00e8me ABM<\/em> [BMDE]\u00bb. La d\u00e9p\u00eache Novosti rappelle obligeamment de r\u00e9centes d\u00e9clarations polonaises \u00e0 propos des missiles <em>Patriot<\/em>, qui n&rsquo;occupaient primitivement qu&rsquo;une place accessoire et accidentelle dans cette affaire, et qui tendent \u00e0 en devenir le centre aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La semaine derni\u00e8re le ministre polonais de la D\u00e9fense Bogdan Klich a esp\u00e9r\u00e9 que Washington et Varsovie pourraient achever leurs n\u00e9gociations sur le d\u00e9ploiement de la premi\u00e8re batterie de missiles antimissiles am\u00e9ricains Patriot en Pologne en avril prochain.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Fin f\u00e9vrier, le ministre polonais des Affaires \u00e9trang\u00e8res Radoslaw Sikorski a d\u00e9clar\u00e9 \u00e0 l&rsquo;issue d&rsquo;un entretien \u00e0 Washington avec la secr\u00e9taire d&rsquo;Etat am\u00e9ricaine Hillary Clinton qu&rsquo;une batterie de missiles antimissiles Patriot serait d\u00e9ploy\u00e9e en Pologne ind\u00e9pendamment des perspectives d&rsquo;installation d&rsquo;\u00e9l\u00e9ments du bouclier ABM am\u00e9ricain le sol polonais.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout cela permet d&rsquo;observer, sinon d&rsquo;admirer une \u00e9tonnante rupture de la rh\u00e9torique de cette affaire, \u00e0 cause de l&rsquo;obligation, pour les USA, de transformer ce qui est manifestement l&rsquo;abandon d\u00e9sormais probable du BMDE, avec le risque d&rsquo;endommager leurs relations avec la Pologne, en une op\u00e9ration de substitution dont on esp\u00e8re qu&rsquo;elle va au contraire resserrer ces liens. D\u00e9sormais, les <em>Patriot<\/em> sont plus importants que le BMDE, <em>dixit<\/em> Brzezinski, alors qu&rsquo;il n&rsquo;en fut jamais question d&rsquo;une fa\u00e7on fondamentale, pour des raisons op\u00e9rationnelles et de s\u00e9curit\u00e9.<\/p>\n<\/p>\n<p><p>\t La question des <em>Patriot<\/em> fut introduite \u00e0 la fin de l&rsquo;ann\u00e9e 2007, au cours des n\u00e9gociations am\u00e9ricano-polonaises pour l&rsquo;installation du BMDE, \u00e0 la demande des Polonais du nouveau gouvernement Tusk. L&rsquo;id\u00e9e \u00e9tait <a href=\"http:\/\/www.dedefensa.org\/article-les_patriot_de_radek_sikorski_14_01_2008.html\" class=\"gen\">sp\u00e9cifiquement<\/a> celle du nouveau ministre des affaires \u00e9trang\u00e8res Sikorski, et elle \u00e9tait sp\u00e9cifiquement li\u00e9e au d\u00e9ploiement du BMDE. Les <em>Patriot<\/em>, qui sont des missiles de d\u00e9fense sol-air, \u00e9taient proclam\u00e9s n\u00e9cessaires pour d\u00e9fendre la base BMDE qui allait \u00eatre install\u00e9e en Pologne, contre la menace suppos\u00e9e d&rsquo;une attaque russe. La situation de tension cr\u00e9\u00e9e artificiellement par la perspective du BMDE \u00e9tait suppos\u00e9e cr\u00e9er artificiellement une menace russe contre le BMDE, contre laquelle il importait de se pr\u00e9munir par avance avec les <em>Patriot<\/em>.<\/p>\n<\/p>\n<p><p>\t Aujourd&rsquo;hui, surprise surprise, on d\u00e9couvre, notamment dans la bouche de Brzezinski, que les missiles <em>Patriot<\/em>, sont n\u00e9cessaires en eux-m\u00eames, sans base BMDE \u00e0 prot\u00e9ger, pour la s\u00e9curit\u00e9 de la Pologne <em>per se<\/em>. Les <em>Patriot<\/em> contre quoi? Eventuellement contre la Russie, cela va de soi car il suffit de regarder une carte, ou bien contre les go\u00e9lands de la Mer Baltique s&rsquo;il s&rsquo;av\u00e8re qu&rsquo;on est (re)devenus amis des Russes. (Qu&rsquo;il soit rappel\u00e9, en passant et pour les \u00e2mes fra\u00eechement acquises \u00e0 l&rsquo;<em>American Dream<\/em>, que le <em>Patriot<\/em> est, comble de prouesse, d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article-d_une_guerre_du_golfe_a_l_autre_le_roman_surrealiste_et_virtualiste_du_missile_americain_patriot_21_04_2003.html\" class=\"gen\">inefficacit\u00e9<\/a> notoire et av\u00e9r\u00e9e.)<\/p>\n<\/p>\n<p><p>\t Les Polonais semblent marcher dans la combine, Brzezinski n&rsquo;ayant pas manqu\u00e9 de rappeler que Sikorski avait lui-m\u00eame rappel\u00e9, \u00e0 Washington le mois dernier apr\u00e8s une rencontre avec Clinton, que la question du BMDE ne regardait que les USA; les <em>Patriot<\/em>, au contraire, concernent au premier chef les Polonais. Cela signifie que la susceptibilit\u00e9 des Polonais peut ainsi \u00eatre rencontr\u00e9e et apais\u00e9e, et c&rsquo;est encore bien mieux sans le BMDE. Lorsqu&rsquo;on parlait du BMDE, les Polonais n&rsquo;avaient pas leur mot \u00e0 dire sur le fond, puisque la d\u00e9cision incombait aux seuls USA, et leur go\u00fbt bien connu de l&rsquo;ind\u00e9pendance pouvait en \u00eatre affect\u00e9 ; avec les <em>Patriot<\/em>, au contraire, ils ont leur mot \u00e0 dire, \u00f4 combien, et leur ind\u00e9pendance nationale en est confort\u00e9e.<\/p>\n<\/p>\n<p><p>\t C&rsquo;est une manuvre \u00e9tonnante. Le besoin pour les <em>Patriot<\/em> n&rsquo;a jamais exist\u00e9 dans les \u00e9valuations op\u00e9rationnelles, et il n&rsquo;existe pas plus aujourd&rsquo;hui. (Les Russes ont d&rsquo;autres chats \u00e0 fouetter \u00e0 cet \u00e9gard.) Le cas du <em>Patriot<\/em> est apparu \u00e0 cause du BMDE, pour la s\u00e9curit\u00e9 de la base projet\u00e9e du BMDE, et pour donner une compensation aux Polonais. Le BMDE est en train de dispara\u00eetre et il appara\u00eet soudain que l&rsquo;important, c&rsquo;est le <em>Patriot<\/em>. Raytheon (fabriquant du <em>Patriot<\/em>) est content; le gouvernement polonais est content, s&rsquo;il obtient des conditions de vente int\u00e9ressantes; l&rsquo;administration Obama est contente, elle va pouvoir abandonner le programme BMDE sans risquer, esp\u00e8re-t-elle, la mauvaise humeur de la Pologne.<\/p>\n<\/p>\n<p><p>\tComme on voit, dans tout cela la logique des imp\u00e9ratifs strat\u00e9giques et des imp\u00e9ratifs op\u00e9rationnels de la s\u00e9curit\u00e9 nationale de la Pologne a jou\u00e9 \u00e0 plein sur un dossier compl\u00e8tement vide et dans le cadre d&rsquo;une r\u00e9alit\u00e9 absolument inexistante. Il se confirme qu&rsquo;il est devenu difficile, dans une \u00e9poque enti\u00e8rement r\u00e9gl\u00e9e par la communication pour habiller des imp\u00e9ratifs politiques fabriqu\u00e9s pour des causes diverses, commerciales et id\u00e9ologiques, de parler s\u00e9rieusement de la g\u00e9opolitique. Le cas BMDE \u00e9tait \u00e0 l&rsquo;origine b\u00e2ti sur une simple op\u00e9ration de communication impliquant le complexe militaro-industriel US et les r\u00e9seaux d&rsquo;influence n\u00e9o-conservateurs; il est en train de s&rsquo;achever sur une op\u00e9ration de communication en sens inverse, de la part de l&rsquo;administration Obama. Dans ce cheminement, on a peine \u00e0 trouver trace de la r\u00e9alit\u00e9 g\u00e9opolitique.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 mars 2009 \u00e0 06H55<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les USA sont engag\u00e9s dans une op\u00e9ration dite, selon le jargon militaro-bureaucratique US, de damage control vis-\u00e0-vis des pays d&rsquo;Europe de l&rsquo;Est. Il s&rsquo;agit essentiellement de la Pologne et de l&rsquo;affaire des syst\u00e8mes anti-missiles en Europe (BMDE) que l&rsquo;administration Obama veut abandonner. Une interview de Zbgniew Brzezinski au journal polonais Gazeta Wyborcza illustre clairement cette&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4314,3950,2827,4862,2828,610],"class_list":["post-70613","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bmde","tag-patriot","tag-pologne","tag-sikorski","tag-tusk","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70613"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70613\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}