{"id":70618,"date":"2009-03-19T06:29:48","date_gmt":"2009-03-19T06:29:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/19\/le-tsunami-de-lus-navy\/"},"modified":"2009-03-19T06:29:48","modified_gmt":"2009-03-19T06:29:48","slug":"le-tsunami-de-lus-navy","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/19\/le-tsunami-de-lus-navy\/","title":{"rendered":"Le <em>tsunami<\/em> de l&rsquo;US. Navy"},"content":{"rendered":"<p><p>Robert Gates a annonc\u00e9 plusieurs recommandations de nomination importantes, qui affirment une extraordinaire pr\u00e9\u00e9minence de l&rsquo;U.S. Navy dans les grands commandements structurels \u00e0 forte implication politique des forces arm\u00e9es US. Une d\u00e9p\u00eache <em>BBC.News<\/em> du <a href=\"http:\/\/news.bbc.co.uk\/2\/hi\/americas\/7951754.stm\" class=\"gen\">18 mars<\/a>, notamment, donnent les indications \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\t L&rsquo;amiral James Stavridis, qui commande Southern Command (la zone de l&rsquo;Am\u00e9rique Latine) est recommand\u00e9 comme nouveau commandant en chef de European Command et nouveau commandant en chef supr\u00eame en Europe (SACEUR, chef militaire de l&rsquo;OTAN) en remplacement du g\u00e9n\u00e9ral de l&rsquo;U.S. Army John Craddock. Cette recommandation est un \u00e9v\u00e9nement, notamment dans la mesure o\u00f9 Stavidris est le premier amiral pour ce poste, qui va traditionnellement depuis un demi-si\u00e8cle \u00e0 l&rsquo;U.S Army (le plus souvent) et \u00e0 l&rsquo;USAF (\u00e0 deux reprises, en 1958 et en 2000). <em>BBC.News<\/em> note: \u00ab<em>But correspondents say appointing an admiral as the alliance prepares to step up its ground war in Afghanistan may cause concern in some quarters.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t L&rsquo;amiral Robert Willard, actuellement chef de la Flotte du Pacifique, est recommand\u00e9 pour devenir commandant en chef de la zone Pacifique (PacCom). C&rsquo;est l\u00e0 aussi une r\u00e9affirmation de la pr\u00e9\u00e9minence de l&rsquo;U.S. Navy, dans un poste de contr\u00f4le strat\u00e9gique essentiel, qui est partag\u00e9 traditionnellement par la Navy et l&rsquo;USAF.<\/p>\n<\/p>\n<p><p>\t L&rsquo;amiral Mullen est recommand\u00e9 pour un nouveau terme (deux ans) \u00e0 la t\u00eate du Joint Chief of Staff, qui contr\u00f4le toutes les forces arm\u00e9es.<\/p>\n<\/p>\n<p><p>\tCes recommandations compl\u00e8tent un dispositif des grands commandements qui assure une \u00e9norme pr\u00e9pond\u00e9rance \u00e0 l&rsquo;U.S. Navy, notamment par l&rsquo;importance strat\u00e9gique et politique des commandements qui lui reviennent. La nomination probable de Stavidris r\u00e9tablit un \u00e9quilibre politique cher \u00e0 Gates, qui avait \u00e9t\u00e9 rompu avec <a href=\"http:\/\/www.dedefensa.org\/article-apres_la_chute_18_03_2008.html?admin=1\" class=\"gen\">la d\u00e9mission<\/a> il y a un an de l&rsquo;amiral Fallon de la direction de Central Command, et son remplacement par le g\u00e9n\u00e9ral Petraeus. Stavidris devrait jouer un r\u00f4le essentiel dans le conflit de l&rsquo;Afghanistan, \u00e0 cause de l&rsquo;implication de l&rsquo;OTAN, et marquera d&rsquo;autant Petraeus, qui a l&rsquo;Afghanistan dans sa zone de responsabilit\u00e9. Petraeus, homme de compromis qui conna\u00eet ses int\u00e9r\u00eats, s&rsquo;est largement ralli\u00e9 \u00e0 la politique de l&rsquo;administration Obama apr\u00e8s avoir \u00e9t\u00e9 l&rsquo;homme de Bush en Irak, mais il sera de cette fa\u00e7on encore mieux encadr\u00e9.<\/p>\n<\/p>\n<p><p>\tLe maintien de Mullen est \u00e9galement un point tr\u00e8s important. C&rsquo;est le renouvellement d&rsquo;une \u00e9quipe (Gates-Mullen) qui a travaill\u00e9 depuis deux ans \u00e0 l&rsquo;apaisement des tensions au sein de l&rsquo;appareil militaire, et \u00e0 une politique de r\u00e9duction radicale de la politique belliciste de l&rsquo;\u00e9poque Bush. Gates-Mullen ont jou\u00e9 un r\u00f4le capital dans le <a href=\"http:\/\/www.dedefensa.org\/article-mullen_en_super-fallon_pas_d_attaque_contre_l_iran_c_est_compris_03_07_2008.html\" class=\"gen\">d\u00e9samor\u00e7age<\/a> de toute tentative d&rsquo;attaque contre l&rsquo;Iran de la partie extr\u00e9miste de l&rsquo;administration Bush.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, ces recommandations renforcent un dispositif g\u00e9n\u00e9ral, voulu par Gates avec le soutien d&rsquo;Obama, qui tend \u00e0 confirmer l&rsquo;orientation de la hi\u00e9rarchie militaire vers une politique syst\u00e9matique d&rsquo;apaisement. La nomination \u00e9ventuelle de Stavidris \u00e0 l&rsquo;OTAN semble impliquer notamment que la recherche d&rsquo;un arrangement en Afghanistan sera privil\u00e9gi\u00e9e sur la poursuite maximaliste de la guerre. Elle indique que les relations entre les USA et l&rsquo;Europe ne sont certainement pas une priorit\u00e9 au niveau militaire et strat\u00e9gique pour l&rsquo;administration Obama, qu&rsquo;elles doivent plut\u00f4t \u00eatre trait\u00e9es au niveau diplomatique et \u00e9conomique.<\/p>\n<\/p>\n<p><p>\tOn ajoutera \u00e0 ces recommandations le rappel que c&rsquo;est \u00e9galement un amiral (\u00e0 la retraite), l&rsquo;amiral <a href=\"http:\/\/www.dedefensa.org\/article-apres_l_ambassadeur_freeman_l_amiral_blair_14_03_2009.html\" class=\"gen\">Dennis Blair<\/a>, qui tient <a href=\"http:\/\/www.dedefensa.org\/article-apocalypse_psychologique_16_02_2009.html\" class=\"gen\">la t\u00eate<\/a> du renseignement US comme Director of National Intelligence (DNI). L&rsquo;U.S. Navy est devenue, au sein de l&rsquo;<em>establishment<\/em> washingtonien, la grande force militaire de stabilisation et de remise en ordre apr\u00e8s l&rsquo;\u00e9poque GW Bush. Cette situation renforce \u00e9galement, par le biais de bons rapports entre le pouvoir civil et la direction militaire au travers de la pr\u00e9pond\u00e9rance de l&rsquo;U.S. Navy, la stabilit\u00e9 politique, la loyaut\u00e9 du pouvoir militaire vis-\u00e0-vis du pouvoir civil en temps de crise. Sont confirm\u00e9es d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale les diverses orientations constat\u00e9es, d&rsquo;un changement de la politique de s\u00e9curit\u00e9 nationale, vers un certain apaisement, toute l&rsquo;attention \u00e9tant d\u00e9sormais port\u00e9e \u00e0 la crise \u00e9conomique et \u00e0 ses cons\u00e9quences.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit aussi, la chose \u00e9tant consid\u00e9r\u00e9e d&rsquo;une fa\u00e7on plus structur\u00e9e, de la confirmation de ce que nous nommons la <a href=\"http:\/\/www.dedefensa.org\/article-le_verrou_afghan_et_la_contraction_de_la_politique_exterieure_us_10_03_2009.html\" class=\"gen\">contraction<\/a> de la politique de s\u00e9curit\u00e9 nationale des USA. Que l&rsquo;U.S. Navy y participe d&rsquo;une fa\u00e7on aussi pr\u00e9pond\u00e9rante est tout \u00e0 fait logique; il s&rsquo;agit d&rsquo;une arme traditionnelle puissante, tr\u00e8s stable, qui assure certes le contr\u00f4le des mers mais qui reste tr\u00e8s centrip\u00e8te, tr\u00e8s li\u00e9e par orientation strat\u00e9gique au centre national et g\u00e9ographique du pouvoir US, et d&rsquo;une fa\u00e7on historique un service de tradition isolationniste. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 mars 2009 \u00e0 06H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robert Gates a annonc\u00e9 plusieurs recommandations de nomination importantes, qui affirment une extraordinaire pr\u00e9\u00e9minence de l&rsquo;U.S. Navy dans les grands commandements structurels \u00e0 forte implication politique des forces arm\u00e9es US. Une d\u00e9p\u00eache BBC.News du 18 mars, notamment, donnent les indications \u00e0 cet \u00e9gard. L&rsquo;amiral James Stavridis, qui commande Southern Command (la zone de l&rsquo;Am\u00e9rique Latine)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8172,3984,7098,3319,584,3194,6264,3312,8185,2671],"class_list":["post-70618","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-contraction","tag-gates","tag-mullen","tag-navy","tag-otan","tag-pentagone","tag-petraeus","tag-saceur","tag-stavridis","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70618"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70618\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}