{"id":70622,"date":"2009-03-20T13:27:15","date_gmt":"2009-03-20T13:27:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/20\/le-crepuscule-de-lusaf-1\/"},"modified":"2009-03-20T13:27:15","modified_gmt":"2009-03-20T13:27:15","slug":"le-crepuscule-de-lusaf-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/20\/le-crepuscule-de-lusaf-1\/","title":{"rendered":"Le cr\u00e9puscule de l&rsquo;USAF ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cr\u00e9puscule de l&rsquo;USAF ?<\/h2>\n<\/p>\n<p><p>Le 19 mars avait lieu \u00e0 Washington la pr\u00e9sentation d&rsquo;un rapport du Mitchell Institute, de l&rsquo;Air Force Association, le principal <em>lobby<\/em> de l&rsquo;USAF. Il s&rsquo;agit du <a class=\"gen\" href=\"http:\/\/www.afa.org\/mitchell\/reports\/CAF_0309.pdf \">rapport<\/a> <em>Combat Air Forces in Crisis<\/em>, sous la direction de Rebecca Grant, auteur tr\u00e8s proche de l&rsquo;AFA. Ce rapport examine la crise de l&rsquo;USAF, et des forces a\u00e9riennes de combat US plus pr\u00e9cis\u00e9ment, au stade actuel; crise non pas mena\u00e7ante, mais d&rsquo;ores et d\u00e9j\u00e0 active et parvenue \u00e0 son point paroxystique.<\/p>\n<\/p>\n<p><p>Extrait de la pr\u00e9sentation du rapport: &laquo;<em>To the extent that the sky is going to fall, it has already fallen.<\/em> <strong><em>It is too late to avert the crisis<\/em><\/strong><em>. Old platforms and years of inadequate procurement have set the force structure on an all-but-irreversible downward course for at least the next several years and probably much longer. Now, the Air Force is assessing the risks and remedies that will help it find ways to cope with an extremely high proportion of legacy aircraft in Combat Air Forces.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Diverses pr\u00e9sentations ont accompagn\u00e9 la pr\u00e9sentation du rapport. Toutes allaient, bien s&ucirc;r, dans le m\u00eame sens. Le <em>Daily Report<\/em> de l&rsquo;AFA de ce jour (<a class=\"gen\" href=\"http:\/\/www.airforce-magazine.com\/Pages\/default.aspx\">20 mars<\/a>) donne des extraits, notamment, de l&rsquo;intervention de Loren B. Thompson, fortement orient\u00e9e sur la situation budg\u00e9taire de crise.<\/p>\n<\/p>\n<p><p>Thompson est extr\u00eamement pessimiste sur les perspectives. Il semble notamment d\u00e9mentir les analyses qui avan\u00e7aient que le programme JSF, r\u00e9duit en dotation pour l&rsquo;ann\u00e9e FY2010, serait ensuite acc\u00e9l\u00e9r\u00e9.<\/p>\n<\/p>\n<p><p>&laquo;<em>The aerospace industry was badly rattled recently by a leaked memo that the Office of Management and Budget wanted the Pentagon to consider postponing a new aerial tanker by five years and killing the 2018 bomber project outright. But that wasn&rsquo;t all OMB had its eyes on, according to Loren Thompson of the Lexington Institute.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Speaking yesterday in Washington, D.C., at an event sponsored by AFA&rsquo;s Mitchell Institute for Airpower Studies, Thompson said the OMB passed on other \u00ab\u00a0suggestions\u00a0\u00bb that signal the White House&rsquo;s intent to cut defense programs deeply. \u00ab\u00a0What you didn&rsquo;t hear about,\u00a0\u00bb Thompson claimed, were suggestions to cut the airborne laser, the transformational satellite communications system, further C-130 purchases, and even a new aircraft carrier. And, that was just for Fiscal 2010. In 2011, Thompson asserted, OMB wants the Pentagon to terminate the F-22 and Navy F\/A-18 Super Hornet and sharply reduce buys of the F-35. \u00ab\u00a0These are exciting times,\u00a0\u00bb Thompson joked, \u00ab\u00a0like Pearl Harbor was exciting.\u00a0\u00bb Unless China suddenly gets visibly belligerent or terrorist attacks in the US resume, Thompson sees little traction for keeping all these programs in a budget drowning in red ink. \u00ab\u00a0This spells big trouble for US airpower,\u00a0\u00bb he said.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>La crise de l&rsquo;USAF <a class=\"gen\" href=\" http:\/\/www.dedefensa.org\/article-la_crise_des_f-15_une_crise_usaf_29_12_2007.html\">existait<\/a> avant la crise, si l&rsquo;on peut dire. Avec la crise financi\u00e8re et \u00e9conomique et ses effets sur le budget de la d\u00e9fense, alors que le Pentagone est lui-m\u00eame en crise, la crise de l&rsquo;USAF prend naturellement, pour des causes d\u00e9sormais ext\u00e9rieures \u00e0 elle-m\u00eame, des proportions catastrophiques. (Trois crises, chacune sp\u00e9cifique, s&rsquo;additionnant, &ndash; crise financi\u00e8re + crise du Pentagone + crise de l&rsquo;USAF.) C&rsquo;est le fondement m\u00eame de la puissance a\u00e9rienne US qui est aujourd&rsquo;hui en cause, et nul n&rsquo;y peut plus rien pour l&rsquo;instant, sinon tenter de colmater quelques br\u00e8ches. La pression de la crise g\u00e9n\u00e9rale entra&icirc;nant l&rsquo;endettement astronomique du gouvernement f\u00e9d\u00e9ral devient le facteur fondamental, que nous irions jusqu&rsquo;\u00e0 consid\u00e9rer comme le facteur exclusif pour le temps pr\u00e9sent, pour mener la danse. C&rsquo;est-\u00e0-dire que les vrais arguments, qui sont strat\u00e9giques, op\u00e9rationnels, etc., n&rsquo;ont plus vraiment cours.<\/p>\n<\/p>\n<p><p>Le v\u00e9ritable d\u00e9bat qui, \u00e0 notre sens, va s&rsquo;ouvrir dans l&rsquo;USAF est celui de savoir si l&rsquo;on ne devrait pas tenter d&rsquo;en revenir en catastrophe \u00e0 des achats d&rsquo;urgence et de sauvegarde des plus r\u00e9centes versions des vieux programmes F-15 et F-16, en laissant s&rsquo;\u00e9tendre le plus possible les programmes de modernisation avanc\u00e9s, essentiellement le JSF. L&rsquo;espoir serait, avec des jours meilleurs, de reprendre ces programmes de modernisation; l&rsquo;urgence, elle, serait de combler les trous qui s&rsquo;\u00e9largissent dans la dotation op\u00e9rationnelle actuelle, avec des avions des programmes F-15 et F-16..<\/p>\n<\/p>\n<p><p>Mis en ligne le 20 mars 2009 \u00e0 13H28<\/p>\n<\/p>\n<p><p>[Ajout \u00e0 16H55: \u00e0 propos et apr\u00e8s tout, comparez cette nouvelle avec celle qui nous donne un aper\u00e7u du renforcement de la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_tsunami_de_l_us_navy_19_03_2009.html\">puissance<\/a> de l&rsquo;U.S. Navy au sein du Pentagone; et interrogez-vous sur la fa\u00e7on dont pourrait \u00e9voluer la posture et la structure strat\u00e9gique des USA dans les ann\u00e9es \u00e0 venir.]<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cr\u00e9puscule de l&rsquo;USAF ? Le 19 mars avait lieu \u00e0 Washington la pr\u00e9sentation d&rsquo;un rapport du Mitchell Institute, de l&rsquo;Air Force Association, le principal lobby de l&rsquo;USAF. Il s&rsquo;agit du rapport Combat Air Forces in Crisis, sous la direction de Rebecca Grant, auteur tr\u00e8s proche de l&rsquo;AFA. Ce rapport examine la crise de l&rsquo;USAF,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[248,3109,3127,3228,3302,1015,3584,3923,250,3473,4846,3194,8187,3474,41],"class_list":["post-70622","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afa","tag-b","tag-budget","tag-crise","tag-f-15","tag-f-16","tag-grant","tag-institute","tag-jsf","tag-loren","tag-mitchell","tag-pentagone","tag-rebecca","tag-thompson","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70622"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70622\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}