{"id":70626,"date":"2009-03-23T05:32:06","date_gmt":"2009-03-23T05:32:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/23\/le-brussels-forum-et-la-houle-transatlantique\/"},"modified":"2009-03-23T05:32:06","modified_gmt":"2009-03-23T05:32:06","slug":"le-brussels-forum-et-la-houle-transatlantique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/23\/le-brussels-forum-et-la-houle-transatlantique\/","title":{"rendered":"Le <em>Brussels Forum<\/em> et la houle transatlantique"},"content":{"rendered":"<p><p>Organis\u00e9 annuellement depuis 2006 par un ensemble sympathique et vari\u00e9 d&rsquo;organisations semi-officielles et transatlantiques, avec le puissant et inspir\u00e9 <em>leadership<\/em> du <em>German Marshall Fund of the United States<\/em>, le <em>Brussels Forum<\/em> est la derni\u00e8re initiative en date de l&rsquo;\u00e9ternel retour de l&rsquo;entente transatlantique. Il s&rsquo;agit de la contribution de l&rsquo;administration Bush, <em>circa<\/em>-relance multilat\u00e9raliste \u00e0 partir de 2005, \u00e0 l&rsquo;inextricable r\u00e9seau d&rsquo;organisation US d&rsquo;influence en Europe, avec le z\u00e8le et la participation enthousiaste des \u00e9lites europ\u00e9ennes. On dit que la chose n&rsquo;est pas tr\u00e8s bien en point et cherche un financement pour le <em>Forum<\/em> de l&rsquo;ann\u00e9e prochaine, signe des temps, de la crise et, peut-\u00eatre, d&rsquo;un certain <a href=\"http:\/\/www.dedefensa.org\/article-la_tension_des_illusions_perdues_20_03_2009.html\" class=\"gen\">d\u00e9couragement<\/a> pour l&rsquo;am\u00e9lioration d\u00e9cisive des relations transatlantiques. Ces relations ressemblent \u00e0 un objet intercontinental non identifi\u00e9; elles nous semblent toujours soumises \u00e0 une impeccable servilit\u00e9 volontaire des Europ\u00e9ens, et pourtant toujours \u00e0 la recherche d&rsquo;une am\u00e9lioration d\u00e9cisive qui semblerait dire, au contraire, que la servilit\u00e9 volontaire ne suffit pas<\/p>\n<\/p>\n<p><p>\tLe vrai est que l&rsquo;atmosph\u00e8re y fut, pendant <a href=\"http:\/\/www.gmfus.org\/brusselsforum\/2009\/\" class=\"gen\">le week-end<\/a>, assez surr\u00e9aliste. Une source diplomatique de haut niveau d\u00e9crivait le <em>Forum<\/em> comme ce dessin anim\u00e9 o\u00f9 le coyote fonce \u00e0 toute vitesse sur une falaise au bord d&rsquo;un pr\u00e9cipice, d\u00e9passe la falaise, toujours avec ses jambes en pleine acc\u00e9l\u00e9ration, soudain suspendu dans les airs, soudain ralentissant jusqu&rsquo;\u00e0 l&rsquo;arr\u00eat complet dans l&rsquo;espace, jambes tournant dans le vide,  qui s&rsquo;interroge, surpris de cet arr\u00eat intempestif, regarde autour de lui, puis sous lui, d\u00e9couvre l&rsquo;ab\u00eeme du vide au-dessus duquel il est suspendu, s&rsquo;en afflige, s&rsquo;affole, avant d&rsquo;entamer sa chute \u00ab<em>Nous sommes \u00e0 cet instant de gr\u00e2ce o\u00f9 nous sommes suspendus dans le vide, o\u00f9 nous regardons le vide, o\u00f9 nous nous interrogeons en nous demandant ce qui va se passer, o\u00f9 tout cela va nous conduire, va nous emmener.<\/em>\u00bb Ainsi en \u00e9tait-il de l&rsquo;atmosph\u00e8re dans les couloirs, derri\u00e8re les interventions plus ou moins convenues, o\u00f9 parfois certaines choses int\u00e9ressantes sont dites.<\/p>\n<\/p>\n<p><p>\tLe climat, du c\u00f4t\u00e9 des Am\u00e9ricains, \u00e9tait si diff\u00e9rent de ce que la coutume des relations transatlantiques nous en dit. Les couloirs r\u00e9sonnaient encore des appels, US cela va de soi, \u00e0 la mobilisation contre la terreur lanc\u00e9 aux figures bien p\u00e2les des Europ\u00e9ens, dont le <em>Forum<\/em> \u00e9tait encore plein il y a un an. En 2009, rien de semblable. \u00ab<em>Plus aucune arrogance chez eux, au contraire un abord amical, un d\u00e9sarroi \u00e0 peine dissimul\u00e9, parfois m\u00eame on sollicite l&rsquo;un ou l&rsquo;autre Europ\u00e9en,  sur le th\u00e8me Vous n&rsquo;auriez pas une petite id\u00e9e ou l&rsquo;autre pour sortir de la crise<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, ne boudons pas notre plaisir. Cette ann\u00e9e, en v\u00e9rit\u00e9, le <em>Brussels Forum<\/em> \u00e9tait parfaitement repr\u00e9sentatif de la situation transatlantique et de la situation occidentale.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 mars 2009 \u00e0 05H36<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organis\u00e9 annuellement depuis 2006 par un ensemble sympathique et vari\u00e9 d&rsquo;organisations semi-officielles et transatlantiques, avec le puissant et inspir\u00e9 leadership du German Marshall Fund of the United States, le Brussels Forum est la derni\u00e8re initiative en date de l&rsquo;\u00e9ternel retour de l&rsquo;entente transatlantique. Il s&rsquo;agit de la contribution de l&rsquo;administration Bush, circa-relance multilat\u00e9raliste \u00e0 partir&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5742,5349,3228,6214,3516,5348,3717,1205],"class_list":["post-70626","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arrogance","tag-brussels","tag-crise","tag-desarroi","tag-forum","tag-fund","tag-marshall","tag-transatlantique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70626"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70626\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}