{"id":70640,"date":"2009-03-26T22:25:53","date_gmt":"2009-03-26T22:25:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/26\/se-revolteront-ils\/"},"modified":"2009-03-26T22:25:53","modified_gmt":"2009-03-26T22:25:53","slug":"se-revolteront-ils","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/03\/26\/se-revolteront-ils\/","title":{"rendered":"Se r\u00e9volteront-ils?"},"content":{"rendered":"<p><h2 class=\"common-article\">Se r\u00e9volteront-ils?<\/h2>\n<\/p>\n<p><p>\t26 mars 2009  D&rsquo;abord un d\u00e9tail qui nous a frapp\u00e9s, que nous signalons \u00e0 nos lecteurs et qui procure l&rsquo;incitation \u00e0 notre r\u00e9flexion. Dans le cadre du <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-contre-pied_de_crise_19_03_2009.html\" class=\"gen\">19 mars 2009<\/a>, nous signalions notamment le voyage en Californie du pr\u00e9sident Obama, son intervention notamment lors d&rsquo;une r\u00e9union, sa posture populiste, anti-Washington dans le cadre de l&rsquo;affaire des <a href=\"http:\/\/www.dedefensa.org\/article-mccarthy_contre_le_systeme_23_03_2009.html\" class=\"gen\">bonus AIG<\/a>, son intervention volontaire sur cette question. Des commentateurs avaient pr\u00e9vu qu&rsquo;Obama s&#8217;emploierait \u00e0 donner une version avantageuse pour sa cause, en \u00e9cartant ou en d\u00e9samor\u00e7ant les accusations contre son secr\u00e9taire au tr\u00e9sor mis en cause par certains pour n&rsquo;\u00eatre pas intervenu plus t\u00f4t et plus r\u00e9solument contre la direction d&rsquo;AIG. L&rsquo;id\u00e9e centrale concerne \u00e9videmment la col\u00e8re des Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>\tAinsi lit-on, dans le texte que nous citions (AP du <a href=\"http:\/\/news.yahoo.com\/s\/ap\/obama_economy\/print;_ylt=Au_zRkgw6yvCIrQMbRUApTkGw_IE;_ylu=X3oDMTB1MjgxN2UzBHBvcwMxNARzZWMDdG9vbHMtdG9wBHNsawNwcmludA--\" class=\"gen\">18 mars 2009<\/a>), ces interventions d&rsquo;Obama:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Obama spoke for 21 minutes, then took eight questions. The first: Will he seek re-election in 2012? If I could get done what I think needs to get done in four years, even if it meant that I was only president for four years, I would rather be a good president  to take on the tough issues for four years  than a mediocre president for eight years, Obama said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There were other whiffs of self-sacrifice. Referring to the uproar over bonuses paid to executives of the largely nationalized AIG insurance company, Obama said: I know Washington&rsquo;s all in a tizzy, and everybody&rsquo;s pointing fingers at each other and saying, It&rsquo;s their fault, the Democrats&rsquo; fault, the Republicans&rsquo; fault.&rsquo; Listen, I&rsquo;ll take responsibility. I&rsquo;m the president. In the same breath, he said, We didn&rsquo;t draft these contracts. But he added, It is appropriate when you&rsquo;re in charge to make sure that stuff doesn&rsquo;t happen like this.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama tried to head off questions about AIG by saying he understood taxpayers&rsquo; anger. And he tried to broaden the issue, which has vexed his young administration.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPuis, comme incidemment, le texte pr\u00e9cise: \u00ab<em>In fact,<\/em> <strong><em>no one<\/em><\/strong> <em>asked Obama about AIG. The questions focused on jobs, schools, unions&rsquo; rights and other issues that are easier for him to handle.<\/em>\u00bb Cette forme m\u00eame du texte, de la d\u00e9p\u00eache, est int\u00e9ressante pour notre propos: le texte se d\u00e9veloppe sur le propos d&rsquo;Obama concernant les bonus d&rsquo;AIG comme s&rsquo;il y avait eu des questions \u00e0 ce propos, comme tous les commentateurs le pr\u00e9voyaient, comme si la col\u00e8re populaire tant appr\u00e9hend\u00e9e s&rsquo;\u00e9tait effectivement manifest\u00e9e, pour enfin ajouter cette pr\u00e9cision (pas de question). <\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/blogs.reuters.com\/great-debate\/2009\/03\/19\/in-american-crisis-anger-and-guns\/\" class=\"gen\">19 Mars 2009<\/a>, Bernd Debusmann , de Reuters, publie une analyse sur l&rsquo;augmentation vertigineuse des ventes d&rsquo;armes aux USA depuis l&rsquo;\u00e9lection de Barack Obama. \u00ab<em>In the first two months of this year, around 2.5 million Americans bought guns, a 26 percent increase over the same period in 2008. It was great news for gun makers and a sign of a dark mood in the country.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDiverses explications sont d\u00e9velopp\u00e9es, toutes selon des hypoth\u00e8ses assez classiques, li\u00e9es certes au caract\u00e8re exceptionnel des temps que nous vivons. Une partie importante est consacr\u00e9e aux craintes de troubles sociaux et au comportement social des citoyens US en temps de crise.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>There are no statistics on how many guns are bought by people who think they need them to defend themselves against desperate fellow citizens. But, as columnist David Ignatius put it in the Washington Post, there&rsquo;s an ugly mood developing as people start looking for villains to blame for the economic mess. In November, an analysis published by the U.S. Army War College&rsquo;s Strategic Studies Institute listed unforeseen economic collapse as one of the possible causes of future widespread civil violence.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The American economy is down but not out, and in mid-March some experts reported signs that the pace of the decline was slowing. But it hasn&rsquo;t slowed enough to sweep away the sense of anxiety and fear that comes through in many conversations and commentaries about the future of this normally optimistic country.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While Obama&rsquo;s approval rating remains high, at 59%, almost two thirds of the population thinks the country is on the wrong track, according to a poll commissioned by National Public Radio in mid-March. What is really remarkable about all this is that there<\/em> <strong><em>hasn&rsquo;t been<\/em><\/strong> <em>social unrest, remarked an executive with business interests in Latin American countries where riots and street demonstrations in response to economic squeezes are routine. The conditions for it are all there.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Anger is building. Just under half of those surveyed in a poll by the Pew Research Center this month expressed anger about bailing out banks and financial institutions that made poor decisions. The poll was taken before details became known of the full extent of the bonus-paying spree to members of the very team that brought the insurance giant AIG close to collapse.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUne appr\u00e9ciation diff\u00e9rente du fait social US dans la crise, dont nos lecteurs devinent qu&rsquo;il est ici l&rsquo;objet principal de notre attention, est donn\u00e9e par l&rsquo;\u00e9crivain et journaliste David Angevin, le <a href=\"http:\/\/www.causeur.fr\/impressions-amerique,2085\" class=\"gen\">13 mars 2009<\/a> sur le site du <em>Causeur<\/em>. L&rsquo;int\u00e9r\u00eat de ce texte est que l&rsquo;auteur est plut\u00f4t pro-am\u00e9ricain, connaisseur de l&rsquo;Am\u00e9rique, qu&rsquo;il est radical dans ses jugements. Voici l&rsquo;entame et la situation de l&rsquo;auteur, et la fin de ce texte: \u00ab<em>Pardonnez-moi, mais j&rsquo;aime bien l&rsquo;Am\u00e9rique. Il y a encore quatre mois, cet aveu \u00e9tait passible du pire. Mais peut-\u00eatre n&rsquo;est-il plus n\u00e9cessaire de se justifier. Vous l&rsquo;aurez remarqu\u00e9, depuis l&rsquo;\u00e9lection d&rsquo;Obama, tout le monde aime l&rsquo;Am\u00e9rique.<\/em> [] <em>Comme toute personne normalement constitu\u00e9e, je dois la majorit\u00e9 de mes \u00e9mois culturels \u00e0 des artistes am\u00e9ricains.<\/em> [] <em>Il m&rsquo;est donc permis d&rsquo;\u00e9mettre quelques r\u00e9serves sans entrer dans le club tr\u00e8s couru chez nous des antiam\u00e9ricains primaires (l&rsquo;antiam\u00e9ricanisme, le progressisme des cons, comme disait Pascal Bruckner).<\/em> [] <em>La semaine derni\u00e8re \u00e0 Miami, en me baladant dans un luxueux shopping mall sur-climatis\u00e9, alors que le givre se formait presque sur mes lunettes, l&rsquo;Am\u00e9rique m&rsquo;a fait penser au Titanic fon\u00e7ant droit sur l&rsquo;iceberg. L&rsquo;\u00e9quipage a enfil\u00e9 les gilets de sauvetage et mis les chaloupes \u00e0 la mer. Pendant ce temps, les passagers continuent \u00e0 danser en sirotant un Manhattan.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVoici notamment le passage qui nous int\u00e9resse, qui concerne directement les Am\u00e9ricains malades de la crise.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Mes deux derniers voyages au pays de l&rsquo;Oncle Sam, en pleine crise des subprimes, m&rsquo;ont particuli\u00e8rement marqu\u00e9. La d\u00e9confiture \u00e9conomique est une chose dans la bouche de Jean-Pierre Gaillard, elle devient une r\u00e9alit\u00e9 \u00e9crasante quand on discute avec l&rsquo;Am\u00e9ricain moyen qui vit dans une ville moyenne o\u00f9 les maisons mises en vente forc\u00e9e (foreclosure) se comptent par dizaines de milliers. Ils font froid dans le dos, ces panneaux bank owned ou for sale by owner, plant\u00e9s devant la porte des pavillons. A Fort Myers, Floride, on voit des camions de d\u00e9m\u00e9nagement \u00e0 tous les coins de rue. Sur les pelouses, on voit des frigos, des v\u00e9los, ou les tuyauteries que les familles vendent avant de partir refaire leur vie ailleurs. Des quartiers entiers ressemblent \u00e0 des villes fant\u00f4mes. Il y a encore quelques mois, ces m\u00eames familles organisaient des barbecues avec leurs voisins. Les types en pantalon chino partaient au boulot en 4X4 le matin et les femmes rejouaient Desperate Housewives en veillant sur leurs t\u00eates blondes. L&rsquo;American way of life, dans toute sa banalit\u00e9, semblait devoir durer pour toujours. Game over.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Aujourd&rsquo;hui, c&rsquo;est le m\u00eame spectacle d&rsquo;exode un peu partout aux \u00c9tats-Unis. Pour autant, et c&rsquo;est peut-\u00eatre le plus surprenant, pas de panique apparente, pas d&rsquo;\u00e9meutes (imaginez la m\u00eame chose en France). On serre les dents. On parle d&rsquo;une passe difficile, mais jamais de la fin d&rsquo;une \u00e9poque dor\u00e9e. Il ne semble venir \u00e0 l&rsquo;id\u00e9e de personne que l&rsquo;American way of life, le mod\u00e8le \u00e9conomique du pays bas\u00e9 sur la consommation de masse, doit \u00eatre s\u00e9rieusement remis en cause. In this economy, difficile de s&rsquo;offrir ceci ou cela, disent les gens en grima\u00e7ant. In this economy, this In this economy, that Comme si l&rsquo;\u00e9conomie, cet animal impr\u00e9visible et coquin, n&rsquo;allait plus tarder \u00e0 reprendre ses esprits. Comme si la sortie de route des classes moyennes n&rsquo;\u00e9tait qu&rsquo;un accident  terrible, certes , et que le plan de relance d&rsquo;Obama allait bient\u00f4t permettre de refermer cette sinistre parenth\u00e8se.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tChacun \u00e0 leur fa\u00e7on, venus d&rsquo;horizons diff\u00e9rents, selon des \u00e9tats d&rsquo;esprit diff\u00e9rents, ces trois exemples nous signifient la m\u00eame observation. Il s&rsquo;agit de l&rsquo;\u00e9tonnement, implicite ou explicite, devant l&rsquo;absence de r\u00e9action publique, populaire, etc., des Am\u00e9ricains dans diverses circonstances de la crise. C&rsquo;est un probl\u00e8me int\u00e9ressant, que nous allons traiter selon deux approches, qui s&rsquo;encha\u00eenent en se compl\u00e9tant.<\/p>\n<\/p>\n<p><p>\t Les Am\u00e9ricains (les citoyens) vont-ils r\u00e9agir et peuvent-ils, ou veulent-ils r\u00e9agir? En d&rsquo;autres mots: les Am\u00e9ricains se r\u00e9volteront-ils?<\/p>\n<\/p>\n<p><p>\t Mais cela a-t-il vraiment de l&rsquo;importance? En d&rsquo;autres mots: aujourd&rsquo;hui, la vraie r\u00e9volte populaire est-elle dans la r\u00e9volte populaire elle-m\u00eame?<\/p>\n<h3>La r\u00e9volte des temps postmodernes<\/h3>\n<\/p>\n<p><p>\tLa situation de la population US, sa potentialit\u00e9 de r\u00e9volte, la menace que cette potentialit\u00e9 ferait peser sur le syst\u00e8me, tout cela est un sujet d&rsquo;actualit\u00e9 assez naturel dans le temps d&rsquo;une crise si profonde, d&rsquo;autant plus que se confirment  des signes concrets de d\u00e9clin acc\u00e9l\u00e9r\u00e9 de la puissance US. C&rsquo;est aussi un sujet historique, et un sujet historiquement r\u00e9current. Par exemple,  mais exemple essentiel, sans aucun doute,  l&rsquo;instabilit\u00e9 sociale mena\u00e7ant le r\u00e9gime, l&rsquo;ordre \u00e9tabli, l&rsquo;am\u00e9ricanisme, pendant la Grande D\u00e9pression, est un th\u00e8me courant. Pour autant, cela ne nous semble pas correspondre \u00e0 la r\u00e9alit\u00e9 historique. Il y eut bien entendu des mouvements sociaux durant la Grande D\u00e9pression mais des r\u00e9voltes spontan\u00e9es plut\u00f4t que des mouvements impliquant une volont\u00e9 d&rsquo;organisation, aboutie ou pas. Lorsque FDR commen\u00e7a son mandat, en mars 1933, il eut moins \u00e0 lutter contre le m\u00e9contentement ou l&rsquo;instabilit\u00e9 que contre une sorte d&rsquo;atonie mortelle qui avait saisi la population am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tM\u00eame les ann\u00e9es 1960 ne virent aucune contestation radicale, dans le sens d&rsquo;une volont\u00e9 d&rsquo;un changement de r\u00e9gime. Les seuls groupes radicaux qui y song\u00e8rent \u00e9taient apparent\u00e9s, <em>volens nolens<\/em>, \u00e0 une subversion ext\u00e9rieure qui les discr\u00e9ditait, m\u00eame si injustement. La seule r\u00e9elle d\u00e9rogation \u00e0 cette r\u00e8gle vint des Noirs s\u00e9paratistes, les gens autour de Malcolm X, qui avaient compris qu&rsquo;on ne peut r\u00e9former le syst\u00e8me, que la seule issue est de rompre avec lui si c&rsquo;est possible. Un Martin Luther King, sur la fin de sa vie, en 1967-68, se radicalisait \u00e9galement, malgr\u00e9 ses succ\u00e8s des droits civiques. (Entretemps, on s&rsquo;\u00e9tait d\u00e9barrass\u00e9 de Malcolm X selon la technique habituelle de l&rsquo;assassinat.) Du c\u00f4t\u00e9 des milieux artistiques radicaux, la seule opposition acceptable est la dissidence, c&rsquo;est-\u00e0-dire le refus du cadre institutionnel au profit d&rsquo;une critique de l&rsquo;ext\u00e9rieur. Le radicalisme de la formule mesure effectivement les entraves du syst\u00e8me, telles que nous les d\u00e9crivons implicitement. Mais ces milieux ne peuvent aller au-del\u00e0 de la description de leur propre impuissance; ils sont incapables de s&rsquo;organiser, et, d&rsquo;ailleurs, ce n&rsquo;est en aucun cas leur r\u00f4le. <\/p>\n<\/p>\n<p><p>\tDans toute l&rsquo;histoire des USA, il est difficile de trouver un mouvement populaire qui ait eu un sens politique et qui se soit donn\u00e9 les moyens de tenter de l&rsquo;imposer, donc qui ait mis en cause le r\u00e9gime. M\u00eame cette rupture int\u00e9rieure fondamentale que les Am\u00e9ricains nomment, d&rsquo;une fa\u00e7on tr\u00e8s int\u00e9ress\u00e9e, guerre civile (<em>Civil War<\/em>), n&rsquo;implique justement pas,  et justement l\u00e0 est le fond du d\u00e9bat autour du fondement de ce conflit qui est une v\u00e9ritable guerre entre Etats,  une r\u00e9volte quelconque, une \u00e9meute ill\u00e9gale, une d\u00e9cision arbitraire ni quoi que ce soit de la sorte; la <em>Civil War<\/em> est en fait la Guerre de S\u00e9cession, d\u00e9clench\u00e9e \u00e0 partir de d\u00e9cisions de s\u00e9cession d&rsquo;un certain nombre d&rsquo;Etats, prises selon les processus constitutionnels propres \u00e0 chacun de ces Etats. Il y a donc, m\u00eame dans les situations les plus tragiques, les plus contradictoires, un respect de la loi aux USA, qui a \u00e9t\u00e9 impos\u00e9e moins comme une vertu, malgr\u00e9 les affirmations int\u00e9ress\u00e9es, que comme une n\u00e9cessit\u00e9,  car, enlevez la loi et pi\u00e9tinez le principe de la Loi, et il ne reste plus gu\u00e8re de structure pour tenir ensemble ce vaste pays.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Am\u00e9rique conna\u00eet \u00e9videmment la violence, et plus qu&rsquo;\u00e0 son tour, bien entendu; c&rsquo;est historiquement la violence ill\u00e9gale et arbitraire, mais \u00e9galement sans finalit\u00e9 politique, des \u00e9pisodes de la conqu\u00eate de l&rsquo;Ouest aux gangs criminels organis\u00e9s, au <em>racket<\/em>, au <em>lynch<\/em> des Noirs, aux milices patronales anti-syndicales et briseuses de gr\u00e8ves. Tout cela semble s&rsquo;arr\u00eater, comme on siffle le coup de sifflet final de la partie, au seuil de la mise en cause du syst\u00e8me. Il y a l\u00e0 l&rsquo;effet d&rsquo;une \u00e9ducation, d&rsquo;une communication absolument orient\u00e9e vers l&rsquo;organisation communautaire du bonheur r\u00e9duit aux acqu\u00eats de la seule R\u00e9publique, d&rsquo;une psychologie fa\u00e7onn\u00e9e \u00e0 partir des racines religieuses d&rsquo;ob\u00e9issance aux imp\u00e9ratifs conformistes sociaux et selon les imp\u00e9ratifs de l&rsquo;id\u00e9ologie courante qui proscrit la politique au profit de l&rsquo;\u00e9conomie, qui promeut une libert\u00e9 qui est d&rsquo;abord \u00e9conomique et r\u00e9fute l&rsquo;organisation politique autonome et originale comme contraire aux bonnes murs de la vertu. Cela n&rsquo;implique nullement la soumission \u00e0 une hi\u00e9rarchie v\u00e9ritable ni l&rsquo;absence de d\u00e9sordre. Au contraire,  il n&rsquo;y a pas de hi\u00e9rarchie sinon celle de l&rsquo;argent, et le d\u00e9sordre est latent ou visible, sous une forme rampante ou affich\u00e9e, permis par l&rsquo;absence d&rsquo;ordre r\u00e9galien qu&rsquo;impose une transcendance nationale. Mais absence de hi\u00e9rarchie (d&rsquo;autorit\u00e9) et d\u00e9sordre latent, dans ce cas, installent la solitude sociale et la peur des comportements hors-normes, et \u00e9cartent l&rsquo;acte supr\u00eame de la mise en cause du syst\u00e8me. L&rsquo;individu est rendu impuissant, et donc interdit d&rsquo;organisation  ill\u00e9gale d&rsquo;une pens\u00e9e antisyst\u00e8me structur\u00e9e. Il subit des contraintes et des pressions inou\u00efes, sans m\u00eame mesurer l&rsquo;injustice de sa situation, mais au contraire, croyant, le premier, \u00e0 l&rsquo;<em>American Dream<\/em>,  par ailleurs d\u00e8s l&rsquo;origine de la formule (en 1931, selon les sociologues du symbole), d&rsquo;une m\u00e9diocrit\u00e9 exceptionnelle et \u00e0 ne pas croire (petite maison comme-chez-soi, voiture, cr\u00e9dit, etc.).<\/p>\n<\/p>\n<p><p>\tDonc, pas d&rsquo;espoir (de possibilit\u00e9 de changement)? Pas du tout. Ceux qui croient le plus \u00e0 l&rsquo;instabilit\u00e9 sociale du syst\u00e8me, derri\u00e8re l&rsquo;apparence de l&rsquo;assurance inoxydable de leur discours conformiste et convenu, ce sont \u00e9videmment ceux qui servent directement ce syst\u00e8me et en forment la soi-disant \u00e9lite (<em>establishment<\/em>). Depuis les origines r\u00e8gne la crainte du d\u00e9sordre social; depuis quelques d\u00e9cennies, disons apr\u00e8s les ann\u00e9es 1960, cette crainte alimente de moins en moins des mesures de r\u00e9pression visibles, qui formeraient une apparence intol\u00e9rable dans un syst\u00e8me de communication o\u00f9 la relation publique et l&rsquo;\u00e9clairage m\u00e9diatique font la loi, et de plus en plus une politique de communication extr\u00eamement d\u00e9magogique, extr\u00eamement attentive \u00e0 flatter et \u00e0 renforcer les convictions populaires de l&rsquo;apparence de la d\u00e9mocratie. Dans des temps de crise, ces attitudes deviennent d\u00e9licates, parce que, de plus en plus souvent, cette politique de communication d\u00e9magogique d\u00e9bouche sur des pol\u00e9miques bien r\u00e9elles (m\u00eame si elles sont artificielles, ou accidentelles, au d\u00e9part), qui mettent en opposition ce qui est suppos\u00e9 \u00eatre l&rsquo;attitude populaire correspondant \u00e0 ces convictions populaires de l&rsquo;apparence de la d\u00e9mocratie (col\u00e8re populaire, appel \u00e0 la justice sociale), contre des \u00e9carts de certaines parties de l&rsquo;\u00e9lite. Ainsi en vient-on \u00e0 pr\u00e9venir des r\u00e9actions populaires, en allant au-devant d&rsquo;elles, sans aucune certitude que ces r\u00e9actions populaires se concr\u00e9tiseraient,  et m\u00eame, pour nombre de cas, et pour notre compte, nous consid\u00e9rerions la probabilit\u00e9 du contraire. Les techniques de communication postmodernes (courrier \u00e9lectronique, dont la puissance de conviction est consid\u00e9rable) font l&rsquo;affaire, en faisant effectivement croire \u00e0 une r\u00e9action populaire violente \u00e0 venir, et en conduisant les dirigeants \u00e0 la r\u00e9action qu&rsquo;on d\u00e9crit.<\/p>\n<\/p>\n<p><p>\tAinsi de l&rsquo;affaire des bonus d&rsquo;AIG. Il est certain qu&rsquo;il y a eu une pr\u00e9-r\u00e9action qui s&rsquo;est traduite par une sur-r\u00e9action des m\u00e9dias, du Congr\u00e8s et de Washington, en partie craignant une r\u00e9action populaire, la pr\u00e9venant, la partageant, dans certains cas la suscitant, pour pouvoir mieux la contr\u00f4ler. Nous sommes proches de l&rsquo;absurde: quel meilleur moyen de contr\u00f4ler une r\u00e9action populaire sinon en la suscitant ou en faisant comme si elle existait, et en l&rsquo;\u00e9pousant? Du c\u00f4t\u00e9 des r\u00e9actions populaires, l&rsquo;envoi de courrier \u00e9lectronique \u00e0 son d\u00e9put\u00e9 semble faire l&rsquo;affaire, puisqu&rsquo;un courrier \u00e9lectronique semble alors annoncer la participation assur\u00e9e de l&rsquo;exp\u00e9diteur \u00e0 la prise du Congr\u00e8s par la foule en col\u00e8re, qui ne saurait tarder s&rsquo;il n&rsquo;est pas r\u00e9pondu \u00e0 ses protestations. Ainsi Christopher Caldwell, du <em>Financial Times<\/em>, notait-il le <a href=\"http:\/\/www.ft.com\/cms\/s\/0\/b72042fc-1585-11de-b9a9-0000779fd2ac.html\" class=\"gen\">21 mars 2009<\/a>, effectivement dans le cadre de l&rsquo;affaire des bonus d&rsquo;AIG (la remarque qui illustre cette situation est soulign\u00e9e en gras par nous ): \u00ab<em>So people want to take the fixing of the system into their own hands. Now that<\/em> <strong><em>the internet has solved the organisational problem of mobs<\/em><\/strong><em>, they can, with the results that we saw this week. Politicians struggle to stay ahead of popular discontent. Within about 72 hours, Barack Obama moved from resignation and fatalism to oratorical outrage, promising to use every means at his disposal to claw the bonuses back.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn dira qu&rsquo;il n&rsquo;y a rien de d\u00e9cisif dans l&rsquo;affaire AIG. Voire Avec des affaires de cette sorte qui se succ\u00e9deraient, ce qui est une hypoth\u00e8se plausible, o\u00f9, pour contenir une col\u00e8re populaire qui n&rsquo;a pas eu lieu mais qu&rsquo;on craint derechef, on verrait le Congr\u00e8s prendre ou sugg\u00e9rer des mesures radicales antisyst\u00e8mes, le d\u00e9sordre dans les esprits et les psychologies ne cessant alors de grandir, le vrai celui-l\u00e0, pas le d\u00e9sordre des rues qui n&rsquo;a plus gu\u00e8re d&rsquo;effet politique mais le d\u00e9sordre qui s&rsquo;installe au cur m\u00eame des normes du syst\u00e8me, qui met en cause les fondamentaux du syst\u00e8me et ainsi de suite. De cette fa\u00e7on, dans quelques temps \u00e0 venir, verrait-on le gouverneur Schwarzenegger faire voter, apr\u00e8s deux jours de d\u00e9bats incessants au Congr\u00e8s de la R\u00e9publique de Californie, de courriers \u00e9lectroniques pressants et de discours angoiss\u00e9s des constituants, la s\u00e9cession de la Californie pour pr\u00e9venir la r\u00e9volte incontr\u00f4l\u00e9e que l&rsquo;on pr\u00e9voit des citoyens de Sacramento refusant de payer plus avant les taxes f\u00e9d\u00e9rales pour ces bons \u00e0 rien de types de Washington, et prendre ainsi cette r\u00e9volte \u00e0 son compte avec la s\u00e9cession.<\/p>\n<\/p>\n<p><p>\tOn peut d&rsquo;ailleurs observer, pour en terminer, que cette situation de la r\u00e9action populaire transform\u00e9e par l&rsquo;\u00e8re de la communication est \u00e9galement devenue tr\u00e8s r\u00e9pandue, y compris dans des pays o\u00f9 l&rsquo;on avait l&rsquo;habitude de changer de r\u00e9gime par la violence de la rue. Si l&rsquo;on consid\u00e8re l&rsquo;\u00e9volution de la situation de l&rsquo;Europe depuis le r\u00e9f\u00e9rendum fran\u00e7ais de mai 2005, r\u00e9sultat d&rsquo;une col\u00e8re populaire par courrier \u00e9lectronique, et toutes choses \u00e9tant similaires par ailleurs, y compris les conditions actuelles de la crise, il faut consid\u00e9rer l&rsquo;hypoth\u00e8se que cette col\u00e8re populaire postmoderne s&rsquo;est montr\u00e9e plus efficace, par rapport aux vux g\u00e9n\u00e9raux de la contestation, que ne l&rsquo;aurait \u00e9t\u00e9 la prise du b\u00e2timent de la Commission europ\u00e9enne par la foule en col\u00e8re en mai 2005. On ne dit pas que les choses sont r\u00e9solues, comme il est absurde d&rsquo;attendre ou de r\u00e9clamer le moyen de la preuve dans l&rsquo;interpr\u00e9tation qu&rsquo;on offre d&rsquo;une telle situation; on dit qu&rsquo;il faut mesurer l&rsquo;\u00e9volution europ\u00e9enne dans les faits depuis 2005, et constater que le processus g\u00e9n\u00e9ral de noyade institutionnelle de l&rsquo;identit\u00e9 (on ne parle que de cela dans cet exemple) a \u00e9t\u00e9 stopp\u00e9 bien plus nettement que par une insurrection. Bien entendu, il faut remarquer que ces col\u00e8res postmodernes, par le biais de la communication imposant aux dirigeants, volontairement ou pas, consciemment ou non,  des r\u00e9actions populaires par anticipation de r\u00e9voltes hypoth\u00e9tiques, s&rsquo;exercent contre des artefacts \u00e9galement postmodernes, sans l\u00e9gitimit\u00e9, \u00e0 l&rsquo;image des USA (cas de l&rsquo;Europe institutionnelle).<\/p>\n<\/p>\n<p><p>\tDe ce point de vue, on conviendra que la situation am\u00e9ricaniste n&rsquo;a rien pour \u00e9tonner. Elle rend compte d&rsquo;une \u00e9poque postmoderne, que l&rsquo;am\u00e9ricanisme a lui-m\u00eame suscit\u00e9e et organis\u00e9e, et inspir\u00e9e \u00e9videmment, o\u00f9 les manifestations de la puissance ont pris une allure compl\u00e8tement diff\u00e9rente de ce qu&rsquo;elles \u00e9taient durant l&rsquo;\u00e9poque g\u00e9opolitique (nous sommes dans l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-politique_d_epoque_l_ere_psychopolitique_rubrique_analyse_volume_22_n07_du_10_decembre_2006_25_12_2006.html\" class=\"gen\">\u00e8re psychopolitique<\/a>). La chose se retourne contre le syst\u00e8me de l&rsquo;am\u00e9ricanisme, avec gr\u00e2ce et \u00e9l\u00e9gance apr\u00e8s tout.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se r\u00e9volteront-ils? 26 mars 2009 D&rsquo;abord un d\u00e9tail qui nous a frapp\u00e9s, que nous signalons \u00e0 nos lecteurs et qui procure l&rsquo;incitation \u00e0 notre r\u00e9flexion. Dans le cadre du F&#038;C du 19 mars 2009, nous signalions notamment le voyage en Californie du pr\u00e9sident Obama, son intervention notamment lors d&rsquo;une r\u00e9union, sa posture populiste, anti-Washington dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[8184,3253,7857,7821,6410,4118,3856,2949],"class_list":["post-70640","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-aig","tag-americanisme","tag-bonus","tag-courrier","tag-electronique","tag-establishment","tag-revolte","tag-secession"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70640"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70640\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}