{"id":70657,"date":"2009-04-01T14:45:46","date_gmt":"2009-04-01T14:45:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/01\/retenez-moi-ou-je-men-vais\/"},"modified":"2009-04-01T14:45:46","modified_gmt":"2009-04-01T14:45:46","slug":"retenez-moi-ou-je-men-vais","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/01\/retenez-moi-ou-je-men-vais\/","title":{"rendered":"\u201cRetenez-moi ou je m&rsquo;en vais !\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">\u00ab\u00a0Retenez-moi ou je m&rsquo;en vais !\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il appara&icirc;t, \u00e0 notre appr\u00e9ciation, que les Britanniques, h\u00f4tes du G20 et consid\u00e9rablement Anglo-Saxons comme chacun sait, sont inquiets de la tournure des \u00e9v\u00e9nements, et surtout du climat autour de ces \u00e9v\u00e9nements &ndash; avant, pendant et apr\u00e8s le G20. Il y a parfois des relents d&rsquo;odeur de r\u00e9volte contre l&rsquo;alignement habituel et anglo-saxon, &ndash; et l&rsquo;on conna&icirc;t le slogan bien fran\u00e7ais \u00ab\u00a0relook\u00e9\u00a0\u00bb fa\u00e7on G20: \u00ab\u00a0Non Votre Tr\u00e8s Gracieuse Majest\u00e9, ce n&rsquo;est pas une r\u00e9volte, c&rsquo;est une r\u00e9volution\u00a0\u00bb. Dans ce tourbillon qui commence \u00e0 ressembler \u00e0 un sourd fracas, les Fran\u00e7ais, Sarko-Carla <em>regnante<\/em> chaotiquement, se r\u00e9veillent et ne sont plus en reste.<\/p>\n<\/p>\n<p><p>Comme l&rsquo;on sait par cons\u00e9quent, le pr\u00e9sident fran\u00e7ais a donc d\u00e9ploy\u00e9 une variante du \u00ab\u00a0retenez-moi ou je fais un malheur\u00a0\u00bb, et qui se nomme \u00ab\u00a0retenez-moi ou je m&rsquo;en vais\u00a0\u00bb (du G20). La chose est appr\u00e9ci\u00e9e avec une philosophie pateline et, \u00f4 surprise, assez bienveillante par le <em>Financial Times<\/em> du <a class=\"gen\" href=\"http:\/\/www.ft.com\/cms\/s\/0\/ee26cd02-1e1d-11de-830b-00144feabdc0.html\">1er avril 2009<\/a>. Le texte se place dans le contexte d&rsquo;un fond d&rsquo;observation g\u00e9n\u00e9rale sur le G20 de demain et avec quelque chose dans la plume qui ressemble effectivement, comme nous en parlions plus haut, \u00e0 de l&rsquo;inqui\u00e9tude. Parfois, il semblerait que le FT prenne au s\u00e9rieux ce qui ne devrait pas l&rsquo;\u00eatre selon les normes courantes du quotidien et l&rsquo;on se demande s&rsquo;il ne se demande pas: et si Sarko partait r\u00e9ellement? (Sous-entendu : qu&rsquo;est-ce qu&rsquo;il resterait de notre G20 favori?) D&rsquo;o&ugrave; les arguments pr\u00e9cipit\u00e9s, 1) que Sarko ne s&rsquo;en ira pas parce que le lendemain (vendredi) il accueille nombre des grands de ce monde r\u00e9unis au G20 au sommet de l&rsquo;OTAN de Strasbourg, et qu&rsquo;il a int\u00e9r\u00eat \u00e0 ce que tout se passe bien, et que tout cela ne peut \u00eatre pr\u00e9c\u00e9d\u00e9 de l&rsquo;esclandre en question; et 2) que Sarko ne s&rsquo;en ira pas parce qu&rsquo;il a de toutes les fa\u00e7ons d&rsquo;ores et d\u00e9j\u00e0 gagn\u00e9&hellip; C&rsquo;est ce dernier point qui est int\u00e9ressant, que nous soulignons d&rsquo;un gras majestueux d\u00e8s l&rsquo;entame de l&rsquo;article.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>France is likely to be one of the nations<\/em> <strong><em>best able to claim victory<\/em><\/strong> <em>when the summit ends on Thursday, suggesting that Nicolas Sarkozy will not have to make good on his threat to walk away from the negotiating table if his demands are not met.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Christine Lagarde, the French finance minister, said on Tuesday that the president had been \u00ab\u00a0very clear\u00a0\u00bb. \u00ab\u00a0He said, &lsquo;If the deliverables aren&rsquo;t there, I won&rsquo;t sign the communiqu\u00e9.&rsquo; It means walking away. I think he&rsquo;s very determined.\u00a0\u00bb Mr Sarkozy reportedly told his cabinet on Monday there would be \u00ab\u00a0an empty chair\u00a0\u00bb &ndash; a reference to Charles de Gaulle&rsquo;s seven-month boycott of the European Economic Community in 1965 &ndash; if he was not satisfied. However, while mindful of his occasional unpredictability, officials and diplomats in Paris scoffed at the idea that Mr Sarkozy might walk off if he did not get his way. \u00ab\u00a0Can you imagine Sarkozy storming out in London only to welcome many of the same people to Strasbourg the next day [for the Nato summit]?\u00a0\u00bb said one official. \u00ab\u00a0This is classic Sarko. It is his provocative thing.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Mr Sarkozy spoke to Gordon Brown by phone on Monday. The UK premier&rsquo;s office said the exchange was \u00ab\u00a0constructive and friendly\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Diplomats said the French threat was a classic pre-summit negotiating technique. It would enable Mr Sarkozy to claim success for what was already likely to emerge. \u00ab\u00a0They are right to keep up the heat but it is already a French victory,\u00a0\u00bb said one. Mr Sarkozy claims paternity of the summit, having argued for it at the United Nations last September. He can claim that many of France&rsquo;s arguments &ndash; and its central thesis that lightly regulated Anglo-US financial capitalism was inherently unstable &ndash; have won the day.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Car c&rsquo;est bien \u00e9trange, &ndash; pardonnez-nous d&rsquo;insister, &ndash; mais cette insistance du FT pour assurer le monde entier que les Fran\u00e7ais ont gagn\u00e9, oui, qu&rsquo;ils seront les grands vainqueurs, etc., cela est tr\u00e8s remarquable. Par cons\u00e9quent, pourquoi ne sp\u00e9culerions-nous pas qu&rsquo;effectivement les Britanniques craignent que Sarko n&rsquo;attend qu&rsquo;une occasion pour faire comme&hellip; &ndash; devinez qui? Charles de Gaulle <em>himself<\/em>, &laquo;<em>a reference to Charles de Gaulle&rsquo;s seven-month boycott of the European Economic Communit<\/em>&raquo;&hellip; (En passant: si Sarko ne remonte pas de vingt points dans les sondages avec un tel esclandre bien pr\u00e9sent\u00e9&#8230; Vingt points dans les sondages, cela vaut bien un esclandre au G20, selon l&rsquo;esprit de la citation fameuse sur Paris et sa messe.)<\/p>\n<\/p>\n<p><p>Bien, soyons d\u00e9cid\u00e9ment s\u00e9rieux et observons combien nous sommes marqu\u00e9s par la tonalit\u00e9 de cet article du FT, l&rsquo;absence compl\u00e8te de r\u00e9f\u00e9rence sarcastique aux Fran\u00e7ais et au pr\u00e9sident fran\u00e7ais \u00e0 l&rsquo;occasion d&rsquo;une menace qui rel\u00e8ve pourtant pour un Anglais du total et <em>gallic<\/em> absence de go&ucirc;t, de l&rsquo;incapacit\u00e9 <em>froggy<\/em> de savoir se tenir et tenir sa place, sourire aux l\u00e8vres, dans l&rsquo;alignement conforme, tasse de th\u00e9 \u00e0 hauteur des l\u00e8vres et petit doigt lev\u00e9, \u00e0 l&rsquo;\u00e9coute des consignes anglo-saxonnes. Mais non, le cas Sarko est trait\u00e9 avec s\u00e9rieux et attention. On en serait presque \u00e0 lui dire qu&rsquo;on le comprend, mais qu&rsquo;il faut qu&rsquo;il comprenne, lui, qu&rsquo;il ne doit pas songer \u00e0 un tel esclandre, parce qu&rsquo;il a gagn\u00e9, gagn\u00e9, mille fois gagn\u00e9, <em>by Jove<\/em>&hellip;<\/p>\n<\/p>\n<p><p>Cette crainte qui nous semble palpable entre les lignes concerne bien s&ucirc;r le comportement du pr\u00e9sident fran\u00e7ais lui-m\u00eame, mais aussi ce comportement en fonction du climat g\u00e9n\u00e9ral, \u00e9ventuellement en fonction de contacts secrets que les Fran\u00e7ais auraient pu \u00e9tablir en pr\u00e9paration, autour, pour et apr\u00e8s le G20, avec l&rsquo;un ou l&rsquo;autre pays de mauvaise r\u00e9putation (la Russie, la Chine, le Br\u00e9sil, qui sait?), en plus de l&rsquo;efficacit\u00e9 contestatrice que forme aujourd&rsquo;hui leur alliance avec Berlin-Merkel. L&rsquo;article refl\u00e8te cette m\u00eame inqui\u00e9tude que les milieux officiels britanniques entretiennent d\u00e9sormais apr\u00e8s l&rsquo;ultime grande tourn\u00e9e pr\u00e9paratoire au G20 qu&rsquo;a effectu\u00e9 Gordon Brown. Nous parlons ici, \u00e9galement, du climat, qui serait effectivement tr\u00e8s lourd, quasiment d&rsquo;une forme pr\u00e9-r\u00e9volutionnaire dans le chef de certains, tel qu&rsquo;a pu le constater le Premier ministre britannique.<\/p>\n<\/p>\n<p><p>Mis en ligne le 1er avril 2009 \u00e0 14H47<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Retenez-moi ou je m&rsquo;en vais !\u00a0\u00bb D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il appara&icirc;t, \u00e0 notre appr\u00e9ciation, que les Britanniques, h\u00f4tes du G20 et consid\u00e9rablement Anglo-Saxons comme chacun sait, sont inquiets de la tournure des \u00e9v\u00e9nements, et surtout du climat autour de ces \u00e9v\u00e9nements &ndash; avant, pendant et apr\u00e8s le G20. Il y a parfois des relents d&rsquo;odeur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6610,8224,2851,2687,7932,2680,4590,3045,2852],"class_list":["post-70657","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-depart","tag-esclandre","tag-financial","tag-france","tag-g20","tag-londres","tag-sarkozy","tag-sommet","tag-times"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70657"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70657\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}