{"id":70667,"date":"2009-04-06T09:16:35","date_gmt":"2009-04-06T09:16:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/06\/wall-street-est-il-pour-obama-ce-que-les-neocons-furent-pour-gw\/"},"modified":"2009-04-06T09:16:35","modified_gmt":"2009-04-06T09:16:35","slug":"wall-street-est-il-pour-obama-ce-que-les-neocons-furent-pour-gw","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/06\/wall-street-est-il-pour-obama-ce-que-les-neocons-furent-pour-gw\/","title":{"rendered":"Wall Street est-il pour Obama ce que les <em>neocons<\/em> furent pour GW?"},"content":{"rendered":"<p><p>Il y a une belle s\u00e9rie d&rsquo;articles ce week-end, dans la presse US qui a quelque int\u00e9r\u00eat, sur les manuvres et l&rsquo;implication totale de Wall Street d&rsquo;une part dans la crise et ses m\u00e9canismes les plus ill\u00e9gaux, d&rsquo;autre part dans le gouvernement d&rsquo;Obama, la fa\u00e7on dont ce gouvernement est contr\u00f4l\u00e9 par le biais de l&rsquo;\u00e9quipe \u00e9conomique du pr\u00e9sident, etc. Il y a une tr\u00e8s nette extension des r\u00e9v\u00e9lations d\u00e9j\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-wall_street_proprietaire_de_washington_dc_a_l_image_des_monstres_qu_il_enfante_28_03_2009.html\" class=\"gen\">soign\u00e9es<\/a> \u00e0 ce propos. Dans l&rsquo;atmosph\u00e8re g\u00e9n\u00e9rale de la crise, ces r\u00e9v\u00e9lations et ces diverses appr\u00e9ciations vont peser de plus en plus lourd sur Obama, de plus en plus confront\u00e9 \u00e0 une position contradictoire entre cette situation et divers aspects de sa politique, et, \u00e9ventuellement, de son caract\u00e8re,  en d&rsquo;autres mots, de plus en plus sollicit\u00e9 par son <a href=\"http:\/\/www.dedefensa.org\/article-le_tango_d_obama_avec_son_moment_de_verite_28_03_2009.html\" class=\"gen\">moment de v\u00e9rit\u00e9<\/a>, d&rsquo;une fa\u00e7on ou l&rsquo;autre.<\/p>\n<\/p>\n<p><p>\t Il y a d&rsquo;abord un long article de Glenn Greenwald, de <em>Salon.com<\/em>, repris sur <em>CommonDream.org<\/em> ce <a href=\"http:\/\/www.commondreams.org\/view\/2009\/04\/04-9\" class=\"gen\">4 avril 2009<\/a>. Greenwald reprend en d\u00e9tails les pr\u00e9cisions qui viennent d&rsquo;\u00eatre donn\u00e9es sur les revenus et les agissements \u00e0 Wall Street de Lawrence Summers et de Tim Geithner, ainsi que diverses autres affaires avec les liens renvoyant \u00e0 d&rsquo;autres articles. Les d\u00e9tails sont \u00e9poustouflants, s&rsquo;il vous reste assez de souffle pour \u00eatre \u00e9poustoufl\u00e9 Par exemple, Summers:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Lawrence H. Summers, one of President Obama&rsquo;s top economic advisers, collected roughly $5.2 million in compensation from hedge fund D.E. Shaw over the past year and was paid more than $2.7 million in speaking fees by several troubled Wall Street firms and other organizations<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Financial institutions including JP Morgan Chase, Citigroup, Goldman Sachs, Lehman Brothers and Merrill Lynch paid Summers for speaking appearances in 2008. Fees ranged from $45,000 for a Nov. 12 Merrill Lynch appearance to $135,000 for an April 16 visit to Goldman Sachs, according to his disclosure form.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That&rsquo;s $135,000 paid by Goldman Sachs to Summers  for a one-day visit.  And the payment was made at a time  in April, 2008  when everyone assumed that the next President would either be Barack Obama or Hillary Clinton and that Larry Summers would therefore become exactly what he now is:  the most influential financial official in the U.S. Government (and the $45,000 Merrill Lynch payment came 8 days after Obama&rsquo;s election). Goldman would not be able to make a one-day $135,000 payment to Summers now that he is Obama&rsquo;s top economics adviser, but doing so a few months beforehand was obviously something about which neither parties felt any compunction. It&rsquo;s basically an advanced bribe. And it&rsquo;s paying off in spades.  And none of it seemed to bother Obama in the slightest when he first strongly considered naming Summers as Treasury Secretary and then named him his top economics adviser instead (thereby avoiding the need for Senate confirmation), knowing that Summers would exert great influence in determining who benefited from the government&rsquo;s response to the financial crisis.<\/em><\/p>\n<\/p>\n<p><p>\t Un article g\u00e9n\u00e9ral de <em>RAW Story<\/em>, du <a href=\"http:\/\/rawstory.com\/news\/2008\/Economist_US_collapse_driven_by_fraud_0404.html\" class=\"gen\">4 avril 2009<\/a>, reprend une s\u00e9rie de liens et d&rsquo;informations li\u00e9s \u00e0 une interview explosive par le pr\u00e9sentateur Bill Moyers (dans la soir\u00e9e du <a href=\"http:\/\/www.pbs.org\/moyers\/journal\/04032009\/watch.html\" class=\"gen\">3 avril 2009<\/a>), du professeur William K. Black, de l&rsquo;universit\u00e9 du Missouri. Black d\u00e9crit comment Wall Street s&rsquo;est organis\u00e9 durant ces deux derni\u00e8res d\u00e9cennies en un gigantesque syst\u00e8me de fraude plan\u00e9taire, qui est \u00e9videmment le d\u00e9tonateur de l&rsquo;effondrement de septembre 2008, et comment le secr\u00e9taire au tr\u00e9sor du pr\u00e9sident Obama organise actuellement le camouflage (<em>cover-up<\/em>) de cette affaire.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In an explosive interview on PBS&rsquo; Bill Moyers Journal, William K. Black, a professor of economics and law with the University of Missouri, alleged that American banks and credit agencies conspired to create a system in which so-called liars loans could receive AAA ratings and zero oversight, amounting to a massive fraud at the epicenter of US finance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But worse still, said Black, Timothy Geithner, President Barack Obama&rsquo;s Secretary of the Treasury, is currently engaged in a cover-up to keep the truth of America&rsquo;s financial insolvency from its citizens.<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Black&rsquo;s most recent published work, The Best Way to Rob a Bank is to Own One, released in 2005, was hailed by Nobel-winning economist George A. Akerlof as extraordinary. There is no one else in the whole world who understands so well exactly how these lootings occurred in all their details and how the changes in government regulations and in statutes in the early 1980s caused this spate of looting, he wrote. This book will be a classic.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes r\u00e9v\u00e9lations sur la situation et l&rsquo;influence de Wall Street, sa p\u00e9n\u00e9tration grossi\u00e8re et \u00e9norme de l&rsquo;\u00e9quipe \u00e9conomique d&rsquo;Obama, constituent un cas extraordinaire d&rsquo;influence et de manipulation directes. La comparaison, portant non sur la politique mais sur la position tactique et l&rsquo;interf\u00e9rence dans le gouvernement, vient \u00e0 l&rsquo;esprit avec la p\u00e9n\u00e9tration, l&rsquo;influence et la manipulation directes des n\u00e9o-conservateurs aupr\u00e8s de GW Bush. Les conditions de pression sont diff\u00e9rentes dans la mesure o\u00f9 la crise est elle-m\u00eame tr\u00e8s pressante aujourd&rsquo;hui, o\u00f9 cette p\u00e9n\u00e9tration est encore plus visible qu&rsquo;avec les <em>neocons<\/em> et GW, et o\u00f9 elle a manifestement pour objet une politique et des mesures absolument centr\u00e9es sur la sauvegarde des int\u00e9r\u00eats ill\u00e9gaux de Wall Street alors que les n\u00e9o-conservateurs pr\u00e9tendaient d\u00e9velopper une doctrine de s\u00e9curit\u00e9 nationale. Les personnalit\u00e9s sont \u00e9galement diff\u00e9rentes. GW Bush, dont la perspicacit\u00e9 n&rsquo;\u00e9tait pas le point fort, acceptait ais\u00e9ment l&rsquo;incursion des n\u00e9o-conservateurs, habill\u00e9e d&rsquo;une rh\u00e9torique pompeuse et guerri\u00e8re faite pour lui plaire et inspirer ce qu&rsquo;il croyait \u00eatre une grande politique. Obama est \u00e9videmment d&rsquo;une psychologie et d&rsquo;un caract\u00e8re tr\u00e8s diff\u00e9rents. On le suppose plus intelligent que GW, avec une personnalit\u00e9 plus marqu\u00e9e, des conceptions propres plus affirm\u00e9es et ainsi de suite. On comprend ais\u00e9ment que le cas BHO-Wall Street est infiniment plus explosif que le cas GW-<em>neocons<\/em>.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 avril 2009 \u00e0 09H19<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a une belle s\u00e9rie d&rsquo;articles ce week-end, dans la presse US qui a quelque int\u00e9r\u00eat, sur les manuvres et l&rsquo;implication totale de Wall Street d&rsquo;une part dans la crise et ses m\u00e9canismes les plus ill\u00e9gaux, d&rsquo;autre part dans le gouvernement d&rsquo;Obama, la fa\u00e7on dont ce gouvernement est contr\u00f4l\u00e9 par le biais de l&rsquo;\u00e9quipe&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8002,3126,3858,6641,8126,3483,3198,8235,1104,3372,5029,3132],"class_list":["post-70667","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bho","tag-black","tag-corruption","tag-fraude","tag-geithner","tag-gorbatchev","tag-gw","tag-moyers","tag-neocons","tag-street","tag-summers","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70667"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70667\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}