{"id":70670,"date":"2009-04-07T14:54:56","date_gmt":"2009-04-07T14:54:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/07\/la-dent-dure-de-robert-gates\/"},"modified":"2009-04-07T14:54:56","modified_gmt":"2009-04-07T14:54:56","slug":"la-dent-dure-de-robert-gates","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/07\/la-dent-dure-de-robert-gates\/","title":{"rendered":"La dent dure de Robert Gates"},"content":{"rendered":"<p><p>Le secr\u00e9taire \u00e0 la d\u00e9fense Robert Gates a pr\u00e9sent\u00e9 hier les grandes lignes de son budget pour l&rsquo;ann\u00e9e FY2009 (en retard, pour cause de restructuration). Ce budget doit \u00eatre approuv\u00e9 par la Maison-Blanche avant d&rsquo;aller au Congr\u00e8s o\u00f9 il sera longuement discut\u00e9, avec des interf\u00e9rences et diverses modifications possibles. Il s&rsquo;agit d&rsquo;un budget qui se place dans l&rsquo;orientation affirm\u00e9e d&rsquo;une r\u00e9forme fondamentale du Pentagone, avec l&rsquo;affirmation que l&rsquo;accent est mis sur l&rsquo;\u00e9quipement pour les conflits non conventionnels et la recherche de l&rsquo;\u00e9limination de syst\u00e8mes tr\u00e8s co\u00fbteux et consid\u00e9r\u00e9s comme inutiles dans les conditions strat\u00e9giques actuelles.<\/p>\n<\/p>\n<p><p>\tLes r\u00e9actions au Congr\u00e8s sont du genre: bravo, tr\u00e8s bel effort du secr\u00e9taire \u00e0 la d\u00e9fense pour tenter de restructurer les d\u00e9penses du Pentagone et lancer la grande r\u00e9forme,  mais les choix faits par le secr\u00e9taire et approuv\u00e9s par la Maison-Blanche d\u00e9pendront de notre accord. Selon le site <em>DoDBuzz.com<\/em>, qui pr\u00e9sente le projet de budget de Gates, ce <a href=\"http:\/\/www.dodbuzz.com\/2009\/04\/06\/gates-speech-marks-start-of-huge-acquisition-shift\/\" class=\"gen\">7 avril 2009<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Regardless of who won and lost in Gates&rsquo; plan, what will really matter now is how Congress reacts. So far, Hill reaction to the Gates&rsquo; moves is cautiously supportive. House Armed Services Committee Chairman Rep. Ike Skelton (D-Mo.) called it a good faith effort but pointedly noted that, the buck stops with Congress which has the critical Constitutional responsibility to decide whether to support these proposals.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Rep. Murtha praised Gates for taking an important first step in balancing the Department&rsquo;s wants with our nation&rsquo;s needs. For far too long, the Defense Department has failed to address these challenges, and I applaud the Secretary for conducting this comprehensive review. But he echoed Skelton&rsquo;s comments that Congress will have the next say in how the nation spends its treasure.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est l&rsquo;USAF qui se taille la part du lion, si l&rsquo;on peut dire, dans les mesures de restriction propos\u00e9es par Gates. Le <em>Daily Digest<\/em> de Air Force Association pr\u00e9sente les d\u00e9cisions affectant l&rsquo;USAF, ce <a href=\"http:\/\/www.airforce-magazine.com\/DRArchive\/Pages\/2009\/April%202009\/April%2006%202009\/GatesSharpensHisAxe.aspx\" class=\"gen\">6 avril 2009<\/a>. Dans le domaine le plus sensible des avions de combat, quatre d\u00e9cisions sont propos\u00e9es concernant l&rsquo;USAF:<\/p>\n<\/p>\n<p><p>\t Arr\u00eat du programme F-22 \u00e0 187 exemplaires, quasiment au point o\u00f9 il se trouve aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>\t Retrait de 250 chasseurs (F-15 et F-16) en 2010.<\/p>\n<\/p>\n<p><p>\t Acc\u00e9l\u00e9ration du programme F-35 (JSF), dans les conditions suivantes (selon les mots de Gates): \u00ab<em>I will recommend increasing the buy of the F-35 Joint Strike Fighter from the 14 aircraft bought in FY09 to 30 in FY10, with corresponding funding increases from $6.8 billion to $11.2 billion.  We would plan to buy 513 F-35s over the five-year defense plan, and, ultimately, plan to buy 2,443.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Report ind\u00e9fini du projet de nouveau bombardier strat\u00e9gique envisag\u00e9 pour 2018.<\/p>\n<\/p>\n<p><p>\tLes propositions de Gates, si elles sont accept\u00e9es, reviennent \u00e0 concentrer tout l&rsquo;avenir de l&rsquo;USAF en tant que force de combat sur le seul JSF, en abandonnant toute voie alternative et tout effort compl\u00e9mentaire. Elles font du JSF le programme de sauvegarde de l&rsquo;USAF, et imposent \u00e9videmment d&rsquo;autorit\u00e9 \u00e0 l&rsquo;USAF la responsabilit\u00e9 vitale pour elle de la r\u00e9ussite du programme. Cette r\u00e9ussite est rendue plus probl\u00e9matique que facilit\u00e9e par la d\u00e9cision d&rsquo;acc\u00e9l\u00e9rer le d\u00e9veloppement du programme, qui repr\u00e9sente un risque tr\u00e8s important, notamment \u00e0 cause de sa structure qui fait se chevaucher les quatre-cinq derni\u00e8res ann\u00e9es de d\u00e9veloppement et les quatre-cinq premi\u00e8res ann\u00e9es de production, avec des avions de production utilis\u00e9s pour la fin du d\u00e9veloppement (le dernier rapport du Government Accounting Office, du <a href=\"http:\/\/www.defense-aerospace.com\/article-view\/release\/103561\/gao-warns-of-rising-costs%2C-schedule-risks-in-jsf-development-program.html\" class=\"gen\">13 mars 2009<\/a>, renouvelait ses avertissements des risques de cette m\u00e9thode). Mais la situation est corn\u00e9lienne dans la mesure o\u00f9 cette acc\u00e9l\u00e9ration si risqu\u00e9e du programme JSF est \u00e9galement la condition essentielle du maintien de l&rsquo;USAF comme premi\u00e8re force a\u00e9rienne du monde puisque, par ailleurs, ses effectifs vont se r\u00e9duire de plus en plus vite d\u00e8s 2010 (retrait de 250 avions de combat).<\/p>\n<\/p>\n<p><p>\tCe choix de Gates de soutien \u00e0 fond du JSF est largement explicable par diff\u00e9rents \u00e9l\u00e9ments, dont les engagements ext\u00e9rieurs du programme. Dans les conditions o\u00f9 il est fait, il repr\u00e9sente beaucoup plus. Il lie, pour la premi\u00e8re fois de cette fa\u00e7on si radicale, le sort de la premi\u00e8re force a\u00e9rienne du monde au destin d&rsquo;un seul programme dont on ne sait pour l&rsquo;instant s&rsquo;il aboutira et dans quel \u00e9tat, dont les performances sont de plus en plus mises en cause, qui est l&rsquo;objet d&rsquo;une contestation grandissante et justifi\u00e9e et qui est conduit par une gestion et une ma\u00eetrise extr\u00eamement contestables. C&rsquo;est beaucoup pour une seule force a\u00e9rienne, f\u00fbt-elle l&rsquo;USAF.<\/p>\n<\/p>\n<p><p>\tLes propositions de Gates reviennent \u00e0 choisir l&rsquo;USAF comme service en pointe, ou comme cobaye de pointe pour la r\u00e9forme du Pentagone, avec pour mission de s&rsquo;arranger de diff\u00e9rentes restrictions et d&rsquo;arriver \u00e0 s&rsquo;en sortir, r\u00e9form\u00e9e, \u00e9quip\u00e9e de neuf, d\u00e9pensant moins et mieux, ayant r\u00e9solu les probl\u00e8mes \u00e9normes de sa propre bureaucratie. Le choix est d&rsquo;autant plus \u00e9vident, mais d&rsquo;autant plus vicieux si l&rsquo;on veut, que le programme sur lequel s&rsquo;articule cette tentative, le JSF, concerne \u00e9galement la Navy, le Corps des Marines et les clients \u00e9trangers. Est-ce un cadeau fait \u00e0 l&rsquo;USAF, d&rsquo;ainsi devenir le service <em>leader<\/em> de la r\u00e9forme au Pentagone? Cadeau, ce n&rsquo;est pas vraiment le mot, en moins d&rsquo;en appr\u00e9cier le poids de poison qui l&rsquo;accompagne On retrouve l\u00e0, de toutes les fa\u00e7ons, la solide inimiti\u00e9 qui s&rsquo;est \u00e9tablie entre le secr\u00e9taire \u00e0 la d\u00e9fense et l&rsquo;USAF depuis les incidents de l&rsquo;\u00e9t\u00e9 2008 (<a href=\"http:\/\/www.dedefensa.org\/article-gates_versus_l_usaf_a_fond_06_06_2008.html\" class=\"gen\">mise \u00e0 pied<\/a> de la direction de l&rsquo;USAF, affaire du <a href=\"http:\/\/www.dedefensa.org\/article-_et_gates_entre_dans_la_fosse_aux_lions_ultimately_he_s_the_boss__27_06_2008.html\" class=\"gen\">KC-45<\/a>).<\/p>\n<\/p>\n<p><p>\tEncore une fois, tout cela est \u00e0 pond\u00e9rer \u00e0 la lumi\u00e8re des interventions qui vont suivre (Maison-Blanche, Congr\u00e8s). La position de l&rsquo;USAF est \u00e9galement pour l&rsquo;instant tr\u00e8s insaisissable. M\u00eame le <em>Daily Digest<\/em> de l&rsquo;Air Force Association, pourtant si proche du service dont il assure le lobbying, se demande, ce <a href=\"http:\/\/www.airforce-magazine.com\/Pages\/default.aspx\" class=\"gen\">7 avril 2009<\/a>, d&rsquo;o\u00f9 vient cette id\u00e9e \u00e9nonc\u00e9e par Gates que l&rsquo;USAF a recommand\u00e9 elle-m\u00eame l&rsquo;abandon du F-22: \u00ab<em>The F-22 buy completes the program at the 183 level set for it in 2005, plus four more added by Congress, Gates said, adding that there is no military requirement for more. He later said that the Air Force told him that no more were needed, which is surprising because the service has been strongly promoting its need for more F-22s and unofficially quoting 60 as the number. Even Joint Chiefs of Staff Chairman Adm. Mike Mullen has said USAF needs 60 more F-22s.<\/em>\u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 avril 2009 \u00e0 14H57<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secr\u00e9taire \u00e0 la d\u00e9fense Robert Gates a pr\u00e9sent\u00e9 hier les grandes lignes de son budget pour l&rsquo;ann\u00e9e FY2009 (en retard, pour cause de restructuration). Ce budget doit \u00eatre approuv\u00e9 par la Maison-Blanche avant d&rsquo;aller au Congr\u00e8s o\u00f9 il sera longuement discut\u00e9, avec des interf\u00e9rences et diverses modifications possibles. Il s&rsquo;agit d&rsquo;un budget qui se&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[249,2969,3984,250,3194,3320,41],"class_list":["post-70670","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-f-22","tag-f-35","tag-gates","tag-jsf","tag-pentagone","tag-reforme","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70670"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70670\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}