{"id":70671,"date":"2009-04-08T11:14:30","date_gmt":"2009-04-08T11:14:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/08\/parcours-parfait-mais-a-interpreter\/"},"modified":"2009-04-08T11:14:30","modified_gmt":"2009-04-08T11:14:30","slug":"parcours-parfait-mais-a-interpreter","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/08\/parcours-parfait-mais-a-interpreter\/","title":{"rendered":"Parcours parfait, mais \u00e0 interpr\u00e9ter"},"content":{"rendered":"<p><p>Le pr\u00e9sident Barack Obama a termin\u00e9 sa premi\u00e8re grande tourn\u00e9e hors les murs, en Europe jusqu&rsquo;au Moyen-Orient, avec trois sommets, un salut au monde musulman et une escale impromptue en Irak. L&rsquo;\u00e9ditorial de <em>The Independent<\/em> de ce <a href=\"http:\/\/www.independent.co.uk\/opinion\/leading-articles\/leading-article-a-pitchperfect-president-has-set-the-right-tone-1665252.html\" class=\"gen\">8 avril 2009<\/a> pr\u00e9sente ce qu&rsquo;il qualifie assez justement,  pour l&rsquo;homme, sans aucun doute,  de \u00ab<em>Obama&rsquo;s triumph abroad<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa surprise de derni\u00e8re minute, notamment, cette escale impromptue \u00e0 Bagdad pour annoncer qu&rsquo;il est temps que la direction irakienne prenne son sort en mains, est salu\u00e9e comme un ma\u00eetre coup de communication politique. Sur l&rsquo;essentiel du voyage, l&rsquo;<em>Independent<\/em> met en \u00e9vidence l&rsquo;acquis incontestable et, apr\u00e8s avoir pass\u00e9 en revue les d\u00e9tails du triomphe, la question fondamentale que ce triomphe soul\u00e8ve pour les relations internationales. (La seconde question mentionn\u00e9e dans l&rsquo;\u00e9ditorial est \u00e9voqu\u00e9e par ailleurs, dans notre <em>Faits &#038; Commentaires<\/em> de ce <a href=\"http:\/\/www.dedefensa.org\/article-welcome_home_bho_pas_si_sur__08_04_2009.html?admin=1\" class=\"gen\">8 avril 2009<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>If it was re-engagement with America&rsquo;s old friends and allies that the new President was after, he was amply rewarded  but only because, in his phrase, he arrived with hand outstretched. We cannot know what took place behind closed doors, but we can judge, from the smiles of such stony-faced characters as the Russian President, Dmitry Medvedev, and China&rsquo;s President, Hu Jintao, that a new international atmosphere has been established.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The G20 London summit may have produced more style than substance. But style and, above all, tone are not to be despised in international relations. Getting such things right is something many new national leaders have to learn and some never really master. Mr Obama, and  it must also be said  his wife, are naturals.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>To pull all this off and leave so few dissatisfied in his wake is a considerable feat. Not for the first time, we have to go back as far as JFK for comparisons. If Mr Obama&rsquo;s main objective was to cast the United States as a different type of global player  more culturally sensitive, more collegiate  then he succeeded. To demand more of a relatively young President in office not yet 100 days would be unreasonable. Yet what was, without doubt, a personal and political triumph leaves two questions.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The low-key geniality favoured by Mr Obama was of a piece with his early pledges to listen. But a time will come when listening must give way to doing, and then it will be harder to please everyone. We were certainly watching an accomplished politician and orator, but were we watching a world leader in the making?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa nostalgie est une belle chose \u00e0 condition de s&rsquo;en garder pour trop en faire l&rsquo;instrument d&rsquo;une analogie avec le temps pr\u00e9sent, avec les automatismes de jugement qui vont avec. L&rsquo;\u00e9vocation imparable de JFK en tourn\u00e9e en Europe \u00e0 des \u00e9poques variables, avec ses bons mots (\u00ab<em>Je suis le type qui accompagne Jackie Kennedy<\/em>\u00bb) et son <em>Ich bin ein Berliner <\/em>, conduit inconsciemment le jugement vers des param\u00e8tres d\u00e9pass\u00e9s. Se demander si Barack Obama sera bien un <em>world leader<\/em> invite implicitement \u00e0 s&rsquo;interroger pour savoir s&rsquo;il sera <strong>le<\/strong> <em>world leader<\/em> que nous attendons \u00e9videmment tous depuis l&rsquo;\u00e9pouvantable soupe \u00e0 la grimace de GW. Cette id\u00e9e est effectivement tr\u00e8s r\u00e9pandue (Obama devenant notre nouveau <em>world leader<\/em>), \u00e0 ce point qu&rsquo;elle nous para\u00eet essentiellement ressortir de cette vision partiale et contestable tr\u00e8s en vogue, renvoyant \u00e0 la culture anglo-saxonne, britannique en particulier, qui ne con\u00e7oit les relations internationales qu&rsquo;en termes imp\u00e9riaux, en termes de rapports de force et en termes de domination et de concurrence (cette culture, dominante m\u00eame chez d&rsquo;\u00e9ventuels anti-imp\u00e9riaux du domaine, c&rsquo;est-\u00e0-dire une culture dont les r\u00e9f\u00e9rences, consid\u00e9r\u00e9es positivement ou n\u00e9gativement, sont effectivement li\u00e9es par cette id\u00e9e des rapports de la force brute). Nous sommes dans une \u00e9poque qui n&rsquo;a plus besoin d&rsquo;un <em>world leader<\/em>, f\u00fbt-ce Barack Obama, f\u00fbt-ce monsieur Hu.<\/p>\n<\/p>\n<p><p>\tLe succ\u00e8s d&rsquo;Obama est \u00e0 mesure directe de l&rsquo;effacement du <em>leadership<\/em> am\u00e9ricaniste, qui s&rsquo;est marqu\u00e9 de diff\u00e9rentes fa\u00e7ons. L&rsquo;incapacit\u00e9 des USA d&rsquo;obtenir au G20 un engagement europ\u00e9en pour un plan de relance international coordonn\u00e9, l&rsquo;incapacit\u00e9 des m\u00eames USA d&rsquo;obtenir au sommet de l&rsquo;OTAN des renforts europ\u00e9ens pour l&rsquo;Afghanistan, ce sont la marque de cet effacement. De tels revers ne peuvent plus \u00eatre d\u00e9sormais mis au d\u00e9bit d&rsquo;une catastrophique pr\u00e9sidence GW Bush. D\u00e9sormais c&rsquo;est \u00e0 un pr\u00e9sident populaire, brillant, intelligent qu&rsquo;on oppose de tels refus. Plus on est son amis, moins on recule devant des reproches fermes s&rsquo;il le faut (<a href=\"http:\/\/www.dedefensa.org\/article-un_jour_dans_l_otan_le_lendemain_anti-americain_07_04_2009.html\" class=\"gen\">Sarkozy<\/a> et la Turquie). L&rsquo;\u00e9volution n&rsquo;est pas surprenante, elle est in\u00e9luctable et Obama la conduit avec gr\u00e2ce et \u00e9l\u00e9gance.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, ce n&rsquo;est certainement pas pour autant qu&rsquo;un autre <em>world leader<\/em> pour le reste du monde appara\u00eet pour prendre la place \u00e9ventuellement des USA. (L&rsquo;\u00e9vocation,  notamment par Zbigniew Brzezinski,  de l&rsquo;installation <em>de facto<\/em> d&rsquo;un G2 informel, un directoire USA-Chine pour diriger le monde qui rendrait ainsi plus douce la chute de la puissance US, nous para\u00eet notamment relever de la pure construction rationnelle et th\u00e9orique d&rsquo;esprits attach\u00e9s \u00e0 ces conceptions entretenues par la nostalgie.) C&rsquo;est la formule qui est vici\u00e9e, parce qu&rsquo;elle repose sur l&rsquo;entretien de tensions artificielles permanentes, comme l&rsquo;a amplement montr\u00e9 l&rsquo;\u00e9poque Bush, qui a pouss\u00e9 la chose \u00e0 son extr\u00eame. Il se trouve que nous avons bien assez des crises du monde et des crises du syst\u00e8me, crises eschatologiques et d\u00e9passant notre capacit\u00e9 de contr\u00f4le, pour y rajouter celles que cr\u00e9ent artificiellement une formule bas\u00e9e sur des attitudes dont certaines sont parfois stup\u00e9fiantes de crudit\u00e9 et de d\u00e9rision,  la vanit\u00e9 anglo-saxonne n&rsquo;\u00e9tant pas la derni\u00e8re \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\tUne autre r\u00e9alit\u00e9, plus importante et plus impressionnante, est sans doute en train d&rsquo;appara\u00eetre. Il s&rsquo;agit du fait que la puissance s&rsquo;exprime et se diffuse dans un nombre de plus en plus \u00e9lev\u00e9 de domaines, la cons\u00e9quence directe \u00e9tant que le nombre de domaines d\u00e9cisifs de la puissance d\u00e9cro\u00eet \u00e0 mesure. Le d\u00e9veloppement de la communication, avec l&rsquo;interpr\u00e9tation de la r\u00e9alit\u00e9 qu&rsquo;elle permet, est une des causes conjoncturelles essentielles de cette \u00e9volution. Il en r\u00e9sulte que plus aucun pays n&rsquo;est capable de ma\u00eetriser tous les domaines d&rsquo;expression de la puissance, ni de disposer de suffisamment de domaines d\u00e9cisifs de la puissance pour affirmer une pr\u00e9\u00e9minence sans discussion. La d\u00e9cadence de l&rsquo;influence et de la capacit\u00e9 d&rsquo;expression de la puissance de l&rsquo;outil militaire US est, \u00e0 cet \u00e9gard, un ph\u00e9nom\u00e8ne d\u00e9cisif pour illustrer la tendance.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 avril 2009 \u00e0 11H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident Barack Obama a termin\u00e9 sa premi\u00e8re grande tourn\u00e9e hors les murs, en Europe jusqu&rsquo;au Moyen-Orient, avec trois sommets, un salut au monde musulman et une escale impromptue en Irak. L&rsquo;\u00e9ditorial de The Independent de ce 8 avril 2009 pr\u00e9sente ce qu&rsquo;il qualifie assez justement, pour l&rsquo;homme, sans aucun doute, de \u00abObama&rsquo;s triumph abroad\u00bb&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2631,5185,8236,7932,2622,5674,6208,584,2779,8237,2671],"class_list":["post-70671","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-de","tag-decadence","tag-expression","tag-g20","tag-la","tag-leadership","tag-obama","tag-otan","tag-puissance","tag-satkozy","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70671"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70671\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}