{"id":70677,"date":"2009-04-10T14:49:45","date_gmt":"2009-04-10T14:49:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/10\/lesprit-du-temps-aux-usa-et-le-capitalisme-reduit-a-ses-exces\/"},"modified":"2009-04-10T14:49:45","modified_gmt":"2009-04-10T14:49:45","slug":"lesprit-du-temps-aux-usa-et-le-capitalisme-reduit-a-ses-exces","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/10\/lesprit-du-temps-aux-usa-et-le-capitalisme-reduit-a-ses-exces\/","title":{"rendered":"L&rsquo;\u201cesprit du temps\u201d (aux USA) et le capitalisme r\u00e9duit \u00e0 ses exc\u00e8s"},"content":{"rendered":"<p><p>Certains en parlent \u00e0 mots couverts, d&rsquo;autres \u00e9vitent simplement d&rsquo;en parler. D&rsquo;autres jugent la chose d\u00e9risoire et sans int\u00e9r\u00eat, mettant en doute que les m\u00e9thodes statistiques aient quelque signification que ce soit. Pour notre compte, nous tenons cette sorte de nouvelle comme l&rsquo;expression de l&rsquo;esprit du temps, lorsqu&rsquo;elle peut \u00eatre plac\u00e9e dans la perspective qui importe, lorsqu&rsquo;elle peut \u00eatre \u00e9clair\u00e9e par des r\u00e9f\u00e9rences significatives, et il ne manque ni des unes ni des autres par les temps qui courent. Il se trouve, crise et moyens de communication obligent, que l&rsquo;esprit du temps \u00e9volue \u00e0 la vitesse de l&rsquo;\u00e9clair ces temps-ci.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dire qu&rsquo;il s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement qui a une forte signification de d\u00e9couvrir, dans un sondage d&rsquo;un institut r\u00e9put\u00e9 (Rasmussen Report), que la question le capitalisme est-il le meilleur syst\u00e8me \u00e9conomique? obtient 53% de r\u00e9ponses affirmatives, alors que 20% du m\u00eame \u00e9chantillonnage jugent que le socialisme est le meilleur syst\u00e8me \u00e9conomique,  cela, aux USA, c&rsquo;est le plus important \u00e0 savoir, on s&rsquo;en doute. (Le sondage porte sur un millier de personnes, il a eu lieu les 6 et 7 avril; 27% des personnes interrog\u00e9es disent ne pas se prononcer sur le fait de pr\u00e9f\u00e9rer l&rsquo;un ou l&rsquo;autre syst\u00e8me.)<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on curieuse ou bien confuse, on ne sait, les enqu\u00eateurs observent qu&rsquo;en d\u00e9cembre 2008, 70% des personnes interrog\u00e9es selon la m\u00eame technique avaient r\u00e9pondu par l&rsquo;affirmative \u00e0 la question l&rsquo;\u00e9conomie de march\u00e9 libre est-elle le meilleur syst\u00e8me \u00e9conomique?. Les commentateurs de Rasmussen Repport font une remarque ambig\u00fce, avec, notamment, l&rsquo;absence de pr\u00e9cision sur une possible \u00e9volution n\u00e9gative des opinions sur le syst\u00e8me d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale entre d\u00e9cembre 2008 et avril 2009: \u00ab<em>The fact that a free-market economy&rsquo; attracts substantially more support than capitalism&rsquo; may suggest some skepticism about whether capitalism in the United States today relies on free markets.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bad news for those fearful of creeping socialism in the United States  only 53 percent of Americans now believe capitalism is the better system, according to a new poll Thursday. Fully 20 percent in the Rasmussen Reports survey said that socialism was their preferred economic system  a startling number that suggests growing disaffection as the land of the free fights its worst recession in decades.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Republican critics fret that President Barack Obama&rsquo;s big-spending recovery policies amount to an un-American creeping socialism, but Rasmussen said its findings pointed to suspicion of business and government elites alike. It noted that in another survey last month, two out of three Americans said that big government and big business often collude to undermine the interests of consumers and investors.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Meanwhile in another Rasmussen survey in late December, as Obama prepared to take power, 70 percent of respondents said they preferred a free-market economy. The fact that a &lsquo;free-market economy&rsquo; attracts substantially more support than &lsquo;capitalism&rsquo; may suggest some skepticism about whether capitalism in the United States today relies on free markets, the pollsters said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t(Selon AFP, relay\u00e9e par <em>RAW Story<\/em>, le <a href=\"http:\/\/rawstory.com\/news\/afp\/Land_of_the_free_sours_on_capitalis_04092009.html\" class=\"gen\">9 avril 2009<\/a>.)<\/p>\n<\/p>\n<p><p>\tC&rsquo;est bien un fait significatif, une audace certes, d&rsquo;envisager une telle correspondance d&rsquo;\u00e9valuation comparative dans un sondage US,  capitalisme <em>versus<\/em> socialisme,  et d&rsquo;obtenir un pourcentage de moins de 3 contre 1 en faveur du capitalisme. Lorsqu&rsquo;on mesure le conditionnement g\u00e9n\u00e9ral, militant, syst\u00e9matique, la quasi-terreur sociale du conformisme, que le syst\u00e8me entretient en faveur du capitalisme \u00e0 tous les stades de formation du citoyen, et, au contraire, l&rsquo;opprobre diabolisant o\u00f9 est tenu le socialisme dans une mesure correspondante, le r\u00e9sultat est impressionnant. Il n&rsquo;est pas assur\u00e9 que de tels r\u00e9sultats, y compris la faveur pour le socialisme, auraient \u00e9t\u00e9 obtenus, m\u00eame durant la Grande D\u00e9pression (impossible \u00e0 savoir d&rsquo;une fa\u00e7on comparative acceptable, les techniques de sondage modernes et fiables n&rsquo;\u00e9tant pas encore en place, n&rsquo;\u00e9tant apparues qu&rsquo;au d\u00e9but des ann\u00e9es 1940)<\/p>\n<\/p>\n<p><p>\t(Nous ajouterions qu&rsquo;il n&rsquo;est pas assur\u00e9 qu&rsquo;on trouverait un r\u00e9sultat plus favorable au socialisme, et moins au capitalisme, dans nombre de pays d&rsquo;Europe aujourd&rsquo;hui. Mais, \u00e9videmment, comme on l&rsquo;a dit, l&rsquo;esprit du temps \u00e9volue vite.)<\/p>\n<\/p>\n<p><p>\tOn parle moins ici d&rsquo;un sens politique et \u00e9conomique pr\u00e9cis que, effectivement, de l&rsquo;esprit du temps. Le sondage est approximatif, les termes mis en balance n&rsquo;ont qu&rsquo;un sens tr\u00e8s g\u00e9n\u00e9ral; par contre, ces termes repr\u00e9sentent de fortes images symboliques et, de ce point de vue, ils ont indubitablement un sens tr\u00e8s r\u00e9el. Il existe un tr\u00e8s fort mouvement de d\u00e9saffection pour le syst\u00e8me, tout entier sacralis\u00e9 dans le terme capitalisme, qui peut prendre un aspect tragique aux USA o\u00f9 il s&rsquo;agit de la poutre ma\u00eetresse de la coh\u00e9sion du pays. Bien \u00e9videmment, on dira que ce sont les exc\u00e8s du capitalisme qui portent la principale responsabilit\u00e9 de cette \u00e9volution psychologique, \u00e0 c\u00f4t\u00e9, sans doute \u00e0 parts \u00e9gales, de la situation \u00e9conomique catastrophique.<\/p>\n<\/p>\n<p><p>\tLa question devient alors plus simplement: et si le capitalisme se r\u00e9duisait, dans tous les cas aujourd&rsquo;hui, \u00e0 sa rubrique exc\u00e8s du capitalisme&rsquo;? On ne peut avancer de r\u00e9ponse pr\u00e9cise mais on comprend bien l&rsquo;esprit de la chose et on sait la part essentielle que jouent les marges, ou les situations parasitaires dans la crise d&rsquo;un syst\u00e8me qui, d\u00e9sormais, semble effectivement s&rsquo;y r\u00e9duire (voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_d_une_civilisation_parasitaire_18_10_2008.html\" class=\"gen\">18 octobre 2009<\/a>). La question que sugg\u00e8rent ces divers constats est de savoir, enfin, si sa r\u00e9duction \u00e0 ses exc\u00e8s et \u00e0 ses marges parasitaires n&rsquo;est pas une fatalit\u00e9 du capitalisme. Cette fatalit\u00e9 serait d&rsquo;autant plus irr\u00e9sistible qu&rsquo;il y a le reste des diverses avanc\u00e9es de la m\u00eame civilisation capitaliste,  technologies des communications pour syst\u00e9matiser un univers factice, syst\u00e9matisation de l&rsquo;individualisme in\u00e9galitaire, de la corruption psychologique, d\u00e9gradation des murs sociaux et du caract\u00e8re; et que ce reste-l\u00e0 semble renforcer cette dynamique de r\u00e9duction aux exc\u00e8s, non seulement sans espoir de retour, mais en plus selon un rythme d&rsquo;acc\u00e9l\u00e9ration exponentielle.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 avril 2009 \u00e0 14H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains en parlent \u00e0 mots couverts, d&rsquo;autres \u00e9vitent simplement d&rsquo;en parler. D&rsquo;autres jugent la chose d\u00e9risoire et sans int\u00e9r\u00eat, mettant en doute que les m\u00e9thodes statistiques aient quelque signification que ce soit. Pour notre compte, nous tenons cette sorte de nouvelle comme l&rsquo;expression de l&rsquo;esprit du temps, lorsqu&rsquo;elle peut \u00eatre plac\u00e9e dans la perspective qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4363,8243,4434,3715,7859,5304,1492],"class_list":["post-70677","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-capitalisme","tag-exces","tag-libre","tag-marche","tag-marges","tag-socialisme","tag-sondages"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70677"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70677\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}