{"id":70708,"date":"2009-04-24T12:44:40","date_gmt":"2009-04-24T12:44:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/24\/deconstruction-de-la-guerre\/"},"modified":"2009-04-24T12:44:40","modified_gmt":"2009-04-24T12:44:40","slug":"deconstruction-de-la-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/04\/24\/deconstruction-de-la-guerre\/","title":{"rendered":"D\u00e9construction de \u201cla guerre\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">D\u00e9construction de la \u00ab\u00a0guerre\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>24 avril 2009 &mdash; Comment gagner en Afghanistan? Ou plut\u00f4t: comment ne pas perdre en Afghanistan? Ou plut\u00f4t : comment faire la guerre en Afghanistan? Il y a des agitations originales autour de ces question, dans des lieux, c\u00e9nacles et colonnes de journaux au-del\u00e0, bien au-del\u00e0 de l&rsquo;Afghanistan, &ndash; dans un autre monde que celui o&ugrave; tel ou tel g\u00e9n\u00e9ral, en g\u00e9n\u00e9ral terriblement anglo-saxon, vous annonce qu&rsquo;on pourrait esp\u00e9rer d&rsquo;\u00e9viter la catastrophe cet \u00e9t\u00e9, qu&rsquo;on pourrait gagner si les talibans voulaient bien y mettre du leur, et ainsi de suite. Le g\u00e9n\u00e9ral poursuit, en g\u00e9n\u00e9ral, en sugg\u00e9rant qu&rsquo;on pourrait renforcer la couverture a\u00e9rienne des op\u00e9rations en cours, pour leur donner un \u00e9lan d\u00e9cisif.<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0couverture a\u00e9rienne\u00a0\u00bb, justement&hellip; C&rsquo;est cet aspect qui commence \u00e0 \u00eatre mis en question aux USA. Il faut bien dire que la question de l&rsquo;appui a\u00e9rien est centrale au conflit afghan, que l&rsquo;appui a\u00e9rien provoque des pertes civiles sans nombre, qu&rsquo;il s&rsquo;impose sans discussion, pour tout esprit sens\u00e9, comme le principal recruteur des talibans. La puissance a\u00e9rienne alli\u00e9e qui soutient massivement l&rsquo;effort de guerre alli\u00e9, comme principal ennemi des forces alli\u00e9es, &ndash; voil\u00e0 de l&rsquo;original.<\/p>\n<\/p>\n<p><p>Ce dogme de l&rsquo;intervention a\u00e9rienne est essentiellement d&rsquo;inspiration am\u00e9ricaniste. Il ressort principalement de deux tendances et\/ou concepts bien connus du c\u00f4t\u00e9 US. D&rsquo;une part, il y a l&rsquo;affection sans mesure des militaires US pour la puissance de feu, pour ce qu&rsquo;ils nomment \u00ab\u00a0<em>the brute force<\/em>\u00ab\u00a0. Inutile de refaire l&rsquo;histoire, on sait qu&rsquo;elle est jalonn\u00e9e, sinon galonn\u00e9e, de Sherman \u00e0 LeMay, d&rsquo;exemples sans nombre de l&rsquo;application syst\u00e9matique de cette \u00ab\u00a0strat\u00e9gie de l&rsquo;attrition\u00a0\u00bb ch\u00e8re \u00e0 la pens\u00e9e militaire US. D&rsquo;autre part, il y a la doctrine dite de \u00ab\u00a0<em>Force Protection<\/em>\u00ab\u00a0, si en vogue depuis les ann\u00e9es 1990, consistant \u00e0 rechercher la protection des forces US et la r\u00e9duction des pertes US par tous les moyens, y compris et surtout les plus brutaux, notamment par le vide fait autour des forces US, par la destruction syst\u00e9matique, y compris des infrastructures civiles avec ses habitants.<\/p>\n<\/p>\n<p><p>Deux experts US s&rsquo;attaquent \u00e0 ce dogme, de fa\u00e7on indirecte mais cat\u00e9gorique, \u00e0 propos de la guerre en Afghanistan et de la strat\u00e9gie g\u00e9n\u00e9rale des USA dans cette guerre. Pour William S. Lind, ces pratiques doivent \u00eatre d\u00e9nonc\u00e9es dans le cadre de l&rsquo;attachement des conceptions US \u00e0 une technique de guerre d\u00e9pass\u00e9e, celle de la \u00ab\u00a0guerre de 2\u00e8me g\u00e9n\u00e9ration\u00a0\u00bb (<em>Second Generation Warfare<\/em>, ou 2GW, G2G en fran\u00e7ais), m\u00e9thode d&rsquo;avant la <em>Blitzkrieg<\/em> allemande (\u00ab\u00a0guerre de 3\u00e8me g\u00e9n\u00e9ration\u00a0\u00bb pour Lind). Ce texte de Lind, &laquo;<em>Escaping the 2GW Trap<\/em>&raquo;, est publi\u00e9 le <a class=\"gen\" href=\"http:\/\/www.d-n-i.net\/dni\/2009\/04\/20\/on-war-301-escaping-the-2gw-trap\/#more-694\">20 avril 2009<\/a> sur <em>Defense &#038; National Interest<\/em>.<\/p>\n<\/p>\n<p><p>&laquo;<em>As the U.S. sends thousands more American soldiers to Afghanistan, it risks speeding its own defeat in that graveyard of empires. Why? Because the Second Generation practice of the U.S. military reduces tactics to little more than bumping into the enemy and calling for fire. The fire, most often delivered by aircraft that can see and understand little of what is happening on the ground, often kills civilians. Even when it does not, the disproportion of pitting jet fighter-bombers and attack helicopters against guys in bathrobes armed with rusty rifles turns us into Goliath, a monster. Both effects bring about our defeat on the moral level. In effect, the Second Generation leaves us in a trap of our own making: to win the engagements we have to lose the war.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>How might U.S. forces in Afghanistan escape the 2GW trap? To start with, they should accept and live by a principle laid down by Marine Corps General James Mattis, one of our more successful commanders in Iraq. That principle, taken from medicine, is, \u00ab\u00a0First, do no harm.\u00a0\u00bb When and where fighting is likely to cause civilian casualties, wreck the civilian infrastructure and alienate the population, don&rsquo;t fight. A withdrawal is better than a combination of tactical victory and strategic loss.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Second, seek to de-escalate. De-escalation is the way state armed forces prevail in Fourth Generation wars&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le <a class=\"gen\" href=\"http:\/\/original.antiwar.com\/porter\/2009\/04\/21\/us-lacks-capacity-to-win-over-afghans\/\">22 avril 2009<\/a>, sur <em>Antiwar.com<\/em>, l&rsquo;historien Gareth Porter analyse ce qu&rsquo;il juge \u00eatre la cause centrale de l&rsquo;incapacit\u00e9 US de gagner la guerre. Il s&rsquo;agit d&rsquo;une incapacit\u00e9 d&rsquo;adaptation des USA, notamment l&rsquo;incapacit\u00e9 de \u00ab\u00a0civiliser\u00a0\u00bb la guerre en la portant plus sur les mati\u00e8res civiles que sur les aspects militaires. (C&rsquo;est en principe l&rsquo;orientation annonc\u00e9e par l&rsquo;administration Obama, ce changement vers les mati\u00e8res civiles. Porter fait remarquer l&rsquo;absence compl\u00e8te de moyens humains \u00e0 cet \u00e9gard, par exemple l&rsquo;absence d&rsquo;experts US au niveau des langues, des coutumes, etc., en Afghanistan.) Sur la fin de son texte, Porter aborde l&rsquo;aspect qui nous int\u00e9resse ici principalement, bien entendu compl\u00e9mentaire de sa r\u00e9flexion.<\/p>\n<\/p>\n<p><p>&laquo;<em>Col. David Lamm, who was chief of staff of the top U.S. commander in Afghanistan from 2003 to 2005, Lt. Gen. David Barno, is doubtful about the willingness of the Army leadership to shift to a counter-insurgency strategy in Afghanistan. \u00ab\u00a0The institutional army doesn&rsquo;t want to do this,\u00a0\u00bb he told IPS in an interview last September. \u00ab\u00a0There isn&rsquo;t a lot of money in counter-insurgency. It isn&rsquo;t a high-tech war &ndash; it&rsquo;s a low-tech humint<\/em> [<em>human intelligence<\/em>] <em>operation.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Lamm recalled that the army&rsquo;s role in Afghanistan before Barno took command in 2003 had been \u00ab\u00a0counter-terrorism\u00a0\u00bb rather than counter-insurgency. The army \u00ab\u00a0wanted to roll in, round up terrorists, drive them out of the country, kill them,\u00a0\u00bb he said. Barno shifted the mission to one aimed at winning over the Afghan population, but he did so on his own, without any guidance from Washington, according to Lamm.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>With the transition to NATO responsibility for Afghanistan that began in late 2005, the emphasis in U.S. military strategy was on \u00ab\u00a0force protection\u00a0\u00bb and keeping casualties low, Lamm said. After the shift to NATO responsibility, most U.S. troops in Afghanistan were still committed to an explicitly \u00ab\u00a0counter-terrorism\u00a0\u00bb role of destroying al-Qaeda and Taliban \u00ab\u00a0holdouts.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>One of the hallmarks of that role, which has continued since 2006, is heavy reliance on air power as a means of trying to weaken the insurgency. Barno, now director of the Near East South Asia Center for Strategic Studies at the National Defense University, told IPS in an interview last September, \u00ab\u00a0There is a predilection to use air power in lieu of close up encounters<\/em> [<em>with insurgents<\/em>] <em>to avoid U.S. casualties.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Barno recalled that he dramatically reduced reliance on air power, because he regarded the Afghan tolerance for the U.S. military presence as a \u00ab\u00a0bag of capital\u00a0\u00bb that was used up \u00ab\u00a0every time we used air power or knocked down doors or detained someone in front of their family.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Barno&rsquo;s policy of curbing air power was abandoned by his successor, Gen. Karl W. Eikenberry, from 2005 to 2007, and the number of air strikes has continued to grow exponentially since 2005. Eikenberry was nominated by Obama to be ambassador to Afghanistan &ndash; an indication that the broad outlines of U.S. strategy in Afghanistan will continue to emphasize air attacks on suspected Taliban targets.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Growing Afghan anger at the hundreds of civilian casualties from U.S. air strikes, often based on bad intelligence, has been exploited by insurgents across the country.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">D\u00e9construction puis contraction&#8230;<\/h3>\n<\/p>\n<p><p>&hellip; Qu&rsquo;est-ce que la \u00ab\u00a0guerre\u00a0\u00bb devenue? Lind \u00e9crit: &laquo;&hellip;[S]<em>eek to de-escalate. De-escalation is the way state armed forces prevail in Fourth Generation.<\/em>&raquo; Tous ces termes renvoient \u00e0 un processus de d\u00e9construction, et c&rsquo;est bien entendu la caract\u00e9ristique principale, non seulement de la guerre, mais de toute une \u00e9poque, &ndash; et alors, les tourments de la guerre apparaissent parfaitement logiques et compr\u00e9hensibles.<\/p>\n<\/p>\n<p><p>La guerre (le concept de guerre autant que la technique de la guerre) est aujourd&rsquo;hui soumise \u00e0 une m\u00eame dynamique critique et totalement d\u00e9structurante que tous les grands domaines constitutifs des relations internationales. Cette dynamique poss\u00e8de la puissance inou\u00efe de la crise et son contenu renvoie \u00e9videmment aux composants et aux divers avatars de la crise. Dans ce contexte, il appara&icirc;t \u00e9vident qu&rsquo;il existe une crise de la guerre qui ne se d\u00e9finit plus par la r\u00e9flexion critique habituelle, \u00e9voluant dans un cadre conformiste, mais par cette dynamique critique.<\/p>\n<\/p>\n<p><p>La situation que l&rsquo;on d\u00e9couvre est effectivement celle de la G4G, comme la nomme Lind, mais d&rsquo;une G4G en constante red\u00e9finition pour cerner de mieux en mieux sa nature et sa fonction. La G4G appara&icirc;t de plus en plus comme une doctrine g\u00e9n\u00e9rale couvrant nombre de domaines, qui, pour le domaine de la guerre, se voudrait la doctrine d&rsquo;une nouvelle forme de guerre et serait paradoxalement le contraire de la guerre selon la conception conventionnelle du concept de guerre, qu&rsquo;on pourrait ainsi qualifier d'\u00a0\u00bbanti-guerre\u00a0\u00bb. Ainsi la G4G acte-t-elle, aujourd&rsquo;hui, une tendance puissante \u00e0 la \u00ab\u00a0contraction\u00a0\u00bb de la guerre, c&rsquo;est-\u00e0-dire un processus de d\u00e9construction du concept de guerre permettant d&rsquo;introduire ce mouvement de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-sous_le_soleil_de_mexico_17_04_2009.html\">contraction<\/a> dont on a vu qu&rsquo;il caract\u00e9rise par ailleurs la politique ext\u00e9rieure US (et occidentale, dans la foul\u00e9e). Il doit \u00eatre gard\u00e9 \u00e0 l&rsquo;esprit et constamment r\u00e9p\u00e9t\u00e9 pour bien saisir l&rsquo;importance de la chose et sa puissance, que ces dynamique de d\u00e9construction-contraction sont impos\u00e9es par les \u00e9v\u00e9nements et nullement pr\u00e9m\u00e9dit\u00e9es par les hommes, y compris bien entendu par la nouvelle administration US.<\/p>\n<\/p>\n<p><p>Le mouvement affectant la conception de la guerre que d\u00e9crivent implicitement Lind et Prather, chacun \u00e0 des propos diff\u00e9rents (ce qui montre bien combien cette dynamique impr\u00e8gne tous les domaines de la r\u00e9flexion), est effectivement un mouvement de contraction se caract\u00e9risant concr\u00e8tement pour ce cas par la mise en cause de la dimension a\u00e9rienne de la guerre et de la forme de la guerre. Les arguments sempiternels des experts asserment\u00e9s selon lesquels, bien entendu, il faut pr\u00e9parer d&rsquo;autres guerres, que des guerres conventionnelles \u00e0 tr\u00e8s haut niveau (force a\u00e9rienne jouant un r\u00f4le essentiel) sont toujours possibles et redeviendront probables, notamment avec l&rsquo;\u00e9mergence de la Chine, deviennent ineptes et perdent toute substance. La crise leur r\u00e9pond. La crise syst\u00e9mique et eschatologique, qui frappe le c&oelig;ur et le fonctionnement du syst\u00e8me, rend notre civilisation, par absence de moyens budg\u00e9taires, par paralysie bureaucratique et par incapacit\u00e9 technique d\u00e9sormais, impuissante \u00e0 fournir l&rsquo;outil de la guerre conventionnelle. De ce c\u00f4t\u00e9 \u00e9galement, la G4G triomphe en se confirmant comme une \u00ab\u00a0anti-guerre\u00a0\u00bb (\u00ab\u00a0anti-notre-guerre\u00a0\u00bb) qui prend en compte la dynamique irr\u00e9sistible de la crise, s&rsquo;en abreuve et s&rsquo;en nourrit.<\/p>\n<\/p>\n<p><p>Ce que nous disent <em>in fine<\/em> ces deux experts, Lind et Prather, en attaquant l&rsquo;\u00e9vidente absurdit\u00e9 de l&#8217;emploi de la force a\u00e9rienne comme il en est fait usage, qui agit comme du p\u00e9trole qu&rsquo;on r\u00e9pand sur l&rsquo;incendie, c&rsquo;est que notre civilisation am\u00e9ricaniste et occidentaliste est devenue impuissante dans l&rsquo;art de la guerre selon ses conceptions. (\u00ab\u00a0L&rsquo;art de la guerre selon ses conceptions\u00a0\u00bb, c&rsquo;est-\u00e0-dire un \u00ab\u00a0art de la guerre\u00a0\u00bb caricatural et monstrueux, plut\u00f4t une \u00ab\u00a0science technologique de la guerre\u00a0\u00bb quand la science est devenue monstruosit\u00e9 dans son application, comme on le constate aujourd&rsquo;hui \u00e0 la lumi\u00e8re de la crise du syst\u00e8me, et la technologie un monstre dont on a perdu le contr\u00f4le; et, dans son application, \u00ab\u00a0l&rsquo;art de la guerre\u00a0\u00bb devenu une \u00ab\u00a0bureaucratisation technologique de la guerre\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Bien entendu, on ne doit pas voir dans tout cela une querelle de sp\u00e9cialistes comme on en trouve dans nos s\u00e9minaires d&rsquo;experts asserment\u00e9s du syst\u00e8me. La dimension a\u00e9rienne est sur la sellette parce que les circonstances l&rsquo;y mettent, et que les imb\u00e9ciles au front bas en font grand usage comme chacun sait. Ce n&rsquo;est pas elle sp\u00e9cifiquement qui est en cause; nous ne sommes pas dans une querelle sectorielle et, demain, les autres dimensions pourraient subir un proc\u00e8s semblable. Ce qui est en cause, c&rsquo;est la \u00ab\u00a0guerre\u00a0\u00bb elle-m\u00eame, telle que notre syst\u00e8me l&rsquo;a con\u00e7ue, enfant\u00e9e, et dont il vit et prosp\u00e8re \u00e0 plus d&rsquo;un \u00e9gard; puisque notre syst\u00e8me est dans crise qu&rsquo;on sait, \u00ab\u00a0sa\u00a0\u00bb guerre l&rsquo;est \u00e9galement.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9construction de la \u00ab\u00a0guerre\u00a0\u00bb 24 avril 2009 &mdash; Comment gagner en Afghanistan? Ou plut\u00f4t: comment ne pas perdre en Afghanistan? Ou plut\u00f4t : comment faire la guerre en Afghanistan? Il y a des agitations originales autour de ces question, dans des lieux, c\u00e9nacles et colonnes de journaux au-del\u00e0, bien au-del\u00e0 de l&rsquo;Afghanistan, &ndash; dans un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3020,3236,8172,7482,8276,5701,2645,1012,7463],"class_list":["post-70708","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-aerienne","tag-afghanistan","tag-contraction","tag-deconstruction","tag-dimension","tag-g4g","tag-guerre","tag-lind","tag-porther"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70708"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70708\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}