{"id":70734,"date":"2009-05-05T06:25:57","date_gmt":"2009-05-05T06:25:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/05\/05\/eurofighter-retour-en-hollande\/"},"modified":"2009-05-05T06:25:57","modified_gmt":"2009-05-05T06:25:57","slug":"eurofighter-retour-en-hollande","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/05\/05\/eurofighter-retour-en-hollande\/","title":{"rendered":"Eurofighter, retour en Hollande"},"content":{"rendered":"<p><p>Le consortium Eurofighter (EADS) a annonc\u00e9 (le <a href=\"http:\/\/www.eu-digest.com\/2009\/05\/eurofighter-typhoon-eurofighter.html\" class=\"gen\">2 mai 2009<\/a>, selon <em>Euro-Digest<\/em>) qu&rsquo;il faisait une proposition \u00e0 la Hollande pour le remplacement des chasseurs F-16 de ce pays. Il s&rsquo;agit d&rsquo;une proposition industrielle  de 7 milliards, pour des investissements \u00e0 court terme et \u00e0 long terme, en plus de la proposition elle-m\u00eame portant sur les avions de combat.<\/p>\n<\/p>\n<p><p>\tCette proposition est \u00e9videmment une cons\u00e9quence directe des derni\u00e8res <a href=\"http:\/\/www.dedefensa.org\/article-si_ce_n_est_waterloo_c_est_au_moins_trafalgar_28_04_2009.html\" class=\"gen\">p\u00e9rip\u00e9ties<\/a>, notamment hollandaises, qu&rsquo;a connues le programme JSF.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Rainer Hertrich CEO EADS, and Steve Mogford, COO BAE SYSTEMS today unveiled details of a euro7 billion (Gld15 approx.) industrial partnership program that could benefit Netherlands industry. The package was presented on behalf of the Eurofighter Partner Companies (Alenia Aerospazio, BAE SYSTEMS, EADS-Deutschland, EADS-CASA) in support of the Eurofighter bid as candidate in the program for a replacement of the Royal Netherlands Air Force (RNLAF) F-16 fleet. The industrial package is geared to both short term participation in production programmes, and long term, high-value defence and aerospace partnerships across the defence and aerospace activities of the Eurofighter partner companies.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEurofighter (avec le chasseur <em>Typhoon<\/em>) \u00e9tait pr\u00e9sent dans la <a href=\"http:\/\/www.dedefensa.org\/article-la_hollande_le_jsf_et_le_destin_de_l_europe_30_01_2002.html?admin=1\" class=\"gen\">premi\u00e8re<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-les_pays-bas_choisissent_le_jsf_l_actualite_d_un_echec_et_l_avenir_d_une_erreur_15_02_2002.html?admin=1\" class=\"gen\">comp\u00e9tition<\/a> de s\u00e9lection, ou plut\u00f4t de pr\u00e9-s\u00e9lection du successeur du F-16 hollandais, \u00e0 l&rsquo;hiver 2001-2002. Le <em>Typhoon<\/em> avait \u00e9t\u00e9 distanc\u00e9 par le JSF et le <em>Rafale<\/em> respectivement. (Le <em>Typhoon<\/em> avait re\u00e7u, sur l&rsquo;ensemble de ses performances, une cotation de 5,83 points de la RNethAF, contre 6,97 et 6,95 respectivement pour le JSF et le <em>Rafale<\/em>.) Il y eut ensuite diverses p\u00e9rip\u00e9ties que nos lecteurs connaissent et peuvent retrouver sur notre site, et notamment, depuis plus d&rsquo;un an en <a href=\"http:\/\/www.dedefensa.org\/article-jsf_la_hollande_bouge_29_05_2008.html?admin=1\" class=\"gen\">Hollande<\/a>. On sait que, finalement, le secr\u00e9taire d&rsquo;Etat \u00e0 la d\u00e9fense de Vries, d\u00e9cida un nouveau processus de s\u00e9lection pour satisfaire aux pressions des parlementaires. La chose ne trompa personne, et surtout pas EADS (Eurofighter <em>Typhoon<\/em>) et Dassault (<em>Rafale<\/em>), qui <a href=\"http:\/\/www.dedefensa.org\/article-jsf_la_hollande_se_complique_01_07_2008.html\" class=\"gen\">refus\u00e8rent<\/a> la participation \u00e0 cette comp\u00e9tition consid\u00e9r\u00e9e comme un faux-nez pour justifier le choix du JSF. Seul le SAAB <em>Vigen<\/em> su\u00e9dois (absent en 2001-2002) d\u00e9cida de jouer le jeu m\u00eame fauss\u00e9. Depuis, les choses ont \u00e9volu\u00e9, comme on sait.<\/p>\n<\/p>\n<p><p>\tEADS\/Eurofighter revient, confirmant ainsi que ce qui se passe en Hollande est tr\u00e8s s\u00e9rieux, que le JSF, qui semblait \u00eatre le choix hollandais boucl\u00e9 pour tout le monde depuis 2002, est r\u00e9ellement menac\u00e9. La d\u00e9cision a sans aucun doute une signification fondamentale, quand on a \u00e0 l&rsquo;esprit la suspicion totale o\u00f9 ce comp\u00e9titeur (les comp\u00e9titeurs, Dassault bien s\u00fbr, m\u00eame \u00e9galement SAAB) tenait la position du gouvernement hollandais \u00e0 l&rsquo;\u00e9t\u00e9 2008. EADS constate d&rsquo;une part qu&rsquo;il y a d\u00e9sormais un d\u00e9lai important avant qu&rsquo;une d\u00e9cision soit prise, en 2012, tr\u00e8s certainement apr\u00e8s une nouvelle comp\u00e9tition. D&rsquo;autre part, EADS estime que la situation du JSF a chang\u00e9, aux USA certes mais aussi en Hollande. Tous ces \u00e9v\u00e9nements sont pris s\u00e9rieusement, simplement parce qu&rsquo;ils sont s\u00e9rieux.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9v\u00e9nement constitue un tournant symbolique dans la mesure o\u00f9 il marque un tournant de la dynamique, jusqu&rsquo;ici marqu\u00e9e par un retrait,  une abstention ou une absence europ\u00e9enne face au JSF. (La participation du <em>Vigen<\/em> \u00e0 la comp\u00e9tition avec le JSF, il y a un an, ne constituait qu&rsquo;une tentative atypique, le constructeur su\u00e9dois ayant \u00e9t\u00e9 hors de cette comp\u00e9tition auparavant.) Dans ce cas, Eurofighter lance une dynamique de retour ou de contre-attaque. Ainsi se trouve confirm\u00e9e l&rsquo;\u00e9volution actuelle du ph\u00e9nom\u00e8ne JSF, une \u00e9volution \u00e0 laquelle bien peu de gens, et aucun sp\u00e9cialiste digne (indigne?) de ce nom, ne croyait \u00e9videmment il y a encore 2 ou 3 ans.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement europ\u00e9en, sans aucun doute, et l&rsquo;on esp\u00e8re que les Fran\u00e7ais,  qui se montrent, si souvent, beaucoup trop impressionn\u00e9s par leurs concurrents am\u00e9ricanistes,  vont le compl\u00e9ter par un retour de leur c\u00f4t\u00e9, avec le <em>Rafale<\/em>. Il est aujourd&rsquo;hui \u00e9vident que l&rsquo;on se trouve dans une dynamique nouvelle, ou en train de devenir nouvelle, o\u00f9 la m\u00e9canique de bulldozer du syst\u00e8me de l&rsquo;am\u00e9ricanisme se trouve confront\u00e9e \u00e0 un m\u00e9chant grain de sable qui s&rsquo;av\u00e8re \u00eatre un \u00e9norme rocher, qui s&rsquo;est install\u00e9 en travers de sa route.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 mai 2009 \u00e0 05H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le consortium Eurofighter (EADS) a annonc\u00e9 (le 2 mai 2009, selon Euro-Digest) qu&rsquo;il faisait une proposition \u00e0 la Hollande pour le remplacement des chasseurs F-16 de ce pays. Il s&rsquo;agit d&rsquo;une proposition industrielle de 7 milliards, pour des investissements \u00e0 court terme et \u00e0 long terme, en plus de la proposition elle-m\u00eame portant sur les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3220,3203,250,3219,8225,3129],"class_list":["post-70734","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-eurofighter","tag-hollande","tag-jsf","tag-rafale","tag-retour","tag-typhoon"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70734"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70734\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}