{"id":70807,"date":"2009-06-04T10:19:45","date_gmt":"2009-06-04T10:19:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/04\/les-a-cotes-de-bho\/"},"modified":"2009-06-04T10:19:45","modified_gmt":"2009-06-04T10:19:45","slug":"les-a-cotes-de-bho","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/04\/les-a-cotes-de-bho\/","title":{"rendered":"Les \u00e0-c\u00f4t\u00e9s de BHO"},"content":{"rendered":"<p><h2 class=\"common-article\">Les \u00e0-c\u00f4t\u00e9s de BHO<\/h2>\n<\/p>\n<p><p>\t4 juin 2009  Barack Obama, en voyage dans la r\u00e9gion, parle au Caire. Il s&rsquo;agit d&rsquo;un grand discours du pr\u00e9sident des USA destin\u00e9 au monde musulman; un connaisseur, BHO, avec son deuxi\u00e8me pr\u00e9nom (Barack Hussein Obama) et sa paternit\u00e9 musulmane. Ce qui nous importe \u00e0 cet \u00e9gard, c&rsquo;est le tr\u00e8s grand d\u00e9bat politique derri\u00e8re ce discours et ce voyage,  d\u00e9bat encore assez discret, la grande presse-<em>Pravda<\/em> pr\u00e9f\u00e9rant les vaticinations essentielles sur les droits de l&rsquo;homme place Tienanmen, il y a vingt ans. On a les occupations qu&rsquo;on peut, et le pass\u00e9 ripolin\u00e9 comme il se doit est une option int\u00e9ressante pour la pens\u00e9e progressiste quand le pr\u00e9sent donne du fil \u00e0 retordre.<\/p>\n<\/p>\n<p><p>\tTr\u00eave de sarcasmes et passons \u00e0 ce tr\u00e8s grand d\u00e9bat politique, qui concerne les relations entre les USA et Isra\u00ebl qui, sous la direction \u00e9clair\u00e9e de BHO, commencent \u00e0 prendre une dr\u00f4le de tournure. Chaque jour qui passe confirme le durcissement spectaculaire dans sa substance de la politique US. Comme on pu le lire, Arnaud de <a href=\"http:\/\/www.dedefensa.org\/article-la_plus_grave_crise_entre_washington_et_israel_depuis_suez-1956_02_06_2009.html\" class=\"gen\">Borchgrave<\/a> juge que c&rsquo;est la plus grave crise entre les USA et Isra\u00ebl depuis 1956 (Suez). Disons-le autrement et plus justement, c&rsquo;est la plus grave crise tout court entre les USA et Isra\u00ebl, parce que cette gravit\u00e9 existe aujourd&rsquo;hui alors que les liens USA-Isra\u00ebl \u00e9taient, il y a quelques mois encore, resserr\u00e9s comme ils n&rsquo;avaient jamais \u00e9t\u00e9 auparavant, et surtout pas en 1956, lorsque les liens USA-Isra\u00ebl n&rsquo;avaient absolument aucun rapport avec ceux de la p\u00e9riode GW Bush. (Tout a bascul\u00e9, dans la connivence USA-Isra\u00ebl, \u00e0 partir de 1967, avec acc\u00e9l\u00e9ration irr\u00e9sistible \u00e0 partir du d\u00e9but des ann\u00e9es 1980, lorsque le Pentagone est devenu le principal inspirateur de la politique militaris\u00e9e d&rsquo;Isra\u00ebl.)<\/p>\n<\/p>\n<p><p>\tUne question vitale, \u00e9galement effleur\u00e9e par Borgrave, c&rsquo;est l&rsquo;attitude du Congr\u00e8s US: \u00ab<em>Mr. Netanyahu&rsquo;s new team is also confident Congress would never allow Mr. Obama to make aid to Israel conditional on a settlement freeze, let alone dismantling 160 major colonies that house about 300,000 Jews.<\/em>\u00bb BHO n&rsquo;est-il pas un homme pour lequel il faudrait songer au fameux adage ne dites jamais jamais&rsquo;?<\/p>\n<\/p>\n<p><p>\tIl y a eu quelques \u00e9chos sur les r\u00e9actions au Congr\u00e8s jusqu&rsquo;\u00e0 ce point, \u00e0 propos d&rsquo;une \u00e9volution qui est pourtant d\u00e9sormais \u00e9vidente, au moins depuis deux mois. <em>Antiwar.com<\/em> faisait, hier <a href=\"http:\/\/news.antiwar.com\/2009\/06\/02\/dems-tell-obama-to-back-off-israel-criticism\/\" class=\"gen\">3 juin 2009<\/a>, un rapide <em>check-up<\/em> des critiques de BHO au Congr\u00e8s. <\/p>\n<\/p>\n<p><p>\tDan Froomkin, dans le Washington <em>Post<\/em> du <a href=\"http:\/\/voices.washingtonpost.com\/white-house-watch\/middle-east\/obama-getting-honest-with-isra.html\" class=\"gen\">2 juin 2009<\/a>, cite divers commentaires de nombreuses sources, exposant les changements de la politique US avec Obama, les r\u00e9actions du Congr\u00e8s, etc. Pour rappel, il situe le probl\u00e8me dans son contexte, avec des remarques int\u00e9ressantes,  notamment cette pr\u00e9cision (soulign\u00e9 en gras par nous: BHO \u00ab<em>believes Israel has been indulged  even deluded  by<\/em> <strong><em>previous administrations<\/em><\/strong><em>, to its own d\u00e9triment<\/em>\u00bb), qui implique qu&rsquo;Obama met en cause non seulement la politique de Bush vis-\u00e0-vis d&rsquo;Isra\u00ebl mais la politique des administrations pr\u00e9c\u00e9dentes qui aurait conduit Isra\u00ebl \u00e0 se faire des illusions sur la co\u00efncidence compl\u00e8te des int\u00e9r\u00eats US avec les siens,  ce qui pourrait nous faire remonter loin<\/p>\n<\/p>\n<p><p>\t\u00ab<em>President Obama&rsquo;s call for a new dialogue in the Middle East  one in which the U.S. would be honest about what Israel has to do to achieve security  is the clearest indication yet that the new administration is taking a dramatically different and much more assertive approach with its long-time ally.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama&rsquo;s comments indicate that he believes Israel has been indulged  even deluded  by previous administrations, to its own detriment. By contrast, this president&rsquo;s view seems to be that what Israel really needs is to be pushed into making the difficult concessions that are in its own long-term interests. And Obama has been clear that the first concession Israel needs to make is to freeze the growth of Jewish settlements in the West Bank that both literally and figuratively set the occupation of Palestinian territories in concrete.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est certainement dans le texte qu&rsquo;a publi\u00e9 Ben Smith, de <em>Politico.com<\/em>, le <a href=\"http:\/\/www.politico.com\/news\/stories\/0609\/23207.html\" class=\"gen\">1er juin 2009<\/a>, qu&rsquo;on trouve le plus d&rsquo;indications sur l&rsquo;attitude du Congr\u00e8s. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>My concern is that we are applying pressure to the wrong party in this dispute, said Rep. Shelley Berkley (D-Nev.). I think it would serve America&rsquo;s interest better if we were pressuring the Iranians to eliminate the potential of a nuclear threat from Iran, and less time pressuring our allies and the only democracy in the Middle East to stop the natural growth of their settlements. When Congress gets back into session the administration is going to hear from many more members than just me, she said.<\/em>  [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb[E]<em>ven a key defender of Obama&rsquo;s Mideast policy, Rep. Robert Wexler (D-Fla.), is seeking to narrow the administration&rsquo;s definition of settlement to take pressure off Obama. And the unusual criticism by congressional Democrats of the popular president is a sign that it may take more than a transformative presidential election to change the domestic politics of Israel.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Other Democrats, in interviews with Politico, raised similar concerns. While few will defend illegal Jewish outposts on land they hope will be part of a Palestinian state, they question putting public pressure on Israel while  so far  paying less public attention to Palestinian terrorism and other Arab states&rsquo; hostility to Israel.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> There&rsquo;s a line between articulating U.S. policy and seeming to be pressuring a democracy on what are their domestic policies, and the president is tiptoeing right up to that line, said Rep. Anthony Weiner (D-N.Y.), who said he&rsquo;d heard complaints from constituents during the congressional recess. I would have liked to hear the president talk more about the Palestinian obligation to cut down on terrorism.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em> I don&rsquo;t think anybody wants to dictate to an ally what they have to do in their own national security interests, said Rep. Gary Ackerman (D-N.Y.), who said he thinks there&rsquo;s room for compromise. I have to hear specifically from the administration exactly how they define their terms and is there room for defining the terms, he said, referring to the terms settlement and natural growth.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes r\u00e9publicains sont \u00e9videmment encore plus critiques des initiatives de Barack Obama, selon les arguments habituels dont l&rsquo;extr\u00eame est celle d&rsquo;un Isra\u00ebl expos\u00e9 \u00e0 la destruction totale par l&rsquo;Iran dont on sait la puissance unique dans l&rsquo;histoire, alors que le pr\u00e9sident US chicane sur des implantations d\u00e9risoires. Il s&rsquo;agit de l&rsquo;habituelle hypocrisie, la monotonie de la d\u00e9formation, la pens\u00e9e r\u00e9duite au slogan, tout cela un peu \u00e9puisant et \u00e0 laisser pour nourrir les \u00e9ditos de la presse-<em>Pravda<\/em> parisienne. A noter ceci, tout de m\u00eame, fort int\u00e9ressant \u00e0 plus d&rsquo;un \u00e9gard \u00ab<em>The pro-Israel lobby AIPAC last week got the signatures of 329 members of Congress, including key figures in both parties, on a letter calling on the administration to work closely and privately with Israel  in contrast to the current public pressure.<\/em>\u00bb  Fort int\u00e9ressant parce qu&rsquo;on voit soudain la v\u00e9ritable crainte de Netanyahou et de la bande parlementaire US qui le suit: que les critiques soient publiques, que la querelle soit expos\u00e9e sur la place publique, comme elle en prend le chemin. On devra revenir l\u00e0-dessus, parce que cela est tout simplement <strong>essentiel<\/strong>, parce que c&rsquo;est l\u00e0-dessus qu&rsquo;on jugera de la capacit\u00e9 d&rsquo;Obama \u00e0 ne pas c\u00e9der.<\/p>\n<\/p>\n<p><p>\tTerminons par ceci, toujours du m\u00eame texte, qui n&rsquo;est pas moins int\u00e9ressant :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Other Democrats allied with Israel didn&rsquo;t respond to questions about Obama&rsquo;s policy, however. And the rhetoric, even from Obama&rsquo;s critics, remains relatively sedate compared with the open insurrection other presidents, from Carter to the elder Bush, have triggered with attempts to apply direct pressure on Israel. <\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There&rsquo;s such a desire for him to be successful that he&rsquo;s lived this charmed life that most politicians, and most presidents, dealing with Israel wouldn&rsquo;t have, said one congressional Democrat. In the early months, the finger is off the hair trigger on these issues.<\/em>\u00bb<\/p>\n<h3>Un regard gaulliste?<\/h3>\n<\/p>\n<p><p>\tVis-\u00e0-vis d&rsquo;Isra\u00ebl, aujourd&rsquo;hui, s&rsquo;il y a un homme qui pourrait avoir un regard gaulliste pos\u00e9 sur ce pays avec sa politique devenue \u00e0 tous \u00e9gards nuisible; avec une direction archi-belliciste et compl\u00e8tement conform\u00e9e \u00e0 l&rsquo;orientation politico-militaire du Pentagone et \u00e0 l&rsquo;id\u00e9ologie maximaliste qui soutient cette orientation,  cet homme c&rsquo;est Barack Obama,  BHO gaulliste sur ce point, cela pourrait servir \u00e0 la compr\u00e9hension des choses du vaste monde de Sarko. Ce regard gaulliste tient dans le fait d&rsquo;\u00e9largir le probl\u00e8me d&rsquo;Isra\u00ebl \u00e0 tous les composants de la s\u00e9curit\u00e9 de la r\u00e9gion, au lieu de s&rsquo;en tenir \u00e0 la <strong>seule<\/strong> s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl, dont la pr\u00e9sentation est faite selon des facteurs r\u00e9partis en g\u00e9n\u00e9ral et \u00e0 parts \u00e0 peu pr\u00e8s \u00e9gales entre des dissimulations, des obsessions, des actions terroristes de relations publiques et de <em>lobbying<\/em>, et ce qu&rsquo;il y a d&rsquo;arrangeant dans la r\u00e9alit\u00e9 pour la cause pr\u00e9sent\u00e9e. Regard gaulliste, ou disons plut\u00f4t, pour \u00eatre plus pr\u00e9cis, possibilit\u00e9 d&rsquo;un regard gaulliste,  et la restriction montre bien que, pour autant, rien n&rsquo;est dit, et surtout pas la messe.<\/p>\n<\/p>\n<p><p>\tUn premier point essentiel est le climat nouveau install\u00e9 autour du probl\u00e8me isra\u00e9lo-palestinien qui tient \u00e0 cette question de <em>linkage<\/em> entre ce probl\u00e8me isra\u00e9lo-palestinien r\u00e9duit aux chicaneries dont les Isra\u00e9liens sont experts des implantations, et la question iranienne. C&rsquo;est l\u00e0 le fondement op\u00e9rationnel de la remarque de <a href=\"http:\/\/www.dedefensa.org\/article-la_plus_grave_crise_entre_washington_et_israel_depuis_suez-1956_02_06_2009.html\" class=\"gen\">Borchgrave<\/a> d\u00e9j\u00e0 rappel\u00e9e ci-dessus: \u00ab<em>Iran&rsquo;s nukes also are pulling apart the Obama administration and Israel&rsquo;s new government under Prime Minister Benjamin Netanyahu. For the first time since 1956, when President Eisenhower ordered Israel, France and Britain to cease their occupation of the Suez Canal, U.S. and Israeli strategic interests are no longer seen as one and the same.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa question de la divergence des int\u00e9r\u00eats strat\u00e9giques entre USA et Isra\u00ebl implique que l&rsquo;administration Obama n&rsquo;accepte plus la division dramatique et habile que les Isra\u00e9liens ont toujours fait. D&rsquo;une part, la question isra\u00e9lo-palestinienne, avec les chicaneries sans fin des implantations, qui est un marais o\u00f9 se perd l&rsquo;\u00e9norme importance de la situation g\u00e9n\u00e9rale du Moyen-Orient avec la question nucl\u00e9aire iranienne, o\u00f9 Isra\u00ebl peut arguer sans fin et embrouiller le cas dans les arcanes de discussions byzantines, d&rsquo;o\u00f9 il sortira toujours vainqueur face aux Palestiniens, gr\u00e2ce \u00e0 la puissance de sa pression et de sa politique brutale. D&rsquo;autre part la question de l&rsquo;Iran nucl\u00e9aire isol\u00e9e de son contexte, o\u00f9 Isra\u00ebl peut arguer dramatiquement de la menace existentielle contre lui, o\u00f9 le sentiment exacerb\u00e9 et entretenu dans son exacerbation comme l&rsquo;on sait, \u00e9carte la fermet\u00e9 de la raison. En liant les deux (<em>linkage<\/em>), on \u00e9claire l&rsquo;aspect irresponsable et partisan de la politique isra\u00e9lo-palestinienne des implantations et on relative l&rsquo;argument iranien, aussi bien le soi disant destin tragique d&rsquo;Isra\u00ebl (menace existentielle) que les v\u00e9ritables intentions iraniennes qui sont d\u00e9gag\u00e9es des incantations extr\u00e9mistes. En d&rsquo;autres mots, on \u00e9largit la question de la s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl \u00e0 la question de la s\u00e9curit\u00e9 collective de la r\u00e9gion, o\u00f9 est naturellement incluse la question de la s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le second apport du texte de Borchgrave, l\u00e0 o\u00f9 diff\u00e8rent brutalement les int\u00e9r\u00eats strat\u00e9giques des deux pays (USA et Isra\u00ebl). Il y a l&rsquo;analyse apocalyptique des USA sur les risques de prolif\u00e9ration nucl\u00e9aire, non pas vers certains Etats, mais vers des groupes terroristes. (Cette analyse vaut ce qu&rsquo;elle vaut et on peut la critiquer et la d\u00e9noncer ais\u00e9ment comme excessive, li\u00e9e aux obsessions terroristes; en l&rsquo;occurrence, n&rsquo;en tenons pas compte si, par ailleurs, cette analyse conduit \u00e0 des possibilit\u00e9s nouvelles de traitement du probl\u00e8me g\u00e9n\u00e9ral de la zone.) Les Isra\u00e9liens peuvent difficilement rejeter l&rsquo;argument puisqu&rsquo;il s&rsquo;agit d&rsquo;un argument fond\u00e9 sur l&rsquo;obsession terroriste dont ils sont les ma\u00eetres, et l&rsquo;argument finit pas se retourner contre eux et les conduit vers une impasse qui \u00e9claire cette divergence strat\u00e9gique dont parle Borchgrave. La logique de l&rsquo;administration US, c&rsquo;est de pousser le cas iranien jusqu&rsquo;\u00e0 un constat qui pourrait \u00eatre ceci: pour \u00e9viter une prolif\u00e9ration nucl\u00e9aire vers les terroristes, il faut faire entrer l&rsquo;Iran dans le cadre l\u00e9gal international de la situation nucl\u00e9aire. Si l&rsquo;Iran y est conduit dans des conditions qui le satisfont, il se trouvera \u00e0 son tour, par ses propres int\u00e9r\u00eats, conduit \u00e0 lutter contre la prolif\u00e9ration vers des terroristes. Pour ce faire, une seule solution qui ne passerait pas par l&rsquo;acceptation du nucl\u00e9aire iranien devenu armes nucl\u00e9aires: accepter que l&rsquo;Iran arrive au seuil (capacit\u00e9 de faire des bombes sans les faire) dans le cadre d&rsquo;une zone (Moyen-Orient) qui doit \u00eatre d\u00e9nucl\u00e9aris\u00e9e pour satisfaire les exigences de l&rsquo;Iran sur sa propre s\u00e9curit\u00e9. Puisqu&rsquo;il s&rsquo;agit d&rsquo;une d\u00e9nucl\u00e9arisation g\u00e9n\u00e9rale (suppression des armes nucl\u00e9aires) de la zone, cela implique Isra\u00ebl dans le probl\u00e8me central de sa position de sup\u00e9riorit\u00e9 absolue, qui est une menace pour tous les autres Etats, de son arsenal nucl\u00e9aire. La position de propagande d&rsquo;Isra\u00ebl d&rsquo;un Etat menac\u00e9 d&rsquo;an\u00e9antissement est expos\u00e9e dans sa fausset\u00e9, d&rsquo;une fa\u00e7on publique. Les USA ont d\u00e9j\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-israel_bho_et_le_biais_nucleaire_09_05_2009.html\" class=\"gen\">sorti<\/a> ce lapin iconoclaste de leur chapeau. Cela tend \u00e0 prendre Isra\u00ebl \u00e0 sa propre rh\u00e9torique si l&rsquo;on revient au motif g\u00e9n\u00e9ral expos\u00e9 plus haut: puisqu&rsquo;Isra\u00ebl brandit la menace terroriste comme menace supr\u00eame, la logique ainsi expos\u00e9e r\u00e9pond \u00e0 son argument. Dans le sch\u00e9ma id\u00e9al de la zone d\u00e9nucl\u00e9aris\u00e9e (pas d&rsquo;arme nucl\u00e9aire pour aucun des Etats concern\u00e9s), l&rsquo;Iran ne peut plus fournir une arme nucl\u00e9aire au Hezbollah et deux hypoth\u00e8se apocalyptique agit\u00e9es par les strat\u00e8ges isra\u00e9liens comme menace existentielle contre Isra\u00ebl (l&rsquo;Iran nucl\u00e9aire qui menace Isra\u00ebl et la prolif\u00e9ration nucl\u00e9aire vers les terroristes) sont r\u00e9duites \u00e0 n\u00e9ant Mais, bien entendu, Isra\u00ebl doit \u00eatre <strong>aussi<\/strong> d\u00e9nucl\u00e9aris\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de cette logique est qu&rsquo;elle est un peu comme le diable sorti de sa bouteille, image qu&rsquo;on emploie pour l&rsquo;apparition du nucl\u00e9aire. Une fois qu&rsquo;on a sorti <strong>publiquement<\/strong> l&rsquo;argument que la zone d\u00e9nucl\u00e9aris\u00e9e est le moyen, et finalement le <strong>seul<\/strong> moyen s\u00fbr d&rsquo;\u00e9viter pour cette zone un Iran nucl\u00e9aire et la prolif\u00e9ration vers des groupes terroristes, il est tr\u00e8s difficile de le r\u00e9duire d&rsquo;une fa\u00e7on d\u00e9cisive lorsqu&rsquo;on argue par ailleurs (Isra\u00ebl) que le terrorisme et un Iran nucl\u00e9aire sont les deux menaces existentielles. La seule r\u00e9ponse d\u00e9cisive qu&rsquo;Isra\u00ebl puisse apporter est la destruction <strong>assur\u00e9e<\/strong> du nucl\u00e9aire de l&rsquo;Iran, et la seule assurance <strong>totale<\/strong> \u00e0 cet \u00e9gard (nous sommes dans le domaine de la r\u00e9flexion th\u00e9orique absolument radicale mais d&rsquo;une logique implacable), ce ne sont pas quelques raids mais une v\u00e9ritable guerre victorieuse contre l&rsquo;Iran, c&rsquo;est-\u00e0-dire une invasion victorieuse de l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\t(Tous ces gens discutant d&rsquo;une attaque contre l&rsquo;Iran se souviennent-ils qu&rsquo;une \u00e9tude du National War College US de fin 2007, examinant l&rsquo;option extr\u00eame de l&rsquo;invasion terrestre, a d\u00e9termin\u00e9 qu&rsquo;elle n\u00e9cessiterait une mobilisation d&rsquo;un millions d&rsquo;hommes aux USA, qui prendrait <strong>quatre<\/strong> ans pour sa seule <strong>pr\u00e9paration<\/strong>, avant l&rsquo;engagement des op\u00e9rations? Cela situe la logique compl\u00e8tement irr\u00e9aliste et absurde de l&rsquo;option de l&rsquo;attaque qui, pour \u00eatre <strong>assur\u00e9e<\/strong>, condition de la certitude en mati\u00e8re nucl\u00e9aire, doit prendre en compte de mani\u00e8re pressante l&rsquo;option d&rsquo;une guerre d&rsquo;invasion.)<\/p>\n<\/p>\n<p><p>\tLe dernier point est celui qu&rsquo;on a d\u00e9j\u00e0 soulign\u00e9 plus haut. L&rsquo;exigence de l&rsquo;attaque des r\u00e9seaux d&rsquo;influence isra\u00e9liens (AIPAC) contre la politique d&rsquo;Obama, c&rsquo;est qu&rsquo;Obama s&rsquo;abstienne de rendre publique la querelle. C&rsquo;est \u00e0 la fois une habilet\u00e9 et un aveu de faiblesse. Une habilet\u00e9 parce qu&rsquo;un d\u00e9bat retir\u00e9 du public, c&rsquo;est le champ ouvert \u00e0 toutes les manuvres d&rsquo;influence, de pression, etc., o\u00f9 les Isra\u00e9liens sont ma\u00eetres et o\u00f9 ils peuvent mobiliser tous leurs soutiens (notamment au Congr\u00e8s) qui n&rsquo;ont plus peur de s&rsquo;exposer \u00e0 une impopularit\u00e9 \u00e9lectorale en s&rsquo;opposant publiquement au sacro-saint pr\u00e9sident populaire; un aveu de faiblesse parce que la manuvre reconna\u00eet implicitement que les cas en litige tels qu&rsquo;ils sont per\u00e7us par Isra\u00ebl (non seulement la politique isra\u00e9lienne des implantations mais le refus implicite d&rsquo;Isra\u00ebl  d&rsquo;envisager l&rsquo;id\u00e9e d&rsquo;une une zone de non-prolif\u00e9ration comprenant implicitement son nucl\u00e9aire) sont loin d&rsquo;\u00eatre vendables publiquement sur leurs propres vertus, et que ce serait m\u00eame le contraire.<\/p>\n<\/p>\n<p><p>\tLa seule issue pour Obama, c&rsquo;est donc de suivre une diplomatie publique, faite de d\u00e9clarations publiques, d&rsquo;interventions publiques. Le Congr\u00e8s le bloquera-t-il? Tout sera fait pour cela, certes. Mais il y a d&rsquo;une part les restrictions qu&rsquo;on a vues, qui reposent curieusement sur ce facteur bien exotique du charme d&rsquo;Obama: sa popularit\u00e9 et le d\u00e9sir qu&rsquo;on a de le voir r\u00e9ussir (\u00ab<em>There&rsquo;s such a desire for him to be successful that he&rsquo;s lived this charmed life that most politicians, and most presidents, dealing with Israel wouldn&rsquo;t have<\/em>\u00bb),  facteur exotique mais si important dans le climat \u00e9lectoral et d\u00e9magogique constant o\u00f9 vit Washington en crise permanente. Bien s\u00fbr, cela ne vaut en principe que pour les parlementaires US mais tout est l\u00e0; les Isra\u00e9liens de Netanyahou, qui <a href=\"http:\/\/www.dedefensa.org\/article-israel_le_sourire_de_bho_et_son_manque_de_sympathie__27_05_2009.html\" class=\"gen\">d\u00e9testent<\/a> Obama, n&rsquo;ont rien \u00e0 faire de son charme mais doivent tenir compte de la sensibilit\u00e9 \u00e0 la fois \u00e9lectorale et de midinette des parlementaires US. D&rsquo;autre part, l&rsquo;on sait depuis <a href=\"http:\/\/www.dedefensa.org\/article-puisqu_il_n_y_a_pas_de_fumee_sans_feu_entre_israel_et_les_usa__17_01_2009.html\" class=\"gen\">janvier<\/a> (avant Obama), avec <a href=\"http:\/\/www.dedefensa.org\/article-la_these_de_la_victoire_a_la_pyrrhus__13_03_2009.html\" class=\"gen\">l&rsquo;affaire Freeman<\/a> depuis, que le situation isra\u00e9lienne aux USA se d\u00e9t\u00e9riore.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le point d\u00e9cisif, concernant la d\u00e9termination d&rsquo;Obama, qui, pour l&rsquo;instant, semble chaque jour  <a href=\"http:\/\/original.antiwar.com\/kessel-klohendler\/2009\/06\/03\/obama-turns-the-screws-on-israel\/\" class=\"gen\">se confirmer<\/a>. Obama tiendra-t-il dans sa campagne publique vis-\u00e0-vis d&rsquo;Isra\u00ebl? A partir d&rsquo;un certain point dans le cas d&rsquo;une r\u00e9ponse positive, lorsque tout aura \u00e9t\u00e9 mis publiquement sur la table des intentions de BHO, si ces intentions sont bien ce qu&rsquo;on en a dit ci-dessus, on se trouvera au point de non-retour. Les masques tomberont. Chacun sera ce qu&rsquo;il est, dans la vraie position qui est la sienne. Alors, la solution sera l\u00e0, et la paix enfin atteinte? Pas du tout, car il y a bien autre chose que l&rsquo;enjeu de la situation au Moyen-Orient. Le v\u00e9ritable affrontement commencera, notamment avec l&rsquo;exposition publique des v\u00e9ritables liens d&rsquo;influence d&rsquo;Isra\u00ebl aux USA, qui constituent une scandaleuse situation d&rsquo;influence empi\u00e9tant sur la souverainet\u00e9 en mati\u00e8re de s\u00e9curit\u00e9 nationale de la premi\u00e8re puissance du monde; avec, \u00e0 l&rsquo;inverse, l&rsquo;exposition des liens d&rsquo;influence du Pentagone et du complexe militaro-industriel sur la direction isra\u00e9lienne. Seront mis en \u00e9vidence le caract\u00e8re de gouvernement militariste qui m\u00e8ne Isra\u00ebl et l&rsquo;action d\u00e9stabilisante et militariste des milieux du CMI am\u00e9ricaniste qui inspirent et soutiennent cette direction isra\u00e9lienne. C&rsquo;est l\u00e0 l&rsquo;\u00e9preuve supr\u00eame et on jugera BHO sur le fond du fond.<\/p>\n<\/p>\n<p><p>\tAlors, la question  pour conclure est finalement assez simple: est-ce dans cette politique isra\u00e9lo-iranienne des USA avec toutes les implications qu&rsquo;on a dites que va se manifester ce que certains attendent de r\u00e9volutionnaire chez BHO, cette <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">hypoth\u00e8se<\/a> de l&rsquo;<em>American<\/em> Gorbatchev? Comme disait, entre autres analystes, Depardieu dialogu\u00e9 par Labro, c&rsquo;est une putain de bonne question. On ne peut, pour l&rsquo;instant, rien dire de plus, sinon \u00e9ventuellement n&rsquo;en penser pas moins,  et constater qu&rsquo;on en a d\u00e9j\u00e0 dit pas mal pour quatre mois de pr\u00e9sidence.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e0-c\u00f4t\u00e9s de BHO 4 juin 2009 Barack Obama, en voyage dans la r\u00e9gion, parle au Caire. Il s&rsquo;agit d&rsquo;un grand discours du pr\u00e9sident des USA destin\u00e9 au monde musulman; un connaisseur, BHO, avec son deuxi\u00e8me pr\u00e9nom (Barack Hussein Obama) et sa paternit\u00e9 musulmane. Ce qui nous importe \u00e0 cet \u00e9gard, c&rsquo;est le tr\u00e8s grand&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2741,7599,1257,8311,3090,2773,2774,3004,6208,2740],"class_list":["post-70807","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-2741","tag-aipac","tag-borchgrave","tag-denuclearisation","tag-influence","tag-iran","tag-israel","tag-nucleaire","tag-obama","tag-suez"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70807"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70807\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}