{"id":70821,"date":"2009-06-09T05:48:55","date_gmt":"2009-06-09T05:48:55","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/09\/les-russes-nont-qua-bien-se-tenir-la-suede-arrive\/"},"modified":"2009-06-09T05:48:55","modified_gmt":"2009-06-09T05:48:55","slug":"les-russes-nont-qua-bien-se-tenir-la-suede-arrive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/09\/les-russes-nont-qua-bien-se-tenir-la-suede-arrive\/","title":{"rendered":"Les Russes n&rsquo;ont qu&rsquo;\u00e0 bien se tenir, la Su\u00e8de arrive"},"content":{"rendered":"<p><p>L&rsquo;Europe vient de conna\u00eetre une ann\u00e9e de deux pr\u00e9sidences fameuses de l&rsquo;UE, en ce sens qu&rsquo;on savait \u00e0 quoi s&rsquo;en tenir. La pr\u00e9sidence fran\u00e7aise avait \u00e9t\u00e9 annonc\u00e9e d&rsquo;une fa\u00e7on tonitruante et elle fut effectivement remarquable \u00e0 plus d&rsquo;un \u00e9gard avec deux crises majeures (la G\u00e9orgie et la crise financi\u00e8re en ao\u00fbt et septembre 2008). La pr\u00e9sidence tch\u00e8que, par le contraste qu&rsquo;elle formait avec la pr\u00e9sidence fran\u00e7aise, par la fa\u00e7on dont Sarkozy avait mis en question les modalit\u00e9s m\u00eames du syst\u00e8me des pr\u00e9sidences \u00e0 six mois r\u00e9parties sur un pied d&rsquo;\u00e9galit\u00e9, b\u00e9n\u00e9ficiait \u00e9galement d&rsquo;un certain int\u00e9r\u00eat et d&rsquo;une certaine notori\u00e9t\u00e9 avant de s&rsquo;ouvrir, bien entendu dans un sens n\u00e9gatif apr\u00e8s la fran\u00e7aise. Elle fut d&rsquo;ailleurs chaotique et confirma d&rsquo;une certaine fa\u00e7on ce qu&rsquo;on attendait d&rsquo;elle,  une d\u00e9monstration par l&rsquo;absurde des faiblesses du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tPar contraste, on parle fort peu de la pr\u00e9sidence su\u00e9doise qui commence \u00e0 la fin du mois. L&rsquo;atmosph\u00e8re nourrit d&rsquo;ailleurs cette incertitude, avec l&rsquo;esp\u00e8ce d&rsquo;\u00e9touffement de la crise financi\u00e8re et \u00e9conomique sous une avalanche remarquable de propagande virtualiste, ou, si vous voulez, une <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_optimisme_sans_espoir__23_05_2009.html\" class=\"gen\">floraison<\/a> tonitruante et rassurante de jeunes pousses (<em>green shoots<\/em>) printani\u00e8res. Ce climat surr\u00e9aliste est confirm\u00e9e par des sources europ\u00e9ennes qui d\u00e9crivent une bureaucratie europ\u00e9enne au travail \u00ab<em>comme si rien ne s&rsquo;\u00e9tait pass\u00e9, ni la crise g\u00e9orgienne, ni la crise financi\u00e8re<\/em>\u00bb. Il appara\u00eet alors que la pr\u00e9sidence su\u00e9doise semblerait d\u00e9cid\u00e9e \u00e0 ne rien changer \u00e0 ces auspices marqu\u00e9s par un virtualisme militant de la part de l&rsquo;<em>establishment<\/em> europ\u00e9en.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Ce qu&rsquo;on distingue, <\/em>disent nos sources, <em>c&rsquo;est une volont\u00e9 su\u00e9doise de d\u00e9velopper une politique anti-russe tr\u00e8s appuy\u00e9e<\/em>\u00bb. Cela se ferait dans le sens classique de la politique europ\u00e9enne appuy\u00e9e sur les r\u00e9seaux pro-US ou US h\u00e9rit\u00e9s de la pr\u00e9sidence Bush, avec l&rsquo;arsenal de la gu\u00e9rilla humanitaire bien connue: d\u00e9nonciation des conditions d\u00e9mocratiques, droitdel&rsquo;hommisme, d\u00e9nonciation d&rsquo;une politique ext\u00e9rieure russe qualifi\u00e9e d&rsquo;agressive, guerre du gaz, etc. La cause de cette position su\u00e9doise est mal identifi\u00e9e par des indications pr\u00e9cises. \u00ab<em>Ce qui appara\u00eet surtout, c&rsquo;est une direction politique tr\u00e8s inspir\u00e9e par le politiquement correct lib\u00e9ral europ\u00e9en, \u00e0-la-Blair, notamment tr\u00e8s partisane du mod\u00e8le \u00e9conomique lib\u00e9ral, avec lequel la politique anti-russe est parfaitement coh\u00e9rente.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes Su\u00e9dois arrivent donc, sans la moindre attention ni le moindre int\u00e9r\u00eat pour les le\u00e7ons qu&rsquo;on pourrait tirer des crises diverses et r\u00e9centes,  quelles crises, d&rsquo;ailleurs? L&rsquo;hostilit\u00e9 \u00e0 la Russie fait partie de cet arsenal h\u00e9rit\u00e9 de l&rsquo;illusion lib\u00e9rale post-Guerre froide et parfaitement repr\u00e9sent\u00e9e, effectivement, par la blairisme du <em>New Labour<\/em> dont les \u00e9lections europ\u00e9ennes de dimanche ont c\u00e9l\u00e9br\u00e9 une fois de plus le triomphe. Tout cela s&rsquo;accorde tout aussi parfaitement avec l&rsquo;\u00e9tat d&rsquo;esprit r\u00e9gnant dans les institutions et bureaucraties europ\u00e9ennes. Rien n&rsquo;a chang\u00e9, rien ne doit changer dans nos certitudes vertueuses. La Russie reste le principal danger pour la civilisation et le syst\u00e8me sur notre continent,  ou bien, soyons juste, le principal danger avec le protectionnisme, les deux \u00e0 parts \u00e0 peu pr\u00e8s \u00e9gales,  car l&rsquo;on vous rassure l\u00e0-dessus, le protectionnisme, dont on sait qu&rsquo;il est la cause principale de la crise (dans tous les cas, celle des ann\u00e9es 1930), est vivement d\u00e9nonc\u00e9 et combattu.<\/p>\n<\/p>\n<p><p>\tL&rsquo;UE poursuivra donc, sous la baguette su\u00e9doise et  <a href=\"http:\/\/www.dedefensa.org\/article-otan_irresponsabilite_et_conspiration_09_05_2009.html\" class=\"gen\">de concert<\/a> avec sa compagne-soeur, l&rsquo;OTAN, sa vertueuse mission de d\u00e9structuration de la r\u00e9alit\u00e9. (Il se chuchote au reste que la Su\u00e8de ne r\u00eave que d&rsquo;imiter certains visionnaires bien connus. Une entr\u00e9e de ce pays dans l&rsquo;OTAN serait du dernier chic pour compl\u00e9ter le tableau,  c&rsquo;est notre conseil du jour.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 9 juin 2009 \u00e0 05H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Europe vient de conna\u00eetre une ann\u00e9e de deux pr\u00e9sidences fameuses de l&rsquo;UE, en ce sens qu&rsquo;on savait \u00e0 quoi s&rsquo;en tenir. La pr\u00e9sidence fran\u00e7aise avait \u00e9t\u00e9 annonc\u00e9e d&rsquo;une fa\u00e7on tonitruante et elle fut effectivement remarquable \u00e0 plus d&rsquo;un \u00e9gard avec deux crises majeures (la G\u00e9orgie et la crise financi\u00e8re en ao\u00fbt et septembre 2008). La&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8393,3228,398,584,8392,2730,4282,2609,610],"class_list":["post-70821","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-correct","tag-crise","tag-europe","tag-otan","tag-politiquement","tag-russie","tag-suede","tag-ue","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70821"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70821\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}