{"id":70869,"date":"2009-06-29T14:31:51","date_gmt":"2009-06-29T14:31:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/29\/sur-la-frontiere-sud-qui-est-le-vrai-ennemi-de-qui\/"},"modified":"2009-06-29T14:31:51","modified_gmt":"2009-06-29T14:31:51","slug":"sur-la-frontiere-sud-qui-est-le-vrai-ennemi-de-qui","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/06\/29\/sur-la-frontiere-sud-qui-est-le-vrai-ennemi-de-qui\/","title":{"rendered":"Sur la fronti\u00e8re Sud, qui est le VRAI ennemi de qui?"},"content":{"rendered":"<p><p>Cela ne pouvait manquer et cela n&rsquo;a pas manqu\u00e9. Aujourd&rsquo;hui, le Pentagone, ou Department of Defense (DoD) et le minist\u00e8re de la s\u00e9curit\u00e9 int\u00e9rieure, ou Department of Homeland Security (DHS),  les militaires d&rsquo;une part, les services de s\u00e9curit\u00e9 int\u00e9rieure d&rsquo;autre part,  sont engag\u00e9s dans une lutte s\u00e9v\u00e8re pour savoir qui aura la pr\u00e9pond\u00e9rance, sinon l&rsquo;autorit\u00e9, dans la ma\u00eetrise de la surveillance de la fronti\u00e8re Sud des USA, dans la lutte contre les cartels de la drogue dans la guerre des cartels qui fait rage dans la zone. Ainsi la confusion am\u00e9ricaniste commence-t-elle \u00e0 s&rsquo;ajouter, l\u00e0 o\u00f9 r\u00e8gne le bordel classique entre les irr\u00e9guliers et autres trafiquants, les divers services officiels des deux c\u00f4t\u00e9s de la fronti\u00e8re, collaborant comme chiens et chats, ou comme Am\u00e9ricains et Mexicains. Mais, comme le fameux Septi\u00e8me de Cavalerie, la bureaucratie US annonce qu&rsquo;elle arrive enfin sur place.<\/p>\n<\/p>\n<p><p>\tUn article du Washington <em>Post<\/em> du <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2009\/06\/27\/AR2009062700956.html?\" class=\"gen\">27 juin 2009<\/a>, d\u00e9taille cette bataille entre deux puissantes personnalit\u00e9s (Robert Gates et Janet Napolitano, qui dirigent respectivement le DoD et le HSD),  pour savoir qui va contr\u00f4ler les unit\u00e9s de la Garde Nationale qui vont \u00eatre d\u00e9ploy\u00e9es sur la fronti\u00e8re, avec tout ce qui accompagne cette prise d&rsquo;autorit\u00e9 d&rsquo;un acte qui devrait marquer le d\u00e9but de l&rsquo;intervention s\u00e9rieuse de l&rsquo;administration Obama dans la crise&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A proposal to send National Guard troops to the U.S.-Mexico border to counter drug trafficking has triggered a bureaucratic standoff between the Pentagon and Department of Homeland Security over the military&rsquo;s role in domestic affairs, according to officials in both departments.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The debate has engaged a pair of powerful personalities, Homeland Security Secretary Janet Napolitano and Defense Secretary Robert M. Gates, in what their subordinates describe as a turf fight over who should direct the use of troops to assist in the fight against Mexican cartels and who should pay for them.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At issue is a proposal to send 1,500 additional troops to the border to analyze intelligence and to provide air support and technical assistance to border agencies. The governors of Texas, Arizona, California and New Mexico made the request in January, drawing support from Napolitano but prompting objections from the Pentagon, where officials argue that it could lead to a permanent, expanded mission for the military.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;affaire est tr\u00e8s complexe, les arguments \u00e9chang\u00e9s le sont \u00e9galement, avec diverses forces engag\u00e9es, notamment les gouverneurs des Etats concern\u00e9s, qui sont plut\u00f4t du c\u00f4t\u00e9 de HSD (Napolitano \u00e9tait elle-m\u00eame gouverneur de l&rsquo;Etat d&rsquo;Arizona avant de prendre HSD en main). Obama observe tout cela avec son large sourire d\u00e9sormais c\u00e9l\u00e8bre o\u00f9 l&rsquo;on ne sait si l&rsquo;on doit lire de la na\u00efvet\u00e9, du fatalisme ou de l&rsquo;habilet\u00e9 manoeuvri\u00e8re,  ou une part de chaque, apr\u00e8s tout. Sa position est assez incertaine, ou bien supr\u00eamement manipulatrice, ou bien encore tr\u00e8s r\u00e9v\u00e9latrice.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A senior White House national security official said the president is comfortable with the disagreement and wants to see the kind of creative tension and full-out debate that major policy decisions engender. The official added, It&rsquo;s the president&rsquo;s view that<\/em> [&#8230;] <em>frankly, that kind of debate among two Cabinet officers like Secretary Gates and Secretary Napolitano, both of whom he holds in high regard, will inevitably lead to a better policy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t&#8230;Peut-\u00eatre, si l&rsquo;on veut, quoiqu&rsquo;on ait du mal \u00e0 distinguer en quoi les affrontements bureaucratiques, au sein du vaste et complexe syst\u00e8me de s\u00e9curit\u00e9 nationale des USA, ait, jusqu&rsquo;\u00e0 ce jour, permis de fournir la meilleure politique,  un meilleur outil pour r\u00e9soudre une situation de crise. L&rsquo;impression serait plut\u00f4t celle du contraire.<\/p>\n<\/p>\n<p><p>\tL\u00e0-dessus, et pour rendre les choses compliqu\u00e9es encore plus incertaines, se greffe la question du r\u00f4le des militaires qui n&rsquo;est jamais tr\u00e8s loin du soup\u00e7on, r\u00e9current depuis 9\/11, qu&rsquo;ils veulent jouer un r\u00f4le int\u00e9rieur aux USA, pour y installer \u00e9ventuellement, pourquoi pas, une sorte de fasciste militariste rampant. (Certains r\u00e9pondront que le fascisme est d\u00e9j\u00e0 l\u00e0, qu&rsquo;il est naturellement militaris\u00e9 comme \u00e0 peu pr\u00e8s tout dans le syst\u00e8me,  reste \u00e0 voir s&rsquo;il peut ramper&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The debate goes to the heart of the military&rsquo;s role, which has expanded since the 2001 terrorist attacks, with an increasing commitment of troops and resources to homeland defense, particularly to help state and local officials respond to a nuclear attack or other domestic catastrophe. The deployment of new troops to the border would represent a mission the military has not traditionally embraced.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What we&rsquo;re seeing here is a move toward reframing where defense begins and ends, said Bert B. Tussing, director of homeland defense and security issues at the U.S. Army War College&rsquo;s Center for Strategic Leadership. Traditionally the military looks outward, but looking outward has begun a lot closer to home, and it may involve looking just across the border.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes d\u00e9bats sont classiques, et \u00e9galement les soup\u00e7ons qui naissent sur d&rsquo;\u00e9ventuelles intentions subversives des militaires, de m\u00eame, depuis quelques mois, que les interrogations sur la v\u00e9ritable position d&rsquo;Obama. Il reste une constante, qu&rsquo;on observe une fois de plus. Lorsqu&rsquo;il est plac\u00e9 devant un probl\u00e8me qui le mobilise d&rsquo;urgence, le syst\u00e8me se mobilise aussit\u00f4t, effectivement, dans une guerre interne entre les diff\u00e9rentes forces bureaucratiques qui le composent, qui trouvent aussit\u00f4t des arguments pour y r\u00e9clamer leur part d&rsquo;autorit\u00e9 et de responsabilit\u00e9, avec les cr\u00e9dits suppl\u00e9mentaires qui vont avec. A cet \u00e9gard, avouons-le tout de m\u00eame, la fronti\u00e8re Sud est l&rsquo;arch\u00e9type de cette sorte d&rsquo;affrontement Ni l&rsquo;ext\u00e9rieur, ni l&rsquo;int\u00e9rieur, mais l&rsquo;ext\u00e9rieur et l&rsquo;int\u00e9rieur \u00e0 la fois; une action qui est absolument celle du banditisme mais qui s&rsquo;exprime par des actions de gu\u00e9rilla, parfois proches de la guerre conventionnelle, \u00e0 la fois sur le territoire int\u00e9rieur des USA et \u00e0 l&rsquo;\u00e9tranger, au Mexique; les affrontements qui ont lieu essentiellement en territoire \u00e9tranger mais dont les effets finaux (trafic de drogue) se font essentiellement sentir aux USA; des relations \u00e0 la fois avec des autorit\u00e9s int\u00e9rieures (les Etats de l&rsquo;Union) et un gouvernement ext\u00e9rieur (le Mexique).<\/p>\n<\/p>\n<p><p>\tLe clan int\u00e9rieur (HDS, avec le soutien et la collaboration du d\u00e9partement de la justice [FBI, Douanes, ATF, etc.]) clame d\u00e9j\u00e0 qu&rsquo;il a remport\u00e9, depuis janvier, des succ\u00e8s remarquables qui militent pour qu&rsquo;il assure le contr\u00f4le de l&rsquo;intervention f\u00e9d\u00e9rale. (\u00ab<em>The official noted that the administration has already taken some steps, sending 450 DHS and Justice Department agents to the border in March to fight cash and weapons smuggling. And, he pointed out, crime in U.S. border communities and border arrests have fallen.<\/em>\u00bb) Ces r\u00e9sultats sont fortement contest\u00e9s par le Pentagone, qui accuse le HDS de trafiquer les statistiques. La crise de le fronti\u00e8re Sud est bien partie pour devenir une de ces batailles intra-bureaucratiques dont le syst\u00e8me a le secret, qui, en g\u00e9n\u00e9ral, rendent beaucoup plus ais\u00e9e la t\u00e2che de leurs adversaires communs.  <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 juin 2009 \u00e0 14H30<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela ne pouvait manquer et cela n&rsquo;a pas manqu\u00e9. Aujourd&rsquo;hui, le Pentagone, ou Department of Defense (DoD) et le minist\u00e8re de la s\u00e9curit\u00e9 int\u00e9rieure, ou Department of Homeland Security (DHS), les militaires d&rsquo;une part, les services de s\u00e9curit\u00e9 int\u00e9rieure d&rsquo;autre part, sont engag\u00e9s dans une lutte s\u00e9v\u00e8re pour savoir qui aura la pr\u00e9pond\u00e9rance, sinon l&rsquo;autorit\u00e9,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2623,4019,5217,3984,8437,2943,8438,3194,3300],"class_list":["post-70869","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bureaucratie","tag-drogue","tag-frontiere","tag-gates","tag-hds","tag-mexique","tag-napolitano","tag-pentagone","tag-sud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70869"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70869\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}