{"id":70875,"date":"2009-07-01T12:56:46","date_gmt":"2009-07-01T12:56:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/07\/01\/enfin-ils-ont-conquis-les-curs-et-les-esprits\/"},"modified":"2009-07-01T12:56:46","modified_gmt":"2009-07-01T12:56:46","slug":"enfin-ils-ont-conquis-les-curs-et-les-esprits","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/07\/01\/enfin-ils-ont-conquis-les-curs-et-les-esprits\/","title":{"rendered":"Enfin, ils ont conquis \u201cles c\u0153urs et les esprits\u201d"},"content":{"rendered":"<p><p>Entamant un texte sur l&rsquo;Iran o\u00f9 il nous dit que les \u00e9v\u00e9nements r\u00e9cents ont humanis\u00e9 l&rsquo;Iran et rendu impossible, par le choc psychologique, toute attaque de sang-froid de ce pays comme l&rsquo;Occident envisage de la faire en g\u00e9n\u00e9ral entre la poire et le fromage de ses diplomates, Jonathan Freedland ne peut s&#8217;emp\u00eacher de commencer son texte en parlant de l&rsquo;Irak o\u00f9 eut lieu effectivement cette attaque de sang-froid. Il faut dire que la circonstance y invite, puisque nous assistons au commencement de quelque chose qu&rsquo;on pourrait nommer, pour faire bref et sans illusions, la lib\u00e9ration de l&rsquo;Irak du joug am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tFreedland publie son texte ce <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2009\/jun\/30\/iran-barack-obama-ahmadinejad\" class=\"gen\">1er juillet 2009<\/a>, dans le <em>Guardian<\/em> bien s\u00fbr.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>So Dick Cheney was right. In the end, the Iraqi people did respond to American soldiers with flowers. The only trouble was, it was their shipping out, not their digging in, that the Iraqi people celebrated. Today, as US forces marked their formal withdrawal from the towns and cities they invaded more than six years ago, the Iraqi people showed the kind of spontaneous joy the former vice-president once imagined would welcome the 173rd Airborne Brigade. There were streamers and balloons, pop concerts in the park and, yes, flowers  garlanding the abandoned checkpoints of the US military in petals.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe d\u00e9part des troupes am\u00e9ricanistes des villes irakiennes est complet,  ou bien il ne l&rsquo;est pas c&rsquo;est selon. La proclamation du jour de la souverainet\u00e9 par le gouvernement Maliki n&#8217;emp\u00eache que cette souverainet\u00e9 reste totalement sous contr\u00f4le US,  ou bien, elle peut mener \u00e0 de sacr\u00e9s r\u00e8glements de compte, c&rsquo;est selon Il y a toutes ces indications dans un texte d&rsquo;<em>Antiwar.com<\/em> du <a href=\"http:\/\/news.antiwar.com\/2009\/06\/29\/maliki-declares-national-sovereignty-day-in-iraq\/\" class=\"gen\">30 juin 2009<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Tens of thousands of Iraqis flooded the streets of the nation&rsquo;s cities today, celebrating the official departure of the US military from the cities. Baghdad officials said the celebrants were cheering because it&rsquo;s the first day that they&rsquo;re going to protect themselves.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb[W]<em>hile the parties started today, the official celebration begins tomorrow, as Prime Minister Nouri al-Maliki has declared June 30 National Sovereignty Day. The national holiday will include a concert sponsored by Maliki.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Iraqis seem eager to celebrate the withdrawal of US troops, though they&rsquo;re only leaving the city limits for bases along the outskirts and may be invited back at any time by the Iraqi military. There also remain serious doubts over the Iraqi government&rsquo;s ability to provide security, though the growing number of attacks in recent days suggest the US forces hadn&rsquo;t been doing a tremendous job in that regard either<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQu&rsquo;importe tout cela, y compris le niveau assez suspect de la vertu du Premier ministre irakien, des forces irakiennes, de la politique int\u00e9rieure irakienne et ainsi de suite. Il reste que cette fastueuse perspective de mars 2003 (le peuple irakien accueillera les forces de lib\u00e9ration US avec un tapis de p\u00e9tales de rose parce que les forces US conquerront par leur vertu les coeurs et les esprits) d\u00e9bouche aujourd&rsquo;hui sur un tapis de p\u00e9tales de roses fan\u00e9es pour saluer le d\u00e9part symbolique des forces US,  vite, le plus vite possible. Tout le monde en a marre de cette guerre, \u00e0 commencer par les \u00e9ditorialistes de l&rsquo;Occident, les salons parisiens et leurs petits fours, les parlementaires US, les analystes <em>neocons<\/em> et ainsi de suite. Nous avons oubli\u00e9 nos fumets d&rsquo;ivresse d&rsquo;il y a six ans et nous ignorons royalement que les premiers \u00e0 en avoir marre, ce sont les Irakiens.<\/p>\n<\/p>\n<p><p>\tQuelle contraste avec notre attention z\u00e9l\u00e9e pour l&rsquo;Iran, notre vertu d\u00e9cha\u00een\u00e9e, notre agitation hyst\u00e9rique dans le bocal ferm\u00e9 \u00e0 double tour, \u00e0 l&rsquo;\u00e9preuve des faits et de la r\u00e9alit\u00e9, de nos valeurs d\u00e9mocratiques et des droits de l&rsquo;homme. Qui se soucie encore du calvaire extraordinaire qui fut impos\u00e9 \u00e0 ce pays, l&rsquo;Irak, au nom de la vanit\u00e9 nihiliste de l&rsquo;Occident et des ambitions de l&rsquo;<em>hubris<\/em> am\u00e9ricaniste? Qui esquisse une seule tentative de comparaison avec notre fureur pour d\u00e9noncer l&rsquo;Iran, nous qui avons fait ce que nous avons fait \u00e0 l&rsquo;Irak sans lever le petit doigt, sans r\u00e9unir le G8 pour envisager des sanctions contre les USA, sans un seul article scandalis\u00e9 de Bernard-Henri L\u00e9vy? Il est vrai que tant d&rsquo;impudence, tant d&rsquo;incons\u00e9quence, se payent par la d\u00e9cadence acc\u00e9l\u00e9r\u00e9e, ou bien, plus encore, elles sont compl\u00e8tement la marque de cette d\u00e9cadence. Le verdict de notre infamie irakienne se trouve dans l&rsquo;effondrement de notre syst\u00e8me commenc\u00e9 le 15 septembre 2008.<\/p>\n<\/p>\n<p><p>\tLe plus remarquable, le plus significatif, est certainement cet aspect nihiliste que nous ne cessons de souligner dans la politique am\u00e9ricaniste et occidentaliste; cet aspect nihiliste, comme une politique qui serait conduite, contrainte, forc\u00e9e par l&rsquo;exercice de la puissance qu&rsquo;on poss\u00e8de, en quelque sorte une politique de la puissance ne r\u00e9pondant qu&rsquo;\u00e0 la seule contrainte de l&rsquo;utilisation de cette puissance. (Le Russe Rogozine avait offert ce n\u00e9ologisme pour d\u00e9finir la politique de l&rsquo;Ouest: <a href=\"http:\/\/www.dedefensa.org\/article-epoque_des_evidences_cachees_contradictoires_et_peut-etre_irresistibles.html\" class=\"gen\">technologisme<\/a>, ce qui revient \u00e0 repr\u00e9senter effectivement une politique inspir\u00e9e, justifi\u00e9e, conduite et faite par la seule puissance, c&rsquo;est-\u00e0-dire effectivement la technologie qui est l&rsquo;application de cette ivresse de puissance, mais qui en est aussi son inspiration enivr\u00e9e.) Malgr\u00e9 toutes les belles d\u00e9monstrations des g\u00e9opoliticiens qui s&#8217;emploient \u00e0 justifier apr\u00e8s coup des aventures lanc\u00e9es on ne sait pourquoi, malgr\u00e9 ceux qui vous parlent du p\u00e9trole, de la d\u00e9mocratie, du capitalisme et de son chaos cr\u00e9ateur, etc., le fait est que le sentiment qui domine finalement cette aventure irakienne est d&rsquo;une bassesse \u00e0 ne pas croire, parce que c&rsquo;est bien la sottise brute,  comme expression d\u00e9mocratique et ultime du nihilisme.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Irak r\u00e9pond compl\u00e8tement \u00e0 la d\u00e9finition des petits comiques de la bureaucratie du Pentagone, en d\u00e9cembre 1989. Cela concernait l&rsquo;une des premi\u00e8res op\u00e9rations du genre, <em>circa<\/em>&#8211;<em>post<\/em>-Guerre froide, avec l&rsquo;investissement du Panama pour capturer un nomm\u00e9 Noriega, inculp\u00e9 dans un trafic de drogue qui impliquait probablement divers noms de la <em>gentry<\/em> am\u00e9ricaniste,  dont le p\u00e8re Bush lui-m\u00eame, chuchotait-on&#8230; Pour cela, une \u00e9norme op\u00e9ration militaire fut mont\u00e9e, et le nom de code de l&rsquo;op\u00e9ration fut r\u00e9v\u00e9l\u00e9e: <em>Just Cause<\/em>. Les petits comiques du Pentagone s&#8217;empress\u00e8rent de rebaptiser la chose: <em>Just Because<\/em>. Bien vu.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er juillet 2009 \u00e0 12H59<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entamant un texte sur l&rsquo;Iran o\u00f9 il nous dit que les \u00e9v\u00e9nements r\u00e9cents ont humanis\u00e9 l&rsquo;Iran et rendu impossible, par le choc psychologique, toute attaque de sang-froid de ce pays comme l&rsquo;Occident envisage de la faire en g\u00e9n\u00e9ral entre la poire et le fromage de ses diplomates, Jonathan Freedland ne peut s&#8217;emp\u00eacher de commencer son&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7079,1382,857,2773,7078,6663,7825,2779,5969],"class_list":["post-70875","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-because","tag-freedland","tag-irak","tag-iran","tag-just","tag-liberation","tag-nihiliste","tag-puissance","tag-vanite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70875"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70875\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}