{"id":70886,"date":"2009-07-06T06:08:17","date_gmt":"2009-07-06T06:08:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/07\/06\/bho-slalome\/"},"modified":"2009-07-06T06:08:17","modified_gmt":"2009-07-06T06:08:17","slug":"bho-slalome","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/07\/06\/bho-slalome\/","title":{"rendered":"BHO \u201cslalome\u201d"},"content":{"rendered":"<p><p>Parmi les derni\u00e8res nouvelles avant le sommet de Moscou: Barack Obama a nuanc\u00e9 \u00e0 grande vitesse, sinon en catastrophe, ce que ses initiatives ou discours pr\u00e9c\u00e9dents pouvaient avoir d&rsquo;\u00e9ventuellement d\u00e9sobligeant pour ses h\u00f4tes du jour, et \u00e9ventuellement pour sa propre fortune. (La presse russe avait mal pris <a href=\"http:\/\/www.dedefensa.org\/article-de_la_vieille_pensee_a_la_nouvelle_pensee_et_retour_04_07_2009.html\" class=\"gen\">l&rsquo;opposition<\/a> Medvedev-Poutine, \u00e9mettant l&rsquo;hypoth\u00e8se que BHO voulait s\u00e9parer les deux hommes.)<\/p>\n<\/p>\n<p><p>\tDans une interview donn\u00e9e samedi \u00e0 la cha\u00eene de t\u00e9l\u00e9vision <em>Vesti<\/em>, BHO s&rsquo;est fait le dithyrambe des relations russo-am\u00e9ricaines, de la Russie, de sa culture mill\u00e9naire, de ses dirigeants magnifiques,  autant l&rsquo;un (Medvedev) que l&rsquo;autre (Poutine), et chacun avec les deux pieds, on vous l&rsquo;assure. Mieux que tout, enfin, BHO proclame que la Russie est l&rsquo;\u00e9gale de l&rsquo;Am\u00e9rique et que c&rsquo;est sur cette base que l&rsquo;on entend bien <em>to reset the button<\/em> de l&rsquo;entente et de la d\u00e9tente.<\/p>\n<\/p>\n<p><p>\tQuelques extraits, selon une d\u00e9p\u00eache AFP retransmise le <a href=\"http:\/\/rawstory.com\/news\/afp\/US_Russia_are_equals_Obama_07042009.html\" class=\"gen\">4 juillet 2009<\/a> par <em>RAW Story<\/em>. (La d\u00e9p\u00eache signale que les remarques d&rsquo;Obama sont traduites du russe, puisqu&rsquo;elles ont \u00e9t\u00e9 elles-m\u00eames traduites en voix <em>off<\/em> pour les t\u00e9l\u00e9spectateurs russes. Lorsque la d\u00e9p\u00eache fut r\u00e9dig\u00e9e, aucun texte officiel de l&rsquo;interview, en anglais certes, n&rsquo;avait \u00e9t\u00e9 diffus\u00e9 par la Maison-Blanche. Manifestement, l&rsquo;important \u00e9tait que les Russes entendissent le message,  pour les Am\u00e9ricains, c&rsquo;est moins press\u00e9.)<\/p>\n<\/p>\n<p><p>\t Il y a eu bien des incons\u00e9quences dans les relations entre les USA et la Russie sous le gouvernement de son pr\u00e9d\u00e9cesseur, et cela doit changer (\u00ab<em>America respects Russia, we want to build relations where we deal as equals<\/em>\u00bb). La raison de cette n\u00e9cessit\u00e9 du changement est simplement que la Russie est un pays exceptionnel dont on ne peut \u00e9videmment se passer (\u00ab<em>Describing Russia as a great country with extraordinary culture and traditions, he said it remains one of the most powerful countries in the world and is a major guarantor of international stability and prosperity.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t Pour les deux dirigeants russes, il y a d\u00e9sormais \u00e9galit\u00e9 dans la grandeur et la vertu, chacun avec ses particularit\u00e9s tr\u00e8s humaines et extr\u00eamement politiques. \u00ab<em>Obama is due to meet both President Dmitry Medvedev and Prime Minister Vladimir Putin, which would allow him to better understand the concerns and politics of both men. He said he hoped both leaders would reach the conclusion that they can work with me in an effective manner. Labelling Medvedev a thoughtful, forward-looking individual who is doing a fine job of leading Russia into the 21st century, Obama added that Putin has been a very strong leader for the Russian people.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout se passe un peu comme si nous nous trouvions dans les bureaux du service de communication du pr\u00e9sident. Nul ne songera \u00e0 accuser ce service de manquer de souplesse, et le pr\u00e9sident de s&rsquo;y adapter avec un incontestable brio. La fable Medvedev <em>versus<\/em> Poutine ayant fait mauvais effet, il y eut aussit\u00f4t un exercice d&rsquo;urgence en <em>damage control<\/em>, avec convocation expresse de <em>Vesti<\/em> pour une interview impromptue, le Kremlin bic\u00e9phale avis\u00e9 de la chose et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tNous avons l\u00e0 un signe non n\u00e9gligeable de la confirmation d&rsquo;une volont\u00e9, du c\u00f4t\u00e9 US (Obama), de faire de ce sommet une occasion importante pour mettre en place une politique nouvelle qui permette de d\u00e9bloquer divers dossiers. Il y a plusieurs mois qu&rsquo;existe cette impression, mais certains signes r\u00e9cents ont conduit \u00e0 une plus grande circonspection. Cette derni\u00e8re initiative d&rsquo;Obama conduit \u00e0 penser qu&rsquo;effectivement le sommet qui s&rsquo;ouvre aujourd&rsquo;hui \u00e0 Moscou est tr\u00e8s ouvert et tr\u00e8s difficile \u00e0 pr\u00e9voir dans les effets qu&rsquo;il suscitera; il l&rsquo;est d&rsquo;autant plus que les manuvres au niveau de la communication sont intenses et contribuent \u00e0 fortement brouiller la perception de la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>\tNous avons \u00e9galement, avec cette p\u00e9rip\u00e9tie suivant la pr\u00e9c\u00e9dente qui montrait un certain durcissement US, le signe d&rsquo;une certaine confusion du c\u00f4t\u00e9 US, et, notamment, du c\u00f4t\u00e9 d&rsquo;Obama, ce qui est assez inhabituel. L&rsquo;explication peut \u00eatre effectivement la plus simple,  la maladresse,  mais elle ne serait en tout \u00e9tat de cause que circonstancielle. Nous ne serions pas fix\u00e9s pour autant puisqu&rsquo;il reste \u00e0 d\u00e9terminer o\u00f9 se trouve la position r\u00e9elle d&rsquo;Obama. L&rsquo;explication peut \u00e9galement \u00eatre celle de certains affrontements au sein de l&rsquo;\u00e9quipe d&rsquo;Obama, ou\/et de pressions washingtoniennes ext\u00e9rieures \u00e0 l&rsquo;administration (\u00e9ventuellement dans le sens de para\u00eetre durcir l&rsquo;attitude US vis-\u00e0-vis de Moscou). Il appara\u00eet finalement que ce sommet Russie-USA s\u00e8me plus de trouble du c\u00f4t\u00e9 US que du c\u00f4t\u00e9 russe, malgr\u00e9, ou \u00e0 cause de l&rsquo;\u00e9pisode de l&rsquo;appr\u00e9ciation contradictoire de Medvedev-Poutine par BHO.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 juillet 2009 \u00e0 06H04<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les derni\u00e8res nouvelles avant le sommet de Moscou: Barack Obama a nuanc\u00e9 \u00e0 grande vitesse, sinon en catastrophe, ce que ses initiatives ou discours pr\u00e9c\u00e9dents pouvaient avoir d&rsquo;\u00e9ventuellement d\u00e9sobligeant pour ses h\u00f4tes du jour, et \u00e9ventuellement pour sa propre fortune. (La presse russe avait mal pris l&rsquo;opposition Medvedev-Poutine, \u00e9mettant l&rsquo;hypoth\u00e8se que BHO voulait s\u00e9parer&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8002,5270,2858,2707,6208,916,3045,8449],"class_list":["post-70886","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bho","tag-interview","tag-medvedev","tag-moscou","tag-obama","tag-poutine","tag-sommet","tag-vesti"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70886"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70886\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}