{"id":70958,"date":"2009-08-04T06:39:22","date_gmt":"2009-08-04T06:39:22","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/04\/lautre-face-de-lamerique-dite-postraciale\/"},"modified":"2009-08-04T06:39:22","modified_gmt":"2009-08-04T06:39:22","slug":"lautre-face-de-lamerique-dite-postraciale","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/04\/lautre-face-de-lamerique-dite-postraciale\/","title":{"rendered":"L&rsquo;autre face de l&rsquo;Am\u00e9rique dite-\u201cpostraciale\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;autre face de l&rsquo;Am\u00e9rique dite-\u00ab\u00a0postraciale\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Alors que l&rsquo;affaire BHO\/Gates a mis en \u00e9vidence des r\u00e9actions violentes des Anglo-Am\u00e9ricains (WASP) aux USA, comme on l&rsquo;a vu le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_amerique_postraciale_de_bho_ce_pourrait_bien_etre_le_contraire_03_08_2009.html\">3 ao&ucirc;t 2009<\/a>, un autre aspect de la situation de l&rsquo;Am\u00e9rique dite \u00ab\u00a0postraciale\u00a0\u00bb est signal\u00e9 par un texte de Chris Hedges, sur <em>Truthdig.com<\/em>, le m\u00eame <a class=\"gen\" href=\"http:\/\/www.truthdig.com\/report\/print\/20090803_hedges_the_new_racism\/\">3 ao&ucirc;t 2009<\/a>.<\/p>\n<\/p>\n<p><p>Le texte est essentiellement bas\u00e9 sur l&rsquo;argumentation d&rsquo;un candidat, Africain-Am\u00e9ricain, du parti \u00ab\u00a0vert\u00a0\u00bb US (<em>Green Party<\/em>), LeAlan Jones, candidat pour le si\u00e8ge de s\u00e9nateur de l&rsquo;Illinois qu&rsquo;occupait le pr\u00e9sident Barack Obama. Le th\u00e8me abord\u00e9 est exactement l&rsquo;antith\u00e8se du sujet abord\u00e9 pr\u00e9c\u00e9demment puisqu&rsquo;il concerne le malaise de la communaut\u00e9 africaine-am\u00e9ricaine, que LeAlan Jones consid\u00e8re comme trahie par ses \u00e9lites qui sont entr\u00e9es dans le syst\u00e8me et jouent un r\u00f4le de repr\u00e9sentation d&rsquo;une \u00ab\u00a0Am\u00e9rique postraciale\u00a0\u00bb int\u00e9gr\u00e9e, sans le moindre rapport avec la r\u00e9alit\u00e9. Il s&rsquo;agit d&rsquo;un cas typique de la soci\u00e9t\u00e9 de la communication, avec sa capacit\u00e9 de repr\u00e9sentation virtualiste de la r\u00e9alit\u00e9. La chose permet \u00e0 un pr\u00e9sident africain-am\u00e9ricain d&rsquo;\u00eatre \u00e9lu et \u00e0 <em>Lib\u00e9ration<\/em> de faire de beaux \u00e9ditoriaux, mais ne semble pas pour autant r\u00e9soudre la question raciale aux USA, cette fois du point de vue africain-am\u00e9ricain.<\/p>\n<\/p>\n<p><p>Extraits du texte de Hedges:<\/p>\n<\/p>\n<p><p>&laquo;<em>LeAlan Jones, the 30-year-old Green Party candidate for Barack Obama&rsquo;s old Senate seat in Illinois, is as angry at injustice as he is at the African-American intellectual and political class that accommodates it. He does not buy Obama&rsquo;s \u00ab\u00a0post-racial\u00a0\u00bb ideology or have much patience with African-American leaders who, hungry for prestige, power and money, have, in his eyes, forgotten the people they are supposed to represent. They have confused a personal ability to be heard and earn a comfortable living with justice.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0The selflessness of leaders like Malcolm X, Dr. Martin Luther King, Harold Washington and Medgar Evers has produced selfishness within the elite African-American leadership,\u00a0\u00bb Jones told me by phone from Chicago.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0This is the only thing I can do to have peace of mind,\u00a0\u00bb he said when I asked him why he was running for office. \u00ab\u00a0I am looking at a community that is suffering because of a lack of genuine concern from their leaders. This isn&rsquo;t about a contract. This isn&rsquo;t about a grant. This isn&rsquo;t about who gets to stand behind the political elite at a press conference. This is about who is going to stand behind the people. What these leaders talk about and what needs to happen in the community is disjointed.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Jones began his career as a boy making radio documentaries about life in Chicago&rsquo;s public housing projects on the South Side, including the acclaimed \u00ab\u00a0Ghetto Life 101.\u00a0\u00bb He knows the world of which he speaks. He lives in the troubled Chicago neighborhood of Englewood, where he works as a freelance journalist and a high school football coach. He is the legal guardian of a 16-year-old nephew. And he often echoes the denunciations of black leaders by the historian Houston A. Baker Jr., who wrote \u00ab\u00a0Betrayal: How Black Intellectuals Have Abandoned the Ideals of the Civil Rights Era.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Baker excoriates leading public intellectuals including Michael Eric Dyson, Henry Louis Gates Jr., Shelby Steele, Yale law professor Stephen Carter and Manhattan Institute fellow John McWhorter, saying they pander to the powerful. He argues they have lost touch with the reality of most African-Americans. Professor Gates&rsquo; statement after his July 16 arrest that \u00ab\u00a0what it made me realize was how vulnerable all black men are, how vulnerable are all poor people to capricious forces like a rogue policemen\u00a0\u00bb was a stunning example of how distant from black reality many successful African-American figures like Gates have become. These elite African-American figures, Baker argues, long ago placed personal gain and career advancement over the interests of the black majority. They espouse positions that are palatable to a white audience, positions which ignore the radicalism and structural critiques of inequality by W.E.B. Du Bois, Martin Luther King Jr. and Malcolm X. And in a time when, as the poet Yusef Komunyakaa has said, \u00ab\u00a0the cell block has replaced the auction block,\u00a0\u00bb they do not express the rage, frustration and despair of the black underclass.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>En 2002, apr\u00e8s que le g\u00e9n\u00e9ral Colin Powell e&ucirc;t \u00e9t\u00e9 nomm\u00e9 secr\u00e9taire d&rsquo;Etat de l&rsquo;administration GW Bush, alors que Condi Rice devenait la conseill\u00e8re de s\u00e9curit\u00e9 nationale du pr\u00e9sident GW Bush et que tout le monde c\u00e9l\u00e9brait cette pr\u00e9sence des Africains-Am\u00e9ricains dans la direction des affaires, le chanteur <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-contestation_usa_17_10_2002.html\">Harry Belafonte<\/a> avait eu quelques mots furieux (notamment contre Powell), contre ces Noirs qui jouent le r\u00f4le de \u00ab\u00a0<em>house slaves<\/em>\u00ab\u00a0, &ndash; c&rsquo;est-\u00e0-dire, selon la langage des temps esclavagistes, celui de \u00ab\u00a0collaborateurs\u00a0\u00bb, de <em>Kapos<\/em> des Blancs. L&rsquo;image est d\u00e9pass\u00e9e, la situation pas. La question qui se pose est de savoir si le probl\u00e8me est celui du racisme ou celui du syst\u00e8me.<\/p>\n<\/p>\n<p><p>Il est vrai qu&rsquo;il existe dans le syst\u00e8me des structures fondamentales qui favorisent une \u00e9lite au service de ce syst\u00e8me, contre le reste, dont le r\u00f4le et de contr\u00f4ler le reste en lui donnant l&rsquo;illusion de figurer \u00e0 sa place dans le syst\u00e8me. Aujourd&rsquo;hui, c&rsquo;est la communication qui est le moyen essentiel de contr\u00f4le, beaucoup plus que les moyens de coercition brutaux des temps d\u00e9pass\u00e9s. Il n&#8217;emp\u00eache que certains de ces moyens de coercition demeurent actifs, derri\u00e8re l&rsquo;apparence de la loi, notamment le syst\u00e8me policier-carc\u00e9ral, extr\u00eamement actif et brutal aux USA. Comme le dit Hedges, l&rsquo;aventure survenue au professeur Gates est une soudaine incursion de ce syst\u00e8me dans la vie dor\u00e9e et privil\u00e9gi\u00e9 d&rsquo;un membre de l&rsquo;\u00e9lite africaine-am\u00e9ricaine parfaitement int\u00e9gr\u00e9 au syst\u00e8me (&laquo;<em>Professor Gates&rsquo; statement after his July 16 arrest that \u00ab\u00a0what it made me realize was how vulnerable all black men are, how vulnerable are all poor people to capricious forces like a rogue policemen\u00a0\u00bb was a stunning example of how distant from black reality many successful African-American figures like Gates have become.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Il est vrai, il est \u00e9vident \u00e9galement que ces \u00e9lites africaines-am\u00e9ricaines ont compl\u00e8tement trahi l&rsquo;esprit fondamental des dirigeants noirs (ainsi \u00e9taient-ils d\u00e9sign\u00e9s alors, quand la communication n&rsquo;avait pas accouch\u00e9 de ces \u00e9tiquettes-miracle qui font passer les pilules am\u00e8res, comme l&rsquo;expression \u00ab\u00a0Africain-Am\u00e9ricain\u00a0\u00bb), du temps de la lutte pour les droits civiques des ann\u00e9es 1960; il s&rsquo;agit aussi bien de dirigeants comme Malcolm X, bien s&ucirc;r, que comme Martin Luther King sur la fin de sa vie, lorsque son action s&rsquo;\u00e9tait durcie devant l&rsquo;\u00e9vidente tromperie que constituait la proposition d&rsquo;int\u00e9gration du syst\u00e8me, qui porte effectivement sur des \u00e9lites privil\u00e9gi\u00e9es, avec mission de repr\u00e9sentation d&rsquo;une fiction de l&rsquo;int\u00e9gration r\u00e9alis\u00e9e.<\/p>\n<\/p>\n<p><p>Ainsi existe-t-il toujours un \u00ab\u00a0probl\u00e8me racial\u00a0\u00bb aux USA, d&rsquo;autant plus grave qu&rsquo;il est dissimul\u00e9, d&rsquo;autant plus complexe qu&rsquo;il d\u00e9pend moins d&rsquo;un sentiment raciste que de l&rsquo;institutionnalisation syst\u00e9mique d&rsquo;une fiction de la r\u00e9solution de la question raciale. (En ce sens, l&rsquo;expression \u00ab\u00a0probl\u00e8me racial\u00a0\u00bb est aussi une tromperie commode, car nombre de <em>Latinos<\/em> aussi bien que les \u00ab\u00a0petits Blancs\u00a0\u00bb, en nombre grandissant avec la crise, sont des victimes du syst\u00e8me, d&rsquo;une fa\u00e7on similaire.) Cela pose dans tous les cas les vraies questions, \u00e0 savoir les questions sur les responsabilit\u00e9s. Le syst\u00e8me n&rsquo;est pas \u00ab\u00a0raciste\u00a0\u00bb <em>per se<\/em>, m\u00eame s&rsquo;il l&rsquo;est dans des comportements sociaux. Il est d&rsquo;abord d\u00e9structurant, c&rsquo;est-\u00e0-dire qu&rsquo;il travaille \u00e0 d\u00e9truire <strong>toutes<\/strong> les identit\u00e9s (ce pourquoi, m\u00eame les Anglo-Am\u00e9ricains se sentent aujourd&rsquo;hui menac\u00e9s). Un pr\u00e9sident africain-am\u00e9ricain ne signifie pas que la \u00ab\u00a0race noire\u00a0\u00bb aux USA (langage trivial, absolument rejet\u00e9), ou \u00ab\u00a0la communaut\u00e9 africaine-am\u00e9ricaine\u00a0\u00bb (\u00e9tiquette convenue, selon la communication du syst\u00e8me) est int\u00e9gr\u00e9e en tant que telle, avec son identit\u00e9, mais simplement que la trahison des \u00e9lites africaines-am\u00e9ricaines est consomm\u00e9e jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un probl\u00e8me historique. Par divers \u00e9v\u00e9nements, notamment la Guerre de S\u00e9cession telle qu&rsquo;elle fut transform\u00e9e dans ses motifs fondamentaux par Lincoln en cours de conflit, le syst\u00e8me a toujours travaill\u00e9 \u00e0 morceler et \u00e0 opposer les communaut\u00e9s pour emp\u00eacher une opposition efficace, d&rsquo;ailleurs en aggravant les probl\u00e8mes. (Un historien comme William Pfaff a \u00e9mis l&rsquo;hypoth\u00e8se que si la Guerre de S\u00e9cession avait effectivement vu le triomphe du Sud et la division des USA, le \u00ab\u00a0probl\u00e8me noir\u00a0\u00bb (l&rsquo;esclavage) dans le Sud aurait \u00e9t\u00e9 r\u00e9solu d&rsquo;une fa\u00e7on beaucoup plus naturelle et beaucoup plus satisfaisante, par la simple \u00e9volution \u00e9conomique et sociale, au lieu de provoquer un antagonisme renouvel\u00e9 entre les Blancs et les Noirs dans le Sud, apr\u00e8s l&rsquo;\u00e9mancipation des seconds assimil\u00e9e \u00e0 la victoire nordiste.) L&rsquo;opposition, selon l&rsquo;id\u00e9e \u00ab\u00a0raciste\u00a0\u00bb, des Noirs et des \u00ab\u00a0petits Blancs\u00a0\u00bb emp\u00eache la formation d&rsquo;une opposition coh\u00e9rente au c&oelig;ur du syst\u00e8me.<\/p>\n<\/p>\n<p><p>La situation actuelle rencontre les voeux des id\u00e9ologues du syst\u00e8me, les partisans de la soci\u00e9t\u00e9 multiculturelle et antiraciste, qui se satisfont \u00e9videmment de la repr\u00e9sentation permanente des \u00e9lites, avec sa rassurante diversit\u00e9 de couleurs de peau. Il s&rsquo;agit bien d&rsquo;une repr\u00e9sentation, au sens th\u00e9\u00e2trale du terme, ou d&rsquo;une virtualisation. La r\u00e9alit\u00e9, elle, est celle d&rsquo;une offensive constante de d\u00e9structuration des identit\u00e9s, et le processus de d\u00e9structuration ne porte gu\u00e8re d&rsquo;int\u00e9r\u00eat aux questions raciales puisque son attaque est psychologique et culturelle, sans aucune distinction. Le texte de Hedges et l&rsquo;intervention de LeAlan Jones mettent bien en \u00e9vidence combien l&rsquo;Am\u00e9rique \u00ab\u00a0postraciale\u00a0\u00bb, avec les applaudissements des salons, constitue un montage de plus. Le pr\u00e9sident BHO n&rsquo;en a pas fini avec cette affaire.<\/p>\n<\/p>\n<p><p>Il est \u00e0 noter que ce probl\u00e8me du multiculturalisme et de la soci\u00e9t\u00e9 \u00ab\u00a0postraciale\u00a0\u00bb se pose tr\u00e8s diff\u00e9remment en Europe, o&ugrave; n&rsquo;existe pas une \u00ab\u00a0communautarisation\u00a0\u00bb du probl\u00e8me, avec des \u00e9lites sp\u00e9cifiques des communaut\u00e9s. Le syst\u00e8me \u00ab\u00a0communautariste\u00a0\u00bb aux USA, possible \u00e0 cause de l&rsquo;inexistence de la dimension r\u00e9galienne du pays, permet aujourd&rsquo;hui ce r\u00f4le de repr\u00e9sentation et d&rsquo;int\u00e9gration des \u00e9lites dans le syst\u00e8me. Certains verraient cela comme un avantage (?) sur l&rsquo;Europe. Mais lorsqu&rsquo;on d\u00e9couvre l&rsquo;envers de la question, comme on le fait ici, on peut se demander si cet avantage en est vraiment un. Aux USA, le \u00ab\u00a0probl\u00e8me racial\u00a0\u00bb est occult\u00e9 par la repr\u00e9sentation institutionnalis\u00e9e des \u00e9lites dans le syst\u00e8me, mais il est infiniment plus profond qu&rsquo;en Europe o&ugrave; cette occultation n&rsquo;existe pas.<\/p>\n<\/p>\n<p><p>Mis en ligne le 4 ao&ucirc;t 2009 \u00e0 06H37<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;autre face de l&rsquo;Am\u00e9rique dite-\u00ab\u00a0postraciale\u00a0\u00bb Alors que l&rsquo;affaire BHO\/Gates a mis en \u00e9vidence des r\u00e9actions violentes des Anglo-Am\u00e9ricains (WASP) aux USA, comme on l&rsquo;a vu le 3 ao&ucirc;t 2009, un autre aspect de la situation de l&rsquo;Am\u00e9rique dite \u00ab\u00a0postraciale\u00a0\u00bb est signal\u00e9 par un texte de Chris Hedges, sur Truthdig.com, le m\u00eame 3 ao&ucirc;t 2009. Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3654,583,8524,8525,8520,3424,2949,3014],"class_list":["post-70958","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-belafonte","tag-jones","tag-lealan","tag-multiculturel","tag-postraciale","tag-racisme","tag-secession","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70958"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70958\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}