{"id":70962,"date":"2009-08-05T08:48:02","date_gmt":"2009-08-05T08:48:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/05\/le-mensonge-en-justice-ou-les-limites-du-systeme\/"},"modified":"2009-08-05T08:48:02","modified_gmt":"2009-08-05T08:48:02","slug":"le-mensonge-en-justice-ou-les-limites-du-systeme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/05\/le-mensonge-en-justice-ou-les-limites-du-systeme\/","title":{"rendered":"Le mensonge en justice, \u2013 ou les limites du syst\u00e8me?"},"content":{"rendered":"<p><p>C&rsquo;est un proc\u00e8s d&rsquo;un int\u00e9r\u00eat \u00e9vident qui s&rsquo;ouvre \u00e0 Londres aujourd&rsquo;hui, dont les d\u00e9tails sont notamment r\u00e9percut\u00e9es par <em>The Independent<\/em> ce <a href=\"http:\/\/www.independent.co.uk\/news\/uk\/home-news\/lying-about-iraq-made-me-quit-press-officer-claims-1767353.html\" class=\"gen\">5 ao\u00fbt 2009<\/a>, et par <em>The Guardian<\/em>, le <a href=\"http:\/\/www.guardian.co.uk\/uk\/2009\/aug\/04\/mod-british-soldiers-iraq-afghanistan\" class=\"gen\">4 ao\u00fbt 2009<\/a>.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un officier de relations publiques de l&rsquo;arm\u00e9e britannique, John Salisbury-Baker, \u00e2g\u00e9 de 62 ans, engag\u00e9 comme charg\u00e9 de relations publiques en 1996, puis pass\u00e9 au statut militaire. Son r\u00f4le consistait essentiellement \u00e0 prendre contact avec les familles de militaires tu\u00e9s en Irak, pour les informer de la nouvelle, et les soutenir. Souvent, il les accompagnait tr\u00e8s avant dans leurs deuils, participant aux fun\u00e9railles et multipliant les visites.<\/p>\n<\/p>\n<p><p>\tSalisbury-Baker \u00e9tait conduit \u00e0 pr\u00e9senter les conditions de la mort des soldats selon la version officielle, dont il savait la fausset\u00e9, notamment pour ce qui concernait l&rsquo;\u00e9quipement de ces soldats (il y a un grand courant de contestation au Royaume-Uni actuellement, \u00e0 propos de l&rsquo;\u00e9quipement inad\u00e9quat des forces britanniques, dans ce cas en Afghanistan). Kim Sengupta, le correspondant pour les questions de d\u00e9fense de <em>The Independent<\/em>, pr\u00e9sente le cas sans s&rsquo;encombrer d&rsquo;inutiles figures de rh\u00e9torique.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Having to peddle government lies about the safety of soldiers in Iraq led to a Ministry of Defence press officer suffering post-traumatic stress disorder, an employment tribunal will hear. John Salisbury-Baker will claim that he suffered intolerable stress through having to defend the morally indefensible when responding to media inquiries about the ability of army vehicles such as the Snatch Land Rover to protect soldiers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Salisbury-Baker, 62, says he found it impossible to support the official line on deaths and injuries after seeing the suffering of soldiers&rsquo; families. After 11 years of service at Imphal Barracks near York, he could no longer keep working and is taking legal action against the Ministry of Defence (MoD).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <em>Guardian<\/em> rapporte l&rsquo;\u00e9volution de l&rsquo;\u00e9tat psychologique de cet officier de relations publiques \u00e0 mesure qu&rsquo;il a du poursuivre cette mission, notamment au travers du t\u00e9moignage de son avocat et de son amie (le plaignant \u00e9tant requis au silence par la proc\u00e9dure qu&rsquo;il a engag\u00e9e).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Salisbury-Baker&rsquo;s solicitor, David Gordon, said : I think what John would say is, I was put under an inordinate amount of strain without any backup or training. As things have gone on I have realised that what I was being told was not true, and it appears that that was known at a level above for some time.&rsquo; We are looking at the gradual erosion of someone&rsquo;s mental state.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Having signed the Official Secrets Act,<\/em> [Salisbury-Baker] <em>declined to comment , but speaking on his behalf, his partner Christine Brooke said: John is a father, and going along and seeing the fathers of youngsters who had been killed, obviously he could empathise with that. It took a lot out of him. He was going back again and again where yet another funeral was held, and he found that very difficult to cope with.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In addition, she said, he felt he was being frugal with the truth. John was reading the papers<\/em> [<em>about equipment<\/em>], <em>then he might have to go to a family and support them, and he felt that he knew that maybe their son or daughter hadn&rsquo;t been equipped properly. That caused a problem for him. She described the insistence that the equipment was sound as government lies, adding that he had been forced to defend the morally indefensible.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSalisbury-Baker a \u00e9t\u00e9 mis sur une voie de garage au sein de l&rsquo;arm\u00e9e, apr\u00e8s qu&rsquo;il ait manifest\u00e9 les difficult\u00e9s qu&rsquo;il rencontrait, notamment au du point de vue de sa sant\u00e9 psychologique elle-m\u00eame. Il recherche simplement \u00e0 \u00eatre r\u00e9tabli dans ses droits. \u00ab[David Gordon] <em>said that Salisbury-Baker, who is still employed by the MoD on reduced pay but has barely worked for over a year, was seeking only the pension to which he believes he would have been entitled. He wants to leave the service honourably, retire on the package which he was promised and go into private life. He has seen people in the extremes of bereavement  this is not something that he&rsquo;s going to claim<\/em> [<em>large<\/em>] <em>damages over. It&rsquo;s not a question of damages as such.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe cas Salisbury-Baker n&rsquo;a rien de r\u00e9volutionnaire, selon les buts que cherche \u00e0 atteindre l&rsquo;officier de presse. Il n&rsquo;y a nulle mise en cause du syst\u00e8me, et les euph\u00e9mismes eux-m\u00eames sont d&rsquo;une extr\u00eame mod\u00e9ration, typiquement britannique (le <em>frugal with the truth<\/em>, notamment). Salisbury-Baker ne cherche qu&rsquo;\u00e0 faire reconna\u00eetre ses droits apr\u00e8s un traitement qu&rsquo;il juge injuste, suivant une mission dont il juge qu&rsquo;elle fut entach\u00e9e de conditions extr\u00eamement critiquables.<\/p>\n<\/p>\n<p><p>\tPas de quoi fouetter un chat, par cons\u00e9quent, sauf que, justement, au travers de la simplicit\u00e9 du cas et de la modestie de son acteur, c&rsquo;est, mise \u00e0 nu d&rsquo;une fa\u00e7on ainsi plus remarquable, toute la politique et le comportement des autorit\u00e9s officielles qui sont mis en lumi\u00e8re. La chose est importante parce que le cas Salisbury-Baker, bien qu&rsquo;anodin, s&rsquo;ins\u00e8re absolument dans un syst\u00e8me g\u00e9n\u00e9ral de mensonges syst\u00e9matiques qui est l&rsquo;un des fondements du syst\u00e8me du virtualisme caract\u00e9risant les politiques occidentalistes, particuli\u00e8rement anglo-saxonnes, aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat, dans ce cas, est bien d&rsquo;observer, d&rsquo;une part la pression psychologique exerc\u00e9e sur ceux qui sont conduit \u00e0 pr\u00e9senter cette politique au public (et quel public: les familles des victimes) en sachant qu&rsquo;elle est bas\u00e9e sur des mensonges, d&rsquo;autre part l&rsquo;improvisation dans laquelle cette politique g\u00e9n\u00e9rale est conduite (Salisbury-Baker a \u00e9t\u00e9 laiss\u00e9 \u00e0 lui-m\u00eame, aliment\u00e9 par des informations que tout le monde savait fausses, alors qu&rsquo;il \u00e9tait devenu av\u00e9r\u00e9 que cette mission, dans de telles conditions, mettait en p\u00e9ril son  \u00e9quilibre psychologique et pouvait constituer un probl\u00e8me pour la bonne marche de l&rsquo;op\u00e9ration constante de camouflage des r\u00e9alit\u00e9s irakiennes).<\/p>\n<\/p>\n<p><p>\tA l&rsquo;observation que le cas Salisbury-Baker est exceptionnel parce que c&rsquo;est la premi\u00e8re fois \u00e0 notre sens qu&rsquo;une action en justice est intent\u00e9e <em>de facto<\/em> contre cette politique de mensonges, ainsi indirectement mise en accusation, on r\u00e9pondra qu&rsquo;il ne l&rsquo;est pas parce qu&rsquo;il est anodin. Les deux qualificatifs sont antinomiques. Salisbury-Baker ne cherche nulle publicit\u00e9, nulle somme d&rsquo;argent excessive, mais simplement le r\u00e9tablissement de ses droits. Le cas Salisbury-Baker est int\u00e9ressant parce que c&rsquo;est un cas anodin qui n&rsquo;est pas exceptionnel mais qui est pouss\u00e9 jusqu&rsquo;\u00e0 la situation exceptionnelle d&rsquo;une action en justice sans exemple. Cela laisse \u00e0 penser le nombre de cas de cette sorte qui doivent exister, dans lesquels les personnes concern\u00e9es n&rsquo;osent aller jusqu&rsquo;\u00e0 l&rsquo;extr\u00e9mit\u00e9 d&rsquo;une action en justice contre le minist\u00e8re de la d\u00e9fense.<\/p>\n<\/p>\n<p><p>\tOn d\u00e9couvre ici la faiblesse inh\u00e9rente de la politique du virtualisme, c&rsquo;est-\u00e0-dire du mensonge syst\u00e9matique qui caract\u00e9rise les politiques occidentales dans leurs applications. Si, \u00e0 notre sens, le virtualisme induit la croyance g\u00e9n\u00e9rale des th\u00e8ses et des situations g\u00e9n\u00e9rales qu&rsquo;elle expose par ceux qui l&rsquo;\u00e9laborent (le fameux ph\u00e9nom\u00e8ne qui la distingue de la propagande), au contraire dans son application la plus quotidienne, confront\u00e9 aux faits, on finit effectivement par utiliser un mensonge grossier dont est soi-m\u00eame le medium conscient, un mensonge en g\u00e9n\u00e9ral \u00e9hont\u00e9 parce qu&rsquo;on n&rsquo;a rien fait auparavant pour le dissimuler selon l&rsquo;id\u00e9e g\u00e9n\u00e9rale que le virtualisme n&rsquo;est pas bas\u00e9 sur le mensonge. De m\u00eame, on ne re\u00e7oit aucune aide, justement parce qu&rsquo;on remontant la hi\u00e9rarchie l&rsquo;id\u00e9e m\u00eame d&rsquo;un mensonge se dilue dans la croyance virtualiste; on est plac\u00e9 seul avec des montages mensongers qu&rsquo;on doit soutenir, souvent dans des conditions dramatiques (l&rsquo;intervention aupr\u00e8s de familles de soldats tu\u00e9s).<\/p>\n<\/p>\n<p><p>\tLe mensonge conscient \u00e9puise, il contraint les psychologies, il introduit le trouble moral et p\u00e8se sur la conscience surtout lorsqu&rsquo;on est confront\u00e9 \u00e0 ses effets; il am\u00e8ne \u00e0 des situations comme celle de Salisbury-Baker. Il serait int\u00e9ressant que son exemple fasse t\u00e2che d&rsquo;huile, car il s&rsquo;agit bien l\u00e0 du talon d&rsquo;achille du syst\u00e8me, cette mise en lumi\u00e8re du mensonge, et l&rsquo;exploitation d&rsquo;une attitude confrontant ce mensonge avec la loi ne peut conduire qu&rsquo;\u00e0 l&rsquo;affaiblissement de ce m\u00eame syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 ao\u00fbt 2009 \u00e0 08H50<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est un proc\u00e8s d&rsquo;un int\u00e9r\u00eat \u00e9vident qui s&rsquo;ouvre \u00e0 Londres aujourd&rsquo;hui, dont les d\u00e9tails sont notamment r\u00e9percut\u00e9es par The Independent ce 5 ao\u00fbt 2009, et par The Guardian, le 4 ao\u00fbt 2009. Il s&rsquo;agit d&rsquo;un officier de relations publiques de l&rsquo;arm\u00e9e britannique, John Salisbury-Baker, \u00e2g\u00e9 de 62 ans, engag\u00e9 comme charg\u00e9 de relations publiques en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[857,2702,6286,3099,3575,8531,610],"class_list":["post-70962","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-irak","tag-mensonge","tag-proces","tag-psychologie","tag-royaume-uni","tag-salisbury-baker","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70962"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70962\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}